{"id":61776,"date":"2025-06-10T08:46:00","date_gmt":"2025-06-10T14:46:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=61776"},"modified":"2025-06-09T17:28:12","modified_gmt":"2025-06-09T23:28:12","slug":"accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/","title":{"rendered":"Plataforma de apoyo psicol\u00f3gico y legal para migrantes"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"61776\" class=\"elementor elementor-61776\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7fc66b4b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7fc66b4b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2374392c\" data-id=\"2374392c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12ea7f2c elementor-widget elementor-widget-heading\" data-id=\"12ea7f2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Esta iniciativa de la UNAM busca ofrecer l\u00edneas de acci\u00f3n a migrantes que viven en Estados Unidos o que retornaron a M\u00e9xico.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a367c13 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6a367c13\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7aa79be9\" data-id=\"7aa79be9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44cbbbea elementor-widget elementor-widget-text-editor\" data-id=\"44cbbbea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM) y la Secretar\u00eda de Relaciones Exteriores (SRE) pusieron en marcha \u201cAcci\u00f3n Migrante\u201d: <a href=\"https:\/\/accionmigrante.unam.mx\">https:\/\/accionmigrante.unam.mx<\/a>, una plataforma digital destinada a brindar acompa\u00f1amiento en salud mental y orientaci\u00f3n jur\u00eddica a personas migrantes mexicanas. Esta iniciativa es resultado del convenio general de colaboraci\u00f3n firmado entre ambas instituciones en diciembre del a\u00f1o pasado.<\/p><p>El sitio web ofrece dos principales servicios: atenci\u00f3n psicol\u00f3gica y asesor\u00eda legal, ambos a cargo de expertos de la UNAM. En el proyecto participan las cinco sedes de la universidad en Estados Unidos, ubicadas en Los \u00c1ngeles, Tucson, San Antonio, Chicago y Boston, as\u00ed como la estaci\u00f3n noroeste del Instituto de Investigaciones Jur\u00eddicas en Tijuana y los 53 consulados que conforman la Red Consular de M\u00e9xico en Estados Unidos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6be8eef6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6be8eef6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d4daada\" data-id=\"d4daada\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b6e78f4 elementor-widget elementor-widget-image\" data-id=\"5b6e78f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"553\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/accion-unam-salud-mental.png\" class=\"attachment-full size-full wp-image-61785\" alt=\"accion unam salud mental\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/accion-unam-salud-mental.png 553w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/accion-unam-salud-mental-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/accion-unam-salud-mental-18x9.png 18w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6eddbdef\" data-id=\"6eddbdef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19fe2819 elementor-widget elementor-widget-text-editor\" data-id=\"19fe2819\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La atenci\u00f3n psicol\u00f3gica est\u00e1 disponible para personas migrantes tanto en territorio mexicano como estadounidense, con sesiones a distancia que pueden realizarse por tel\u00e9fono o mediante mensajes de WhatsApp. Este servicio est\u00e1 dirigido a quienes enfrentan crisis emocionales derivadas de su experiencia migratoria.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67ad5611 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"67ad5611\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-582d84b5\" data-id=\"582d84b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-446b4129 elementor-widget elementor-widget-text-editor\" data-id=\"446b4129\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En cuanto a la orientaci\u00f3n jur\u00eddica, ofrece informaci\u00f3n b\u00e1sica sobre derechos y procesos legales en Estados Unidos, con \u00e9nfasis en situaciones como detenciones, deportaciones o procesos de repatriaci\u00f3n.<\/p><p>Asimismo, como parte del programa de capacitaci\u00f3n continua #UNAMContigo, se ofrecen diversos programas educativos, por ejemplo, para el cuidado de las finanzas o para la gesti\u00f3n de empresas familiares. Conoce m\u00e1s en el siguiente enlace: <a href=\"https:\/\/accionmigrante.unam.mx\/capacitacion.php\">https:\/\/accionmigrante.unam.mx\/capacitacion.php<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f1f6ec2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6f1f6ec2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c6628ee\" data-id=\"4c6628ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ca607fa elementor-widget elementor-widget-toggle\" data-id=\"3ca607fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1011\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1011\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1011\"><p><strong>ACCI\u00d3N MIGRANTE<\/strong><\/p><p><a href=\"https:\/\/accionmigrante.unam.mx\/\">https:\/\/accionmigrante.unam.mx\/<\/a><\/p><p><strong>SRE<\/strong><\/p><p><a href=\"https:\/\/www.gob.mx\/sre\/prensa\/la-unam-y-la-sre-lanzan-plataforma-para-apoyo-a-migrantes-en-estados-unidos-accion-migrante?idiom=es\">https:\/\/www.gob.mx\/sre\/prensa\/la-unam-y-la-sre-lanzan-plataforma-para-apoyo-a-migrantes-en-estados-unidos-accion-migrante?idiom=es<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Esta iniciativa de la UNAM busca ofrecer l\u00edneas de acci\u00f3n a migrantes que viven en Estados Unidos o que retornaron a M\u00e9xico. La Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM) y la Secretar\u00eda de Relaciones Exteriores (SRE) pusieron en marcha \u201cAcci\u00f3n Migrante\u201d: https:\/\/accionmigrante.unam.mx, una plataforma digital destinada a brindar acompa\u00f1amiento en salud mental y orientaci\u00f3n jur\u00eddica a personas migrantes mexicanas. Esta iniciativa es resultado del convenio general de colaboraci\u00f3n firmado entre ambas instituciones en diciembre del a\u00f1o pasado. El sitio web ofrece dos principales servicios: atenci\u00f3n psicol\u00f3gica y asesor\u00eda legal, ambos a cargo de expertos de la UNAM. En el proyecto participan las cinco sedes de la universidad en Estados Unidos, ubicadas en Los \u00c1ngeles, Tucson, San Antonio, Chicago y Boston, as\u00ed como la estaci\u00f3n noroeste del Instituto de Investigaciones Jur\u00eddicas en Tijuana y los 53 consulados que conforman la Red Consular de M\u00e9xico en Estados Unidos. La atenci\u00f3n psicol\u00f3gica est\u00e1 disponible para personas migrantes tanto en territorio mexicano como estadounidense, con sesiones a distancia que pueden realizarse por tel\u00e9fono o mediante mensajes de WhatsApp. Este servicio est\u00e1 dirigido a quienes enfrentan crisis emocionales derivadas de su experiencia migratoria. En cuanto a la orientaci\u00f3n jur\u00eddica, ofrece informaci\u00f3n b\u00e1sica sobre derechos y procesos legales en Estados Unidos, con \u00e9nfasis en situaciones como detenciones, deportaciones o procesos de repatriaci\u00f3n. Asimismo, como parte del programa de capacitaci\u00f3n continua #UNAMContigo, se ofrecen diversos programas educativos, por ejemplo, para el cuidado de las finanzas o para la gesti\u00f3n de empresas familiares. Conoce m\u00e1s en el siguiente enlace: https:\/\/accionmigrante.unam.mx\/capacitacion.php BIBLIOGRAF\u00cdA ACCI\u00d3N MIGRANTE https:\/\/accionmigrante.unam.mx\/ SRE https:\/\/www.gob.mx\/sre\/prensa\/la-unam-y-la-sre-lanzan-plataforma-para-apoyo-a-migrantes-en-estados-unidos-accion-migrante?idiom=es<\/p>","protected":false},"author":4,"featured_media":61785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[11],"tags":[3514,131,3772,86,743],"class_list":["post-61776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","tag-accion-migrante","tag-apoyo-legal","tag-apoyo-psicologico","tag-migrantes","tag-unam"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | Plataforma de apoyo psicol\u00f3gico y legal para migrantes<\/title>\n<meta name=\"description\" content=\"\u201cAcci\u00f3n Migrante\u201d, la plataforma de apoyo psicol\u00f3gico y legal para migrantes, que naci\u00f3n de una colaboraci\u00f3n entre la SRE y la UNAM.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plataforma de apoyo psicol\u00f3gico y legal para migrantes | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"\u201cAcci\u00f3n Migrante\u201d, la plataforma de apoyo psicol\u00f3gico y legal para migrantes, que naci\u00f3n de una colaboraci\u00f3n entre la SRE y la UNAM.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-10T14:46:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/accion-unam-salud-mental.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Salud Salud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salud Salud\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\\\/salud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\\\/salud\\\/\"},\"author\":{\"name\":\"Salud Salud\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/08cc662f4d6a52ed4a666544f631cc89\"},\"headline\":\"Plataforma de apoyo psicol\u00f3gico y legal para migrantes\",\"datePublished\":\"2025-06-10T14:46:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\\\/salud\\\/\"},\"wordCount\":316,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\\\/salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/accion-unam-salud-mental.png\",\"keywords\":[\"Acci\u00f3n Migrante\",\"Apoyo legal\",\"Apoyo psicol\u00f3gico\",\"Migrantes\",\"UNAM\"],\"articleSection\":[\"Salud\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\\\/salud\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\\\/salud\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\\\/salud\\\/\",\"name\":\"Acceso Latino | Plataforma de apoyo psicol\u00f3gico y legal para migrantes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\\\/salud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\\\/salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/accion-unam-salud-mental.png\",\"datePublished\":\"2025-06-10T14:46:00+00:00\",\"description\":\"\u201cAcci\u00f3n Migrante\u201d, la plataforma de apoyo psicol\u00f3gico y legal para migrantes, que naci\u00f3n de una colaboraci\u00f3n entre la SRE y la UNAM.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\\\/salud\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\\\/salud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\\\/salud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/accion-unam-salud-mental.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/accion-unam-salud-mental.png\",\"width\":553,\"height\":267,\"caption\":\"accion unam salud mental\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\\\/salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salud\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/salud\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plataforma de apoyo psicol\u00f3gico y legal para migrantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/08cc662f4d6a52ed4a666544f631cc89\",\"name\":\"Salud Salud\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | Plataforma de apoyo psicol\u00f3gico y legal para migrantes","description":"\u201cAcci\u00f3n Migrante\u201d, la plataforma de apoyo psicol\u00f3gico y legal para migrantes, que naci\u00f3n de una colaboraci\u00f3n entre la SRE y la UNAM.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/","og_locale":"en_US","og_type":"article","og_title":"Plataforma de apoyo psicol\u00f3gico y legal para migrantes | Acceso Latino","og_description":"\u201cAcci\u00f3n Migrante\u201d, la plataforma de apoyo psicol\u00f3gico y legal para migrantes, que naci\u00f3n de una colaboraci\u00f3n entre la SRE y la UNAM.","og_url":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-06-10T14:46:00+00:00","og_image":[{"width":553,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/accion-unam-salud-mental.png","type":"image\/png"}],"author":"Salud Salud","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Salud Salud","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/"},"author":{"name":"Salud Salud","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/08cc662f4d6a52ed4a666544f631cc89"},"headline":"Plataforma de apoyo psicol\u00f3gico y legal para migrantes","datePublished":"2025-06-10T14:46:00+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/"},"wordCount":316,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/accion-unam-salud-mental.png","keywords":["Acci\u00f3n Migrante","Apoyo legal","Apoyo psicol\u00f3gico","Migrantes","UNAM"],"articleSection":["Salud"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/","url":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/","name":"Acceso Latino | Plataforma de apoyo psicol\u00f3gico y legal para migrantes","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/accion-unam-salud-mental.png","datePublished":"2025-06-10T14:46:00+00:00","description":"\u201cAcci\u00f3n Migrante\u201d, la plataforma de apoyo psicol\u00f3gico y legal para migrantes, que naci\u00f3n de una colaboraci\u00f3n entre la SRE y la UNAM.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/accion-unam-salud-mental.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/accion-unam-salud-mental.png","width":553,"height":267,"caption":"accion unam salud mental"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/accion-migrante-la-plataforma-de-apoyo-psicologico-y-legal-para-migrantes\/salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Salud","item":"https:\/\/accesolatino.org\/category\/salud\/"},{"@type":"ListItem","position":3,"name":"Plataforma de apoyo psicol\u00f3gico y legal para migrantes"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/08cc662f4d6a52ed4a666544f631cc89","name":"Salud Salud"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/61776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=61776"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/61776\/revisions"}],"predecessor-version":[{"id":61793,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/61776\/revisions\/61793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/61785"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=61776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=61776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=61776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}