{"id":1727,"date":"2015-07-22T11:55:51","date_gmt":"2015-07-22T16:55:51","guid":{"rendered":"https:\/\/accesolatino.org\/?p=1727"},"modified":"2025-10-29T22:14:44","modified_gmt":"2025-10-30T04:14:44","slug":"4-programas-para-aprender-ingles","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/4-programas-para-aprender-ingles\/temas-de-interes\/","title":{"rendered":"4 programas para aprender ingl\u00e9s"},"content":{"rendered":"<p>Pr\u00e1cticamente desde sus inicios Estados Unidos es una naci\u00f3n formada por inmigrantes que en muchos casos hablan idiomas diferentes al ingl\u00e9s, es por eso que es de vital importancia que aprendan a hablar el idioma para poderse desarrollar en el pa\u00eds y mientras m\u00e1s temprano comiencen mejor.<\/p>\n<p><strong>Se calcula que cerca de 160 idiomas o dialectos diferentes al ingl\u00e9s son utilizados por los estudiantes que asisten a las escuelas del pa\u00eds.<\/strong><\/p>\n<p>En el aspecto acad\u00e9mico se han tenido que dise\u00f1ar programas encaminados para que los estudiantes que no hablan ingl\u00e9s aprendan el idioma; el prop\u00f3sito es que aprendan ingl\u00e9s desde el kindergarten hasta el 12vo grado para que se puedan desenvolver m\u00e1s en el idioma.<\/p>\n<p>Estos son solo algunos de los programas implementados para que los ni\u00f1os y j\u00f3venes aprendan ingl\u00e9s:<\/p>\n<ol>\n<li><strong>English for Speakers of Other Languages (ESOL):<\/strong> Este programa incorpora aspectos de instrucci\u00f3n, contenido y desarrollo del idioma, de tal manera que involucra el ingl\u00e9s en los aspectos de la vida diaria del estudiante.<\/li>\n<li><strong>Extended Foreign Language (EFL):<\/strong> Este programa existe desde 1997 y tiene como prop\u00f3sito transmitir las destrezas de un lenguaje a otro. El programa ense\u00f1a a los estudiantes a hablar, leer y escribir en ingl\u00e9s por medio de una hora de instrucci\u00f3n diaria o 300 minutos semanales. El programa se ofrece como parte del programa de opciones para padres de familia, Schools of Choice.<\/li>\n<li><strong>Bilingual School Organization (BISO):<\/strong> Este programa ofrece un modelo de ense\u00f1anza del ingl\u00e9s con un 60 por ciento al d\u00eda de instrucci\u00f3n en ingl\u00e9s y el 40 por ciento restante en espa\u00f1ol.<\/li>\n<li><strong>International Studies (IS):<\/strong> El programa es resuoltado de la colaboraci\u00f3n en entre el sistema escolar de Miami-Dade y los ministerios de educaci\u00f3n de Francia, Alemania, Italia, Portugal y Espa\u00f1a. En este programa los estudiantes aprenden el ingl\u00e9s con un enfoque internacional que se rige en normas rigurosas que establecen los ministerios de educaci\u00f3n de la Uni\u00f3n Europea y los Estados Unidos.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><strong>Fuente:<\/strong><em> El Nuevo Herald<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>Pr\u00e1cticamente desde sus inicios Estados Unidos es una naci\u00f3n formada por inmigrantes que en muchos casos hablan idiomas diferentes al ingl\u00e9s, es por eso que es de vital importancia que aprendan a hablar el idioma para poderse desarrollar en el pa\u00eds y mientras m\u00e1s temprano comiencen mejor. Se calcula que cerca de 160 idiomas o dialectos diferentes al ingl\u00e9s son utilizados por los estudiantes que asisten a las escuelas del pa\u00eds. En el aspecto acad\u00e9mico se han tenido que dise\u00f1ar programas encaminados para que los estudiantes que no hablan ingl\u00e9s aprendan el idioma; el prop\u00f3sito es que aprendan ingl\u00e9s desde el kindergarten hasta el 12vo grado para que se puedan desenvolver m\u00e1s en el idioma. Estos son solo algunos de los programas implementados para que los ni\u00f1os y j\u00f3venes aprendan ingl\u00e9s: English for Speakers of Other Languages (ESOL): Este programa incorpora aspectos de instrucci\u00f3n, contenido y desarrollo del idioma, de tal manera que involucra el ingl\u00e9s en los aspectos de la vida diaria del estudiante. Extended Foreign Language (EFL): Este programa existe desde 1997 y tiene como prop\u00f3sito transmitir las destrezas de un lenguaje a otro. El programa ense\u00f1a a los estudiantes a hablar, leer y escribir en ingl\u00e9s por medio de una hora de instrucci\u00f3n diaria o 300 minutos semanales. El programa se ofrece como parte del programa de opciones para padres de familia, Schools of Choice. Bilingual School Organization (BISO): Este programa ofrece un modelo de ense\u00f1anza del ingl\u00e9s con un 60 por ciento al d\u00eda de instrucci\u00f3n en ingl\u00e9s y el 40 por ciento restante en espa\u00f1ol. International Studies (IS): El programa es resuoltado de la colaboraci\u00f3n en entre el sistema escolar de Miami-Dade y los ministerios de educaci\u00f3n de Francia, Alemania, Italia, Portugal y Espa\u00f1a. En este programa los estudiantes aprenden el ingl\u00e9s con un enfoque internacional que se rige en normas rigurosas que establecen los ministerios de educaci\u00f3n de la Uni\u00f3n Europea y los Estados Unidos. &nbsp; Fuente: El Nuevo Herald<\/p>","protected":false},"author":13,"featured_media":1728,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-1727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 programas para aprender ingl\u00e9s<\/title>\n<meta name=\"description\" content=\"Se calcula que cerca de 160 idiomas o dialectos diferentes al ingl\u00e9s son utilizados por los estudiantes que asisten a las escuelas del pa\u00eds.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/4-programas-para-aprender-ingles\/temas-de-interes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 programas para aprender ingl\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Se calcula que cerca de 160 idiomas o dialectos diferentes al ingl\u00e9s son utilizados por los estudiantes que asisten a las escuelas del pa\u00eds.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/4-programas-para-aprender-ingles\/temas-de-interes\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-22T16:55:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T04:14:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/03\/Busqueda-migrantes-extraviados.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/4-programas-para-aprender-ingles\\\/temas-de-interes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/4-programas-para-aprender-ingles\\\/temas-de-interes\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"4 programas para aprender ingl\u00e9s\",\"datePublished\":\"2015-07-22T16:55:51+00:00\",\"dateModified\":\"2025-10-30T04:14:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/4-programas-para-aprender-ingles\\\/temas-de-interes\\\/\"},\"wordCount\":360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/4-programas-para-aprender-ingles\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Busqueda-migrantes-extraviados.jpg\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/4-programas-para-aprender-ingles\\\/temas-de-interes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/4-programas-para-aprender-ingles\\\/temas-de-interes\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/4-programas-para-aprender-ingles\\\/temas-de-interes\\\/\",\"name\":\"4 programas para aprender ingl\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/4-programas-para-aprender-ingles\\\/temas-de-interes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/4-programas-para-aprender-ingles\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Busqueda-migrantes-extraviados.jpg\",\"datePublished\":\"2015-07-22T16:55:51+00:00\",\"dateModified\":\"2025-10-30T04:14:44+00:00\",\"description\":\"Se calcula que cerca de 160 idiomas o dialectos diferentes al ingl\u00e9s son utilizados por los estudiantes que asisten a las escuelas del pa\u00eds.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/4-programas-para-aprender-ingles\\\/temas-de-interes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/4-programas-para-aprender-ingles\\\/temas-de-interes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/4-programas-para-aprender-ingles\\\/temas-de-interes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Busqueda-migrantes-extraviados.jpg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Busqueda-migrantes-extraviados.jpg\",\"width\":\"1000\",\"height\":\"665\",\"caption\":\"Busqueda migrantes extraviados\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/4-programas-para-aprender-ingles\\\/temas-de-interes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"4 programas para aprender ingl\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 programas para aprender ingl\u00e9s","description":"Se calcula que cerca de 160 idiomas o dialectos diferentes al ingl\u00e9s son utilizados por los estudiantes que asisten a las escuelas del pa\u00eds.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/4-programas-para-aprender-ingles\/temas-de-interes\/","og_locale":"en_US","og_type":"article","og_title":"4 programas para aprender ingl\u00e9s","og_description":"Se calcula que cerca de 160 idiomas o dialectos diferentes al ingl\u00e9s son utilizados por los estudiantes que asisten a las escuelas del pa\u00eds.","og_url":"https:\/\/accesolatino.org\/en\/4-programas-para-aprender-ingles\/temas-de-interes\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-07-22T16:55:51+00:00","article_modified_time":"2025-10-30T04:14:44+00:00","og_image":[{"width":1000,"height":665,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/03\/Busqueda-migrantes-extraviados.jpg","type":"image\/jpeg"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/4-programas-para-aprender-ingles\/temas-de-interes\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/4-programas-para-aprender-ingles\/temas-de-interes\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"4 programas para aprender ingl\u00e9s","datePublished":"2015-07-22T16:55:51+00:00","dateModified":"2025-10-30T04:14:44+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/4-programas-para-aprender-ingles\/temas-de-interes\/"},"wordCount":360,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/4-programas-para-aprender-ingles\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/03\/Busqueda-migrantes-extraviados.jpg","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/4-programas-para-aprender-ingles\/temas-de-interes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/4-programas-para-aprender-ingles\/temas-de-interes\/","url":"https:\/\/accesolatino.org\/4-programas-para-aprender-ingles\/temas-de-interes\/","name":"4 programas para aprender ingl\u00e9s","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/4-programas-para-aprender-ingles\/temas-de-interes\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/4-programas-para-aprender-ingles\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/03\/Busqueda-migrantes-extraviados.jpg","datePublished":"2015-07-22T16:55:51+00:00","dateModified":"2025-10-30T04:14:44+00:00","description":"Se calcula que cerca de 160 idiomas o dialectos diferentes al ingl\u00e9s son utilizados por los estudiantes que asisten a las escuelas del pa\u00eds.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/4-programas-para-aprender-ingles\/temas-de-interes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/4-programas-para-aprender-ingles\/temas-de-interes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/4-programas-para-aprender-ingles\/temas-de-interes\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/03\/Busqueda-migrantes-extraviados.jpg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2018\/03\/Busqueda-migrantes-extraviados.jpg","width":"1000","height":"665","caption":"Busqueda migrantes extraviados"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/4-programas-para-aprender-ingles\/temas-de-interes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"4 programas para aprender ingl\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/1727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=1727"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/1727\/revisions"}],"predecessor-version":[{"id":68215,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/1727\/revisions\/68215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/1728"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=1727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=1727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=1727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}