{"id":8436,"date":"2017-03-28T09:18:31","date_gmt":"2017-03-28T15:18:31","guid":{"rendered":"https:\/\/accesolatino.org\/?p=8436"},"modified":"2025-10-28T09:32:39","modified_gmt":"2025-10-28T15:32:39","slug":"otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/","title":{"rendered":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente"},"content":{"rendered":"<p>Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses en zonas rurales o de alto \u00edndice de desempleo<\/p>\n<p>La organizaci\u00f3n Invest in the USA, creada en 2005 para promover la creaci\u00f3n de empleos a trav\u00e9s de este tipo de visado, asegura que la inversi\u00f3n ascendi\u00f3 a 3 mil 816 millones de d\u00f3lares en 2016.<\/p>\n<p>Es una de las pocas opciones migratorias de Estados Unidos que no tiene un factor limitante basado en la nacionalidad, es decir, puede aplicar un inversor de cualquier pa\u00eds.<\/p>\n<p>Los requisitos para participar en este programa son realizar una inversi\u00f3n m\u00ednima de 500 mil d\u00f3lares, seleccionar un proyecto de un tercero para invertir y crear 10 empleos permanentes para trabajadores estadounidenses en zonas rurales o en pol\u00edgonos de alto \u00edndice de desempleo.<\/p>\n<p>Cuando la inversi\u00f3n asciende a 1 mill\u00f3n de d\u00f3lares es porque se trata de una inversi\u00f3n directa, en un proyecto propio. En ambos casos, hay que pasar por un tr\u00e1mite legal para comprobar el origen de los fondos.<\/p>\n<p>La mayor\u00eda de los inversionistas optan por el primer modelo y se asocian con otros inversionistas EB5 y desarrolladores para crear un proyecto.<\/p>\n<p>\u201cLas comunidades cambian de rostro cuando estos conjuntos de inversiones llegan para la construcci\u00f3n de centros de negocios, centros comerciales, nuevos condominios y lo hacen de mano de la generaci\u00f3n de empleos. Las autoridades locales apoyan y promueven estos proyectos transformadores\u201d, explica en entrevista Rodrigo Azpurua, presidente y CEO de Rivera Point, una empresa que capta inversiones EB5 para el desarrollo de edificios de oficinas y hoteles en el sur de Florida.<\/p>\n<p>Actualmente, Rodrigo construye un Hotel Radisson Red en la zona del aeropuerto de Miami con dinero de inversiones que est\u00e1n aplicando para la visa EB5.<\/p>\n<p>La inversi\u00f3n EB5 para un proyecto en particular puede ser de distintos montos, es decir, un n\u00famero cualquiera de inversionistas pueden ser parte del mismo desarrollo.<\/p>\n<p>Juli\u00e1n Montero, un abogado de corporaci\u00f3n que se ha convertido en una especia de abogado de inmigraci\u00f3n al enfocarse en los tr\u00e1mites para el visado EB5 dice que en su despacho ha levantado proyectos por hasta 400 millones de d\u00f3lares con 800 inversionistas distintos.<\/p>\n<p>En septiembre de 2016, el Congreso de Estados Unidos aprob\u00f3 la continuaci\u00f3n del programa EB5 exactamente en los mismos t\u00e9rminos, por lo menos hasta abril de este a\u00f1o.<\/p>\n<p>Pero despu\u00e9s de esa fecha existe la posibilidad de que entre a discusi\u00f3n una iniciativa para reformar el programa. Sin embargo, explica Juli\u00e1n Montero, desde septiembre de 2015 el tema de reforma ha estado sobre la mesa, es decir, mucho antes de la llegada del presidente.<\/p>\n<p>El principal cambio propuesto \u2014que ha acumulado el apoyo de distintos legisladores tanto republicanos como dem\u00f3cratas, as\u00ed como de la industria que se beneficia de la inversi\u00f3n EB5\u2014 es aumentar el monto de la inversi\u00f3n.<\/p>\n<p>Fuente: <em>Animal Pol\u00edtico.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses en zonas rurales o de alto \u00edndice de desempleo La organizaci\u00f3n Invest in the USA, creada en 2005 para promover la creaci\u00f3n de empleos a trav\u00e9s de este tipo de visado, asegura que la inversi\u00f3n ascendi\u00f3 a 3 mil 816 millones de d\u00f3lares en 2016. Es una de las pocas opciones migratorias de Estados Unidos que no tiene un factor limitante basado en la nacionalidad, es decir, puede aplicar un inversor de cualquier pa\u00eds. Los requisitos para participar en este programa son realizar una inversi\u00f3n m\u00ednima de 500 mil d\u00f3lares, seleccionar un proyecto de un tercero para invertir y crear 10 empleos permanentes para trabajadores estadounidenses en zonas rurales o en pol\u00edgonos de alto \u00edndice de desempleo. Cuando la inversi\u00f3n asciende a 1 mill\u00f3n de d\u00f3lares es porque se trata de una inversi\u00f3n directa, en un proyecto propio. En ambos casos, hay que pasar por un tr\u00e1mite legal para comprobar el origen de los fondos. La mayor\u00eda de los inversionistas optan por el primer modelo y se asocian con otros inversionistas EB5 y desarrolladores para crear un proyecto. \u201cLas comunidades cambian de rostro cuando estos conjuntos de inversiones llegan para la construcci\u00f3n de centros de negocios, centros comerciales, nuevos condominios y lo hacen de mano de la generaci\u00f3n de empleos. Las autoridades locales apoyan y promueven estos proyectos transformadores\u201d, explica en entrevista Rodrigo Azpurua, presidente y CEO de Rivera Point, una empresa que capta inversiones EB5 para el desarrollo de edificios de oficinas y hoteles en el sur de Florida. Actualmente, Rodrigo construye un Hotel Radisson Red en la zona del aeropuerto de Miami con dinero de inversiones que est\u00e1n aplicando para la visa EB5. La inversi\u00f3n EB5 para un proyecto en particular puede ser de distintos montos, es decir, un n\u00famero cualquiera de inversionistas pueden ser parte del mismo desarrollo. Juli\u00e1n Montero, un abogado de corporaci\u00f3n que se ha convertido en una especia de abogado de inmigraci\u00f3n al enfocarse en los tr\u00e1mites para el visado EB5 dice que en su despacho ha levantado proyectos por hasta 400 millones de d\u00f3lares con 800 inversionistas distintos. En septiembre de 2016, el Congreso de Estados Unidos aprob\u00f3 la continuaci\u00f3n del programa EB5 exactamente en los mismos t\u00e9rminos, por lo menos hasta abril de este a\u00f1o. Pero despu\u00e9s de esa fecha existe la posibilidad de que entre a discusi\u00f3n una iniciativa para reformar el programa. Sin embargo, explica Juli\u00e1n Montero, desde septiembre de 2015 el tema de reforma ha estado sobre la mesa, es decir, mucho antes de la llegada del presidente. El principal cambio propuesto \u2014que ha acumulado el apoyo de distintos legisladores tanto republicanos como dem\u00f3cratas, as\u00ed como de la industria que se beneficia de la inversi\u00f3n EB5\u2014 es aumentar el monto de la inversi\u00f3n. Fuente: Animal Pol\u00edtico.<\/p>","protected":false},"author":13,"featured_media":8437,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-8436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses en zonas rurales o de alto \u00edndice de desempleo La organizaci\u00f3n Invest in the USA, creada en 2005 para promover la creaci\u00f3n de empleos a trav\u00e9s de este tipo de visado, asegura que la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Noticias\"\/>\n\t<meta name=\"google-site-verification\" content=\"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE\" \/>\n\t<meta name=\"keywords\" content=\"noticias,temas de inter\u00e9s\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente\" \/>\n\t\t<meta property=\"og:description\" content=\"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses en zonas rurales o de alto \u00edndice de desempleo La organizaci\u00f3n Invest in the USA, creada en 2005 para promover la creaci\u00f3n de empleos a trav\u00e9s de este tipo de visado, asegura que la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-03-28T15:18:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-28T15:32:39+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses en zonas rurales o de alto \u00edndice de desempleo La organizaci\u00f3n Invest in the USA, creada en 2005 para promover la creaci\u00f3n de empleos a trav\u00e9s de este tipo de visado, asegura que la\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#blogposting\",\"name\":\"Otra cara de la migraci\\u00f3n a EU: invertir 500 mil d\\u00f3lares y recibir la residencia permanente\",\"headline\":\"Otra cara de la migraci\\u00f3n a EU: invertir 500 mil d\\u00f3lares y recibir la residencia permanente\",\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg\",\"width\":600,\"height\":379,\"caption\":\"Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\"},\"datePublished\":\"2017-03-28T09:18:31-06:00\",\"dateModified\":\"2025-10-28T09:32:39-06:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#webpage\"},\"articleSection\":\"Noticias, Temas de inter\\u00e9s\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/temas-de-interes\\\/#listItem\",\"name\":\"Temas de inter\\u00e9s\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/temas-de-interes\\\/#listItem\",\"position\":2,\"name\":\"Temas de inter\\u00e9s\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/temas-de-interes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#listItem\",\"name\":\"Otra cara de la migraci\\u00f3n a EU: invertir 500 mil d\\u00f3lares y recibir la residencia permanente\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#listItem\",\"position\":3,\"name\":\"Otra cara de la migraci\\u00f3n a EU: invertir 500 mil d\\u00f3lares y recibir la residencia permanente\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/temas-de-interes\\\/#listItem\",\"name\":\"Temas de inter\\u00e9s\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#organizationLogo\",\"width\":240,\"height\":40},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/\",\"name\":\"Noticias\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#webpage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/\",\"name\":\"Otra cara de la migraci\\u00f3n a EU: invertir 500 mil d\\u00f3lares y recibir la residencia permanente\",\"description\":\"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses en zonas rurales o de alto \\u00edndice de desempleo La organizaci\\u00f3n Invest in the USA, creada en 2005 para promover la creaci\\u00f3n de empleos a trav\\u00e9s de este tipo de visado, asegura que la\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#mainImage\",\"width\":600,\"height\":379,\"caption\":\"Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#mainImage\"},\"datePublished\":\"2017-03-28T09:18:31-06:00\",\"dateModified\":\"2025-10-28T09:32:39-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente","description":"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses en zonas rurales o de alto \u00edndice de desempleo La organizaci\u00f3n Invest in the USA, creada en 2005 para promover la creaci\u00f3n de empleos a trav\u00e9s de este tipo de visado, asegura que la","canonical_url":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/","robots":"max-image-preview:large","keywords":"noticias,temas de inter\u00e9s","webmasterTools":{"google-site-verification":"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#blogposting","name":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente","headline":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente","author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2017\/03\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg","width":600,"height":379,"caption":"Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente"},"datePublished":"2017-03-28T09:18:31-06:00","dateModified":"2025-10-28T09:32:39-06:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#webpage"},"isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#webpage"},"articleSection":"Noticias, Temas de inter\u00e9s"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","position":1,"name":"Home","item":"https:\/\/accesolatino.org\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/temas-de-interes\/#listItem","name":"Temas de inter\u00e9s"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/temas-de-interes\/#listItem","position":2,"name":"Temas de inter\u00e9s","item":"https:\/\/accesolatino.org\/en\/category\/temas-de-interes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#listItem","name":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente"},"previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#listItem","position":3,"name":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente","previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/temas-de-interes\/#listItem","name":"Temas de inter\u00e9s"}}]},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/en\/#organization","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","@id":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#organizationLogo","width":240,"height":40},"image":{"@id":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author","url":"https:\/\/accesolatino.org\/en\/author\/noticias\/","name":"Noticias"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#webpage","url":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/","name":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente","description":"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses en zonas rurales o de alto \u00edndice de desempleo La organizaci\u00f3n Invest in the USA, creada en 2005 para promover la creaci\u00f3n de empleos a trav\u00e9s de este tipo de visado, asegura que la","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#breadcrumblist"},"author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"creator":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2017\/03\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg","@id":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#mainImage","width":600,"height":379,"caption":"Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#mainImage"},"datePublished":"2017-03-28T09:18:31-06:00","dateModified":"2025-10-28T09:32:39-06:00"},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/en\/#website","url":"https:\/\/accesolatino.org\/en\/","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","inLanguage":"en-US","publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim","og:type":"article","og:title":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente","og:description":"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses en zonas rurales o de alto \u00edndice de desempleo La organizaci\u00f3n Invest in the USA, creada en 2005 para promover la creaci\u00f3n de empleos a trav\u00e9s de este tipo de visado, asegura que la","og:url":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/","article:published_time":"2017-03-28T15:18:31+00:00","article:modified_time":"2025-10-28T15:32:39+00:00","twitter:card":"summary_large_image","twitter:title":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente","twitter:description":"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses en zonas rurales o de alto \u00edndice de desempleo La organizaci\u00f3n Invest in the USA, creada en 2005 para promover la creaci\u00f3n de empleos a trav\u00e9s de este tipo de visado, asegura que la"},"aioseo_meta_data":{"post_id":"8436","title":"#post_title","description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-07-14 03:30:59","updated":"2025-10-28 15:34:58","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\/category\/temas-de-interes\/\" title=\"Temas de inter\u00e9s\">Temas de inter\u00e9s<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tOtra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/accesolatino.org\/en"},{"label":"Temas de inter\u00e9s","link":"https:\/\/accesolatino.org\/en\/category\/temas-de-interes\/"},{"label":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente","link":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente<\/title>\n<meta name=\"description\" content=\"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente\" \/>\n<meta property=\"og:description\" content=\"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-28T15:18:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-28T15:32:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2017\/03\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"379\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\"},\"headline\":\"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente\",\"datePublished\":\"2017-03-28T15:18:31+00:00\",\"dateModified\":\"2025-10-28T15:32:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/\"},\"wordCount\":519,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/\",\"name\":\"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg\",\"datePublished\":\"2017-03-28T15:18:31+00:00\",\"dateModified\":\"2025-10-28T15:32:39+00:00\",\"description\":\"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg\",\"width\":\"600\",\"height\":\"379\",\"caption\":\"Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente","description":"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente","og_description":"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses","og_url":"https:\/\/accesolatino.org\/en\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2017-03-28T15:18:31+00:00","article_modified_time":"2025-10-28T15:32:39+00:00","og_image":[{"width":600,"height":379,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2017\/03\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg","type":"image\/jpeg"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905"},"headline":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente","datePublished":"2017-03-28T15:18:31+00:00","dateModified":"2025-10-28T15:32:39+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/"},"wordCount":519,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2017\/03\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/","url":"https:\/\/accesolatino.org\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/","name":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2017\/03\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg","datePublished":"2017-03-28T15:18:31+00:00","dateModified":"2025-10-28T15:32:39+00:00","description":"Para recibir la residencia hay que seleccionar un proyecto de un tercero, invertir y crear 10 empleos permanentes para trabajadores estadounidenses","breadcrumb":{"@id":"https:\/\/accesolatino.org\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2017\/03\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2017\/03\/Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente.jpg","width":"600","height":"379","caption":"Otra-cara-de-la-migracion-a-EU-invertir-500-mil-dolares-y-recibir-la-residencia-permanente"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/otra-cara-de-la-migracion-a-eu-invertir-500-mil-dolares-y-recibir-la-residencia-permanente\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Otra cara de la migraci\u00f3n a EU: invertir 500 mil d\u00f3lares y recibir la residencia permanente"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/8436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=8436"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/8436\/revisions"}],"predecessor-version":[{"id":67257,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/8436\/revisions\/67257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/8437"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=8436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=8436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=8436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}