{"id":70882,"date":"2026-03-23T16:07:53","date_gmt":"2026-03-23T22:07:53","guid":{"rendered":"https:\/\/accesolatino.org\/?p=70882"},"modified":"2026-03-26T11:47:24","modified_gmt":"2026-03-26T17:47:24","slug":"year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/","title":{"rendered":"Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"70882\" class=\"elementor elementor-70882\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b44a426 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1b44a426\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c4d7371\" data-id=\"7c4d7371\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a26c4f2 elementor-widget elementor-widget-heading\" data-id=\"2a26c4f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El programa ofrece entrenamiento t\u00e9cnico, pasant\u00edas en empresas reconocidas y un estipendio econ\u00f3mico a j\u00f3venes de 18 a 29 a\u00f1os, incluyendo beneficiarios de DACA.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cc8360 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7cc8360\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5ed6e9\" data-id=\"f5ed6e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4aa1abe7 elementor-widget elementor-widget-text-editor\" data-id=\"4aa1abe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Year Up United representa una alternativa gratuita y accesible para abrir oportunidades laborales y profesionales a j\u00f3venes en Estados Unidos. Se trata de una organizaci\u00f3n sin fines de lucro que ofrece programas de capacitaci\u00f3n t\u00e9cnica y profesional dise\u00f1ados espec\u00edficamente para j\u00f3venes adultos que buscan iniciar o consolidar su trayectoria laboral sin necesidad de contar con un t\u00edtulo universitario.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f8afad5 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2f8afad5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-39c1fe28\" data-id=\"39c1fe28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d72f8f6 elementor-widget elementor-widget-image\" data-id=\"1d72f8f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"829\" height=\"401\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2026\/03\/YUU.png\" class=\"attachment-full size-full wp-image-70884\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2026\/03\/YUU.png 829w, https:\/\/accesolatino.org\/wp-content\/uploads\/2026\/03\/YUU-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2026\/03\/YUU-768x371.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2026\/03\/YUU-18x9.png 18w\" sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-52155b5b\" data-id=\"52155b5b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34403d62 elementor-widget elementor-widget-text-editor\" data-id=\"34403d62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El programa est\u00e1 dirigido a j\u00f3venes de entre 18 y 29 a\u00f1os que cuenten con diploma de preparatoria o GED, tengan ingresos bajos o moderados, no hayan obtenido una licenciatura y est\u00e9n autorizados para trabajar en Estados Unidos durante toda la duraci\u00f3n del programa. Un dato importante para la comunidad latina es que los j\u00f3venes con \u00a0Acci\u00f3n Diferida para los Llegados en la Infancia (DACA) son elegibles para participar, siempre que su autorizaci\u00f3n de trabajo est\u00e9 vigente durante todo el programa. Year Up United cuenta con una p\u00e1gina de orientaci\u00f3n espec\u00edfica para beneficiarios de <a href=\"https:\/\/www.yearup.org\/students\/daca\">DACA disponible en su sitio web.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59ffb8fe elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"59ffb8fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44e9718f\" data-id=\"44e9718f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65280ae0 elementor-widget elementor-widget-text-editor\" data-id=\"65280ae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La capacitaci\u00f3n se ofrece en un modelo h\u00edbrido que combina sesiones presenciales y virtuales, por lo que los participantes deben residir a distancia razonable de alguna de las sedes disponibles y estar disponibles de lunes a viernes durante toda la duraci\u00f3n del programa. Las \u00e1reas de especializaci\u00f3n incluyen tecnolog\u00eda de la informaci\u00f3n, desarrollo de software, negocios y experiencia al cliente, con presencia en ciudades de alta concentraci\u00f3n latina como Nueva York, Los \u00c1ngeles, Miami, Chicago y Atlanta, entre otras.<\/p><p>Entre los beneficios del programa destacan que es completamente gratuito y que los estudiantes reciben un estipendio econ\u00f3mico mientras se capacitan, lo que reduce la carga financiera durante el proceso de formaci\u00f3n. Al concluir la etapa de entrenamiento, los participantes acceden a pasant\u00edas en empresas reconocidas, con acompa\u00f1amiento para la colocaci\u00f3n laboral. A la fecha, la organizaci\u00f3n ha apoyado a m\u00e1s de 50,000 j\u00f3venes adultos en el inicio de carreras mejor remuneradas.<\/p><p>El proceso de solicitud es sencillo y puede completarse en menos de 20 minutos a trav\u00e9s del sitio web de Year Up United. El primer paso es completar la solicitud en l\u00ednea y crear una cuenta en el portal estudiantil, posteriormente es necesario asistir a una entrevista virtual y finalmente esperar la carta de decisi\u00f3n por correo electr\u00f3nico. Antes de aplicar, la organizaci\u00f3n invita a los interesados a asistir a una sesi\u00f3n informativa donde se explican los beneficios, las fases del programa y se resuelven dudas. El calendario de sesiones est\u00e1 disponible en el siguiente enlace: <a href=\"https:\/\/yuprogram.my.salesforce-sites.com\/events#\/calendar\">https:\/\/yuprogram.my.salesforce-sites.com\/events#\/calendar<\/a><\/p><p>Year Up es una oportunidad importante para los j\u00f3venes que buscan una v\u00eda de acceso al mercado laboral formal sin los costos ni los tiempos que implica una carrera universitaria tradicional. A trav\u00e9s de una ruta estructurada con respaldo institucional, esta organizaci\u00f3n ha brindado resultados a j\u00f3venes adultos en Estados Unidos. Por ejemplo, la organizaci\u00f3n ha compartido el caso de Brayan Luna, un joven inmigrante, que a\u00fan sin estatus legal logr\u00f3 acceder a una oportunidad laboral a trav\u00e9s de Year Up.<\/p><p>\u201cRecib\u00ed una oferta de trabajo y, en cuanto supe que se me presentaba esa oportunidad, me sent\u00ed muy feliz. Sab\u00eda que iba a dar un salto hacia algo diferente. Era algo que iba a cambiarme no solo a m\u00ed, sino tambi\u00e9n a mi hijo&#8221;, cont\u00f3 Lunas quien ahora se desempe\u00f1a como Analytics Solutions Associate en\u00a0 JPMorgan Chase.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6874b28f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6874b28f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1bdfe05b\" data-id=\"1bdfe05b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29190247 elementor-widget elementor-widget-toggle\" data-id=\"29190247\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6891\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6891\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6891\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6891\"><p><strong>YEAR UP<\/strong><\/p><p><a href=\"https:\/\/www.yearup.org\/about\/stories\/brayan-luna-building-his-career-jpmorgan-chase\">https:\/\/www.yearup.org\/about\/stories\/brayan-luna-building-his-career-jpmorgan-chase<\/a><\/p><p><a href=\"https:\/\/www.yearup.org\/students\/our-alumni\">https:\/\/www.yearup.org\/students\/our-alumni<\/a><\/p><p><a href=\"https:\/\/www.yearup.org\/students\/how-it-works\">https:\/\/www.yearup.org\/students\/how-it-works<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El programa ofrece entrenamiento t\u00e9cnico, pasant\u00edas en empresas reconocidas y un estipendio econ\u00f3mico a j\u00f3venes de 18 a 29 a\u00f1os, incluyendo beneficiarios de DACA. Year Up United representa una alternativa gratuita y accesible para abrir oportunidades laborales y profesionales a j\u00f3venes en Estados Unidos. Se trata de una organizaci\u00f3n sin fines de lucro que ofrece programas de capacitaci\u00f3n t\u00e9cnica y profesional dise\u00f1ados espec\u00edficamente para j\u00f3venes adultos que buscan iniciar o consolidar su trayectoria laboral sin necesidad de contar con un t\u00edtulo universitario. El programa est\u00e1 dirigido a j\u00f3venes de entre 18 y 29 a\u00f1os que cuenten con diploma de preparatoria o GED, tengan ingresos bajos o moderados, no hayan obtenido una licenciatura y est\u00e9n autorizados para trabajar en Estados Unidos durante toda la duraci\u00f3n del programa. Un dato importante para la comunidad latina es que los j\u00f3venes con \u00a0Acci\u00f3n Diferida para los Llegados en la Infancia (DACA) son elegibles para participar, siempre que su autorizaci\u00f3n de trabajo est\u00e9 vigente durante todo el programa. Year Up United cuenta con una p\u00e1gina de orientaci\u00f3n espec\u00edfica para beneficiarios de DACA disponible en su sitio web. La capacitaci\u00f3n se ofrece en un modelo h\u00edbrido que combina sesiones presenciales y virtuales, por lo que los participantes deben residir a distancia razonable de alguna de las sedes disponibles y estar disponibles de lunes a viernes durante toda la duraci\u00f3n del programa. Las \u00e1reas de especializaci\u00f3n incluyen tecnolog\u00eda de la informaci\u00f3n, desarrollo de software, negocios y experiencia al cliente, con presencia en ciudades de alta concentraci\u00f3n latina como Nueva York, Los \u00c1ngeles, Miami, Chicago y Atlanta, entre otras. Entre los beneficios del programa destacan que es completamente gratuito y que los estudiantes reciben un estipendio econ\u00f3mico mientras se capacitan, lo que reduce la carga financiera durante el proceso de formaci\u00f3n. Al concluir la etapa de entrenamiento, los participantes acceden a pasant\u00edas en empresas reconocidas, con acompa\u00f1amiento para la colocaci\u00f3n laboral. A la fecha, la organizaci\u00f3n ha apoyado a m\u00e1s de 50,000 j\u00f3venes adultos en el inicio de carreras mejor remuneradas. El proceso de solicitud es sencillo y puede completarse en menos de 20 minutos a trav\u00e9s del sitio web de Year Up United. El primer paso es completar la solicitud en l\u00ednea y crear una cuenta en el portal estudiantil, posteriormente es necesario asistir a una entrevista virtual y finalmente esperar la carta de decisi\u00f3n por correo electr\u00f3nico. Antes de aplicar, la organizaci\u00f3n invita a los interesados a asistir a una sesi\u00f3n informativa donde se explican los beneficios, las fases del programa y se resuelven dudas. El calendario de sesiones est\u00e1 disponible en el siguiente enlace: https:\/\/yuprogram.my.salesforce-sites.com\/events#\/calendar Year Up es una oportunidad importante para los j\u00f3venes que buscan una v\u00eda de acceso al mercado laboral formal sin los costos ni los tiempos que implica una carrera universitaria tradicional. A trav\u00e9s de una ruta estructurada con respaldo institucional, esta organizaci\u00f3n ha brindado resultados a j\u00f3venes adultos en Estados Unidos. Por ejemplo, la organizaci\u00f3n ha compartido el caso de Brayan Luna, un joven inmigrante, que a\u00fan sin estatus legal logr\u00f3 acceder a una oportunidad laboral a trav\u00e9s de Year Up. \u201cRecib\u00ed una oferta de trabajo y, en cuanto supe que se me presentaba esa oportunidad, me sent\u00ed muy feliz. Sab\u00eda que iba a dar un salto hacia algo diferente. Era algo que iba a cambiarme no solo a m\u00ed, sino tambi\u00e9n a mi hijo&#8221;, cont\u00f3 Lunas quien ahora se desempe\u00f1a como Analytics Solutions Associate en\u00a0 JPMorgan Chase. BIBLIOGRAF\u00cdA YEAR UP https:\/\/www.yearup.org\/about\/stories\/brayan-luna-building-his-career-jpmorgan-chase https:\/\/www.yearup.org\/students\/our-alumni https:\/\/www.yearup.org\/students\/how-it-works<\/p>","protected":false},"author":13,"featured_media":70944,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10],"tags":[4479,4334,1466,4480,4477],"class_list":["post-70882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-capacitacion-profesional","tag-capacitacion-tecnologica","tag-gratuita","tag-jovenes-en-estados-unidos","tag-year-up"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos<\/title>\n<meta name=\"description\" content=\"Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos; una alternativa a la educaci\u00f3n universitaria.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos; una alternativa a la educaci\u00f3n universitaria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-23T22:07:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T17:47:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2026\/03\/year-up.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"829\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\"},\"headline\":\"Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos\",\"datePublished\":\"2026-03-23T22:07:53+00:00\",\"dateModified\":\"2026-03-26T17:47:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\\\/noticias\\\/\"},\"wordCount\":663,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/year-up.jpg\",\"keywords\":[\"Capacitaci\u00f3n profesional \u2022\",\"capacitaci\u00f3n tecnol\u00f3gica\",\"Gratuita\",\"J\u00f3venes en Estados Unidos\",\"Year Up \u2022\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\\\/noticias\\\/\",\"name\":\"Acceso Latino | Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/year-up.jpg\",\"datePublished\":\"2026-03-23T22:07:53+00:00\",\"dateModified\":\"2026-03-26T17:47:24+00:00\",\"description\":\"Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos; una alternativa a la educaci\u00f3n universitaria.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/year-up.jpg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/year-up.jpg\",\"width\":829,\"height\":401},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos","description":"Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos; una alternativa a la educaci\u00f3n universitaria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos | Acceso Latino","og_description":"Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos; una alternativa a la educaci\u00f3n universitaria.","og_url":"https:\/\/accesolatino.org\/en\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2026-03-23T22:07:53+00:00","article_modified_time":"2026-03-26T17:47:24+00:00","og_image":[{"width":829,"height":401,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2026\/03\/year-up.jpg","type":"image\/jpeg"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b"},"headline":"Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos","datePublished":"2026-03-23T22:07:53+00:00","dateModified":"2026-03-26T17:47:24+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/"},"wordCount":663,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2026\/03\/year-up.jpg","keywords":["Capacitaci\u00f3n profesional \u2022","capacitaci\u00f3n tecnol\u00f3gica","Gratuita","J\u00f3venes en Estados Unidos","Year Up \u2022"],"articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/","url":"https:\/\/accesolatino.org\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/","name":"Acceso Latino | Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2026\/03\/year-up.jpg","datePublished":"2026-03-23T22:07:53+00:00","dateModified":"2026-03-26T17:47:24+00:00","description":"Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos; una alternativa a la educaci\u00f3n universitaria.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2026\/03\/year-up.jpg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2026\/03\/year-up.jpg","width":829,"height":401},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/year-up-united-ofrece-capacitacion-tecnologica-y-profesional-gratuita-para-jovenes-en-estados-unidos\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Year Up United ofrece capacitaci\u00f3n tecnol\u00f3gica y profesional gratuita para j\u00f3venes en Estados Unidos"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/70882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=70882"}],"version-history":[{"count":7,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/70882\/revisions"}],"predecessor-version":[{"id":70897,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/70882\/revisions\/70897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/70944"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=70882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=70882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=70882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}