{"id":69468,"date":"2025-12-29T10:32:25","date_gmt":"2025-12-29T16:32:25","guid":{"rendered":"https:\/\/accesolatino.org\/?p=69468"},"modified":"2025-12-29T10:42:38","modified_gmt":"2025-12-29T16:42:38","slug":"dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/","title":{"rendered":"DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"69468\" class=\"elementor elementor-69468\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14cf092b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"14cf092b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ec22755\" data-id=\"1ec22755\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d705997 elementor-widget elementor-widget-heading\" data-id=\"2d705997\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Seg\u00fan el gobierno estadounidense, 1.9 millones de inmigrantes sin documentos optaron por su salida voluntaria del pa\u00eds.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bfd4a60 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5bfd4a60\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2872d546\" data-id=\"2872d546\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29f43417 elementor-widget elementor-widget-text-editor\" data-id=\"29f43417\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Departamento de Seguridad Nacional (DHS) inform\u00f3 que, desde el 20 de enero de 2025, m\u00e1s de 2.5 millones de personas en situaci\u00f3n migratoria irregular han salido del pa\u00eds, como resultado de deportaciones y salidas voluntarias. De acuerdo con la dependencia, las autoridades migratorias han llevado a cabo m\u00e1s de 605 mil deportaciones durante este periodo. Adem\u00e1s, el DHS se\u00f1al\u00f3 que sus operaciones se han enfocado en personas con antecedentes criminales considerados de alto riesgo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29a1e9b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"29a1e9b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78f1061c\" data-id=\"78f1061c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77383e2a elementor-widget elementor-widget-image\" data-id=\"77383e2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/homeland-security.png\" class=\"attachment-full size-full wp-image-69470\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/homeland-security.png 1500w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/homeland-security-300x200.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/homeland-security-1024x683.png 1024w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/homeland-security-768x512.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/homeland-security-18x12.png 18w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Foto: Telemundo<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-20143079\" data-id=\"20143079\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b747638 elementor-widget elementor-widget-text-editor\" data-id=\"5b747638\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La agencia tambi\u00e9n report\u00f3 que aproximadamente 1.9 millones de personas optaron por la salida voluntaria. Seg\u00fan DHS, este incremento est\u00e1 relacionado con las acciones de vigilancia y con el uso de aplicaciones como CBP Home, que promueve procesos de retorno voluntario a trav\u00e9s de un est\u00edmulo econ\u00f3mico de mil d\u00f3lares y el pago boletos de avi\u00f3n a los pa\u00edses de origen de los inmigrantes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af26952 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"af26952\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2fe896d3\" data-id=\"2fe896d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1949d1f2 elementor-widget elementor-widget-text-editor\" data-id=\"1949d1f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cLa administraci\u00f3n ha registrado m\u00e1s de 2.5 millones de salidas de personas en situaci\u00f3n irregular. Desde el 20 de enero, DHS ha arrestado a m\u00e1s de 595,000 personas,\u201d declar\u00f3 la subsecretaria Tricia McLaughlin. Seg\u00fan\u00a0 McLaughlin, estos resultados son parte de un esfuerzo en el cumplimiento de leyes migratorias.<\/p><p>Asimismo, el DHS indic\u00f3 que la Oficina de Inmigraci\u00f3n y Control de Aduanas (ICE) y la Oficina de Aduanas y Protecci\u00f3n Fronteriza (CBP) han llevado a cabo operaciones focalizadas para detener y procesar a personas buscadas por delitos. La dependencia tambi\u00e9n asegur\u00f3 que estas acciones forman parte de una estrategia m\u00e1s amplia para reforzar el control fronterizo.<\/p><p>El comunicado se\u00f1ala que, de acuerdo con el gobierno federal, la disminuci\u00f3n en el n\u00famero de personas indocumentadas tendr\u00eda efectos en diversos servicios p\u00fablicos y en algunos sectores laborales, aunque no se detallaron m\u00e9tricas espec\u00edficas sobre estos impactos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-545fad92 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"545fad92\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-564d3817\" data-id=\"564d3817\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60faf697 elementor-widget elementor-widget-toggle\" data-id=\"60faf697\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1621\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1621\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1621\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1621\"><p><strong>DHS<\/strong><\/p><p><a href=\"https:\/\/www.dhs.gov\/news\/2025\/12\/10\/thanks-president-trump-and-secretary-noem-more-25-million-illegal-aliens-left-us\">https:\/\/www.dhs.gov\/news\/2025\/12\/10\/thanks-president-trump-and-secretary-noem-more-25-million-illegal-aliens-left-us<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan el gobierno estadounidense, 1.9 millones de inmigrantes sin documentos optaron por su salida voluntaria del pa\u00eds. El Departamento de Seguridad Nacional (DHS) inform\u00f3 que, desde el 20 de enero de 2025, m\u00e1s de 2.5 millones de personas en situaci\u00f3n migratoria irregular han salido del pa\u00eds, como resultado de deportaciones y salidas voluntarias. De acuerdo con la dependencia, las autoridades migratorias han llevado a cabo m\u00e1s de 605 mil deportaciones durante este periodo. Adem\u00e1s, el DHS se\u00f1al\u00f3 que sus operaciones se han enfocado en personas con antecedentes criminales considerados de alto riesgo. Foto: Telemundo La agencia tambi\u00e9n report\u00f3 que aproximadamente 1.9 millones de personas optaron por la salida voluntaria. Seg\u00fan DHS, este incremento est\u00e1 relacionado con las acciones de vigilancia y con el uso de aplicaciones como CBP Home, que promueve procesos de retorno voluntario a trav\u00e9s de un est\u00edmulo econ\u00f3mico de mil d\u00f3lares y el pago boletos de avi\u00f3n a los pa\u00edses de origen de los inmigrantes. \u201cLa administraci\u00f3n ha registrado m\u00e1s de 2.5 millones de salidas de personas en situaci\u00f3n irregular. Desde el 20 de enero, DHS ha arrestado a m\u00e1s de 595,000 personas,\u201d declar\u00f3 la subsecretaria Tricia McLaughlin. Seg\u00fan\u00a0 McLaughlin, estos resultados son parte de un esfuerzo en el cumplimiento de leyes migratorias. Asimismo, el DHS indic\u00f3 que la Oficina de Inmigraci\u00f3n y Control de Aduanas (ICE) y la Oficina de Aduanas y Protecci\u00f3n Fronteriza (CBP) han llevado a cabo operaciones focalizadas para detener y procesar a personas buscadas por delitos. La dependencia tambi\u00e9n asegur\u00f3 que estas acciones forman parte de una estrategia m\u00e1s amplia para reforzar el control fronterizo. El comunicado se\u00f1ala que, de acuerdo con el gobierno federal, la disminuci\u00f3n en el n\u00famero de personas indocumentadas tendr\u00eda efectos en diversos servicios p\u00fablicos y en algunos sectores laborales, aunque no se detallaron m\u00e9tricas espec\u00edficas sobre estos impactos. BIBLIOGRAF\u00cdA DHS https:\/\/www.dhs.gov\/news\/2025\/12\/10\/thanks-president-trump-and-secretary-noem-more-25-million-illegal-aliens-left-us<\/p>","protected":false},"author":13,"featured_media":69470,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[3432,10],"tags":[4256,3580,800,283,4255],"class_list":["post-69468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacada","category-noticias","tag-2-5-millones-de-salidas","tag-cbp-home","tag-deportaciones","tag-dhs","tag-persona-indocumentadas"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025<\/title>\n<meta name=\"description\" content=\"El Departamento de Seguridad Nacional \u2013 DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025 | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"El Departamento de Seguridad Nacional \u2013 DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-29T16:32:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-29T16:42:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/homeland-security-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\\\/destacada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\\\/destacada\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025\",\"datePublished\":\"2025-12-29T16:32:25+00:00\",\"dateModified\":\"2025-12-29T16:42:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\\\/destacada\\\/\"},\"wordCount\":349,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\\\/destacada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/homeland-security.png\",\"keywords\":[\"2.5 millones de salidas\",\"CBP Home\",\"deportaciones\",\"DHS\",\"Persona indocumentadas\"],\"articleSection\":[\"Noticia Destacada\",\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\\\/destacada\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\\\/destacada\\\/\",\"name\":\"Acceso Latino | DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\\\/destacada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\\\/destacada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/homeland-security.png\",\"datePublished\":\"2025-12-29T16:32:25+00:00\",\"dateModified\":\"2025-12-29T16:42:38+00:00\",\"description\":\"El Departamento de Seguridad Nacional \u2013 DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\\\/destacada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\\\/destacada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\\\/destacada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/homeland-security.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/homeland-security.png\",\"width\":1500,\"height\":1000,\"caption\":\"Foto: Telemundo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\\\/destacada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticia Destacada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/destacada\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025","description":"El Departamento de Seguridad Nacional \u2013 DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/","og_locale":"en_US","og_type":"article","og_title":"DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025 | Acceso Latino","og_description":"El Departamento de Seguridad Nacional \u2013 DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025.","og_url":"https:\/\/accesolatino.org\/en\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-12-29T16:32:25+00:00","article_modified_time":"2025-12-29T16:42:38+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/homeland-security-1024x683.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025","datePublished":"2025-12-29T16:32:25+00:00","dateModified":"2025-12-29T16:42:38+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/"},"wordCount":349,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/homeland-security.png","keywords":["2.5 millones de salidas","CBP Home","deportaciones","DHS","Persona indocumentadas"],"articleSection":["Noticia Destacada","Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/","url":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/","name":"Acceso Latino | DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/homeland-security.png","datePublished":"2025-12-29T16:32:25+00:00","dateModified":"2025-12-29T16:42:38+00:00","description":"El Departamento de Seguridad Nacional \u2013 DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/homeland-security.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/homeland-security.png","width":1500,"height":1000,"caption":"Foto: Telemundo"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-2-5-millones-de-salidas-de-personas-indocumentadas-de-estados-unidos-en-2025\/destacada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticia Destacada","item":"https:\/\/accesolatino.org\/category\/destacada\/"},{"@type":"ListItem","position":3,"name":"DHS reporta m\u00e1s de 2.5 millones de salidas de personas indocumentadas de Estados Unidos en 2025"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/69468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=69468"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/69468\/revisions"}],"predecessor-version":[{"id":69482,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/69468\/revisions\/69482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/69470"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=69468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=69468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=69468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}