{"id":69317,"date":"2025-12-15T11:19:40","date_gmt":"2025-12-15T17:19:40","guid":{"rendered":"https:\/\/accesolatino.org\/?p=69317"},"modified":"2025-12-15T11:34:18","modified_gmt":"2025-12-15T17:34:18","slug":"uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/","title":{"rendered":"USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"69317\" class=\"elementor elementor-69317\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f1d5401 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7f1d5401\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52c6c81c\" data-id=\"52c6c81c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b4f5a9c elementor-widget elementor-widget-heading\" data-id=\"1b4f5a9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La agencia aplicar\u00e1 evaluaciones m\u00e1s detalladas a personas originarias de pa\u00edses incluidos en una proclamaci\u00f3n presidencial de alto riesgo.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65d8e746 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"65d8e746\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13741e4f\" data-id=\"13741e4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-694961bf elementor-widget elementor-widget-text-editor\" data-id=\"694961bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n (USCIS) emiti\u00f3 un memorando en el que instruye a su personal a <strong>aplicar una pausa temporal en la resoluci\u00f3n de todas las solicitudes de asilo pendientes, as\u00ed como de diversos tr\u00e1mites migratorios presentados por personas originarias de pa\u00edses identificados como de \u201calto riesgo\u201d<\/strong> en la Proclamaci\u00f3n Presidencial 10949.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47764eff elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"47764eff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-13b2fd59\" data-id=\"13b2fd59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37ffc769 elementor-widget elementor-widget-image\" data-id=\"37ffc769\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"553\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo.png\" class=\"attachment-full size-full wp-image-69318\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo.png 553w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo-18x9.png 18w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Foto: star-telegram.com<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1c296365\" data-id=\"1c296365\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-322be12 elementor-widget elementor-widget-text-editor\" data-id=\"322be12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>De acuerdo con el documento, la medida tiene efecto inmediato y forma parte de un proceso de revisi\u00f3n integral de casos, pol\u00edticas y procedimientos internos. USCIS indic\u00f3 que la pausa permitir\u00e1 realizar an\u00e1lisis adicionales sobre los expedientes en curso para verificar informaci\u00f3n, revisar antecedentes y evaluar si existen elementos relacionados con seguridad nacional o seguridad p\u00fablica que deban considerarse antes de tomar una determinaci\u00f3n final.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47bee5c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"47bee5c0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43b1d711\" data-id=\"43b1d711\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-661512 elementor-widget elementor-widget-text-editor\" data-id=\"661512\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La instrucci\u00f3n establece tres acciones principales: una suspensi\u00f3n temporal de la adjudicaci\u00f3n de todas las solicitudes de asilo; un alto en el procesamiento de ciertos beneficios migratorios solicitados por personas nacidas o ciudadanas de los 19 pa\u00edses mencionados en la proclamaci\u00f3n (la lita incluye a Cuba, Hait\u00ed y Venezuela); y la revisi\u00f3n de casos previamente aprobados para personas que ingresaron a Estados Unidos a partir del 20 de enero de 2021. <strong>Para esta poblaci\u00f3n, las entrevistas no podr\u00e1n ser exentadas y, cuando sea necesario, podr\u00e1n requerirse entrevistas adicionales.<\/strong><\/p><p>USCIS explic\u00f3 que la revisi\u00f3n incluir\u00e1 un an\u00e1lisis individual de cada expediente, considerando informaci\u00f3n relevante como coincidencias en bases de datos de seguridad, posibles v\u00ednculos con actividades prohibidas por la Ley de Inmigraci\u00f3n y Nacionalidad (INA), antecedentes delictivos o dificultades para confirmar identidad. La agencia aclar\u00f3 que estas acciones se realizan bajo la autoridad prevista en leyes y delegaciones vigentes.<\/p><p>El comunicado reconoce que <strong>este proceso puede generar demoras en la resoluci\u00f3n de algunas solicitudes<\/strong>, pero se\u00f1ala que la agencia valor\u00f3 este impacto frente a la prioridad de reforzar los procedimientos de revisi\u00f3n. <strong>La pausa permanecer\u00e1 vigente hasta que USCIS emita una nueva comunicaci\u00f3n que indique su conclusi\u00f3n.<\/strong><\/p><p>Finalmente, la agencia inform\u00f3 que, en un plazo de 90 d\u00edas, elaborar\u00e1 criterios operativos para identificar casos que requieran entrevistas o posibles remisiones a otras instancias, como el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d6248e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7d6248e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e269015\" data-id=\"1e269015\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1eaeeeb elementor-widget elementor-widget-toggle\" data-id=\"1eaeeeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3211\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-3211\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3211\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-3211\"><p><strong>USCIS<\/strong><\/p><p><a href=\"https:\/\/www.uscis.gov\/sites\/default\/files\/document\/policy-alerts\/PM-602-0192-PendingApplicationsHighRiskCountries-20251202.pdf\">https:\/\/www.uscis.gov\/sites\/default\/files\/document\/policy-alerts\/PM-602-0192-PendingApplicationsHighRiskCountries-20251202.pdf<\/a><\/p><p><a href=\"https:\/\/www.uscis.gov\/newsroom\/news-releases\/uscis-implements-additional-national-security-measures-in-the-wake-of-national-guard-shooting-by\">https:\/\/www.uscis.gov\/newsroom\/news-releases\/uscis-implements-additional-national-security-measures-in-the-wake-of-national-guard-shooting-by<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La agencia aplicar\u00e1 evaluaciones m\u00e1s detalladas a personas originarias de pa\u00edses incluidos en una proclamaci\u00f3n presidencial de alto riesgo. El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n (USCIS) emiti\u00f3 un memorando en el que instruye a su personal a aplicar una pausa temporal en la resoluci\u00f3n de todas las solicitudes de asilo pendientes, as\u00ed como de diversos tr\u00e1mites migratorios presentados por personas originarias de pa\u00edses identificados como de \u201calto riesgo\u201d en la Proclamaci\u00f3n Presidencial 10949. Foto: star-telegram.com De acuerdo con el documento, la medida tiene efecto inmediato y forma parte de un proceso de revisi\u00f3n integral de casos, pol\u00edticas y procedimientos internos. USCIS indic\u00f3 que la pausa permitir\u00e1 realizar an\u00e1lisis adicionales sobre los expedientes en curso para verificar informaci\u00f3n, revisar antecedentes y evaluar si existen elementos relacionados con seguridad nacional o seguridad p\u00fablica que deban considerarse antes de tomar una determinaci\u00f3n final. La instrucci\u00f3n establece tres acciones principales: una suspensi\u00f3n temporal de la adjudicaci\u00f3n de todas las solicitudes de asilo; un alto en el procesamiento de ciertos beneficios migratorios solicitados por personas nacidas o ciudadanas de los 19 pa\u00edses mencionados en la proclamaci\u00f3n (la lita incluye a Cuba, Hait\u00ed y Venezuela); y la revisi\u00f3n de casos previamente aprobados para personas que ingresaron a Estados Unidos a partir del 20 de enero de 2021. Para esta poblaci\u00f3n, las entrevistas no podr\u00e1n ser exentadas y, cuando sea necesario, podr\u00e1n requerirse entrevistas adicionales. USCIS explic\u00f3 que la revisi\u00f3n incluir\u00e1 un an\u00e1lisis individual de cada expediente, considerando informaci\u00f3n relevante como coincidencias en bases de datos de seguridad, posibles v\u00ednculos con actividades prohibidas por la Ley de Inmigraci\u00f3n y Nacionalidad (INA), antecedentes delictivos o dificultades para confirmar identidad. La agencia aclar\u00f3 que estas acciones se realizan bajo la autoridad prevista en leyes y delegaciones vigentes. El comunicado reconoce que este proceso puede generar demoras en la resoluci\u00f3n de algunas solicitudes, pero se\u00f1ala que la agencia valor\u00f3 este impacto frente a la prioridad de reforzar los procedimientos de revisi\u00f3n. La pausa permanecer\u00e1 vigente hasta que USCIS emita una nueva comunicaci\u00f3n que indique su conclusi\u00f3n. Finalmente, la agencia inform\u00f3 que, en un plazo de 90 d\u00edas, elaborar\u00e1 criterios operativos para identificar casos que requieran entrevistas o posibles remisiones a otras instancias, como el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE). BIBLIOGRAF\u00cdA USCIS https:\/\/www.uscis.gov\/sites\/default\/files\/document\/policy-alerts\/PM-602-0192-PendingApplicationsHighRiskCountries-20251202.pdf https:\/\/www.uscis.gov\/newsroom\/news-releases\/uscis-implements-additional-national-security-measures-in-the-wake-of-national-guard-shooting-by<\/p>","protected":false},"author":13,"featured_media":69318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10],"tags":[4223,4222,285,240,173],"class_list":["post-69317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-en-pausa","tag-revision-adicional","tag-solicitudes-de-asilo","tag-tramites-migratorios","tag-uscis"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional<\/title>\n<meta name=\"description\" content=\"USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-15T17:19:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T17:34:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional\",\"datePublished\":\"2025-12-15T17:19:40+00:00\",\"dateModified\":\"2025-12-15T17:34:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\\\/noticias\\\/\"},\"wordCount\":449,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo.png\",\"keywords\":[\"En pausa\",\"Revisi\u00f3n adicional\",\"Solicitudes de asilo\",\"Tr\u00e1mites migratorios\",\"USCIS\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\\\/noticias\\\/\",\"name\":\"Acceso Latino | USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo.png\",\"datePublished\":\"2025-12-15T17:19:40+00:00\",\"dateModified\":\"2025-12-15T17:34:18+00:00\",\"description\":\"USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo.png\",\"width\":553,\"height\":267,\"caption\":\"Foto: star-telegram.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional","description":"USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional | Acceso Latino","og_description":"USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional.","og_url":"https:\/\/accesolatino.org\/en\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-12-15T17:19:40+00:00","article_modified_time":"2025-12-15T17:34:18+00:00","og_image":[{"width":553,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional","datePublished":"2025-12-15T17:19:40+00:00","dateModified":"2025-12-15T17:34:18+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/"},"wordCount":449,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo.png","keywords":["En pausa","Revisi\u00f3n adicional","Solicitudes de asilo","Tr\u00e1mites migratorios","USCIS"],"articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/","url":"https:\/\/accesolatino.org\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/","name":"Acceso Latino | USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo.png","datePublished":"2025-12-15T17:19:40+00:00","dateModified":"2025-12-15T17:34:18+00:00","description":"USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/12\/USCIS_pone_en_pausa_la_resolucion_de_solicitudes_de_asilo.png","width":553,"height":267,"caption":"Foto: star-telegram.com"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/uscis-pone-en-pausa-la-resolucion-de-solicitudes-de-asilo-y-ciertos-tramites-migratorios-para-realizar-una-revision-adicional\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"USCIS pone en pausa la resoluci\u00f3n de solicitudes de asilo y ciertos tr\u00e1mites migratorios para realizar una revisi\u00f3n adicional"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/69317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=69317"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/69317\/revisions"}],"predecessor-version":[{"id":69336,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/69317\/revisions\/69336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/69318"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=69317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=69317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=69317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}