{"id":68997,"date":"2025-11-21T08:57:00","date_gmt":"2025-11-21T14:57:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=68997"},"modified":"2025-11-20T12:08:44","modified_gmt":"2025-11-20T18:08:44","slug":"tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/","title":{"rendered":"Tribunal federal suspende nuevas medidas que limitaban licencias comerciales de conducir para inmigrantes"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"68997\" class=\"elementor elementor-68997\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40d5d91a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"40d5d91a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74212fa5\" data-id=\"74212fa5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1395128d elementor-widget elementor-widget-heading\" data-id=\"1395128d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Una corte de apelaciones en Washington D. C. bloque\u00f3 temporalmente la norma del Departamento de Transporte que buscaba limitar qu\u00e9 inmigrantes pueden acceder a licencias para manejar camiones y autobuses.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e9ba3b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"e9ba3b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ff88c19\" data-id=\"3ff88c19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35a8a6 elementor-widget elementor-widget-text-editor\" data-id=\"35a8a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las nuevas reglas del Departamento de Transporte de Estados Unidos (DOT) que buscaban restringir el acceso de ciertos inmigrantes a licencias comerciales de conducir fueron detenidas tras una decisi\u00f3n de la Corte de Apelaciones del Distrito de Columbia. La regulaci\u00f3n, presentada en septiembre, habr\u00eda reducido significativamente el n\u00famero de no ciudadanos elegibles para operar veh\u00edculos pesados como tr\u00e1ileres y autobuses.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8c454d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"8c454d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2a6aafed\" data-id=\"2a6aafed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e09e1fb elementor-widget elementor-widget-image\" data-id=\"e09e1fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"553\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir.png\" class=\"attachment-full size-full wp-image-68998\" alt=\"posible_regulacio\u0301n_del_DHS\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir.png 553w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir-18x9.png 18w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-60410eab\" data-id=\"60410eab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3f91c2 elementor-widget elementor-widget-text-editor\" data-id=\"d3f91c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El tribunal determin\u00f3 que el <strong>gobierno federal no sigui\u00f3 los procedimientos adecuados al emitir la norma<\/strong> ni explic\u00f3 de manera convincente c\u00f3mo las restricciones propuestas mejorar\u00edan la seguridad vial. Seg\u00fan los jueces, los propios datos de la Administraci\u00f3n Federal de Seguridad de Autotransportes (FMCSA) muestran que, <strong>aunque alrededor del 5% de las licencias comerciales pertenecen a inmigrantes, estos conductores representan \u00fanicamente el 0.2% de los accidentes mortales registrados<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4733194c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4733194c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4741c3d2\" data-id=\"4741c3d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28699ad4 elementor-widget elementor-widget-text-editor\" data-id=\"28699ad4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las reglas anunciadas por el secretario de transporte, Sean Duffy, surgieron tras un accidente en Florida, donde un conductor sin documentos para permanecer en el pa\u00eds realiz\u00f3 un giro ilegal y provoc\u00f3 una colisi\u00f3n que dej\u00f3 tres personas fallecidas. Ese caso llev\u00f3 al DOT a revisar la emisi\u00f3n de licencias a no ciudadanos, especialmente en <strong>California<\/strong>, estado donde el conductor hab\u00eda obtenido su licencia. Una auditor\u00eda reciente revel\u00f3 que miles de inmigrantes hab\u00edan recibido licencias v\u00e1lidas por m\u00e1s tiempo que sus permisos de trabajo. Cabe destacar, que esta semana, California revoc\u00f3 17 mil licencias comerciales por ese motivo.<\/p><p>La medida suspendida <strong>habr\u00eda limitado la elegibilidad \u00fanicamente a inmigrantes con visas H-2A, H-2B o E-2<\/strong> y requer\u00eda que los estados verificaran el estatus migratorio de cada solicitante en una base de datos federal. Adem\u00e1s, las licencias tendr\u00edan una vigencia m\u00e1xima de un a\u00f1o o menos si el visado del conductor expiraba antes. Se estima que solo 10 mil de los aproximadamente 200 mil no ciudadanos con licencias comerciales actuales cumplir\u00edan con los nuevos requisitos. El resto conservar\u00eda su licencia solo hasta el momento de su renovaci\u00f3n.<\/p><p>Adem\u00e1s, Duffy ha retenido 40 millones de d\u00f3lares en fondos federales al argumentar que California no est\u00e1 aplicando los requisitos de ingl\u00e9s para conductores, y advirti\u00f3 que podr\u00eda retener otros 160 millones si no se cancelan todas las licencias consideradas inv\u00e1lidas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4584efd3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4584efd3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61994d71\" data-id=\"61994d71\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cb7610e elementor-widget elementor-widget-toggle\" data-id=\"7cb7610e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2091\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2091\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2091\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2091\"><p><strong>ABC NEWS<\/strong><\/p><p><a href=\"https:\/\/abcnews.go.com\/US\/wireStory\/court-blocks-new-rules-limiting-immigrants-commercial-drivers-127527676\">https:\/\/abcnews.go.com\/US\/wireStory\/court-blocks-new-rules-limiting-immigrants-commercial-drivers-127527676<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Una corte de apelaciones en Washington D. C. bloque\u00f3 temporalmente la norma del Departamento de Transporte que buscaba limitar qu\u00e9 inmigrantes pueden acceder a licencias para manejar camiones y autobuses. Las nuevas reglas del Departamento de Transporte de Estados Unidos (DOT) que buscaban restringir el acceso de ciertos inmigrantes a licencias comerciales de conducir fueron detenidas tras una decisi\u00f3n de la Corte de Apelaciones del Distrito de Columbia. La regulaci\u00f3n, presentada en septiembre, habr\u00eda reducido significativamente el n\u00famero de no ciudadanos elegibles para operar veh\u00edculos pesados como tr\u00e1ileres y autobuses. El tribunal determin\u00f3 que el gobierno federal no sigui\u00f3 los procedimientos adecuados al emitir la norma ni explic\u00f3 de manera convincente c\u00f3mo las restricciones propuestas mejorar\u00edan la seguridad vial. Seg\u00fan los jueces, los propios datos de la Administraci\u00f3n Federal de Seguridad de Autotransportes (FMCSA) muestran que, aunque alrededor del 5% de las licencias comerciales pertenecen a inmigrantes, estos conductores representan \u00fanicamente el 0.2% de los accidentes mortales registrados. Las reglas anunciadas por el secretario de transporte, Sean Duffy, surgieron tras un accidente en Florida, donde un conductor sin documentos para permanecer en el pa\u00eds realiz\u00f3 un giro ilegal y provoc\u00f3 una colisi\u00f3n que dej\u00f3 tres personas fallecidas. Ese caso llev\u00f3 al DOT a revisar la emisi\u00f3n de licencias a no ciudadanos, especialmente en California, estado donde el conductor hab\u00eda obtenido su licencia. Una auditor\u00eda reciente revel\u00f3 que miles de inmigrantes hab\u00edan recibido licencias v\u00e1lidas por m\u00e1s tiempo que sus permisos de trabajo. Cabe destacar, que esta semana, California revoc\u00f3 17 mil licencias comerciales por ese motivo. La medida suspendida habr\u00eda limitado la elegibilidad \u00fanicamente a inmigrantes con visas H-2A, H-2B o E-2 y requer\u00eda que los estados verificaran el estatus migratorio de cada solicitante en una base de datos federal. Adem\u00e1s, las licencias tendr\u00edan una vigencia m\u00e1xima de un a\u00f1o o menos si el visado del conductor expiraba antes. Se estima que solo 10 mil de los aproximadamente 200 mil no ciudadanos con licencias comerciales actuales cumplir\u00edan con los nuevos requisitos. El resto conservar\u00eda su licencia solo hasta el momento de su renovaci\u00f3n. Adem\u00e1s, Duffy ha retenido 40 millones de d\u00f3lares en fondos federales al argumentar que California no est\u00e1 aplicando los requisitos de ingl\u00e9s para conductores, y advirti\u00f3 que podr\u00eda retener otros 160 millones si no se cancelan todas las licencias consideradas inv\u00e1lidas. BIBLIOGRAF\u00cdA ABC NEWS https:\/\/abcnews.go.com\/US\/wireStory\/court-blocks-new-rules-limiting-immigrants-commercial-drivers-127527676<\/p>","protected":false},"author":13,"featured_media":68998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[3432,10],"tags":[87,1449,302,295,4165],"class_list":["post-68997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacada","category-noticias","tag-inmigrantes","tag-licencias-comerciales","tag-licencias-de-conducir","tag-no-ciudadanos","tag-tribunal-federal"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | Tribunal federal suspende nuevas medidas que limitaban licencias comerciales de conducir para inmigrantes<\/title>\n<meta name=\"description\" content=\"Tribunal federal en D.C. suspende las nuevas medidas del DOT que limitaban licencias comerciales de conducir para inmigrantes y no ciudadanos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal federal suspende nuevas medidas que limitaban licencias comerciales de conducir para inmigrantes | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Tribunal federal en D.C. suspende las nuevas medidas del DOT que limitaban licencias comerciales de conducir para inmigrantes y no ciudadanos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-21T14:57:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\\\/destacada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\\\/destacada\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Tribunal federal suspende nuevas medidas que limitaban licencias comerciales de conducir para inmigrantes\",\"datePublished\":\"2025-11-21T14:57:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\\\/destacada\\\/\"},\"wordCount\":435,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\\\/destacada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir.png\",\"keywords\":[\"Inmigrantes\",\"Licencias comerciales\",\"Licencias de conducir\",\"No ciudadanos\",\"Tribunal federal\"],\"articleSection\":[\"Noticia Destacada\",\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\\\/destacada\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\\\/destacada\\\/\",\"name\":\"Acceso Latino | Tribunal federal suspende nuevas medidas que limitaban licencias comerciales de conducir para inmigrantes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\\\/destacada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\\\/destacada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir.png\",\"datePublished\":\"2025-11-21T14:57:00+00:00\",\"description\":\"Tribunal federal en D.C. suspende las nuevas medidas del DOT que limitaban licencias comerciales de conducir para inmigrantes y no ciudadanos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\\\/destacada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\\\/destacada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\\\/destacada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir.png\",\"width\":553,\"height\":267,\"caption\":\"posible_regulacio\u0301n_del_DHS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\\\/destacada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticia Destacada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/destacada\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tribunal federal suspende nuevas medidas que limitaban licencias comerciales de conducir para inmigrantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | Tribunal federal suspende nuevas medidas que limitaban licencias comerciales de conducir para inmigrantes","description":"Tribunal federal en D.C. suspende las nuevas medidas del DOT que limitaban licencias comerciales de conducir para inmigrantes y no ciudadanos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/","og_locale":"en_US","og_type":"article","og_title":"Tribunal federal suspende nuevas medidas que limitaban licencias comerciales de conducir para inmigrantes | Acceso Latino","og_description":"Tribunal federal en D.C. suspende las nuevas medidas del DOT que limitaban licencias comerciales de conducir para inmigrantes y no ciudadanos.","og_url":"https:\/\/accesolatino.org\/en\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-11-21T14:57:00+00:00","og_image":[{"width":553,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Tribunal federal suspende nuevas medidas que limitaban licencias comerciales de conducir para inmigrantes","datePublished":"2025-11-21T14:57:00+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/"},"wordCount":435,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir.png","keywords":["Inmigrantes","Licencias comerciales","Licencias de conducir","No ciudadanos","Tribunal federal"],"articleSection":["Noticia Destacada","Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/","url":"https:\/\/accesolatino.org\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/","name":"Acceso Latino | Tribunal federal suspende nuevas medidas que limitaban licencias comerciales de conducir para inmigrantes","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir.png","datePublished":"2025-11-21T14:57:00+00:00","description":"Tribunal federal en D.C. suspende las nuevas medidas del DOT que limitaban licencias comerciales de conducir para inmigrantes y no ciudadanos.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/posible_regulacion_del_DHS_podria_impedir_que_miles_de_migrantes_sin_estatus_legal_renueven_sus_licencias_de_conducir.png","width":553,"height":267,"caption":"posible_regulacio\u0301n_del_DHS"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/tribunal-federal-suspende-nuevas-medidas-que-limitaban-licencias-comerciales-de-conducir-para-inmigrantes\/destacada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticia Destacada","item":"https:\/\/accesolatino.org\/category\/destacada\/"},{"@type":"ListItem","position":3,"name":"Tribunal federal suspende nuevas medidas que limitaban licencias comerciales de conducir para inmigrantes"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/68997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=68997"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/68997\/revisions"}],"predecessor-version":[{"id":69014,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/68997\/revisions\/69014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/68998"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=68997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=68997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=68997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}