{"id":68605,"date":"2025-11-10T11:14:51","date_gmt":"2025-11-10T17:14:51","guid":{"rendered":"https:\/\/accesolatino.org\/?p=68605"},"modified":"2025-11-10T11:49:11","modified_gmt":"2025-11-10T17:49:11","slug":"defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/","title":{"rendered":"Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"68605\" class=\"elementor elementor-68605\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10dcdf5f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"10dcdf5f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60ce5333\" data-id=\"60ce5333\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22e2416a elementor-widget elementor-widget-heading\" data-id=\"22e2416a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Impulsado por United We Dream, ACLU y Abundant Futures Fund, el fondo busca recaudar 30 millones de d\u00f3lares para brindar representaci\u00f3n legal y asistencia de fianza a comunidades inmigrantes de todo el pa\u00eds.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49084746 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"49084746\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20f77712\" data-id=\"20f77712\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ce49193 elementor-widget elementor-widget-text-editor\" data-id=\"5ce49193\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En el contexto migratorio actual en el que millones de familias inmigrantes enfrentan procesos de detenci\u00f3n o deportaci\u00f3n sin acceso a un abogado, el <strong>Defending Our Neighbors Fund <\/strong>\u00a0ofrece apoyo urgente para garantizar el derecho a la defensa y mantener unidas a las familias. Este fondo, creado de manera colaborativa entre <strong>United We Dream Network<\/strong> y la <strong>American Civil Liberties Union (ACLU)<\/strong>, es administrado por el <strong>Abundant Futures Fund<\/strong>, un proyecto fiscalmente patrocinado por Rockefeller Philanthropy Advisors.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8228a2d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"8228a2d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e38925d\" data-id=\"5e38925d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b209a38 elementor-widget elementor-widget-image\" data-id=\"3b209a38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"829\" height=\"401\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/defending-neig.png\" class=\"attachment-full size-full wp-image-68606\" alt=\"defending neig\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/defending-neig.png 829w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/defending-neig-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/defending-neig-768x371.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/defending-neig-18x9.png 18w\" sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-48f37da1\" data-id=\"48f37da1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5220b332 elementor-widget elementor-widget-text-editor\" data-id=\"5220b332\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Defending Our Neighbors Fund est\u00e1 impulsado por el compromiso de personas y organizaciones que buscan ofrecer una respuesta inmediata a la falta de asistencia legal que enfrentan las comunidades inmigrantes en Estados Unidos. Su objetivo es recaudar y distribuir recursos de manera r\u00e1pida a organizaciones locales que ofrecen representaci\u00f3n legal y, cuando es posible, apoyo para el pago de fianzas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70dd5883 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"70dd5883\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12e8ca44\" data-id=\"12e8ca44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a36133c elementor-widget elementor-widget-text-editor\" data-id=\"3a36133c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Actualmente, m\u00e1s de <strong>6<\/strong> <strong>millones de hogares estadounidenses<\/strong><strong> tienen al menos un integrante en riesgo de detenci\u00f3n o deportaci\u00f3n<\/strong>. Pese a esta realidad, el gobierno federal ha destinado 170 mil millones de d\u00f3lares para reforzar las acciones de control migratorio, mientras que los fondos p\u00fablicos para servicios legales han disminuido dr\u00e1sticamente.<\/p><p>Contar con representaci\u00f3n legal puede marcar el destino de una familia, por ejemplo, en 2024, m\u00e1s de 2.5 millones de casos en tribunales de inmigraci\u00f3n se desarrollaron sin abogados defensores. En muchos de estos casos, incluso ni\u00f1os y ni\u00f1as enfrentaron procesos sin asesor\u00eda legal, mientras se garantizaba la presencia de fiscales entrenados.<\/p><p>El fondo busca revertir esta desigualdad mediante subvenciones de respuesta r\u00e1pida a organizaciones que atienden a comunidades inmigrantes en zonas con altos \u00edndices de detenci\u00f3n, en regiones con escasa oferta de servicios legales o en centros de procesamiento migratorio.<\/p><p>Este fondo busca reunir 30 millones de d\u00f3lares para fortalecer la red de apoyo legal a familias inmigrantes y ofrecer una alternativa ante la falta de protecci\u00f3n institucional. La campa\u00f1a hace un llamado a la solidaridad ciudadana para construir un movimiento basado en peque\u00f1as donaciones que, en conjunto, pueden marcar una gran diferencia.<\/p><p>\u201cCuando das al <em>Defending Our Neighbors Fund<\/em>, ayudas a sostener una red de organizaciones comprometidas con servir como un salvavidas para las familias inmigrantes que enfrentan un sistema legal abrumador y punitivo\u201d, se\u00f1ala la organizaci\u00f3n United We Dream.<\/p><p>De esta forma, el Defending Our Neighbors Fund representa una iniciativa colectiva y organizada impulsada por la justicia. Al contar con el apoyo de organizaciones l\u00edderes en defensa de migrantes en Estados Unidos, el fondo busca garantizar que ninguna familia enfrente sola un proceso migratorio y que esto sea una realidad para todas las personas, sin importar su origen.<\/p><p>Learn more at the following link: <a href=\"https:\/\/defendingourneighbors.org\/\">https:\/\/defendingourneighbors.org\/<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f3ced36 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"f3ced36\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e819dbb\" data-id=\"5e819dbb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a3b7966 elementor-widget elementor-widget-toggle\" data-id=\"5a3b7966\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1511\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1511\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1511\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1511\"><p><strong>UNITED WE DREAM<\/strong><\/p><p><a href=\"https:\/\/www.threads.com\/@unitedwedream\/post\/DQXMKPvFR76\">https:\/\/www.threads.com\/@unitedwedream\/post\/DQXMKPvFR76<\/a><\/p><p><strong>DEFENDING OUR NEIGHBORS<\/strong><\/p><p><a href=\"https:\/\/defendingourneighbors.org\/\">https:\/\/defendingourneighbors.org\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Impulsado por United We Dream, ACLU y Abundant Futures Fund, el fondo busca recaudar 30 millones de d\u00f3lares para brindar representaci\u00f3n legal y asistencia de fianza a comunidades inmigrantes de todo el pa\u00eds. En el contexto migratorio actual en el que millones de familias inmigrantes enfrentan procesos de detenci\u00f3n o deportaci\u00f3n sin acceso a un abogado, el Defending Our Neighbors Fund \u00a0ofrece apoyo urgente para garantizar el derecho a la defensa y mantener unidas a las familias. Este fondo, creado de manera colaborativa entre United We Dream Network y la American Civil Liberties Union (ACLU), es administrado por el Abundant Futures Fund, un proyecto fiscalmente patrocinado por Rockefeller Philanthropy Advisors. El Defending Our Neighbors Fund est\u00e1 impulsado por el compromiso de personas y organizaciones que buscan ofrecer una respuesta inmediata a la falta de asistencia legal que enfrentan las comunidades inmigrantes en Estados Unidos. Su objetivo es recaudar y distribuir recursos de manera r\u00e1pida a organizaciones locales que ofrecen representaci\u00f3n legal y, cuando es posible, apoyo para el pago de fianzas. Actualmente, m\u00e1s de 6 millones de hogares estadounidenses tienen al menos un integrante en riesgo de detenci\u00f3n o deportaci\u00f3n. Pese a esta realidad, el gobierno federal ha destinado 170 mil millones de d\u00f3lares para reforzar las acciones de control migratorio, mientras que los fondos p\u00fablicos para servicios legales han disminuido dr\u00e1sticamente. Contar con representaci\u00f3n legal puede marcar el destino de una familia, por ejemplo, en 2024, m\u00e1s de 2.5 millones de casos en tribunales de inmigraci\u00f3n se desarrollaron sin abogados defensores. En muchos de estos casos, incluso ni\u00f1os y ni\u00f1as enfrentaron procesos sin asesor\u00eda legal, mientras se garantizaba la presencia de fiscales entrenados. El fondo busca revertir esta desigualdad mediante subvenciones de respuesta r\u00e1pida a organizaciones que atienden a comunidades inmigrantes en zonas con altos \u00edndices de detenci\u00f3n, en regiones con escasa oferta de servicios legales o en centros de procesamiento migratorio. Este fondo busca reunir 30 millones de d\u00f3lares para fortalecer la red de apoyo legal a familias inmigrantes y ofrecer una alternativa ante la falta de protecci\u00f3n institucional. La campa\u00f1a hace un llamado a la solidaridad ciudadana para construir un movimiento basado en peque\u00f1as donaciones que, en conjunto, pueden marcar una gran diferencia. \u201cCuando das al Defending Our Neighbors Fund, ayudas a sostener una red de organizaciones comprometidas con servir como un salvavidas para las familias inmigrantes que enfrentan un sistema legal abrumador y punitivo\u201d, se\u00f1ala la organizaci\u00f3n United We Dream. De esta forma, el Defending Our Neighbors Fund representa una iniciativa colectiva y organizada impulsada por la justicia. Al contar con el apoyo de organizaciones l\u00edderes en defensa de migrantes en Estados Unidos, el fondo busca garantizar que ninguna familia enfrente sola un proceso migratorio y que esto sea una realidad para todas las personas, sin importar su origen. Conoce m\u00e1s en el siguiente enlace: https:\/\/defendingourneighbors.org\/ BIBLIOGRAF\u00cdA UNITED WE DREAM https:\/\/www.threads.com\/@unitedwedream\/post\/DQXMKPvFR76 DEFENDING OUR NEIGHBORS https:\/\/defendingourneighbors.org\/<\/p>","protected":false},"author":13,"featured_media":68606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[90,3432,10,157],"tags":[1316,4131,4130,4132,439],"class_list":["post-68605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apoyo-social","category-destacada","category-noticias","category-red-de-apoyo","tag-aclu","tag-apoyo-legal-urgente","tag-defending-our-neighbors-fund","tag-familiar-migrantes","tag-united-we-dream"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos<\/title>\n<meta name=\"description\" content=\"Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos ante la situaci\u00f3n migratoria.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos ante la situaci\u00f3n migratoria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-10T17:14:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T17:49:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/defending-neig.png\" \/>\n\t<meta property=\"og:image:width\" content=\"829\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\\\/destacada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\\\/destacada\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\"},\"headline\":\"Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos\",\"datePublished\":\"2025-11-10T17:14:51+00:00\",\"dateModified\":\"2025-11-10T17:49:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\\\/destacada\\\/\"},\"wordCount\":527,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\\\/destacada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/defending-neig.png\",\"keywords\":[\"ACLU\",\"Apoyo legal urgente\",\"Defending Our Neighbors Fund\",\"Familiar migrantes\",\"United We Dream\"],\"articleSection\":[\"Apoyo Social\",\"Noticia Destacada\",\"Noticias\",\"Red de apoyo\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\\\/destacada\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\\\/destacada\\\/\",\"name\":\"Acceso Latino | Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\\\/destacada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\\\/destacada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/defending-neig.png\",\"datePublished\":\"2025-11-10T17:14:51+00:00\",\"dateModified\":\"2025-11-10T17:49:11+00:00\",\"description\":\"Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos ante la situaci\u00f3n migratoria.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\\\/destacada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\\\/destacada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\\\/destacada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/defending-neig.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/defending-neig.png\",\"width\":829,\"height\":401,\"caption\":\"defending neig\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\\\/destacada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticia Destacada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/destacada\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos","description":"Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos ante la situaci\u00f3n migratoria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/","og_locale":"en_US","og_type":"article","og_title":"Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos | Acceso Latino","og_description":"Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos ante la situaci\u00f3n migratoria.","og_url":"https:\/\/accesolatino.org\/en\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-11-10T17:14:51+00:00","article_modified_time":"2025-11-10T17:49:11+00:00","og_image":[{"width":829,"height":401,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/defending-neig.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b"},"headline":"Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos","datePublished":"2025-11-10T17:14:51+00:00","dateModified":"2025-11-10T17:49:11+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/"},"wordCount":527,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/defending-neig.png","keywords":["ACLU","Apoyo legal urgente","Defending Our Neighbors Fund","Familiar migrantes","United We Dream"],"articleSection":["Apoyo Social","Noticia Destacada","Noticias","Red de apoyo"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/","url":"https:\/\/accesolatino.org\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/","name":"Acceso Latino | Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/defending-neig.png","datePublished":"2025-11-10T17:14:51+00:00","dateModified":"2025-11-10T17:49:11+00:00","description":"Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos ante la situaci\u00f3n migratoria.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/defending-neig.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/defending-neig.png","width":829,"height":401,"caption":"defending neig"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/defending-our-neighbors-fund-ofrece-apoyo-legal-urgente-para-familias-migrantes-en-estados-unidos\/destacada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticia Destacada","item":"https:\/\/accesolatino.org\/category\/destacada\/"},{"@type":"ListItem","position":3,"name":"Defending Our Neighbors Fund ofrece apoyo legal urgente para familias migrantes en Estados Unidos"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/68605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=68605"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/68605\/revisions"}],"predecessor-version":[{"id":68614,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/68605\/revisions\/68614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/68606"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=68605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=68605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=68605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}