{"id":68433,"date":"2025-11-04T10:57:50","date_gmt":"2025-11-04T16:57:50","guid":{"rendered":"https:\/\/accesolatino.org\/?p=68433"},"modified":"2025-11-04T11:08:17","modified_gmt":"2025-11-04T17:08:17","slug":"dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/","title":{"rendered":"DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"68433\" class=\"elementor elementor-68433\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11a9a44f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"11a9a44f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-363941ca\" data-id=\"363941ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b959c77 elementor-widget elementor-widget-heading\" data-id=\"5b959c77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El Departamento de Seguridad Nacional se\u00f1ala un incremento en las remociones o removals y autodeportaciones.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6dc579ce elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6dc579ce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-150e7f72\" data-id=\"150e7f72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24a7f8e0 elementor-widget elementor-widget-text-editor\" data-id=\"24a7f8e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Departamento de Seguridad Nacional de Estados Unidos (DHS) inform\u00f3 que m\u00e1s de 527 mil personas fueron deportadas desde el pa\u00eds durante 2025, en lo que calific\u00f3 como un \u201cr\u00e9cord hist\u00f3rico\u201d bajo la administraci\u00f3n del presidente Donald Trump y la secretaria de Seguridad Nacional Kristi Noem.<\/p><p>De acuerdo con el comunicado oficial emitido el 27 de octubre, el gobierno report\u00f3 adem\u00e1s que m\u00e1s de 2 millones de personas en situaci\u00f3n migratoria irregular abandonaron el pa\u00eds, de las cuales 1.6 millones lo hicieron de manera voluntaria, mientras que el resto fueron deportadas por las agencias de Inmigraci\u00f3n y Control de Aduanas (ICE) y Aduanas y Protecci\u00f3n Fronteriza (CBP).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-386a1e37 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"386a1e37\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-694f455e\" data-id=\"694f455e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ba2fd89 elementor-widget elementor-widget-image\" data-id=\"1ba2fd89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"460\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/DHS-reporta-mas-de-medio-millon-de-deportaciones.jpg\" class=\"attachment-full size-full wp-image-68434\" alt=\"DHS reporta mas de medio millon de deportaciones\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/DHS-reporta-mas-de-medio-millon-de-deportaciones.jpg 800w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/DHS-reporta-mas-de-medio-millon-de-deportaciones-300x173.jpg 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/DHS-reporta-mas-de-medio-millon-de-deportaciones-768x442.jpg 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/DHS-reporta-mas-de-medio-millon-de-deportaciones-18x10.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5b63540c\" data-id=\"5b63540c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68835787 elementor-widget elementor-widget-text-editor\" data-id=\"68835787\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Adem\u00e1s, el DHS destac\u00f3 que la administraci\u00f3n actual \u201cest\u00e1 en camino de superar las cifras hist\u00f3ricas\u201d de deportaciones, con la meta de alcanzar cerca de 600 mil remociones al cierre del a\u00f1o. Seg\u00fan el comunicado, la pol\u00edtica busca cumplir la promesa presidencial de \u201ccerrar la frontera\u201d y fortalecer la aplicaci\u00f3n de las leyes migratorias.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30a2c24e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"30a2c24e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46f429a3\" data-id=\"46f429a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-663a7cf8 elementor-widget elementor-widget-text-editor\" data-id=\"663a7cf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El comunicado tambi\u00e9n detalla que el n\u00famero de personas que intentan cruzar el Tap\u00f3n del Dari\u00e9n, en Panam\u00e1, ha disminuido en 99.99% debido a las nuevas pol\u00edticas migratorias y a las campa\u00f1as de advertencia impulsadas por el gobierno estadounidense.<\/p><p>El DHS subraya que \u201cel 70% de los arrestos realizados por ICE corresponden a personas con cargos o condenas por delitos en Estados Unidos\u201d. Asimismo, afirma que las acciones de las agencias federales se concentran en quienes representan \u201cun riesgo para la seguridad p\u00fablica\u201d.<\/p><p>Como parte de las nuevas medidas, el gobierno estadounidense ofrece un programa de salida voluntaria a trav\u00e9s de la aplicaci\u00f3n m\u00f3vil CBP Home, mediante el cual las personas que decidan regresar a su pa\u00eds de origen pueden recibir mil d\u00f3lares y un vuelo gratuito. Seg\u00fan el comunicado, quienes participen en este programa \u201cmantendr\u00e1n abierta la posibilidad de volver de forma legal en el futuro\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22783fc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"22783fc0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a99b06e\" data-id=\"1a99b06e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-588785b7 elementor-widget elementor-widget-toggle\" data-id=\"588785b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1481\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1481\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1481\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1481\"><p><strong>DHS<\/strong><\/p><p><a href=\"https:\/\/www.dhs.gov\/news\/2025\/10\/27\/dhs-removes-more-half-million-illegal-aliens-us\">https:\/\/www.dhs.gov\/news\/2025\/10\/27\/dhs-removes-more-half-million-illegal-aliens-us<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El Departamento de Seguridad Nacional se\u00f1ala un incremento en las remociones o removals y autodeportaciones. El Departamento de Seguridad Nacional de Estados Unidos (DHS) inform\u00f3 que m\u00e1s de 527 mil personas fueron deportadas desde el pa\u00eds durante 2025, en lo que calific\u00f3 como un \u201cr\u00e9cord hist\u00f3rico\u201d bajo la administraci\u00f3n del presidente Donald Trump y la secretaria de Seguridad Nacional Kristi Noem. De acuerdo con el comunicado oficial emitido el 27 de octubre, el gobierno report\u00f3 adem\u00e1s que m\u00e1s de 2 millones de personas en situaci\u00f3n migratoria irregular abandonaron el pa\u00eds, de las cuales 1.6 millones lo hicieron de manera voluntaria, mientras que el resto fueron deportadas por las agencias de Inmigraci\u00f3n y Control de Aduanas (ICE) y Aduanas y Protecci\u00f3n Fronteriza (CBP). Adem\u00e1s, el DHS destac\u00f3 que la administraci\u00f3n actual \u201cest\u00e1 en camino de superar las cifras hist\u00f3ricas\u201d de deportaciones, con la meta de alcanzar cerca de 600 mil remociones al cierre del a\u00f1o. Seg\u00fan el comunicado, la pol\u00edtica busca cumplir la promesa presidencial de \u201ccerrar la frontera\u201d y fortalecer la aplicaci\u00f3n de las leyes migratorias. El comunicado tambi\u00e9n detalla que el n\u00famero de personas que intentan cruzar el Tap\u00f3n del Dari\u00e9n, en Panam\u00e1, ha disminuido en 99.99% debido a las nuevas pol\u00edticas migratorias y a las campa\u00f1as de advertencia impulsadas por el gobierno estadounidense. El DHS subraya que \u201cel 70% de los arrestos realizados por ICE corresponden a personas con cargos o condenas por delitos en Estados Unidos\u201d. Asimismo, afirma que las acciones de las agencias federales se concentran en quienes representan \u201cun riesgo para la seguridad p\u00fablica\u201d. Como parte de las nuevas medidas, el gobierno estadounidense ofrece un programa de salida voluntaria a trav\u00e9s de la aplicaci\u00f3n m\u00f3vil CBP Home, mediante el cual las personas que decidan regresar a su pa\u00eds de origen pueden recibir mil d\u00f3lares y un vuelo gratuito. Seg\u00fan el comunicado, quienes participen en este programa \u201cmantendr\u00e1n abierta la posibilidad de volver de forma legal en el futuro\u201d. BIBLIOGRAF\u00cdA DHS https:\/\/www.dhs.gov\/news\/2025\/10\/27\/dhs-removes-more-half-million-illegal-aliens-us<\/p>","protected":false},"author":13,"featured_media":68434,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[3432,10],"tags":[2705,4121,4122,800,283],"class_list":["post-68433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacada","category-noticias","tag-2705","tag-administracion-trump","tag-autodeportaciones","tag-deportaciones","tag-dhs"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump<\/title>\n<meta name=\"description\" content=\"El Departamento de Seguridad Nacional \u2013 DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"El Departamento de Seguridad Nacional \u2013 DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-04T16:57:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-04T17:08:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/DHS-reporta-mas-de-medio-millon-de-deportaciones.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\"},\"headline\":\"DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump\",\"datePublished\":\"2025-11-04T16:57:50+00:00\",\"dateModified\":\"2025-11-04T17:08:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\\\/noticias\\\/\"},\"wordCount\":373,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/DHS-reporta-mas-de-medio-millon-de-deportaciones.jpg\",\"keywords\":[\"2025\",\"Administraci\u00f3n Trump\",\"Autodeportaciones\",\"deportaciones\",\"DHS\"],\"articleSection\":[\"Noticia Destacada\",\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\\\/noticias\\\/\",\"name\":\"Acceso Latino | DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/DHS-reporta-mas-de-medio-millon-de-deportaciones.jpg\",\"datePublished\":\"2025-11-04T16:57:50+00:00\",\"dateModified\":\"2025-11-04T17:08:17+00:00\",\"description\":\"El Departamento de Seguridad Nacional \u2013 DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/DHS-reporta-mas-de-medio-millon-de-deportaciones.jpg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/DHS-reporta-mas-de-medio-millon-de-deportaciones.jpg\",\"width\":800,\"height\":460,\"caption\":\"DHS reporta mas de medio millon de deportaciones\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump","description":"El Departamento de Seguridad Nacional \u2013 DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump | Acceso Latino","og_description":"El Departamento de Seguridad Nacional \u2013 DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump.","og_url":"https:\/\/accesolatino.org\/en\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-11-04T16:57:50+00:00","article_modified_time":"2025-11-04T17:08:17+00:00","og_image":[{"width":800,"height":460,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/DHS-reporta-mas-de-medio-millon-de-deportaciones.jpg","type":"image\/jpeg"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b"},"headline":"DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump","datePublished":"2025-11-04T16:57:50+00:00","dateModified":"2025-11-04T17:08:17+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/"},"wordCount":373,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/DHS-reporta-mas-de-medio-millon-de-deportaciones.jpg","keywords":["2025","Administraci\u00f3n Trump","Autodeportaciones","deportaciones","DHS"],"articleSection":["Noticia Destacada","Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/","url":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/","name":"Acceso Latino | DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/DHS-reporta-mas-de-medio-millon-de-deportaciones.jpg","datePublished":"2025-11-04T16:57:50+00:00","dateModified":"2025-11-04T17:08:17+00:00","description":"El Departamento de Seguridad Nacional \u2013 DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/DHS-reporta-mas-de-medio-millon-de-deportaciones.jpg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/11\/DHS-reporta-mas-de-medio-millon-de-deportaciones.jpg","width":800,"height":460,"caption":"DHS reporta mas de medio millon de deportaciones"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/dhs-reporta-mas-de-medio-millon-de-deportaciones-en-2025-bajo-la-administracion-trump\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"DHS reporta m\u00e1s de medio mill\u00f3n de deportaciones en 2025 bajo la administraci\u00f3n Trump"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/68433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=68433"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/68433\/revisions"}],"predecessor-version":[{"id":68441,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/68433\/revisions\/68441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/68434"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=68433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=68433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=68433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}