{"id":63477,"date":"2025-09-15T01:13:00","date_gmt":"2025-09-15T07:13:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=63477"},"modified":"2025-09-12T13:21:26","modified_gmt":"2025-09-12T19:21:26","slug":"entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/","title":{"rendered":"Entran en vigor nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"63477\" class=\"elementor elementor-63477\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5977feb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5977feb4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44803e7f\" data-id=\"44803e7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4824ba8b elementor-widget elementor-widget-heading\" data-id=\"4824ba8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A partir de este mes, menores y adultos mayores deben presentarse en consulados; solo ciertas categor\u00edas diplom\u00e1ticas y renovaciones est\u00e1n exentas.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15a204cb elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"15a204cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e906da\" data-id=\"e906da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f6d806e elementor-widget elementor-widget-text-editor\" data-id=\"4f6d806e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A partir del 2 de septiembre entraron en vigor las nuevas las reglas sobre las exenciones de entrevistas para visas de no inmigrante. Con esta medida, impulsada por el Departamento de Estado de Estados Unidos (DOS), la mayor\u00eda de los solicitantes, incluidos menores de 14 a\u00f1os y adultos mayores de 79, deben acudir a una entrevista presencial con un agente consular.<\/p><p>El DOS inform\u00f3 que solo ciertos grupos de solicitantes podr\u00e1n quedar exentos. Entre ellos se encuentran quienes aplican bajo las categor\u00edas diplom\u00e1ticas y oficiales, como las visas A-1, A-2, C-3 (con excepci\u00f3n de asistentes o empleados de funcionarios), G-1 a G-4, NATO-1 a NATO-6 y TECRO E-1. Tambi\u00e9n estar\u00e1n exentos los solicitantes de visas diplom\u00e1ticas u oficiales en general.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76b46c81 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"76b46c81\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-55ea86b\" data-id=\"55ea86b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c6b9d57 elementor-widget elementor-widget-image\" data-id=\"4c6b9d57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"735\" height=\"330\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/05\/e-trata-del-Programa-de-Exencion-de-Visa.png\" class=\"attachment-full size-full wp-image-61295\" alt=\"se trata del Programa de Exencio\u0301n de Visa\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/05\/e-trata-del-Programa-de-Exencion-de-Visa.png 735w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/05\/e-trata-del-Programa-de-Exencion-de-Visa-300x135.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/05\/e-trata-del-Programa-de-Exencion-de-Visa-18x8.png 18w\" sizes=\"(max-width: 735px) 100vw, 735px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-26f4d3e1\" data-id=\"26f4d3e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ff4114c elementor-widget elementor-widget-text-editor\" data-id=\"2ff4114c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Asimismo, quienes renueven una visa B-1, B-2, B1\/B2 de validez completa o una tarjeta\/permiso de cruce fronterizo (para ciudadanos mexicanos) podr\u00e1n evitar la entrevista si presentan su solicitud dentro de los 12 meses posteriores al vencimiento de la visa anterior, y si ten\u00edan al menos 18 a\u00f1os al momento de su emisi\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51ebd8f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"51ebd8f3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-517299e6\" data-id=\"517299e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cbc0dc8 elementor-widget elementor-widget-text-editor\" data-id=\"4cbc0dc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En el caso de las visas de turismo y negocios, los solicitantes deber\u00e1n cumplir requisitos adicionales para acceder a la exenci\u00f3n, como presentar la solicitud en su pa\u00eds de residencia o nacionalidad, no haber recibido una negativa de visa anteriormente y no contar con posibles causales de inelegibilidad.<\/p><p>Las categor\u00edas m\u00e1s afectadas por esta actualizaci\u00f3n son las visas O, dirigidas a personas con habilidades extraordinarias y atletas; las visas H, que incluyen trabajadores temporales agr\u00edcolas H-2A, no agr\u00edcolas H-2B y especializados H-1B; las visas L, para transferencias de empleados de empresas multinacionales; las visas M, destinadas a estudiantes en programas vocacionales; las visas F, para estudiantes internacionales en universidades estadounidenses; y las visas J, que abarcan a visitantes de intercambio como acad\u00e9micos, investigadores y <em>au pairs<\/em>.<\/p><p>Finalmente, el DOS subray\u00f3 que los agentes consulares conservan la facultad de solicitar entrevistas presenciales en cualquier caso individual y por cualquier motivo. Esta disposici\u00f3n sustituye la pol\u00edtica de exenci\u00f3n de entrevistas anunciada en febrero de 2025.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76baddc3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"76baddc3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2cbc173\" data-id=\"2cbc173\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69d6cc30 elementor-widget elementor-widget-toggle\" data-id=\"69d6cc30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1771\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1771\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1771\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1771\"><p><strong>D<\/strong><strong>EPARTMENT OF STATE<\/strong><\/p><p><a href=\"https:\/\/travel.state.gov\/content\/travel\/en\/News\/visas-news\/interview-waiver-update-july-25-2025.html\">https:\/\/travel.state.gov\/content\/travel\/en\/News\/visas-news\/interview-waiver-update-july-25-2025.html<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>A partir de este mes, menores y adultos mayores deben presentarse en consulados; solo ciertas categor\u00edas diplom\u00e1ticas y renovaciones est\u00e1n exentas. A partir del 2 de septiembre entraron en vigor las nuevas las reglas sobre las exenciones de entrevistas para visas de no inmigrante. Con esta medida, impulsada por el Departamento de Estado de Estados Unidos (DOS), la mayor\u00eda de los solicitantes, incluidos menores de 14 a\u00f1os y adultos mayores de 79, deben acudir a una entrevista presencial con un agente consular. El DOS inform\u00f3 que solo ciertos grupos de solicitantes podr\u00e1n quedar exentos. Entre ellos se encuentran quienes aplican bajo las categor\u00edas diplom\u00e1ticas y oficiales, como las visas A-1, A-2, C-3 (con excepci\u00f3n de asistentes o empleados de funcionarios), G-1 a G-4, NATO-1 a NATO-6 y TECRO E-1. Tambi\u00e9n estar\u00e1n exentos los solicitantes de visas diplom\u00e1ticas u oficiales en general. Asimismo, quienes renueven una visa B-1, B-2, B1\/B2 de validez completa o una tarjeta\/permiso de cruce fronterizo (para ciudadanos mexicanos) podr\u00e1n evitar la entrevista si presentan su solicitud dentro de los 12 meses posteriores al vencimiento de la visa anterior, y si ten\u00edan al menos 18 a\u00f1os al momento de su emisi\u00f3n. En el caso de las visas de turismo y negocios, los solicitantes deber\u00e1n cumplir requisitos adicionales para acceder a la exenci\u00f3n, como presentar la solicitud en su pa\u00eds de residencia o nacionalidad, no haber recibido una negativa de visa anteriormente y no contar con posibles causales de inelegibilidad. Las categor\u00edas m\u00e1s afectadas por esta actualizaci\u00f3n son las visas O, dirigidas a personas con habilidades extraordinarias y atletas; las visas H, que incluyen trabajadores temporales agr\u00edcolas H-2A, no agr\u00edcolas H-2B y especializados H-1B; las visas L, para transferencias de empleados de empresas multinacionales; las visas M, destinadas a estudiantes en programas vocacionales; las visas F, para estudiantes internacionales en universidades estadounidenses; y las visas J, que abarcan a visitantes de intercambio como acad\u00e9micos, investigadores y au pairs. Finalmente, el DOS subray\u00f3 que los agentes consulares conservan la facultad de solicitar entrevistas presenciales en cualquier caso individual y por cualquier motivo. Esta disposici\u00f3n sustituye la pol\u00edtica de exenci\u00f3n de entrevistas anunciada en febrero de 2025. BIBLIOGRAF\u00cdA DEPARTMENT OF STATE https:\/\/travel.state.gov\/content\/travel\/en\/News\/visas-news\/interview-waiver-update-july-25-2025.html<\/p>","protected":false},"author":13,"featured_media":61295,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[12,1934],"tags":[1383,228,4003,4004,192],"class_list":["post-63477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tramites","category-tramites-y-permisos","tag-entrevista","tag-estados-unidos","tag-obligatoria","tag-septiembre-2025","tag-visas"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | Entran en vigor nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas<\/title>\n<meta name=\"description\" content=\"A partir de septiembre entraron en vigor las nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas en Estados Unidos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entran en vigor nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"A partir de septiembre entraron en vigor las nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas en Estados Unidos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-15T07:13:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/05\/e-trata-del-Programa-de-Exencion-de-Visa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\\\/tramites\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\\\/tramites\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\"},\"headline\":\"Entran en vigor nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas\",\"datePublished\":\"2025-09-15T07:13:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\\\/tramites\\\/\"},\"wordCount\":416,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\\\/tramites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/e-trata-del-Programa-de-Exencion-de-Visa.png\",\"keywords\":[\"Entrevista\",\"Estados Unidos\",\"Obligatoria\",\"Septiembre 2025\",\"Visas\"],\"articleSection\":[\"Tr\u00e1mites\",\"Tr\u00e1mites y Permisos\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\\\/tramites\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\\\/tramites\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\\\/tramites\\\/\",\"name\":\"Acceso Latino | Entran en vigor nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\\\/tramites\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\\\/tramites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/e-trata-del-Programa-de-Exencion-de-Visa.png\",\"datePublished\":\"2025-09-15T07:13:00+00:00\",\"description\":\"A partir de septiembre entraron en vigor las nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas en Estados Unidos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\\\/tramites\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\\\/tramites\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\\\/tramites\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/e-trata-del-Programa-de-Exencion-de-Visa.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/e-trata-del-Programa-de-Exencion-de-Visa.png\",\"width\":735,\"height\":330,\"caption\":\"se trata del Programa de Exencio\u0301n de Visa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\\\/tramites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tr\u00e1mites\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/tramites\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Entran en vigor nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | Entran en vigor nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas","description":"A partir de septiembre entraron en vigor las nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas en Estados Unidos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/","og_locale":"en_US","og_type":"article","og_title":"Entran en vigor nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas | Acceso Latino","og_description":"A partir de septiembre entraron en vigor las nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas en Estados Unidos.","og_url":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-09-15T07:13:00+00:00","og_image":[{"width":735,"height":330,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/05\/e-trata-del-Programa-de-Exencion-de-Visa.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b"},"headline":"Entran en vigor nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas","datePublished":"2025-09-15T07:13:00+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/"},"wordCount":416,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/05\/e-trata-del-Programa-de-Exencion-de-Visa.png","keywords":["Entrevista","Estados Unidos","Obligatoria","Septiembre 2025","Visas"],"articleSection":["Tr\u00e1mites","Tr\u00e1mites y Permisos"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/","url":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/","name":"Acceso Latino | Entran en vigor nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/05\/e-trata-del-Programa-de-Exencion-de-Visa.png","datePublished":"2025-09-15T07:13:00+00:00","description":"A partir de septiembre entraron en vigor las nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas en Estados Unidos.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/05\/e-trata-del-Programa-de-Exencion-de-Visa.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/05\/e-trata-del-Programa-de-Exencion-de-Visa.png","width":735,"height":330,"caption":"se trata del Programa de Exencio\u0301n de Visa"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/entran-en-vigor-nuevas-reglas-de-entrevistas-obligatorias-para-la-mayoria-de-las-visas\/tramites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Tr\u00e1mites","item":"https:\/\/accesolatino.org\/category\/tramites\/"},{"@type":"ListItem","position":3,"name":"Entran en vigor nuevas reglas de entrevistas obligatorias para la mayor\u00eda de las visas"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/63477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=63477"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/63477\/revisions"}],"predecessor-version":[{"id":63486,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/63477\/revisions\/63486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/61295"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=63477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=63477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=63477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}