{"id":63407,"date":"2025-09-09T11:34:28","date_gmt":"2025-09-09T17:34:28","guid":{"rendered":"https:\/\/accesolatino.org\/?p=63407"},"modified":"2025-09-09T11:38:32","modified_gmt":"2025-09-09T17:38:32","slug":"el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/","title":{"rendered":"El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"63407\" class=\"elementor elementor-63407\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3420e48c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3420e48c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ed945aa\" data-id=\"3ed945aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d78d62b elementor-widget elementor-widget-heading\" data-id=\"d78d62b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El c\u00f3nsul de M\u00e9xico en Los \u00c1ngeles, Carlos Gonz\u00e1lez Guti\u00e9rrez enfrenta el reto de apoyar a los migrantes en medio de redadas y tensiones pol\u00edticas en Estados Unidos.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-282cf480 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"282cf480\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b66d7b8\" data-id=\"b66d7b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c017570 elementor-widget elementor-widget-text-editor\" data-id=\"c017570\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En Los \u00c1ngeles, ciudad con una de las comunidades mexicanas m\u00e1s grandes fuera de M\u00e9xico, el c\u00f3nsul general Carlos Gonz\u00e1lez Guti\u00e9rrez trabaja para resguardar a sus connacionales frente a las crecientes pol\u00edticas y medidas de inmigraci\u00f3n impulsadas por la administraci\u00f3n de Donald Trump.<\/p><p>Uno de los episodios m\u00e1s simb\u00f3licos ocurri\u00f3 cuando agentes federales irrumpieron en MacArthur Park, frente al consulado. Gonz\u00e1lez Guti\u00e9rrez ofreci\u00f3 refugio inmediato a quienes se encontraban dentro y fuera del edificio, recordando que el consulado es inviolable por ley internacional. Aunque en esa ocasi\u00f3n no hubo detenidos, la acci\u00f3n represent\u00f3 un acto de intimidaci\u00f3n hacia la comunidad inmigrante mexicana en la ciudad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29275ee8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"29275ee8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-441d118e\" data-id=\"441d118e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30803a43 elementor-widget elementor-widget-image\" data-id=\"30803a43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1105\" height=\"534\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/09\/ElFightforMexicanLosAngeles.png\" class=\"attachment-full size-full wp-image-63408\" alt=\"ElFightforMexicanLosAngeles\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/09\/ElFightforMexicanLosAngeles.png 1105w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/09\/ElFightforMexicanLosAngeles-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/09\/ElFightforMexicanLosAngeles-1024x495.png 1024w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/09\/ElFightforMexicanLosAngeles-768x371.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/09\/ElFightforMexicanLosAngeles-18x9.png 18w\" sizes=\"(max-width: 1105px) 100vw, 1105px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-75b9f574\" data-id=\"75b9f574\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea0c497 elementor-widget elementor-widget-text-editor\" data-id=\"ea0c497\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El diplom\u00e1tico, con m\u00e1s de tres d\u00e9cadas de experiencia, conoce la importancia de la poblaci\u00f3n mexicana en el estado de California. Desde la amnist\u00eda migratoria de 1986 hasta las movilizaciones contra la Proposici\u00f3n 187 en 1994, Gonz\u00e1lez Guti\u00e9rrez ha sido testigo de c\u00f3mo los inmigrantes se han convertido en pieza central del tejido social y econ\u00f3mico angelino. Ahora, son los descendientes de aquellos inmigrantes quienes encabezan protestas contra las redadas, defendiendo tanto a sus familias como su identidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bdc1d3e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"bdc1d3e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57147424\" data-id=\"57147424\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43af1b54 elementor-widget elementor-widget-text-editor\" data-id=\"43af1b54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las detenciones por las pol\u00edticas actuales afectan principalmente a hombres con d\u00e9cadas de residencia en Estados Unidos, muchos de ellos con hijos y nietos ciudadanos. Funcionarios del consulado visitan a diario el centro de detenci\u00f3n metropolitano para verificar condiciones, brindar asesor\u00eda legal y notificar a familiares. No obstante, los testimonios de abusos y el hacinamiento reflejan las limitaciones de la protecci\u00f3n consular en estos casos.<\/p><p>Para Gonz\u00e1lez Guti\u00e9rrez, Los \u00c1ngeles es la \u201ccapital pol\u00edtica de la di\u00e1spora mexicana\u201d, un espacio donde se entrelazan luchas hist\u00f3ricas y presentes por el reconocimiento de la identidad inmigrante y mexicana.<\/p><p>Ante la presi\u00f3n, algunos inmigrantes optan por aceptar la deportaci\u00f3n, mientras que otros, con ra\u00edces profundas en el pa\u00eds, deciden enfrentar procesos legales para intentar permanecer. El c\u00f3nsul insiste en la importancia de mantener la calma, ejercer los derechos b\u00e1sicos y acudir siempre al consulado en caso de detenci\u00f3n. No obstante, aclara que su papel se circunscribe a acompa\u00f1ar y documentar, m\u00e1s que a cambiar el rumbo de cada caso.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20496d95 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"20496d95\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ea7b88e\" data-id=\"7ea7b88e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5791123e elementor-widget elementor-widget-toggle\" data-id=\"5791123e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1461\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1461\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1461\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1461\"><p><strong>NEW YORKER<\/strong><\/p><p><a href=\"https:\/\/www.newyorker.com\/news\/the-lede\/the-fight-for-mexican-los-angeles\">https:\/\/www.newyorker.com\/news\/the-lede\/the-fight-for-mexican-los-angeles<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El c\u00f3nsul de M\u00e9xico en Los \u00c1ngeles, Carlos Gonz\u00e1lez Guti\u00e9rrez enfrenta el reto de apoyar a los migrantes en medio de redadas y tensiones pol\u00edticas en Estados Unidos. En Los \u00c1ngeles, ciudad con una de las comunidades mexicanas m\u00e1s grandes fuera de M\u00e9xico, el c\u00f3nsul general Carlos Gonz\u00e1lez Guti\u00e9rrez trabaja para resguardar a sus connacionales frente a las crecientes pol\u00edticas y medidas de inmigraci\u00f3n impulsadas por la administraci\u00f3n de Donald Trump. Uno de los episodios m\u00e1s simb\u00f3licos ocurri\u00f3 cuando agentes federales irrumpieron en MacArthur Park, frente al consulado. Gonz\u00e1lez Guti\u00e9rrez ofreci\u00f3 refugio inmediato a quienes se encontraban dentro y fuera del edificio, recordando que el consulado es inviolable por ley internacional. Aunque en esa ocasi\u00f3n no hubo detenidos, la acci\u00f3n represent\u00f3 un acto de intimidaci\u00f3n hacia la comunidad inmigrante mexicana en la ciudad. El diplom\u00e1tico, con m\u00e1s de tres d\u00e9cadas de experiencia, conoce la importancia de la poblaci\u00f3n mexicana en el estado de California. Desde la amnist\u00eda migratoria de 1986 hasta las movilizaciones contra la Proposici\u00f3n 187 en 1994, Gonz\u00e1lez Guti\u00e9rrez ha sido testigo de c\u00f3mo los inmigrantes se han convertido en pieza central del tejido social y econ\u00f3mico angelino. Ahora, son los descendientes de aquellos inmigrantes quienes encabezan protestas contra las redadas, defendiendo tanto a sus familias como su identidad. Las detenciones por las pol\u00edticas actuales afectan principalmente a hombres con d\u00e9cadas de residencia en Estados Unidos, muchos de ellos con hijos y nietos ciudadanos. Funcionarios del consulado visitan a diario el centro de detenci\u00f3n metropolitano para verificar condiciones, brindar asesor\u00eda legal y notificar a familiares. No obstante, los testimonios de abusos y el hacinamiento reflejan las limitaciones de la protecci\u00f3n consular en estos casos. Para Gonz\u00e1lez Guti\u00e9rrez, Los \u00c1ngeles es la \u201ccapital pol\u00edtica de la di\u00e1spora mexicana\u201d, un espacio donde se entrelazan luchas hist\u00f3ricas y presentes por el reconocimiento de la identidad inmigrante y mexicana. Ante la presi\u00f3n, algunos inmigrantes optan por aceptar la deportaci\u00f3n, mientras que otros, con ra\u00edces profundas en el pa\u00eds, deciden enfrentar procesos legales para intentar permanecer. El c\u00f3nsul insiste en la importancia de mantener la calma, ejercer los derechos b\u00e1sicos y acudir siempre al consulado en caso de detenci\u00f3n. No obstante, aclara que su papel se circunscribe a acompa\u00f1ar y documentar, m\u00e1s que a cambiar el rumbo de cada caso. BIBLIOGRAF\u00cdA NEW YORKER https:\/\/www.newyorker.com\/news\/the-lede\/the-fight-for-mexican-los-angeles<\/p>","protected":false},"author":13,"featured_media":63408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10],"tags":[3988,2246,3989,87,1100],"class_list":["post-63407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-carlos-gonzalez-gutierrez","tag-comunidad-mexicana","tag-consul-mexicano","tag-inmigrantes","tag-los-angeles"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles<\/title>\n<meta name=\"description\" content=\"El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles, seg\u00fan el c\u00f3nsul mexicano Carlos Gonz\u00e1lez Guti\u00e9rrez.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles, seg\u00fan el c\u00f3nsul mexicano Carlos Gonz\u00e1lez Guti\u00e9rrez.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-09T17:34:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-09T17:38:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/09\/ElFightforMexicanLosAngeles.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1105\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\"},\"headline\":\"El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles\",\"datePublished\":\"2025-09-09T17:34:28+00:00\",\"dateModified\":\"2025-09-09T17:38:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\\\/noticias\\\/\"},\"wordCount\":446,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ElFightforMexicanLosAngeles.png\",\"keywords\":[\"Carlos Gonz\u00e1lez Guti\u00e9rrez\",\"Comunidad mexicana\",\"C\u00f3nsul mexicano\",\"Inmigrantes\",\"Los \u00c1ngeles\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\\\/noticias\\\/\",\"name\":\"Acceso Latino | El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ElFightforMexicanLosAngeles.png\",\"datePublished\":\"2025-09-09T17:34:28+00:00\",\"dateModified\":\"2025-09-09T17:38:32+00:00\",\"description\":\"El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles, seg\u00fan el c\u00f3nsul mexicano Carlos Gonz\u00e1lez Guti\u00e9rrez.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ElFightforMexicanLosAngeles.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ElFightforMexicanLosAngeles.png\",\"width\":1105,\"height\":534,\"caption\":\"ElFightforMexicanLosAngeles\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles","description":"El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles, seg\u00fan el c\u00f3nsul mexicano Carlos Gonz\u00e1lez Guti\u00e9rrez.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles | Acceso Latino","og_description":"El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles, seg\u00fan el c\u00f3nsul mexicano Carlos Gonz\u00e1lez Guti\u00e9rrez.","og_url":"https:\/\/accesolatino.org\/en\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-09-09T17:34:28+00:00","article_modified_time":"2025-09-09T17:38:32+00:00","og_image":[{"width":1105,"height":534,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/09\/ElFightforMexicanLosAngeles.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b"},"headline":"El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles","datePublished":"2025-09-09T17:34:28+00:00","dateModified":"2025-09-09T17:38:32+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/"},"wordCount":446,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/09\/ElFightforMexicanLosAngeles.png","keywords":["Carlos Gonz\u00e1lez Guti\u00e9rrez","Comunidad mexicana","C\u00f3nsul mexicano","Inmigrantes","Los \u00c1ngeles"],"articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/","url":"https:\/\/accesolatino.org\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/","name":"Acceso Latino | El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/09\/ElFightforMexicanLosAngeles.png","datePublished":"2025-09-09T17:34:28+00:00","dateModified":"2025-09-09T17:38:32+00:00","description":"El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles, seg\u00fan el c\u00f3nsul mexicano Carlos Gonz\u00e1lez Guti\u00e9rrez.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/09\/ElFightforMexicanLosAngeles.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/09\/ElFightforMexicanLosAngeles.png","width":1105,"height":534,"caption":"ElFightforMexicanLosAngeles"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/el-desafio-de-proteger-a-la-comunidad-mexicana-en-los-angeles\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"El desaf\u00edo de proteger a la comunidad mexicana en Los \u00c1ngeles"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/63407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=63407"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/63407\/revisions"}],"predecessor-version":[{"id":63415,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/63407\/revisions\/63415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/63408"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=63407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=63407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=63407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}