{"id":62823,"date":"2025-08-01T06:14:00","date_gmt":"2025-08-01T12:14:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=62823"},"modified":"2025-07-31T18:37:58","modified_gmt":"2025-08-01T00:37:58","slug":"crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/","title":{"rendered":"Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"62823\" class=\"elementor elementor-62823\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6723636a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6723636a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1beed69b\" data-id=\"1beed69b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db51e5 elementor-widget elementor-widget-heading\" data-id=\"db51e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Luego de la derogaci\u00f3n de la Ley Dream de Texas y demandas federales en otros estados, docentes, estudiantes y expertos legales exigen proteger el acceso equitativo a la educaci\u00f3n superior.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f6acabc elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6f6acabc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15dd849c\" data-id=\"15dd849c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b239ee3 elementor-widget elementor-widget-text-editor\" data-id=\"4b239ee3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Organizaciones educativas, estudiantes y defensores de derechos civiles alzaron la voz est\u00e1 para denunciar la creciente ofensiva contra el acceso a matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos. En una conferencia de prensa organizada por la organizaci\u00f3n United We Dream, participantes de Texas, Kentucky y Minnesota alertaron sobre las consecuencias sociales y econ\u00f3micas que implican estos retrocesos legislativos.<br \/>La conferencia de prensa se llev\u00f3 a cabo en el contexto de la reciente derogaci\u00f3n de la Ley Dream de Texas, que estuvo vigente por 24 a\u00f1os, y de las acciones del Departamento de Justicia (DOJ), que present\u00f3 demandas legales contra los estados de Kentucky y Minnesota por ofrecer tarifas de matr\u00edcula estatal a estudiantes indocumentados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74cd7fd2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"74cd7fd2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-77b46463\" data-id=\"77b46463\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92a48a9 elementor-widget elementor-widget-image\" data-id=\"92a48a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"829\" height=\"401\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/education.png\" class=\"attachment-full size-full wp-image-62827\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/education.png 829w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/education-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/education-768x371.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/education-18x9.png 18w\" sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7f55e7fb\" data-id=\"7f55e7fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-699384aa elementor-widget elementor-widget-text-editor\" data-id=\"699384aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Juan Mart\u00ednez-Guevara, gerente de incidencia en Texas para United We Dream, calific\u00f3 la derogaci\u00f3n como un precedente peligroso: \u201cEl fin de la Ley Dream en Texas se est\u00e1 utilizando como modelo para atacar a estudiantes en otros estados. No se trata de beneficiar a un grupo sobre otro, sino de garantizar que todos los estudiantes, sin importar su origen, tengan oportunidad de aprender y contribuir a sus comunidades\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ba56d42 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1ba56d42\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e491e67\" data-id=\"6e491e67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73c30c7b elementor-widget elementor-widget-text-editor\" data-id=\"73c30c7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Otra de las participantes fue Rory, una estudiante universitaria en Texas, quien comparti\u00f3 su experiencia personal, explicando que la Ley Dream de Texas, m\u00e1s que una pol\u00edtica, represent\u00f3 una oportunidad para los estudiantes indocumentados. \u201cNegar la educaci\u00f3n seg\u00fan el estatus migratorio socava los principios de justicia y equidad que deber\u00edan regir en nuestro pa\u00eds\u201d, detall\u00f3.<\/p><p>Desde una perspectiva econ\u00f3mica, Al, reci\u00e9n graduado, advirti\u00f3 acerca de los efectos negativos que esta medida tendr\u00e1 para el estado. \u201cSu eliminaci\u00f3n significa que estudiantes que aspiraban a ser enfermeros o maestros ya no podr\u00e1n cubrir las vacantes cr\u00edticas en zonas rurales como Big Bend o distritos escolares con escasez de personal como Bryan ISD\u201d.<\/p><p>Por otro lado, expertos legales y educativos tambi\u00e9n se pronunciaron. Krystal M. G\u00f3mez, abogada de Texas Immigration Law Council, recalc\u00f3 que el programa era una pol\u00edtica bipartidista sensata: \u201cPor m\u00e1s de dos d\u00e9cadas, la Ley Dream de Texas fortaleci\u00f3 la fuerza laboral y la econom\u00eda del estado. Era una promesa a los estudiantes y al futuro de Texas\u201d.<\/p><p>Asimismo, Ovidia Molina, presidenta de la Asociaci\u00f3n de Maestros del Estado de Texas, cuestion\u00f3 el cambio abrupto en la pol\u00edtica p\u00fablica que estuvo vigente por 24 a\u00f1os y que adem\u00e1s convirti\u00f3 a Texas en el estado pionero de las pol\u00edticas educativas a favor de los inmigrantes. \u201cAhora, se usa como otra forma de decirle a las comunidades inmigrantes que no pertenecen aqu\u00ed, lo cual no es cierto. Todos pertenecemos a Texas\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f0481de elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5f0481de\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75a44839\" data-id=\"75a44839\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55dfc5c7 elementor-widget elementor-widget-toggle\" data-id=\"55dfc5c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1441\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1441\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1441\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1441\"><p><strong>UNITED WE DREAM<\/strong><\/p><p><a href=\"https:\/\/unitedwedream.org\/press\/as-efforts-to-end-in-state-tuition-accelerate-nationwide-students-teachers-and-education-leaders-demand-elected-officials-protect-the-right-to-education-for-all\/\">https:\/\/unitedwedream.org\/press\/as-efforts-to-end-in-state-tuition-accelerate-nationwide-students-teachers-and-education-leaders-demand-elected-officials-protect-the-right-to-education-for-all\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Luego de la derogaci\u00f3n de la Ley Dream de Texas y demandas federales en otros estados, docentes, estudiantes y expertos legales exigen proteger el acceso equitativo a la educaci\u00f3n superior. Organizaciones educativas, estudiantes y defensores de derechos civiles alzaron la voz est\u00e1 para denunciar la creciente ofensiva contra el acceso a matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos. En una conferencia de prensa organizada por la organizaci\u00f3n United We Dream, participantes de Texas, Kentucky y Minnesota alertaron sobre las consecuencias sociales y econ\u00f3micas que implican estos retrocesos legislativos.La conferencia de prensa se llev\u00f3 a cabo en el contexto de la reciente derogaci\u00f3n de la Ley Dream de Texas, que estuvo vigente por 24 a\u00f1os, y de las acciones del Departamento de Justicia (DOJ), que present\u00f3 demandas legales contra los estados de Kentucky y Minnesota por ofrecer tarifas de matr\u00edcula estatal a estudiantes indocumentados. Juan Mart\u00ednez-Guevara, gerente de incidencia en Texas para United We Dream, calific\u00f3 la derogaci\u00f3n como un precedente peligroso: \u201cEl fin de la Ley Dream en Texas se est\u00e1 utilizando como modelo para atacar a estudiantes en otros estados. No se trata de beneficiar a un grupo sobre otro, sino de garantizar que todos los estudiantes, sin importar su origen, tengan oportunidad de aprender y contribuir a sus comunidades\u201d. Otra de las participantes fue Rory, una estudiante universitaria en Texas, quien comparti\u00f3 su experiencia personal, explicando que la Ley Dream de Texas, m\u00e1s que una pol\u00edtica, represent\u00f3 una oportunidad para los estudiantes indocumentados. \u201cNegar la educaci\u00f3n seg\u00fan el estatus migratorio socava los principios de justicia y equidad que deber\u00edan regir en nuestro pa\u00eds\u201d, detall\u00f3. Desde una perspectiva econ\u00f3mica, Al, reci\u00e9n graduado, advirti\u00f3 acerca de los efectos negativos que esta medida tendr\u00e1 para el estado. \u201cSu eliminaci\u00f3n significa que estudiantes que aspiraban a ser enfermeros o maestros ya no podr\u00e1n cubrir las vacantes cr\u00edticas en zonas rurales como Big Bend o distritos escolares con escasez de personal como Bryan ISD\u201d. Por otro lado, expertos legales y educativos tambi\u00e9n se pronunciaron. Krystal M. G\u00f3mez, abogada de Texas Immigration Law Council, recalc\u00f3 que el programa era una pol\u00edtica bipartidista sensata: \u201cPor m\u00e1s de dos d\u00e9cadas, la Ley Dream de Texas fortaleci\u00f3 la fuerza laboral y la econom\u00eda del estado. Era una promesa a los estudiantes y al futuro de Texas\u201d. Asimismo, Ovidia Molina, presidenta de la Asociaci\u00f3n de Maestros del Estado de Texas, cuestion\u00f3 el cambio abrupto en la pol\u00edtica p\u00fablica que estuvo vigente por 24 a\u00f1os y que adem\u00e1s convirti\u00f3 a Texas en el estado pionero de las pol\u00edticas educativas a favor de los inmigrantes. \u201cAhora, se usa como otra forma de decirle a las comunidades inmigrantes que no pertenecen aqu\u00ed, lo cual no es cierto. Todos pertenecemos a Texas\u201d. BIBLIOGRAF\u00cdA UNITED WE DREAM https:\/\/unitedwedream.org\/press\/as-efforts-to-end-in-state-tuition-accelerate-nationwide-students-teachers-and-education-leaders-demand-elected-officials-protect-the-right-to-education-for-all\/<\/p>","protected":false},"author":13,"featured_media":62827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1933,13,157],"tags":[775,3911,1407,3910,439],"class_list":["post-62823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-becas-y-educacion","category-educacion","category-red-de-apoyo","tag-estudiantes-indocumentados","tag-ley-dream-texas","tag-matricula-estatal","tag-retrocesos-legislativos","tag-united-we-dream"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos<\/title>\n<meta name=\"description\" content=\"Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-01T12:14:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/education.png\" \/>\n\t<meta property=\"og:image:width\" content=\"829\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\\\/becas-y-educacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\\\/becas-y-educacion\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos\",\"datePublished\":\"2025-08-01T12:14:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\\\/becas-y-educacion\\\/\"},\"wordCount\":510,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\\\/becas-y-educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/education.png\",\"keywords\":[\"Estudiantes indocumentados\",\"Ley Dream Texas\",\"Matr\u00edcula estatal\",\"Retrocesos legislativos\",\"United We Dream\"],\"articleSection\":[\"Becas y Educaci\u00f3n\",\"Educaci\u00f3n\",\"Red de apoyo\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\\\/becas-y-educacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\\\/becas-y-educacion\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\\\/becas-y-educacion\\\/\",\"name\":\"Acceso Latino | Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\\\/becas-y-educacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\\\/becas-y-educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/education.png\",\"datePublished\":\"2025-08-01T12:14:00+00:00\",\"description\":\"Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\\\/becas-y-educacion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\\\/becas-y-educacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\\\/becas-y-educacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/education.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/education.png\",\"width\":829,\"height\":401},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\\\/becas-y-educacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Becas y Educaci\u00f3n\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/becas-y-educacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos","description":"Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/","og_locale":"en_US","og_type":"article","og_title":"Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos | Acceso Latino","og_description":"Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos.","og_url":"https:\/\/accesolatino.org\/en\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-08-01T12:14:00+00:00","og_image":[{"width":829,"height":401,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/education.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos","datePublished":"2025-08-01T12:14:00+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/"},"wordCount":510,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/education.png","keywords":["Estudiantes indocumentados","Ley Dream Texas","Matr\u00edcula estatal","Retrocesos legislativos","United We Dream"],"articleSection":["Becas y Educaci\u00f3n","Educaci\u00f3n","Red de apoyo"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/","url":"https:\/\/accesolatino.org\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/","name":"Acceso Latino | Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/education.png","datePublished":"2025-08-01T12:14:00+00:00","description":"Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/education.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/education.png","width":829,"height":401},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/crece-la-preocupacion-por-retrocesos-contra-la-matricula-estatal-para-estudiantes-indocumentados-en-estados-unidos\/becas-y-educacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Becas y Educaci\u00f3n","item":"https:\/\/accesolatino.org\/category\/becas-y-educacion\/"},{"@type":"ListItem","position":3,"name":"Crece la preocupaci\u00f3n por retrocesos contra la matr\u00edcula estatal para estudiantes indocumentados en Estados Unidos"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=62823"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62823\/revisions"}],"predecessor-version":[{"id":62837,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62823\/revisions\/62837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/62827"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=62823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=62823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=62823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}