{"id":62674,"date":"2025-07-28T11:40:22","date_gmt":"2025-07-28T17:40:22","guid":{"rendered":"https:\/\/accesolatino.org\/?p=62674"},"modified":"2025-11-18T18:41:01","modified_gmt":"2025-11-19T00:41:01","slug":"colorado-defiende-matricula-estatal-para-estudiantes-indocumentados","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/becas-y-educacion\/","title":{"rendered":"Colorado defiende matr\u00edcula estatal para estudiantes indocumentados"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"62674\" class=\"elementor elementor-62674\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5de7dd98 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5de7dd98\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c24fcbb\" data-id=\"5c24fcbb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55d0302f elementor-widget elementor-widget-heading\" data-id=\"55d0302f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Colorado defiende la matr\u00edcula estatal para estudiantes sin documentos ante las presiones del gobierno federal. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37914e38 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"37914e38\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f20d559\" data-id=\"3f20d559\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ba3c383 elementor-widget elementor-widget-text-editor\" data-id=\"1ba3c383\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En Colorado, la ley estatal establece que la residencia no es un requerimiento para acceder a las tarifas de matr\u00edcula estatal o <em>in-state tuition<\/em>, en cambio, requiere que los estudiantes sean egresados de un high school en Colorado y que haya estados f\u00edsicamente presentes en el estado por al menos un a\u00f1o.<\/p><p>El portal especializado Higher Ed Immigration Portal, clasifica al estado de Colorado como uno de los 18 estados con \u201cAcceso Integral\u201d a las tarifas de matr\u00edcula estatal. El acceso integral se refiere a pol\u00edticas que proporcionan acceso estatal a matr\u00edcula estatal, apoyos financieros o becas estatales a estudiantes que residen en el estado, independientemente de su estatus migratorio. Seg\u00fan el mismo portal, actualmente hay alrededor de 6 mil 800 estudiantes indocumentados en educaci\u00f3n superior en este estado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78d04b33 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"78d04b33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-71d85581\" data-id=\"71d85581\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-108c8945 elementor-widget elementor-widget-image\" data-id=\"108c8945\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"829\" height=\"401\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/matricula-escolar.png\" class=\"attachment-full size-full wp-image-62677\" alt=\"matricula escolar\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/matricula-escolar.png 829w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/matricula-escolar-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/matricula-escolar-768x371.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/matricula-escolar-18x9.png 18w\" sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-43f99958\" data-id=\"43f99958\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-328e9ea4 elementor-widget elementor-widget-text-editor\" data-id=\"328e9ea4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En Colorado las tarifas de matr\u00edcula estatal van desde los 10 mil a los\u00a0 14 mil d\u00f3lares, mientras que los estudiantes de fuera del estado o <em>out-of-state tuition<\/em> deben pagar una tarifa que va desde los 29 mil hasta los 43 mil d\u00f3lares. Por lo que la matr\u00edcula estatal es una oportunidad importante para que los estudiantes sin documentos en Colorado accedan a la educaci\u00f3n superior.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ad9ea2e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7ad9ea2e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-263e4b9f\" data-id=\"263e4b9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a462543 elementor-widget elementor-widget-text-editor\" data-id=\"6a462543\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En este sentido, Phil Weiser el fiscal general de Colorado y funcionarios p\u00fablicos del\u00a0 estado, han argumentado que el programa de matr\u00edcula estatal en Colorado est\u00e1 en terreno legal firme. Asimismo, Weiser ha dicho que est\u00e1 comprometido a defender la ley de matr\u00edcula estatal de Colorado de 2013.<\/p><p>Luego de la cancelaci\u00f3n de la matr\u00edcula estatal para estudiantes sin estatus legal en Texas, que fue el primer estado en establecer una ley en 2001, los estados con leyes vigentes sobre matr\u00edcula estatal se encuentran protegiendo el acceso a la educaci\u00f3n universitaria para todos los estudiantes sin importar su estatus migratorio.<\/p><p>Por su parte, el gobernador Jared Polis, a trav\u00e9s de un portavoz, explic\u00f3 que \u201cDesmantelar o microgestionar la matr\u00edcula estatal en todo el pa\u00eds es absurdo y solo cerrar\u00e1 oportunidades y har\u00e1 que cursar estudios superiores sea m\u00e1s dif\u00edcil y costoso\u201d, dijo el portavoz en el comunicado.<\/p><p>\u201cBajo la ley federal, los estados tienen la autoridad para ofrecer ciertos tipos de asistencia a las personas independientemente de su estatus migratorio\u201d, indica el comunicado. \u201cQueremos dejar claro que si bien las \u00f3rdenes ejecutivas federales dan forma a las prioridades federales de aplicaci\u00f3n, no crean nuevas leyes, ni anulan los estatutos federales existentes\u201d, concluy\u00f3 el comunicado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b49b3b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1b49b3b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff22d9c\" data-id=\"ff22d9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-499d46e7 elementor-widget elementor-widget-toggle\" data-id=\"499d46e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1231\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1231\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1231\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1231\"><p><strong>HIGHER ED IMMIGRATION PORTAL<\/strong><\/p><p><a href=\"https:\/\/www.higheredimmigrationportal.org\/states\/tuition-financial-aid-equity-for-undocumented-students\/\">https:\/\/www.higheredimmigrationportal.org\/states\/tuition-financial-aid-equity-for-undocumented-students\/<\/a><\/p><p><a href=\"https:\/\/www.higheredimmigrationportal.org\/state\/colorado\/\">https:\/\/www.higheredimmigrationportal.org\/state\/colorado\/<\/a><\/p><p><strong>UC DENVER<\/strong><\/p><p><a href=\"https:\/\/www.ucdenver.edu\/student-finances\/tuition-fees\/cost-of-attendance\">https:\/\/www.ucdenver.edu\/student-finances\/tuition-fees\/cost-of-attendance<\/a><\/p><p><a href=\"https:\/\/www.ucdenver.edu\/tuition-cost\">https:\/\/www.ucdenver.edu\/tuition-cost<\/a><\/p><p><strong>CPR NEWS<\/strong><\/p><p><a href=\"https:\/\/www.cpr.org\/2025\/07\/23\/texas-in-state-college-tuition-undocumented-students-impact-colorado\/\">https:\/\/www.cpr.org\/2025\/07\/23\/texas-in-state-college-tuition-undocumented-students-impact-colorado\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Colorado defiende la matr\u00edcula estatal para estudiantes sin documentos ante las presiones del gobierno federal. En Colorado, la ley estatal establece que la residencia no es un requerimiento para acceder a las tarifas de matr\u00edcula estatal o in-state tuition, en cambio, requiere que los estudiantes sean egresados de un high school en Colorado y que haya estados f\u00edsicamente presentes en el estado por al menos un a\u00f1o. El portal especializado Higher Ed Immigration Portal, clasifica al estado de Colorado como uno de los 18 estados con \u201cAcceso Integral\u201d a las tarifas de matr\u00edcula estatal. El acceso integral se refiere a pol\u00edticas que proporcionan acceso estatal a matr\u00edcula estatal, apoyos financieros o becas estatales a estudiantes que residen en el estado, independientemente de su estatus migratorio. Seg\u00fan el mismo portal, actualmente hay alrededor de 6 mil 800 estudiantes indocumentados en educaci\u00f3n superior en este estado. En Colorado las tarifas de matr\u00edcula estatal van desde los 10 mil a los\u00a0 14 mil d\u00f3lares, mientras que los estudiantes de fuera del estado o out-of-state tuition deben pagar una tarifa que va desde los 29 mil hasta los 43 mil d\u00f3lares. Por lo que la matr\u00edcula estatal es una oportunidad importante para que los estudiantes sin documentos en Colorado accedan a la educaci\u00f3n superior. En este sentido, Phil Weiser el fiscal general de Colorado y funcionarios p\u00fablicos del\u00a0 estado, han argumentado que el programa de matr\u00edcula estatal en Colorado est\u00e1 en terreno legal firme. Asimismo, Weiser ha dicho que est\u00e1 comprometido a defender la ley de matr\u00edcula estatal de Colorado de 2013. Luego de la cancelaci\u00f3n de la matr\u00edcula estatal para estudiantes sin estatus legal en Texas, que fue el primer estado en establecer una ley en 2001, los estados con leyes vigentes sobre matr\u00edcula estatal se encuentran protegiendo el acceso a la educaci\u00f3n universitaria para todos los estudiantes sin importar su estatus migratorio. Por su parte, el gobernador Jared Polis, a trav\u00e9s de un portavoz, explic\u00f3 que \u201cDesmantelar o microgestionar la matr\u00edcula estatal en todo el pa\u00eds es absurdo y solo cerrar\u00e1 oportunidades y har\u00e1 que cursar estudios superiores sea m\u00e1s dif\u00edcil y costoso\u201d, dijo el portavoz en el comunicado. \u201cBajo la ley federal, los estados tienen la autoridad para ofrecer ciertos tipos de asistencia a las personas independientemente de su estatus migratorio\u201d, indica el comunicado. \u201cQueremos dejar claro que si bien las \u00f3rdenes ejecutivas federales dan forma a las prioridades federales de aplicaci\u00f3n, no crean nuevas leyes, ni anulan los estatutos federales existentes\u201d, concluy\u00f3 el comunicado. BIBLIOGRAF\u00cdA HIGHER ED IMMIGRATION PORTAL https:\/\/www.higheredimmigrationportal.org\/states\/tuition-financial-aid-equity-for-undocumented-students\/ https:\/\/www.higheredimmigrationportal.org\/state\/colorado\/ UC DENVER https:\/\/www.ucdenver.edu\/student-finances\/tuition-fees\/cost-of-attendance https:\/\/www.ucdenver.edu\/tuition-cost CPR NEWS https:\/\/www.cpr.org\/2025\/07\/23\/texas-in-state-college-tuition-undocumented-students-impact-colorado\/<\/p>","protected":false},"author":13,"featured_media":62677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1933,13,157],"tags":[120,1658,775,1131,1407],"class_list":["post-62674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-becas-y-educacion","category-educacion","category-red-de-apoyo","tag-colorado","tag-educacion-universitaria","tag-estudiantes-indocumentados","tag-in-state-tuition","tag-matricula-estatal"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | Colorado defiende matr\u00edcula estatal para estudiantes indocumentados<\/title>\n<meta name=\"description\" content=\"Colorado defiende matr\u00edcula estatal para estudiantes indocumentados ante la presi\u00f3n del gobierno federal y las pol\u00edticas anti inmigrantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colorado defiende matr\u00edcula estatal para estudiantes indocumentados | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Colorado defiende matr\u00edcula estatal para estudiantes indocumentados ante la presi\u00f3n del gobierno federal y las pol\u00edticas anti inmigrantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-28T17:40:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T00:41:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/matricula-escolar.png\" \/>\n\t<meta property=\"og:image:width\" content=\"829\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\\\/educacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\\\/educacion\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Colorado defiende matr\u00edcula estatal para estudiantes indocumentados\",\"datePublished\":\"2025-07-28T17:40:22+00:00\",\"dateModified\":\"2025-11-19T00:41:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\\\/educacion\\\/\"},\"wordCount\":479,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\\\/educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/matricula-escolar.png\",\"keywords\":[\"Colorado\",\"Educaci\u00f3n universitaria\",\"Estudiantes indocumentados\",\"In-state tuition\",\"Matr\u00edcula estatal\"],\"articleSection\":[\"Becas y Educaci\u00f3n\",\"Educaci\u00f3n\",\"Red de apoyo\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\\\/educacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\\\/educacion\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\\\/educacion\\\/\",\"name\":\"Acceso Latino | Colorado defiende matr\u00edcula estatal para estudiantes indocumentados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\\\/educacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\\\/educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/matricula-escolar.png\",\"datePublished\":\"2025-07-28T17:40:22+00:00\",\"dateModified\":\"2025-11-19T00:41:01+00:00\",\"description\":\"Colorado defiende matr\u00edcula estatal para estudiantes indocumentados ante la presi\u00f3n del gobierno federal y las pol\u00edticas anti inmigrantes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\\\/educacion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\\\/educacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\\\/educacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/matricula-escolar.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/matricula-escolar.png\",\"width\":829,\"height\":401,\"caption\":\"matricula escolar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\\\/educacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Becas y Educaci\u00f3n\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/becas-y-educacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Colorado defiende matr\u00edcula estatal para estudiantes indocumentados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | Colorado defiende matr\u00edcula estatal para estudiantes indocumentados","description":"Colorado defiende matr\u00edcula estatal para estudiantes indocumentados ante la presi\u00f3n del gobierno federal y las pol\u00edticas anti inmigrantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/","og_locale":"en_US","og_type":"article","og_title":"Colorado defiende matr\u00edcula estatal para estudiantes indocumentados | Acceso Latino","og_description":"Colorado defiende matr\u00edcula estatal para estudiantes indocumentados ante la presi\u00f3n del gobierno federal y las pol\u00edticas anti inmigrantes.","og_url":"https:\/\/accesolatino.org\/en\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-07-28T17:40:22+00:00","article_modified_time":"2025-11-19T00:41:01+00:00","og_image":[{"width":829,"height":401,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/matricula-escolar.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Colorado defiende matr\u00edcula estatal para estudiantes indocumentados","datePublished":"2025-07-28T17:40:22+00:00","dateModified":"2025-11-19T00:41:01+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/"},"wordCount":479,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/matricula-escolar.png","keywords":["Colorado","Educaci\u00f3n universitaria","Estudiantes indocumentados","In-state tuition","Matr\u00edcula estatal"],"articleSection":["Becas y Educaci\u00f3n","Educaci\u00f3n","Red de apoyo"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/","url":"https:\/\/accesolatino.org\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/","name":"Acceso Latino | Colorado defiende matr\u00edcula estatal para estudiantes indocumentados","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/matricula-escolar.png","datePublished":"2025-07-28T17:40:22+00:00","dateModified":"2025-11-19T00:41:01+00:00","description":"Colorado defiende matr\u00edcula estatal para estudiantes indocumentados ante la presi\u00f3n del gobierno federal y las pol\u00edticas anti inmigrantes.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/matricula-escolar.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/matricula-escolar.png","width":829,"height":401,"caption":"matricula escolar"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/colorado-defiende-matricula-estatal-para-estudiantes-indocumentados\/educacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Becas y Educaci\u00f3n","item":"https:\/\/accesolatino.org\/category\/becas-y-educacion\/"},{"@type":"ListItem","position":3,"name":"Colorado defiende matr\u00edcula estatal para estudiantes indocumentados"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=62674"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62674\/revisions"}],"predecessor-version":[{"id":68876,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62674\/revisions\/68876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/62677"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=62674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=62674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=62674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}