{"id":62629,"date":"2025-07-24T09:53:42","date_gmt":"2025-07-24T15:53:42","guid":{"rendered":"https:\/\/accesolatino.org\/?p=62629"},"modified":"2025-07-24T10:01:46","modified_gmt":"2025-07-24T16:01:46","slug":"avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/","title":{"rendered":"Avanza reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"62629\" class=\"elementor elementor-62629\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-460b95fc elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"460b95fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-493e6d7f\" data-id=\"493e6d7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a266dc elementor-widget elementor-widget-heading\" data-id=\"8a266dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El Congreso cambios en la INA, que convierte las condenas por DUI en causa de inadmisibilidad y deportaci\u00f3n para personas extranjeras, sin importar su estatus migratorio.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-adfbdc elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"adfbdc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2caedfc7\" data-id=\"2caedfc7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4562d5fa elementor-widget elementor-widget-text-editor\" data-id=\"4562d5fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La C\u00e1mara de Representantes de Estados Unidos aprob\u00f3 la HR 875, conocida como el <strong><em>Jeremy and Angel Seay and Sergeant Brandon Mendoza Protect Our Communities from DUIs Act of 2025<\/em><\/strong>. Esta propuesta, que ahora ha sido enviada al Senado para su lectura por el Comit\u00e9 Judicial, busca modificar la Ley de Inmigraci\u00f3n y Nacionalidad (INA) para considerar inadmisibles y deportables a los inmigrantes que hayan sido condenados por manejar bajo los efectos del alcohol o las drogas (driving under the influence \u2013 DUI).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ecc19be elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3ecc19be\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2453ff02\" data-id=\"2453ff02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73543271 elementor-widget elementor-widget-image\" data-id=\"73543271\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"829\" height=\"401\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/drunk-driving.png\" class=\"attachment-full size-full wp-image-62630\" alt=\"drunk driving\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/drunk-driving.png 829w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/drunk-driving-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/drunk-driving-768x371.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/drunk-driving-18x9.png 18w\" sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-54a0bcb0\" data-id=\"54a0bcb0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4628a20d elementor-widget elementor-widget-text-editor\" data-id=\"4628a20d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El proyecto propone una enmienda directa a los art\u00edculos 212(a) (2) y 237(a)(2) de la INA. De acuerdo con el texto legislativo, <strong>cualquier persona extranjera que haya sido condenada, que admita haber cometido o haber realizado actos que constituyan el delito de conducir intoxicado o bajo influencia de sustancias<\/strong>, ser\u00e1 considerada inadmisible para ingresar a Estados Unidos. Es decir, cualquier persona extranjera, independientemente de su estatus migratorio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2580de3d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2580de3d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61dec392\" data-id=\"61dec392\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59585e2c elementor-widget elementor-widget-text-editor\" data-id=\"59585e2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Adem\u00e1s, la iniciativa <strong>establece que aquellos inmigrantes ya presentes en el pa\u00eds tambi\u00e9n ser\u00e1n sujetos a deportaci\u00f3n si cuentan con una condena por manejar intoxicados<\/strong>, sin importar si el delito fue clasificado como falta menor o <em>misdemeanor<\/em> o delito grave o <em>felony<\/em>, ni si ocurri\u00f3 bajo jurisdicci\u00f3n federal, estatal, tribal o local.<\/p><p>De convertirse en ley, esta reforma afectar\u00eda directamente a inmigrantes con historial de DUI, incluso si los hechos ocurrieron a\u00f1os atr\u00e1s o si se trat\u00f3 de una primera infracci\u00f3n.<\/p><p>El nombre del proyecto hace referencia a Jeremy y Angel Seay, as\u00ed como al sargento Brandon Mendoza, quienes perdieron la vida en incidentes relacionados con conductores en estado de ebriedad y cuyos casos han sido usados por legisladores como ejemplo del riesgo p\u00fablico que representa este tipo de conducta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60f164f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"60f164f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2f1aab\" data-id=\"b2f1aab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-119ed00c elementor-widget elementor-widget-toggle\" data-id=\"119ed00c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2951\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2951\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2951\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2951\"><p><strong>CONGRESS<\/strong><\/p><p><a href=\"https:\/\/www.congress.gov\/bill\/119th-congress\/house-bill\/875\/text#:~:text=%E2%80%9C(J)%20DRIVING%20WHILE,Clerk\">https:\/\/www.congress.gov\/bill\/119th-congress\/house-bill\/875\/text#:~:text=%E2%80%9C(J)%20DRIVING%20WHILE,Clerk<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El Congreso cambios en la INA, que convierte las condenas por DUI en causa de inadmisibilidad y deportaci\u00f3n para personas extranjeras, sin importar su estatus migratorio. La C\u00e1mara de Representantes de Estados Unidos aprob\u00f3 la HR 875, conocida como el Jeremy and Angel Seay and Sergeant Brandon Mendoza Protect Our Communities from DUIs Act of 2025. Esta propuesta, que ahora ha sido enviada al Senado para su lectura por el Comit\u00e9 Judicial, busca modificar la Ley de Inmigraci\u00f3n y Nacionalidad (INA) para considerar inadmisibles y deportables a los inmigrantes que hayan sido condenados por manejar bajo los efectos del alcohol o las drogas (driving under the influence \u2013 DUI). El proyecto propone una enmienda directa a los art\u00edculos 212(a) (2) y 237(a)(2) de la INA. De acuerdo con el texto legislativo, cualquier persona extranjera que haya sido condenada, que admita haber cometido o haber realizado actos que constituyan el delito de conducir intoxicado o bajo influencia de sustancias, ser\u00e1 considerada inadmisible para ingresar a Estados Unidos. Es decir, cualquier persona extranjera, independientemente de su estatus migratorio. Adem\u00e1s, la iniciativa establece que aquellos inmigrantes ya presentes en el pa\u00eds tambi\u00e9n ser\u00e1n sujetos a deportaci\u00f3n si cuentan con una condena por manejar intoxicados, sin importar si el delito fue clasificado como falta menor o misdemeanor o delito grave o felony, ni si ocurri\u00f3 bajo jurisdicci\u00f3n federal, estatal, tribal o local. De convertirse en ley, esta reforma afectar\u00eda directamente a inmigrantes con historial de DUI, incluso si los hechos ocurrieron a\u00f1os atr\u00e1s o si se trat\u00f3 de una primera infracci\u00f3n. El nombre del proyecto hace referencia a Jeremy y Angel Seay, as\u00ed como al sargento Brandon Mendoza, quienes perdieron la vida en incidentes relacionados con conductores en estado de ebriedad y cuyos casos han sido usados por legisladores como ejemplo del riesgo p\u00fablico que representa este tipo de conducta. BIBLIOGRAF\u00cdA CONGRESS https:\/\/www.congress.gov\/bill\/119th-congress\/house-bill\/875\/text#:~:text=%E2%80%9C(J)%20DRIVING%20WHILE,Clerk<\/p>","protected":false},"author":13,"featured_media":62630,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[3432,10],"tags":[1205,247,2827,3883,3882],"class_list":["post-62629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacada","category-noticias","tag-camara-de-representantes","tag-deportacion","tag-dui","tag-hr-875","tag-manejar-en-estado-de-ebriedad"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | Avanza reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad<\/title>\n<meta name=\"description\" content=\"Avanza en el Congreso reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad, independientemente de su estatus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avanza reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Avanza en el Congreso reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad, independientemente de su estatus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-24T15:53:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T16:01:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/drunk-driving.png\" \/>\n\t<meta property=\"og:image:width\" content=\"829\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Avanza reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad\",\"datePublished\":\"2025-07-24T15:53:42+00:00\",\"dateModified\":\"2025-07-24T16:01:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\\\/noticias\\\/\"},\"wordCount\":351,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/drunk-driving.png\",\"keywords\":[\"C\u00e1mara de Representantes\",\"Deportaci\u00f3n\",\"DUI\",\"HR 875\",\"Manejar en estado de ebriedad\"],\"articleSection\":[\"Noticia Destacada\",\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\\\/noticias\\\/\",\"name\":\"Acceso Latino | Avanza reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/drunk-driving.png\",\"datePublished\":\"2025-07-24T15:53:42+00:00\",\"dateModified\":\"2025-07-24T16:01:46+00:00\",\"description\":\"Avanza en el Congreso reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad, independientemente de su estatus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/drunk-driving.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/drunk-driving.png\",\"width\":829,\"height\":401,\"caption\":\"drunk driving\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Avanza reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | Avanza reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad","description":"Avanza en el Congreso reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad, independientemente de su estatus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Avanza reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad | Acceso Latino","og_description":"Avanza en el Congreso reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad, independientemente de su estatus.","og_url":"https:\/\/accesolatino.org\/en\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-07-24T15:53:42+00:00","article_modified_time":"2025-07-24T16:01:46+00:00","og_image":[{"width":829,"height":401,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/drunk-driving.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Avanza reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad","datePublished":"2025-07-24T15:53:42+00:00","dateModified":"2025-07-24T16:01:46+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/"},"wordCount":351,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/drunk-driving.png","keywords":["C\u00e1mara de Representantes","Deportaci\u00f3n","DUI","HR 875","Manejar en estado de ebriedad"],"articleSection":["Noticia Destacada","Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/","url":"https:\/\/accesolatino.org\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/","name":"Acceso Latino | Avanza reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/drunk-driving.png","datePublished":"2025-07-24T15:53:42+00:00","dateModified":"2025-07-24T16:01:46+00:00","description":"Avanza en el Congreso reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad, independientemente de su estatus.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/drunk-driving.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/drunk-driving.png","width":829,"height":401,"caption":"drunk driving"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/avanza-reforma-que-busca-la-deportacion-de-inmigrantes-condenados-por-manejar-en-estado-de-ebriedad\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Avanza reforma que busca la deportaci\u00f3n de inmigrantes condenados por manejar en estado de ebriedad"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=62629"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62629\/revisions"}],"predecessor-version":[{"id":62637,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62629\/revisions\/62637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/62630"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=62629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=62629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=62629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}