{"id":62151,"date":"2025-07-01T11:12:40","date_gmt":"2025-07-01T17:12:40","guid":{"rendered":"https:\/\/accesolatino.org\/?p=62151"},"modified":"2025-07-17T19:01:29","modified_gmt":"2025-07-18T01:01:29","slug":"legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/","title":{"rendered":"Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica a ciertos inmigrantes a partir de 2026"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"62151\" class=\"elementor elementor-62151\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-550d242c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"550d242c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d39009\" data-id=\"7d39009\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44a65f11 elementor-widget elementor-widget-heading\" data-id=\"44a65f11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Los inmigrantes sin estatus que se benefician de Medi-Cal, no perder\u00e1n sus beneficios hasta julio de 2026.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d8d13aa elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2d8d13aa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc76574\" data-id=\"cc76574\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-437b5ed1 elementor-widget elementor-widget-text-editor\" data-id=\"437b5ed1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hace m\u00e1s de un a\u00f1o, California hizo historia al permitir el acceso a Medi-Cal, el programa de atenci\u00f3n m\u00e9dica del estado, a inmigrantes sin estatus. Sin embargo, actualmente, legisladores de California buscan cerrar un d\u00e9ficit de 12 mil millones de d\u00f3lares al aprobar un presupuesto que reduce\u00a0 el acceso de los inmigrantes a la atenci\u00f3n m\u00e9dica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3174ab99 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3174ab99\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2f62f8af\" data-id=\"2f62f8af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11d46a0f elementor-widget elementor-widget-image\" data-id=\"11d46a0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"553\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/cobertura-medica.png\" class=\"attachment-full size-full wp-image-62152\" alt=\"cobertura medica\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/cobertura-medica.png 553w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/cobertura-medica-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/cobertura-medica-18x9.png 18w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-44fc5858\" data-id=\"44fc5858\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2df0aa65 elementor-widget elementor-widget-text-editor\" data-id=\"2df0aa65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los \u00faltimos a\u00f1os, California se ha visto orillado a recortar fondo para suspender ciertos programas p\u00fablicos. El plan de gastos de 321 mil millones de d\u00f3lares fue negociado por el gobernador Gavin Newsom y los principales legisladores estatales. Este presupuesto env\u00eda recortes a programas esenciales de seguridad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37e334cb elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"37e334cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b9b0f26\" data-id=\"4b9b0f26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29486729 elementor-widget elementor-widget-text-editor\" data-id=\"29486729\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Asimismo, el estado enfrenta potencialmente una serie de recortes a nivel de federal de sus programas de salud.\u00a0 El nuevo acuerdo indica que California dejar\u00e1 de inscribir a los nuevos pacientes adultos sin estatus legal a Medi-Cal a partir de 2026.<\/p><p>Seg\u00fan el plan presupuestario de Newsom, los adultos que ya est\u00e1n inscritos a Medi-Cal no ser\u00e1n expulsados, pero tendr\u00edan que comenzar a pagar una prima mensual de cien d\u00f3lares en 2027. De igual forma, el programa implementar\u00e1 una prima mensual de 30 d\u00f3lares a partir de julio de 2027, para los inmigrantes de bajos recursos que permanezcan en el programa, incluyendo a la gente a volver a inscribirse seis meses despu\u00e9s si pierden la cobertura por falta de pago. La prima se reducir\u00eda a 30 d\u00f3lares y solo se aprobar\u00eda a adultos de 19 a 59 a\u00f1os.<\/p><p>\u201cEsta no es forma de responder a las preocupaciones sobre la salud y la seguridad de las comunidades que impulsan nuestra econom\u00eda y contribuyen con miles de millones en impuestos estatales\u201d, dijo Masih Fouladi, director ejecutivo del \u00a0\u00a0\u00a0 California Immigrant Policy Center.<\/p><p>De esta manera, California, que hace un a\u00f1o se acercaba al objetivo de la atenci\u00f3n m\u00e9dica universal al ofrecer atenci\u00f3n m\u00e9dica a inmigrantes irregulares de bajos recursos, ahora se encuentra en una reducci\u00f3n de su presupuesto. Cabe destacar que, el estado ahorrar\u00eda m\u00e1s de 5 mil millones de d\u00f3lares en el ejercicio fiscal 2028-2029 y 3 mil 600 millones en el ejercicio 2027-2028, \u00a0seg\u00fan estimaciones.<\/p><p>Cabe destacar, que California fue uno de los primeros estados del pa\u00eds en ofrecer cobertura m\u00e9dica a todos los adultos de bajos recursos, independientemente de su estatus migratorio. Actualmente, California ofrece atenci\u00f3n m\u00e9dica gratuita a m\u00e1s de 13 millones de personas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d7de9cf elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5d7de9cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46758a82\" data-id=\"46758a82\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26764837 elementor-widget elementor-widget-toggle\" data-id=\"26764837\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6451\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6451\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6451\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6451\"><p><strong>WALL STREET JOURNAL<\/strong><\/p><p><a href=\"https:\/\/www.wsj.com\/health\/healthcare\/medicaid-undocumented-immigrants-california-illinois-minnesota-962b3124\">https:\/\/www.wsj.com\/health\/healthcare\/medicaid-undocumented-immigrants-california-illinois-minnesota-962b3124<\/a><\/p><p><strong>AP<\/strong><\/p><p><a href=\"https:\/\/apnews.com\/article\/california-budget-deficit-medicaid-immigrant-84c1b09713cd973935788943703697bd\">https:\/\/apnews.com\/article\/california-budget-deficit-medicaid-immigrant-84c1b09713cd973935788943703697bd<\/a><\/p><p><a href=\"https:\/\/apnews.com\/article\/california-budget-deficit-immigrant-health-care-medicaid-5f45a2bfc47750ec5736f5d326557247\">https:\/\/apnews.com\/article\/california-budget-deficit-immigrant-health-care-medicaid-5f45a2bfc47750ec5736f5d326557247<\/a><\/p><p><strong>CALMATTERS<\/strong><\/p><p><a href=\"https:\/\/calmatters.org\/health\/2025\/05\/newsom-freeze-medi-cal-undocumented-immigrants\/\">https:\/\/calmatters.org\/health\/2025\/05\/newsom-freeze-medi-cal-undocumented-immigrants\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Los inmigrantes sin estatus que se benefician de Medi-Cal, no perder\u00e1n sus beneficios hasta julio de 2026. Hace m\u00e1s de un a\u00f1o, California hizo historia al permitir el acceso a Medi-Cal, el programa de atenci\u00f3n m\u00e9dica del estado, a inmigrantes sin estatus. Sin embargo, actualmente, legisladores de California buscan cerrar un d\u00e9ficit de 12 mil millones de d\u00f3lares al aprobar un presupuesto que reduce\u00a0 el acceso de los inmigrantes a la atenci\u00f3n m\u00e9dica. Los \u00faltimos a\u00f1os, California se ha visto orillado a recortar fondo para suspender ciertos programas p\u00fablicos. El plan de gastos de 321 mil millones de d\u00f3lares fue negociado por el gobernador Gavin Newsom y los principales legisladores estatales. Este presupuesto env\u00eda recortes a programas esenciales de seguridad. Asimismo, el estado enfrenta potencialmente una serie de recortes a nivel de federal de sus programas de salud.\u00a0 El nuevo acuerdo indica que California dejar\u00e1 de inscribir a los nuevos pacientes adultos sin estatus legal a Medi-Cal a partir de 2026. Seg\u00fan el plan presupuestario de Newsom, los adultos que ya est\u00e1n inscritos a Medi-Cal no ser\u00e1n expulsados, pero tendr\u00edan que comenzar a pagar una prima mensual de cien d\u00f3lares en 2027. De igual forma, el programa implementar\u00e1 una prima mensual de 30 d\u00f3lares a partir de julio de 2027, para los inmigrantes de bajos recursos que permanezcan en el programa, incluyendo a la gente a volver a inscribirse seis meses despu\u00e9s si pierden la cobertura por falta de pago. La prima se reducir\u00eda a 30 d\u00f3lares y solo se aprobar\u00eda a adultos de 19 a 59 a\u00f1os. \u201cEsta no es forma de responder a las preocupaciones sobre la salud y la seguridad de las comunidades que impulsan nuestra econom\u00eda y contribuyen con miles de millones en impuestos estatales\u201d, dijo Masih Fouladi, director ejecutivo del \u00a0\u00a0\u00a0 California Immigrant Policy Center. De esta manera, California, que hace un a\u00f1o se acercaba al objetivo de la atenci\u00f3n m\u00e9dica universal al ofrecer atenci\u00f3n m\u00e9dica a inmigrantes irregulares de bajos recursos, ahora se encuentra en una reducci\u00f3n de su presupuesto. Cabe destacar que, el estado ahorrar\u00eda m\u00e1s de 5 mil millones de d\u00f3lares en el ejercicio fiscal 2028-2029 y 3 mil 600 millones en el ejercicio 2027-2028, \u00a0seg\u00fan estimaciones. Cabe destacar, que California fue uno de los primeros estados del pa\u00eds en ofrecer cobertura m\u00e9dica a todos los adultos de bajos recursos, independientemente de su estatus migratorio. Actualmente, California ofrece atenci\u00f3n m\u00e9dica gratuita a m\u00e1s de 13 millones de personas. BIBLIOGRAF\u00cdA WALL STREET JOURNAL https:\/\/www.wsj.com\/health\/healthcare\/medicaid-undocumented-immigrants-california-illinois-minnesota-962b3124 AP https:\/\/apnews.com\/article\/california-budget-deficit-medicaid-immigrant-84c1b09713cd973935788943703697bd https:\/\/apnews.com\/article\/california-budget-deficit-immigrant-health-care-medicaid-5f45a2bfc47750ec5736f5d326557247 CALMATTERS https:\/\/calmatters.org\/health\/2025\/05\/newsom-freeze-medi-cal-undocumented-immigrants\/<\/p>","protected":false},"author":13,"featured_media":62152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10],"tags":[118,364,87,445,2032],"class_list":["post-62151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-california","tag-cobertura-medica","tag-inmigrantes","tag-medi-cal","tag-presupuesto"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica a ciertos inmigrantes a partir de 2026<\/title>\n<meta name=\"description\" content=\"Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica, a trav\u00e9s de Medi-Cal, a ciertos inmigrantes a partir de 2026.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica a ciertos inmigrantes a partir de 2026 | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica, a trav\u00e9s de Medi-Cal, a ciertos inmigrantes a partir de 2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-01T17:12:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-18T01:01:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/cobertura-medica.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica a ciertos inmigrantes a partir de 2026\",\"datePublished\":\"2025-07-01T17:12:40+00:00\",\"dateModified\":\"2025-07-18T01:01:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\\\/noticias\\\/\"},\"wordCount\":487,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cobertura-medica.png\",\"keywords\":[\"California\",\"Cobertura m\u00e9dica\",\"Inmigrantes\",\"Medi-cal\",\"Presupuesto\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\\\/noticias\\\/\",\"name\":\"Acceso Latino | Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica a ciertos inmigrantes a partir de 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cobertura-medica.png\",\"datePublished\":\"2025-07-01T17:12:40+00:00\",\"dateModified\":\"2025-07-18T01:01:29+00:00\",\"description\":\"Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica, a trav\u00e9s de Medi-Cal, a ciertos inmigrantes a partir de 2026.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cobertura-medica.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cobertura-medica.png\",\"width\":553,\"height\":267,\"caption\":\"cobertura medica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica a ciertos inmigrantes a partir de 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica a ciertos inmigrantes a partir de 2026","description":"Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica, a trav\u00e9s de Medi-Cal, a ciertos inmigrantes a partir de 2026.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica a ciertos inmigrantes a partir de 2026 | Acceso Latino","og_description":"Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica, a trav\u00e9s de Medi-Cal, a ciertos inmigrantes a partir de 2026.","og_url":"https:\/\/accesolatino.org\/en\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-07-01T17:12:40+00:00","article_modified_time":"2025-07-18T01:01:29+00:00","og_image":[{"width":553,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/cobertura-medica.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica a ciertos inmigrantes a partir de 2026","datePublished":"2025-07-01T17:12:40+00:00","dateModified":"2025-07-18T01:01:29+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/"},"wordCount":487,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/cobertura-medica.png","keywords":["California","Cobertura m\u00e9dica","Inmigrantes","Medi-cal","Presupuesto"],"articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/","url":"https:\/\/accesolatino.org\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/","name":"Acceso Latino | Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica a ciertos inmigrantes a partir de 2026","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/cobertura-medica.png","datePublished":"2025-07-01T17:12:40+00:00","dateModified":"2025-07-18T01:01:29+00:00","description":"Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica, a trav\u00e9s de Medi-Cal, a ciertos inmigrantes a partir de 2026.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/cobertura-medica.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/07\/cobertura-medica.png","width":553,"height":267,"caption":"cobertura medica"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/legisladores-en-california-aprueban-presupuesto-que-congela-cobertura-medica-a-ciertos-inmigrantes-a-partir-de-2026\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Legisladores en California aprueban presupuesto que congela cobertura m\u00e9dica a ciertos inmigrantes a partir de 2026"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=62151"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62151\/revisions"}],"predecessor-version":[{"id":62159,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62151\/revisions\/62159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/62152"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=62151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=62151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=62151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}