{"id":62088,"date":"2025-06-26T11:46:49","date_gmt":"2025-06-26T17:46:49","guid":{"rendered":"https:\/\/accesolatino.org\/?p=62088"},"modified":"2025-07-17T19:04:40","modified_gmt":"2025-07-18T01:04:40","slug":"stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/","title":{"rendered":"Stitches by Hugo: formaci\u00f3n en costura para migrantes y personas de bajos ingresos en NuevaYork"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"62088\" class=\"elementor elementor-62088\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21057163 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"21057163\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-189290d0\" data-id=\"189290d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4dd0912e elementor-widget elementor-widget-heading\" data-id=\"4dd0912e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Desde 2015, esta organizaci\u00f3n ofrece educaci\u00f3n accesible en moda y dise\u00f1o, con impacto comunitario y vocaci\u00f3n social.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-514d9ef7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"514d9ef7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3baaf147\" data-id=\"3baaf147\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71070ead elementor-widget elementor-widget-text-editor\" data-id=\"71070ead\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cada s\u00e1bado por la ma\u00f1ana, en un taller ubicado en Manhattan, se re\u00fanen mujeres, en su mayor\u00eda migrantes latinoamericanas, para aprender costura y dise\u00f1o de moda. El espacio, conocido como <strong>Stitches by Hugo<\/strong>, es una organizaci\u00f3n sin fines de lucro que desde 2015 ofrece formaci\u00f3n t\u00e9cnica gratuita a personas de bajos recursos. Su enfoque es propone la ense\u00f1anza de un oficio \u00fatil, pr\u00e1ctico y generador de ingresos, mientras fortalece la autoestima y la comunidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bf9e2fb elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2bf9e2fb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-288d1b1a\" data-id=\"288d1b1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ab0ba06 elementor-widget elementor-widget-image\" data-id=\"1ab0ba06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"553\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Cursos-de-costura.png\" class=\"attachment-full size-full wp-image-62089\" alt=\"Cursos de costura\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Cursos-de-costura.png 553w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Cursos-de-costura-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Cursos-de-costura-18x9.png 18w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-101f1bb6\" data-id=\"101f1bb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7eae77bd elementor-widget elementor-widget-text-editor\" data-id=\"7eae77bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Creado por el dise\u00f1ador colombiano Hugo Herrera y su esposa Nidia, Stitches by Hugo se ha consolidado como una alternativa formativa para quienes enfrentan barreras econ\u00f3micas o migratorias para acceder a estudios tradicionales. Con una estructura legal como organizaci\u00f3n sin fines de lucro, la iniciativa ha capacitado a m\u00e1s de 160 personas mediante un curso de ocho semanas en t\u00e9cnicas de corte, confecci\u00f3n y patronaje. Las clases se imparten en grupos peque\u00f1os, los s\u00e1bados, de 9 am a 1 pm, y culminan con una ceremonia de graduaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a25dca1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2a25dca1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2183dfd3\" data-id=\"2183dfd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-428efc5d elementor-widget elementor-widget-text-editor\" data-id=\"428efc5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El programa ha crecido gracias a la colaboraci\u00f3n directa entre docentes y estudiantes, las alumnas no solo aprenden a confeccionar prendas, sino que tambi\u00e9n acceden a m\u00e1quinas de coser reparadas por el propio Hugo, quien aprovecha recursos limitados y donaciones simb\u00f3licas para mantener el proyecto en marcha. La creciente demanda, impulsada por la difusi\u00f3n en redes sociales, ha generado listas de espera que superan las mil personas.<\/p><p>Adem\u00e1s de su enfoque t\u00e9cnico, Stitches by Hugo ofrece un entorno seguro donde las participantes pueden reconstruir su confianza personal en grupo. La experiencia de egresadas como Zaida Quizhpi, quien ahora colabora en el taller como instructora, refleja el potencial transformador del modelo. Su historia, que comenz\u00f3 como una operaria en f\u00e1bricas hasta llegar a convertirse en dise\u00f1adora,\u00a0 muestra el impacto de esta iniciativa gracias a la educaci\u00f3n pr\u00e1ctica y gratuita.<\/p><p>Actualmente, el proyecto busca expandirse hacia nuevos espacios y p\u00fablicos, incluyendo colaboraciones con instituciones del Bronx interesadas en replicar el modelo. Aunque sigue operando con recursos limitados, el compromiso de sus fundadores es continuar formando, empoderando y ofreciendo herramientas \u00fatiles a la comunidad que lo necesite.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f72a8a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2f72a8a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ee083d1\" data-id=\"2ee083d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27ae7023 elementor-widget elementor-widget-toggle\" data-id=\"27ae7023\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6651\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6651\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6651\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6651\"><p><strong>EL DIARIO DE NY<\/strong><\/p><p><a href=\"https:\/\/eldiariony.com\/2025\/05\/26\/stitches-by-hugo-una-puntada-de-esperanza-en-el-corazon-de-nueva-york\/\">https:\/\/eldiariony.com\/2025\/05\/26\/stitches-by-hugo-una-puntada-de-esperanza-en-el-corazon-de-nueva-york\/<\/a><\/p><p><a href=\"https:\/\/www.linkedin.com\/company\/stitches-by-hugo\">https:\/\/www.linkedin.com\/company\/stitches-by-hugo<\/a><\/p><p><strong>STITCHES BY HUGO<\/strong><\/p><p><a href=\"https:\/\/stitchesbyhugo.org\/about-us\/\">https:\/\/stitchesbyhugo.org\/about-us\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Desde 2015, esta organizaci\u00f3n ofrece educaci\u00f3n accesible en moda y dise\u00f1o, con impacto comunitario y vocaci\u00f3n social. Cada s\u00e1bado por la ma\u00f1ana, en un taller ubicado en Manhattan, se re\u00fanen mujeres, en su mayor\u00eda migrantes latinoamericanas, para aprender costura y dise\u00f1o de moda. El espacio, conocido como Stitches by Hugo, es una organizaci\u00f3n sin fines de lucro que desde 2015 ofrece formaci\u00f3n t\u00e9cnica gratuita a personas de bajos recursos. Su enfoque es propone la ense\u00f1anza de un oficio \u00fatil, pr\u00e1ctico y generador de ingresos, mientras fortalece la autoestima y la comunidad. Creado por el dise\u00f1ador colombiano Hugo Herrera y su esposa Nidia, Stitches by Hugo se ha consolidado como una alternativa formativa para quienes enfrentan barreras econ\u00f3micas o migratorias para acceder a estudios tradicionales. Con una estructura legal como organizaci\u00f3n sin fines de lucro, la iniciativa ha capacitado a m\u00e1s de 160 personas mediante un curso de ocho semanas en t\u00e9cnicas de corte, confecci\u00f3n y patronaje. Las clases se imparten en grupos peque\u00f1os, los s\u00e1bados, de 9 am a 1 pm, y culminan con una ceremonia de graduaci\u00f3n. El programa ha crecido gracias a la colaboraci\u00f3n directa entre docentes y estudiantes, las alumnas no solo aprenden a confeccionar prendas, sino que tambi\u00e9n acceden a m\u00e1quinas de coser reparadas por el propio Hugo, quien aprovecha recursos limitados y donaciones simb\u00f3licas para mantener el proyecto en marcha. La creciente demanda, impulsada por la difusi\u00f3n en redes sociales, ha generado listas de espera que superan las mil personas. Adem\u00e1s de su enfoque t\u00e9cnico, Stitches by Hugo ofrece un entorno seguro donde las participantes pueden reconstruir su confianza personal en grupo. La experiencia de egresadas como Zaida Quizhpi, quien ahora colabora en el taller como instructora, refleja el potencial transformador del modelo. Su historia, que comenz\u00f3 como una operaria en f\u00e1bricas hasta llegar a convertirse en dise\u00f1adora,\u00a0 muestra el impacto de esta iniciativa gracias a la educaci\u00f3n pr\u00e1ctica y gratuita. Actualmente, el proyecto busca expandirse hacia nuevos espacios y p\u00fablicos, incluyendo colaboraciones con instituciones del Bronx interesadas en replicar el modelo. Aunque sigue operando con recursos limitados, el compromiso de sus fundadores es continuar formando, empoderando y ofreciendo herramientas \u00fatiles a la comunidad que lo necesite. BIBLIOGRAF\u00cdA EL DIARIO DE NY https:\/\/eldiariony.com\/2025\/05\/26\/stitches-by-hugo-una-puntada-de-esperanza-en-el-corazon-de-nueva-york\/ https:\/\/www.linkedin.com\/company\/stitches-by-hugo STITCHES BY HUGO https:\/\/stitchesbyhugo.org\/about-us\/<\/p>","protected":false},"author":13,"featured_media":62089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1931,14],"tags":[3814,1393,86,32,3815],"class_list":["post-62088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empleabilidad-y-emprendimiento","category-empleo","tag-costura","tag-educacion-gratuita","tag-migrantes","tag-nueva-york","tag-sitches-by-hugo"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | Stitches by Hugo: formaci\u00f3n en costura para migrantes y personas de bajos ingresos en NuevaYork<\/title>\n<meta name=\"description\" content=\"Stitches by Hugo es una iniciativa que promueve la formaci\u00f3n en costura para migrantes y personas de bajos ingresos en Nueva York.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stitches by Hugo: formaci\u00f3n en costura para migrantes y personas de bajos ingresos en NuevaYork | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Stitches by Hugo es una iniciativa que promueve la formaci\u00f3n en costura para migrantes y personas de bajos ingresos en Nueva York.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-26T17:46:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-18T01:04:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Cursos-de-costura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\\\/empleabilidad-y-emprendimiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\\\/empleabilidad-y-emprendimiento\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Stitches by Hugo: formaci\u00f3n en costura para migrantes y personas de bajos ingresos en NuevaYork\",\"datePublished\":\"2025-06-26T17:46:49+00:00\",\"dateModified\":\"2025-07-18T01:04:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\\\/empleabilidad-y-emprendimiento\\\/\"},\"wordCount\":431,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\\\/empleabilidad-y-emprendimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Cursos-de-costura.png\",\"keywords\":[\"Costura\",\"Educaci\u00f3n gratuita\",\"Migrantes\",\"nueva york\",\"Sitches by Hugo\"],\"articleSection\":[\"Empleabilidad y emprendimiento\",\"Empleo\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\\\/empleabilidad-y-emprendimiento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\\\/empleabilidad-y-emprendimiento\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\\\/empleabilidad-y-emprendimiento\\\/\",\"name\":\"Acceso Latino | Stitches by Hugo: formaci\u00f3n en costura para migrantes y personas de bajos ingresos en NuevaYork\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\\\/empleabilidad-y-emprendimiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\\\/empleabilidad-y-emprendimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Cursos-de-costura.png\",\"datePublished\":\"2025-06-26T17:46:49+00:00\",\"dateModified\":\"2025-07-18T01:04:40+00:00\",\"description\":\"Stitches by Hugo es una iniciativa que promueve la formaci\u00f3n en costura para migrantes y personas de bajos ingresos en Nueva York.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\\\/empleabilidad-y-emprendimiento\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\\\/empleabilidad-y-emprendimiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\\\/empleabilidad-y-emprendimiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Cursos-de-costura.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Cursos-de-costura.png\",\"width\":553,\"height\":267,\"caption\":\"Cursos de costura\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\\\/empleabilidad-y-emprendimiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empleabilidad y emprendimiento\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/empleabilidad-y-emprendimiento\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stitches by Hugo: formaci\u00f3n en costura para migrantes y personas de bajos ingresos en NuevaYork\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | Stitches by Hugo: formaci\u00f3n en costura para migrantes y personas de bajos ingresos en NuevaYork","description":"Stitches by Hugo es una iniciativa que promueve la formaci\u00f3n en costura para migrantes y personas de bajos ingresos en Nueva York.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/","og_locale":"en_US","og_type":"article","og_title":"Stitches by Hugo: formaci\u00f3n en costura para migrantes y personas de bajos ingresos en NuevaYork | Acceso Latino","og_description":"Stitches by Hugo es una iniciativa que promueve la formaci\u00f3n en costura para migrantes y personas de bajos ingresos en Nueva York.","og_url":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-06-26T17:46:49+00:00","article_modified_time":"2025-07-18T01:04:40+00:00","og_image":[{"width":553,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Cursos-de-costura.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Stitches by Hugo: formaci\u00f3n en costura para migrantes y personas de bajos ingresos en NuevaYork","datePublished":"2025-06-26T17:46:49+00:00","dateModified":"2025-07-18T01:04:40+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/"},"wordCount":431,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Cursos-de-costura.png","keywords":["Costura","Educaci\u00f3n gratuita","Migrantes","nueva york","Sitches by Hugo"],"articleSection":["Empleabilidad y emprendimiento","Empleo"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/","url":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/","name":"Acceso Latino | Stitches by Hugo: formaci\u00f3n en costura para migrantes y personas de bajos ingresos en NuevaYork","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Cursos-de-costura.png","datePublished":"2025-06-26T17:46:49+00:00","dateModified":"2025-07-18T01:04:40+00:00","description":"Stitches by Hugo es una iniciativa que promueve la formaci\u00f3n en costura para migrantes y personas de bajos ingresos en Nueva York.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Cursos-de-costura.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Cursos-de-costura.png","width":553,"height":267,"caption":"Cursos de costura"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/stitches-by-hugo-formacion-en-costura-para-migrantes-y-personas-de-bajos-ingresos-en-nuevayork\/empleabilidad-y-emprendimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Empleabilidad y emprendimiento","item":"https:\/\/accesolatino.org\/category\/empleabilidad-y-emprendimiento\/"},{"@type":"ListItem","position":3,"name":"Stitches by Hugo: formaci\u00f3n en costura para migrantes y personas de bajos ingresos en NuevaYork"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=62088"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62088\/revisions"}],"predecessor-version":[{"id":62097,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62088\/revisions\/62097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/62089"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=62088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=62088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=62088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}