{"id":62011,"date":"2025-06-23T08:20:00","date_gmt":"2025-06-23T14:20:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=62011"},"modified":"2025-07-17T19:07:46","modified_gmt":"2025-07-18T01:07:46","slug":"la-laken-riley-act","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/","title":{"rendered":"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"62011\" class=\"elementor elementor-62011\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23020b0d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"23020b0d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-424ca4d0\" data-id=\"424ca4d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32e7a962 elementor-widget elementor-widget-heading\" data-id=\"32e7a962\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Esta ley obliga a elementos federales a detener a inmigrantes que hayan sido acusados de delitos violentos, incluso sin condena.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd4e0f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"dd4e0f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f3fd4c1\" data-id=\"1f3fd4c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36499317 elementor-widget elementor-widget-text-editor\" data-id=\"36499317\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Laken Riley Act, es una ley que exige que el Departamento de Seguridad Nacional (DHS), detenga a extranjeros que hayan sido arrestados por robo, hurto, latrocinio o hurto en tiendas (shoplifting). Esta ley tambi\u00e9n autoriza a los estados a demandar al gobierno federal por decisiones o supuestos fallos relacionados con la aplicaci\u00f3n de las leyes de inmigraci\u00f3n.<\/p><p>Bajo esta ley, el DHS debe detener a una persona que: se encuentra ilegalmente en Estados Unidos o cuenta con un estatus migratorio irregular y que haya sido acusada, detenida, condenada o admita haber cometido actos que constituyan elementos esenciales de robo, hurto, latrocinio o robo en tiendas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1fe9f3d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1fe9f3d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-37890358\" data-id=\"37890358\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fb40757 elementor-widget elementor-widget-image\" data-id=\"1fb40757\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"829\" height=\"401\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Laken-Riley-Act.png\" class=\"attachment-full size-full wp-image-62012\" alt=\"Laken Riley Act\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Laken-Riley-Act.png 829w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Laken-Riley-Act-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Laken-Riley-Act-768x371.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Laken-Riley-Act-18x9.png 18w\" sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Laken Riley Act<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-69f36bc8\" data-id=\"69f36bc8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14c97983 elementor-widget elementor-widget-text-editor\" data-id=\"14c97983\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esta ley, firmada el 29 de enero de 2025, surgi\u00f3 a partir del asesinato de la estudiante de enfermer\u00eda\u00a0 Laken Riley en febrero de 2024. El perpetrador del crimen, Jos\u00e9 Antonio Ibarra, un inmigrante indocumentado de Venezuela,\u00a0 hab\u00eda sido arrestado en 2022 por ingresar ilegalmente al pa\u00eds cerca de la frontera de El Paso, Texas. Ibarra fue puesto en libertad para seguir su caso en un tribunal de inmigraci\u00f3n, pero no fue expulsado del pa\u00eds.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5620834d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5620834d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9db9d46\" data-id=\"9db9d46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12f02284 elementor-widget elementor-widget-text-editor\" data-id=\"12f02284\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Previo al asesinato, Ibarra hab\u00eda sido acusado de actuar de una forma tal de herir a un menor de 17 a\u00f1os y una infracci\u00f3n en licencia de conducir en Nueva\u00a0 York, asimismo fue arrestado por cargos de robo en Georgia.<\/p><p>En este sentido, esta ley esta ley obliga a funcionarios federales a detener a cualquier inmigrante que haya sido arrestado o acusado de los delitos antes mencionados, as\u00ed como agresi\u00f3n a oficiales de polic\u00eda o delito delitos que hieran o maten.<\/p><p><strong>\u00bfA qui\u00e9nes afecta esta ley?<\/strong><\/p><p>Esta ley afecta principalmente a inmigrantes indocumentados con que hayan sido arrestados o cuentan con antecedentes penales aunque no hayan sido condenados todav\u00eda.<\/p><p>Cabe destacar que esta ley tambi\u00e9n contempla el retiro de fondos federales a jurisdicciones que limiten la cooperaci\u00f3n de las autoridades locales con las federales, como ocurre en las denominadas ciudades santuario.<\/p><p>En t\u00e9rminos generales, esta ley endurece las pol\u00edticas de detenci\u00f3n obligatoria y deportaci\u00f3n para este grupo, eliminando en algunos casos la discreci\u00f3n de los jueces migratorios. Por lo tanto, esta ley ha sido cuestionada por organizaciones de derechos civiles, defensores de los inmigrantes y algunos legisladores han por criminalizar a los inmigrantes, fomentar perfiles raciales y debilitar el debido proceso legal, especialmente al autorizar detenciones sin condena judicial.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bc658cd elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6bc658cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e86be42\" data-id=\"1e86be42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a5e20f8 elementor-widget elementor-widget-toggle\" data-id=\"4a5e20f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1241\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1241\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1241\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1241\"><p><strong>AP <\/strong><\/p><p><a href=\"https:\/\/apnews.com\/article\/what-is-laken-riley-act-trump-immigration-2667d626139ddf5a16d1533516eab18f\">https:\/\/apnews.com\/article\/what-is-laken-riley-act-trump-immigration-2667d626139ddf5a16d1533516eab18f<\/a><\/p><p><a href=\"https:\/\/apnews.com\/article\/congress-laken-riley-immigration-ibarra-georgia-34b06b0829772900eb55c123fe151845\">https:\/\/apnews.com\/article\/congress-laken-riley-immigration-ibarra-georgia-34b06b0829772900eb55c123fe151845<\/a><\/p><p><a href=\"https:\/\/apnews.com\/article\/congress-laken-riley-immigration-ibarra-georgia-34b06b0829772900eb55c123fe151845\">https:\/\/apnews.com\/article\/congress-laken-riley-immigration-ibarra-georgia-34b06b0829772900eb55c123fe151845<\/a><\/p><p><strong>ACLU<\/strong><\/p><p><a href=\"https:\/\/www.aclu.org\/press-releases\/aclu-responds-to-house-passage-of-h-r-29-the-laken-riley-act\">https:\/\/www.aclu.org\/press-releases\/aclu-responds-to-house-passage-of-h-r-29-the-laken-riley-act<\/a><\/p><p><strong>CONGRESS<\/strong><\/p><p><a href=\"https:\/\/www.congress.gov\/bill\/119th-congress\/senate-bill\/5\">https:\/\/www.congress.gov\/bill\/119th-congress\/senate-bill\/5<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Esta ley obliga a elementos federales a detener a inmigrantes que hayan sido acusados de delitos violentos, incluso sin condena. La Laken Riley Act, es una ley que exige que el Departamento de Seguridad Nacional (DHS), detenga a extranjeros que hayan sido arrestados por robo, hurto, latrocinio o hurto en tiendas (shoplifting). Esta ley tambi\u00e9n autoriza a los estados a demandar al gobierno federal por decisiones o supuestos fallos relacionados con la aplicaci\u00f3n de las leyes de inmigraci\u00f3n. Bajo esta ley, el DHS debe detener a una persona que: se encuentra ilegalmente en Estados Unidos o cuenta con un estatus migratorio irregular y que haya sido acusada, detenida, condenada o admita haber cometido actos que constituyan elementos esenciales de robo, hurto, latrocinio o robo en tiendas. Foto: NY Times Esta ley, firmada el 29 de enero de 2025, surgi\u00f3 a partir del asesinato de la estudiante de enfermer\u00eda\u00a0 Laken Riley en febrero de 2024. El perpetrador del crimen, Jos\u00e9 Antonio Ibarra, un inmigrante indocumentado de Venezuela,\u00a0 hab\u00eda sido arrestado en 2022 por ingresar ilegalmente al pa\u00eds cerca de la frontera de El Paso, Texas. Ibarra fue puesto en libertad para seguir su caso en un tribunal de inmigraci\u00f3n, pero no fue expulsado del pa\u00eds. Previo al asesinato, Ibarra hab\u00eda sido acusado de actuar de una forma tal de herir a un menor de 17 a\u00f1os y una infracci\u00f3n en licencia de conducir en Nueva\u00a0 York, asimismo fue arrestado por cargos de robo en Georgia. En este sentido, esta ley esta ley obliga a funcionarios federales a detener a cualquier inmigrante que haya sido arrestado o acusado de los delitos antes mencionados, as\u00ed como agresi\u00f3n a oficiales de polic\u00eda o delito delitos que hieran o maten. \u00bfA qui\u00e9nes afecta esta ley? Esta ley afecta principalmente a inmigrantes indocumentados con que hayan sido arrestados o cuentan con antecedentes penales aunque no hayan sido condenados todav\u00eda. Cabe destacar que esta ley tambi\u00e9n contempla el retiro de fondos federales a jurisdicciones que limiten la cooperaci\u00f3n de las autoridades locales con las federales, como ocurre en las denominadas ciudades santuario. En t\u00e9rminos generales, esta ley endurece las pol\u00edticas de detenci\u00f3n obligatoria y deportaci\u00f3n para este grupo, eliminando en algunos casos la discreci\u00f3n de los jueces migratorios. Por lo tanto, esta ley ha sido cuestionada por organizaciones de derechos civiles, defensores de los inmigrantes y algunos legisladores han por criminalizar a los inmigrantes, fomentar perfiles raciales y debilitar el debido proceso legal, especialmente al autorizar detenciones sin condena judicial. BIBLIOGRAF\u00cdA AP https:\/\/apnews.com\/article\/what-is-laken-riley-act-trump-immigration-2667d626139ddf5a16d1533516eab18f https:\/\/apnews.com\/article\/congress-laken-riley-immigration-ibarra-georgia-34b06b0829772900eb55c123fe151845 https:\/\/apnews.com\/article\/congress-laken-riley-immigration-ibarra-georgia-34b06b0829772900eb55c123fe151845 ACLU https:\/\/www.aclu.org\/press-releases\/aclu-responds-to-house-passage-of-h-r-29-the-laken-riley-act CONGRESS https:\/\/www.congress.gov\/bill\/119th-congress\/senate-bill\/5<\/p>","protected":false},"author":13,"featured_media":62012,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10],"tags":[3804,443,87,3803,3805],"class_list":["post-62011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-delitos-violentos","tag-indocumentados","tag-inmigrantes","tag-laken-riley-act","tag-robo"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Esta ley obliga a elementos federales a detener a inmigrantes que hayan sido acusados de delitos violentos, incluso sin condena. La Laken Riley Act, es una ley que exige que el Departamento de Seguridad Nacional (DHS), detenga a extranjeros que hayan sido arrestados por robo, hurto, latrocinio o hurto en tiendas (shoplifting). Esta ley tambi\u00e9n\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Noticias\"\/>\n\t<meta name=\"google-site-verification\" content=\"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE\" \/>\n\t<meta name=\"keywords\" content=\"delitos violentos,indocumentados,inmigrantes,laken riley act,robo,noticias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?\" \/>\n\t\t<meta property=\"og:description\" content=\"Esta ley obliga a elementos federales a detener a inmigrantes que hayan sido acusados de delitos violentos, incluso sin condena. La Laken Riley Act, es una ley que exige que el Departamento de Seguridad Nacional (DHS), detenga a extranjeros que hayan sido arrestados por robo, hurto, latrocinio o hurto en tiendas (shoplifting). Esta ley tambi\u00e9n\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-06-23T14:20:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-07-18T01:07:46+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Esta ley obliga a elementos federales a detener a inmigrantes que hayan sido acusados de delitos violentos, incluso sin condena. La Laken Riley Act, es una ley que exige que el Departamento de Seguridad Nacional (DHS), detenga a extranjeros que hayan sido arrestados por robo, hurto, latrocinio o hurto en tiendas (shoplifting). Esta ley tambi\u00e9n\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-laken-riley-act\\\/noticias\\\/#blogposting\",\"name\":\"\\u00bfLa Laken Riley Act afecta a todos los inmigrantes?\",\"headline\":\"\\u00bfLa Laken Riley Act afecta a todos los inmigrantes?\",\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Laken-Riley-Act.png\",\"width\":829,\"height\":401,\"caption\":\"Laken Riley Act\"},\"datePublished\":\"2025-06-23T08:20:00-06:00\",\"dateModified\":\"2025-07-17T19:07:46-06:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-laken-riley-act\\\/noticias\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-laken-riley-act\\\/noticias\\\/#webpage\"},\"articleSection\":\"Noticias, Delitos violentos, Indocumentados, Inmigrantes, Laken Riley Act, Robo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-laken-riley-act\\\/noticias\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-laken-riley-act\\\/noticias\\\/#listItem\",\"name\":\"\\u00bfLa Laken Riley Act afecta a todos los inmigrantes?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-laken-riley-act\\\/noticias\\\/#listItem\",\"position\":3,\"name\":\"\\u00bfLa Laken Riley Act afecta a todos los inmigrantes?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-laken-riley-act\\\/noticias\\\/#organizationLogo\",\"width\":240,\"height\":40},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-laken-riley-act\\\/noticias\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/\",\"name\":\"Noticias\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-laken-riley-act\\\/noticias\\\/#webpage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-laken-riley-act\\\/noticias\\\/\",\"name\":\"\\u00bfLa Laken Riley Act afecta a todos los inmigrantes?\",\"description\":\"Esta ley obliga a elementos federales a detener a inmigrantes que hayan sido acusados de delitos violentos, incluso sin condena. La Laken Riley Act, es una ley que exige que el Departamento de Seguridad Nacional (DHS), detenga a extranjeros que hayan sido arrestados por robo, hurto, latrocinio o hurto en tiendas (shoplifting). Esta ley tambi\\u00e9n\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-laken-riley-act\\\/noticias\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Laken-Riley-Act.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-laken-riley-act\\\/noticias\\\/#mainImage\",\"width\":829,\"height\":401,\"caption\":\"Laken Riley Act\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-laken-riley-act\\\/noticias\\\/#mainImage\"},\"datePublished\":\"2025-06-23T08:20:00-06:00\",\"dateModified\":\"2025-07-17T19:07:46-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?","description":"Esta ley obliga a elementos federales a detener a inmigrantes que hayan sido acusados de delitos violentos, incluso sin condena. La Laken Riley Act, es una ley que exige que el Departamento de Seguridad Nacional (DHS), detenga a extranjeros que hayan sido arrestados por robo, hurto, latrocinio o hurto en tiendas (shoplifting). Esta ley tambi\u00e9n","canonical_url":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/","robots":"max-image-preview:large","keywords":"delitos violentos,indocumentados,inmigrantes,laken riley act,robo,noticias","webmasterTools":{"google-site-verification":"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/#blogposting","name":"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?","headline":"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?","author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Laken-Riley-Act.png","width":829,"height":401,"caption":"Laken Riley Act"},"datePublished":"2025-06-23T08:20:00-06:00","dateModified":"2025-07-17T19:07:46-06:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/#webpage"},"isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/#webpage"},"articleSection":"Noticias, Delitos violentos, Indocumentados, Inmigrantes, Laken Riley Act, Robo"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","position":1,"name":"Home","item":"https:\/\/accesolatino.org\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/en\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/#listItem","name":"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/#listItem","position":3,"name":"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?","previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/en\/#organization","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","@id":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/#organizationLogo","width":240,"height":40},"image":{"@id":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author","url":"https:\/\/accesolatino.org\/en\/author\/noticias\/","name":"Noticias"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/#webpage","url":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/","name":"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?","description":"Esta ley obliga a elementos federales a detener a inmigrantes que hayan sido acusados de delitos violentos, incluso sin condena. La Laken Riley Act, es una ley que exige que el Departamento de Seguridad Nacional (DHS), detenga a extranjeros que hayan sido arrestados por robo, hurto, latrocinio o hurto en tiendas (shoplifting). Esta ley tambi\u00e9n","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/#breadcrumblist"},"author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"creator":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Laken-Riley-Act.png","@id":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/#mainImage","width":829,"height":401,"caption":"Laken Riley Act"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/#mainImage"},"datePublished":"2025-06-23T08:20:00-06:00","dateModified":"2025-07-17T19:07:46-06:00"},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/en\/#website","url":"https:\/\/accesolatino.org\/en\/","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","inLanguage":"en-US","publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim","og:type":"article","og:title":"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?","og:description":"Esta ley obliga a elementos federales a detener a inmigrantes que hayan sido acusados de delitos violentos, incluso sin condena. La Laken Riley Act, es una ley que exige que el Departamento de Seguridad Nacional (DHS), detenga a extranjeros que hayan sido arrestados por robo, hurto, latrocinio o hurto en tiendas (shoplifting). Esta ley tambi\u00e9n","og:url":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/","article:published_time":"2025-06-23T14:20:00+00:00","article:modified_time":"2025-07-18T01:07:46+00:00","twitter:card":"summary_large_image","twitter:title":"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?","twitter:description":"Esta ley obliga a elementos federales a detener a inmigrantes que hayan sido acusados de delitos violentos, incluso sin condena. La Laken Riley Act, es una ley que exige que el Departamento de Seguridad Nacional (DHS), detenga a extranjeros que hayan sido arrestados por robo, hurto, latrocinio o hurto en tiendas (shoplifting). Esta ley tambi\u00e9n"},"aioseo_meta_data":{"post_id":"62011","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-06-23 16:55:44","updated":"2025-07-18 01:08:26","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfLa Laken Riley Act afecta a todos los inmigrantes?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/accesolatino.org\/en"},{"label":"Noticias","link":"https:\/\/accesolatino.org\/en\/category\/noticias\/"},{"label":"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?","link":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | \u00bfLa Laken Riley Act afecta a todos los inmigrantes?<\/title>\n<meta name=\"description\" content=\"La Laken Riley Act afecta principalmente a los inmigrantes indocumentados que han sido acusados de cometer delitos violentos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfLa Laken Riley Act afecta a todos los inmigrantes? | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"La Laken Riley Act afecta principalmente a los inmigrantes indocumentados que han sido acusados de cometer delitos violentos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-23T14:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-18T01:07:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Laken-Riley-Act.png\" \/>\n\t<meta property=\"og:image:width\" content=\"829\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-laken-riley-act\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-laken-riley-act\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/19b22d08149ec674bbc49ad942c74e1a\"},\"headline\":\"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?\",\"datePublished\":\"2025-06-23T14:20:00+00:00\",\"dateModified\":\"2025-07-18T01:07:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-laken-riley-act\\\/noticias\\\/\"},\"wordCount\":489,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-laken-riley-act\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Laken-Riley-Act.png\",\"keywords\":[\"Delitos violentos\",\"Indocumentados\",\"Inmigrantes\",\"Laken Riley Act\",\"Robo\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/la-laken-riley-act\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-laken-riley-act\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/la-laken-riley-act\\\/noticias\\\/\",\"name\":\"Acceso Latino | \u00bfLa Laken Riley Act afecta a todos los inmigrantes?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-laken-riley-act\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-laken-riley-act\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Laken-Riley-Act.png\",\"datePublished\":\"2025-06-23T14:20:00+00:00\",\"dateModified\":\"2025-07-18T01:07:46+00:00\",\"description\":\"La Laken Riley Act afecta principalmente a los inmigrantes indocumentados que han sido acusados de cometer delitos violentos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-laken-riley-act\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/la-laken-riley-act\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-laken-riley-act\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Laken-Riley-Act.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Laken-Riley-Act.png\",\"width\":829,\"height\":401,\"caption\":\"Laken Riley Act\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-laken-riley-act\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/19b22d08149ec674bbc49ad942c74e1a\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | \u00bfLa Laken Riley Act afecta a todos los inmigrantes?","description":"La Laken Riley Act afecta principalmente a los inmigrantes indocumentados que han sido acusados de cometer delitos violentos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfLa Laken Riley Act afecta a todos los inmigrantes? | Acceso Latino","og_description":"La Laken Riley Act afecta principalmente a los inmigrantes indocumentados que han sido acusados de cometer delitos violentos.","og_url":"https:\/\/accesolatino.org\/en\/la-laken-riley-act\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-06-23T14:20:00+00:00","article_modified_time":"2025-07-18T01:07:46+00:00","og_image":[{"width":829,"height":401,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Laken-Riley-Act.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/la-laken-riley-act\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/la-laken-riley-act\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/19b22d08149ec674bbc49ad942c74e1a"},"headline":"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?","datePublished":"2025-06-23T14:20:00+00:00","dateModified":"2025-07-18T01:07:46+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/la-laken-riley-act\/noticias\/"},"wordCount":489,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/la-laken-riley-act\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Laken-Riley-Act.png","keywords":["Delitos violentos","Indocumentados","Inmigrantes","Laken Riley Act","Robo"],"articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/la-laken-riley-act\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/la-laken-riley-act\/noticias\/","url":"https:\/\/accesolatino.org\/la-laken-riley-act\/noticias\/","name":"Acceso Latino | \u00bfLa Laken Riley Act afecta a todos los inmigrantes?","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/la-laken-riley-act\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/la-laken-riley-act\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Laken-Riley-Act.png","datePublished":"2025-06-23T14:20:00+00:00","dateModified":"2025-07-18T01:07:46+00:00","description":"La Laken Riley Act afecta principalmente a los inmigrantes indocumentados que han sido acusados de cometer delitos violentos.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/la-laken-riley-act\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/la-laken-riley-act\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/la-laken-riley-act\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Laken-Riley-Act.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/06\/Laken-Riley-Act.png","width":829,"height":401,"caption":"Laken Riley Act"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/la-laken-riley-act\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"\u00bfLa Laken Riley Act afecta a todos los inmigrantes?"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/19b22d08149ec674bbc49ad942c74e1a","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=62011"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62011\/revisions"}],"predecessor-version":[{"id":62031,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/62011\/revisions\/62031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/62012"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=62011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=62011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=62011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}