{"id":61570,"date":"2025-05-26T10:15:55","date_gmt":"2025-05-26T16:15:55","guid":{"rendered":"https:\/\/accesolatino.org\/?p=61570"},"modified":"2025-05-26T10:29:22","modified_gmt":"2025-05-26T16:29:22","slug":"jueza-federal-permite-la-colaboracion-entre-ice-e-irs","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/","title":{"rendered":"Jueza federal permite la colaboraci\u00f3n entre ICE e IRS"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"61570\" class=\"elementor elementor-61570\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b366fc3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4b366fc3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e2d595b\" data-id=\"4e2d595b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3787b55f elementor-widget elementor-widget-heading\" data-id=\"3787b55f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Los trabajadores indocumentados est\u00e1n legalmente obligados a pagar impuestos federales sobre sus ingresos.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1158aa7e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1158aa7e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1cd2e199\" data-id=\"1cd2e199\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33c1194e elementor-widget elementor-widget-text-editor\" data-id=\"33c1194e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los contribuyentes indocumentados deben pagar impuestos en Estados Unidos, para ello es necesario contar con un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN) otorgado por el Servicio de Impuestos Internos (IRS). La informaci\u00f3n de las declaraciones de impuestos de todos los contribuyentes, seg\u00fan el C\u00f3digo de Rentas Internas (IRC), debe ser confidencial y actualmente no hay ninguna ley que autorice si divulgaci\u00f3n con fines de control migratorio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61d1eb12 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"61d1eb12\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-59d58d9f\" data-id=\"59d58d9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d5987f4 elementor-widget elementor-widget-image\" data-id=\"6d5987f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"829\" height=\"401\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/03\/Identificar-agente-ICE-png.webp\" class=\"attachment-full size-full wp-image-59912\" alt=\"Identificar agente ICE\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/03\/Identificar-agente-ICE-png.webp 829w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/03\/Identificar-agente-ICE-300x145.webp 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/03\/Identificar-agente-ICE-768x371.webp 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/03\/Identificar-agente-ICE-18x9.webp 18w\" sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-56204932\" data-id=\"56204932\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d0ccac2 elementor-widget elementor-widget-text-editor\" data-id=\"2d0ccac2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sin embargo, la jueza federal Dabney Friedrich del Tribunal de Distrito para el Distrito de Columbia, nombrada por Donald Trump en 2017, se neg\u00f3 a impedir que el IRS comparta datos fiscales de trabajadores indocumentados con el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE), con el prop\u00f3sito de identificar a personas que se encuentran ilegalmente en el pa\u00eds para su posterior deportaci\u00f3n. Friedrich deneg\u00f3 una orden judicial preliminar que fue interpuesta por organizaciones sin fines de lucro, que argumentaba que los inmigrantes sin documentos que pagan impuestos tienen derecho a protecciones de privacidad iguales a los ciudadanos o inmigrantes con estatus legal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-787bd983 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"787bd983\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-731b64bd\" data-id=\"731b64bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e41d02 elementor-widget elementor-widget-text-editor\" data-id=\"7e41d02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A finales de abril de 2025, el Departamento del Tesoro y el Departamento de Seguridad Nacional (DHS) llegaron a un acuerdo que permitir\u00eda que el IRS compartiera informaci\u00f3n de contribuyentes inmigrantes con ICE. Posteriormente, tras la publicaci\u00f3n de un memor\u00e1ndum de entendimiento (MOU)\u00a0 que detallaba esta acci\u00f3n, surgi\u00f3 una demanda por parte del Centro de Trabajadores Unidos y otras organizaciones. La demanda busc\u00f3 evitar que el IRS divulgara de manera no autorizada informaci\u00f3n de contribuyentes inmigrantes con la finalidad de facilitar tareas de detenci\u00f3n y deportaci\u00f3n.<\/p><p>Asimismo, la Orden Ejecutiva 14161 firmada el 20 de enero de este a\u00f1o, orden\u00f3 a jefes de agencias como DHS identificar y expulsar a personas presentes ilegalmente en el pa\u00eds. Adem\u00e1s, el MOU establece que el DHS ha identificado a personas presentes ilegalmente y que tiene \u00f3rdenes de expulsi\u00f3n. Bajo esa base, el MOU intervino para que el IRS revelara a ICE, que pertenece al DHS, informaci\u00f3n de los contribuyentes que de otro modo ser\u00eda confidencial. La informaci\u00f3n incluir\u00eda datos como nombre, direcci\u00f3n, informaci\u00f3n de la declaraci\u00f3n, entre otros. Esta\u00a0 decisi\u00f3n incluso provoc\u00f3 la renuncia de la comisionada interina del IRS, Melanie Krause y otros funcionarios.<\/p><p>Organizaciones civiles han catalogado esta acci\u00f3n del gobierno estadunidense como una injusticia hacia los contribuyentes indocumentados, que durante d\u00e9cadas fueron invitados a pagar sus impuestos para poder obtener una posible v\u00eda para legalizar su estatus migratorio en un futuro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28c514f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"28c514f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7dd290b7\" data-id=\"7dd290b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6baf936 elementor-widget elementor-widget-toggle\" data-id=\"6baf936\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1121\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1121\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1121\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1121\"><p><strong>EFF<\/strong><\/p><p><a href=\"https:\/\/www.eff.org\/deeplinks\/2025\/04\/irs-ice-immigrant-data-sharing-agreement-betrays-data-privacy-and-taxpayers-trust\">https:\/\/www.eff.org\/deeplinks\/2025\/04\/irs-ice-immigrant-data-sharing-agreement-betrays-data-privacy-and-taxpayers-trust<\/a><\/p><p><strong>NRP<\/strong><\/p><p><a href=\"https:\/\/www.npr.org\/2025\/05\/13\/nx-s1-5396461\/courts-irs-tax-undocumented-immigrants\">https:\/\/www.npr.org\/2025\/05\/13\/nx-s1-5396461\/courts-irs-tax-undocumented-immigrants<\/a><\/p><p><strong>CITIZEN<\/strong><\/p><p><a href=\"https:\/\/www.citizen.org\/litigation\/centro-de-trabajadores-unidos-v-bessent\/\">https:\/\/www.citizen.org\/litigation\/centro-de-trabajadores-unidos-v-bessent\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Los trabajadores indocumentados est\u00e1n legalmente obligados a pagar impuestos federales sobre sus ingresos. Los contribuyentes indocumentados deben pagar impuestos en Estados Unidos, para ello es necesario contar con un N\u00famero de Identificaci\u00f3n Personal del Contribuyente (ITIN) otorgado por el Servicio de Impuestos Internos (IRS). La informaci\u00f3n de las declaraciones de impuestos de todos los contribuyentes, seg\u00fan el C\u00f3digo de Rentas Internas (IRC), debe ser confidencial y actualmente no hay ninguna ley que autorice si divulgaci\u00f3n con fines de control migratorio. Sin embargo, la jueza federal Dabney Friedrich del Tribunal de Distrito para el Distrito de Columbia, nombrada por Donald Trump en 2017, se neg\u00f3 a impedir que el IRS comparta datos fiscales de trabajadores indocumentados con el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE), con el prop\u00f3sito de identificar a personas que se encuentran ilegalmente en el pa\u00eds para su posterior deportaci\u00f3n. Friedrich deneg\u00f3 una orden judicial preliminar que fue interpuesta por organizaciones sin fines de lucro, que argumentaba que los inmigrantes sin documentos que pagan impuestos tienen derecho a protecciones de privacidad iguales a los ciudadanos o inmigrantes con estatus legal. A finales de abril de 2025, el Departamento del Tesoro y el Departamento de Seguridad Nacional (DHS) llegaron a un acuerdo que permitir\u00eda que el IRS compartiera informaci\u00f3n de contribuyentes inmigrantes con ICE. Posteriormente, tras la publicaci\u00f3n de un memor\u00e1ndum de entendimiento (MOU)\u00a0 que detallaba esta acci\u00f3n, surgi\u00f3 una demanda por parte del Centro de Trabajadores Unidos y otras organizaciones. La demanda busc\u00f3 evitar que el IRS divulgara de manera no autorizada informaci\u00f3n de contribuyentes inmigrantes con la finalidad de facilitar tareas de detenci\u00f3n y deportaci\u00f3n. Asimismo, la Orden Ejecutiva 14161 firmada el 20 de enero de este a\u00f1o, orden\u00f3 a jefes de agencias como DHS identificar y expulsar a personas presentes ilegalmente en el pa\u00eds. Adem\u00e1s, el MOU establece que el DHS ha identificado a personas presentes ilegalmente y que tiene \u00f3rdenes de expulsi\u00f3n. Bajo esa base, el MOU intervino para que el IRS revelara a ICE, que pertenece al DHS, informaci\u00f3n de los contribuyentes que de otro modo ser\u00eda confidencial. La informaci\u00f3n incluir\u00eda datos como nombre, direcci\u00f3n, informaci\u00f3n de la declaraci\u00f3n, entre otros. Esta\u00a0 decisi\u00f3n incluso provoc\u00f3 la renuncia de la comisionada interina del IRS, Melanie Krause y otros funcionarios. Organizaciones civiles han catalogado esta acci\u00f3n del gobierno estadunidense como una injusticia hacia los contribuyentes indocumentados, que durante d\u00e9cadas fueron invitados a pagar sus impuestos para poder obtener una posible v\u00eda para legalizar su estatus migratorio en un futuro. BIBLIOGRAF\u00cdA EFF https:\/\/www.eff.org\/deeplinks\/2025\/04\/irs-ice-immigrant-data-sharing-agreement-betrays-data-privacy-and-taxpayers-trust NRP https:\/\/www.npr.org\/2025\/05\/13\/nx-s1-5396461\/courts-irs-tax-undocumented-immigrants CITIZEN https:\/\/www.citizen.org\/litigation\/centro-de-trabajadores-unidos-v-bessent\/<\/p>","protected":false},"author":13,"featured_media":59912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[3432,10],"tags":[1242,139,321,3730,947],"class_list":["post-61570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacada","category-noticias","tag-contribuyentes","tag-ice","tag-irs","tag-jueza-federal","tag-trabajadores-indocumentados"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | Jueza federal permite la colaboraci\u00f3n entre ICE e IRS<\/title>\n<meta name=\"description\" content=\"La jueza federal Dabney Friedrich se rehus\u00f3 a impedir la colaboraci\u00f3n entre ICE e IRS con el prop\u00f3sito de identificar inmigrantes sin documentos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jueza federal permite la colaboraci\u00f3n entre ICE e IRS | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"La jueza federal Dabney Friedrich se rehus\u00f3 a impedir la colaboraci\u00f3n entre ICE e IRS con el prop\u00f3sito de identificar inmigrantes sin documentos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-26T16:15:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-26T16:29:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/03\/Identificar-agente-ICE-png.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"829\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\\\/destacada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\\\/destacada\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\"},\"headline\":\"Jueza federal permite la colaboraci\u00f3n entre ICE e IRS\",\"datePublished\":\"2025-05-26T16:15:55+00:00\",\"dateModified\":\"2025-05-26T16:29:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\\\/destacada\\\/\"},\"wordCount\":478,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\\\/destacada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Identificar-agente-ICE-png.webp\",\"keywords\":[\"Contribuyentes\",\"ICE\",\"IRS\",\"Jueza federal\",\"trabajadores indocumentados\"],\"articleSection\":[\"Noticia Destacada\",\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\\\/destacada\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\\\/destacada\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\\\/destacada\\\/\",\"name\":\"Acceso Latino | Jueza federal permite la colaboraci\u00f3n entre ICE e IRS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\\\/destacada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\\\/destacada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Identificar-agente-ICE-png.webp\",\"datePublished\":\"2025-05-26T16:15:55+00:00\",\"dateModified\":\"2025-05-26T16:29:22+00:00\",\"description\":\"La jueza federal Dabney Friedrich se rehus\u00f3 a impedir la colaboraci\u00f3n entre ICE e IRS con el prop\u00f3sito de identificar inmigrantes sin documentos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\\\/destacada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\\\/destacada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\\\/destacada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Identificar-agente-ICE-png.webp\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Identificar-agente-ICE-png.webp\",\"width\":829,\"height\":401,\"caption\":\"Identificar agente ICE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\\\/destacada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticia Destacada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/destacada\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jueza federal permite la colaboraci\u00f3n entre ICE e IRS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | Jueza federal permite la colaboraci\u00f3n entre ICE e IRS","description":"La jueza federal Dabney Friedrich se rehus\u00f3 a impedir la colaboraci\u00f3n entre ICE e IRS con el prop\u00f3sito de identificar inmigrantes sin documentos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/","og_locale":"en_US","og_type":"article","og_title":"Jueza federal permite la colaboraci\u00f3n entre ICE e IRS | Acceso Latino","og_description":"La jueza federal Dabney Friedrich se rehus\u00f3 a impedir la colaboraci\u00f3n entre ICE e IRS con el prop\u00f3sito de identificar inmigrantes sin documentos.","og_url":"https:\/\/accesolatino.org\/en\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-05-26T16:15:55+00:00","article_modified_time":"2025-05-26T16:29:22+00:00","og_image":[{"width":829,"height":401,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/03\/Identificar-agente-ICE-png.webp","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b"},"headline":"Jueza federal permite la colaboraci\u00f3n entre ICE e IRS","datePublished":"2025-05-26T16:15:55+00:00","dateModified":"2025-05-26T16:29:22+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/"},"wordCount":478,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/03\/Identificar-agente-ICE-png.webp","keywords":["Contribuyentes","ICE","IRS","Jueza federal","trabajadores indocumentados"],"articleSection":["Noticia Destacada","Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/","url":"https:\/\/accesolatino.org\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/","name":"Acceso Latino | Jueza federal permite la colaboraci\u00f3n entre ICE e IRS","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/03\/Identificar-agente-ICE-png.webp","datePublished":"2025-05-26T16:15:55+00:00","dateModified":"2025-05-26T16:29:22+00:00","description":"La jueza federal Dabney Friedrich se rehus\u00f3 a impedir la colaboraci\u00f3n entre ICE e IRS con el prop\u00f3sito de identificar inmigrantes sin documentos.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/03\/Identificar-agente-ICE-png.webp","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/03\/Identificar-agente-ICE-png.webp","width":829,"height":401,"caption":"Identificar agente ICE"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/jueza-federal-permite-la-colaboracion-entre-ice-e-irs\/destacada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticia Destacada","item":"https:\/\/accesolatino.org\/category\/destacada\/"},{"@type":"ListItem","position":3,"name":"Jueza federal permite la colaboraci\u00f3n entre ICE e IRS"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/61570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=61570"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/61570\/revisions"}],"predecessor-version":[{"id":61581,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/61570\/revisions\/61581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/59912"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=61570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=61570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=61570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}