{"id":60644,"date":"2025-04-07T10:31:11","date_gmt":"2025-04-07T16:31:11","guid":{"rendered":"https:\/\/accesolatino.org\/?p=60644"},"modified":"2025-11-18T18:38:11","modified_gmt":"2025-11-19T00:38:11","slug":"estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/","title":{"rendered":"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"60644\" class=\"elementor elementor-60644\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-775f4919 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"775f4919\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56cda5a0\" data-id=\"56cda5a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ec5f205 elementor-widget elementor-widget-heading\" data-id=\"4ec5f205\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Estudiantes se han manifestado en diversas universidades de California por temor a deportaciones. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37d1a25d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"37d1a25d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27a476b2\" data-id=\"27a476b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e521e01 elementor-widget elementor-widget-text-editor\" data-id=\"2e521e01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ante el anuncio de posibles deportaciones masivas durante el segundo mandato del presidente Donald Trump, estudiantes en California han alzado la voz para exigir mayor protecci\u00f3n en sus campus. Manifestaciones en universidades como UC Berkeley, Sacramento State y Cal State Northridge demuestran la incertidumbre y preocupaci\u00f3n de la comunidad estudiantil de California, que cuenta con un importante porcentaje de alumnos migrantes o de familias con estatus migratorio mixto.<\/p><p>En Cal State Northridge (CSUN), alrededor de 300 estudiantes se reunieron con pancartas y consignas \u00a0a favor del empleo y la educaci\u00f3n y en contra de las deportaciones masivas. Asimismo, mostraron carteles en contra de la presencia de elementos del Servicio de Control de Inmigraci\u00f3n y Aduanas (ICE). Seg\u00fan datos del Equity Research Institute, cerca de 100 mil universitarios en California carecen de estatus migratorio permanente, y 3.3 millones de personas en el estado viven en hogares con estatus mixto.<\/p><p>Karisma Ramos Ayala, estudiante de escritura creativa en CSUN, cont\u00f3 su experiencia: \u201cNo creo que ICE deba estar cerca de escuelas o universidades. La gente est\u00e1 aqu\u00ed para educarse, y no podemos permitir que nos lo arrebaten\u201d.<\/p><p>En enero, la administraci\u00f3n Trump derog\u00f3 una pol\u00edtica que prohib\u00eda arrestos migratorios en escuelas, iglesias y otros lugares considerados \u201csensibles\u201d. Aunque a\u00fan no se han reportado operativos en campus universitarios, los estudiantes viven en incertidumbre.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5f0044 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"a5f0044\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3ef74305\" data-id=\"3ef74305\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ea4ff6a elementor-widget elementor-widget-image\" data-id=\"6ea4ff6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/04\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg\" class=\"attachment-full size-full wp-image-60645\" alt=\"Estudiantes de diversas universidades de California piden mayor proteccio\u0301n contra autoridades migratorias.\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/04\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg 1020w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/04\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias-300x200.jpg 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/04\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias-768x512.jpg 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/04\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias-18x12.jpg 18w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Estudiantes de diversas universidades de California piden mayor proteccio\u0301n contra autoridades migratorias.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6224a627\" data-id=\"6224a627\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58b2014b elementor-widget elementor-widget-text-editor\" data-id=\"58b2014b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Por otro lado, el fiscal general de California, Rob Bonta, emiti\u00f3 directrices claras sobre\u00a0 esta situaci\u00f3n: ICE puede ingresar en \u00e1reas p\u00fablicas como parques y bibliotecas, no as\u00ed en espacios privados como viviendas estudiantiles o aulas restringidas. Para ello es necesaria una orden judicial.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8beaeec elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"8beaeec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce6b7fc\" data-id=\"ce6b7fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-314e9b25 elementor-widget elementor-widget-text-editor\" data-id=\"314e9b25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Asimismo, las universidades han reforzado sus protocolos. La UC, la CSU y colegios comunitarios proh\u00edben a sus polic\u00edas colaborar con ICE, de acuerdo con la ley estatal de 2017. Adem\u00e1s, los Centros \u201cDream\u201d ubicados en los diferentes campus universitarios ofrecen asesor\u00eda legal, salud mental y recursos financieros para estudiantes.<\/p><p>Por su parte, los estudiantes tienen tres exigencias clave:<\/p><ul><li>Declarar los campus como \u201csantuarios\u201d y prohibir el acceso a ICE<\/li><li>Mayor financiamiento para recursos legales y apoyo a estudiantes indocumentados<\/li><li>Sistemas de alerta ante la presencia de agentes migratorios<\/li><\/ul><p>\u00a0<\/p><p>Aditi Hariharan, presidenta de la Asociaci\u00f3n de Estudiantes de la UC, critic\u00f3 la falta de empleo en campus para indocumentados: \u201cLa UC debe demostrar su apoyo, o ser\u00e1 dif\u00edcil crear un ambiente seguro\u201d Asimismo, Amy Bentley-Smith, portavoz de Cal State, afirm\u00f3 que \u201cNuestros campus est\u00e1n comprometidos con la seguridad de todos los estudiantes, sin importar su estatus\u201d. Mientras, la UC destac\u00f3 sus programas de asesor\u00eda legal y apoyo financiero.<\/p><p>Algunos grupos conservadores, como en Cal State Long Beach, respaldan las deportaciones, argumentando que las universidades no deben ser santuarios. Este debate ha generado tensiones, con enfrentamientos entre manifestantes y contramanifestantes<\/p><p>La profesora Rosa Rivera Furumoto de CSUN destac\u00f3 la importancia de la resistencia estudiantil: \u201cEstamos en una situaci\u00f3n aterradora, y necesitamos levantarnos\u201d. Con el aumento de las pol\u00edticas migratorias restrictivas, las universidades de California se convierten en un frente clave para la defensa de los derechos de los migrantes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12921908 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"12921908\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-453d737b\" data-id=\"453d737b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17ccc9c2 elementor-widget elementor-widget-toggle\" data-id=\"17ccc9c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3991\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-3991\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3991\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-3991\"><p><strong>CAL MATTERS<\/strong><\/p><p><a href=\"https:\/\/calmatters.org\/calmatters-en-espanol\/2025\/03\/universidades-estudiantes-migrantes-recursos-autoridades-migratorias\/\">https:\/\/calmatters.org\/calmatters-en-espanol\/2025\/03\/universidades-estudiantes-migrantes-recursos-autoridades-migratorias\/<\/a><\/p><p><strong>KQED<\/strong><\/p><p><a href=\"https:\/\/www.kqed.org\/news\/12032339\/students-call-on-california-colleges-to-protect-campuses-from-immigration-enforcement\">https:\/\/www.kqed.org\/news\/12032339\/students-call-on-california-colleges-to-protect-campuses-from-immigration-enforcement<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Estudiantes se han manifestado en diversas universidades de California por temor a deportaciones. Ante el anuncio de posibles deportaciones masivas durante el segundo mandato del presidente Donald Trump, estudiantes en California han alzado la voz para exigir mayor protecci\u00f3n en sus campus. Manifestaciones en universidades como UC Berkeley, Sacramento State y Cal State Northridge demuestran la incertidumbre y preocupaci\u00f3n de la comunidad estudiantil de California, que cuenta con un importante porcentaje de alumnos migrantes o de familias con estatus migratorio mixto. En Cal State Northridge (CSUN), alrededor de 300 estudiantes se reunieron con pancartas y consignas \u00a0a favor del empleo y la educaci\u00f3n y en contra de las deportaciones masivas. Asimismo, mostraron carteles en contra de la presencia de elementos del Servicio de Control de Inmigraci\u00f3n y Aduanas (ICE). Seg\u00fan datos del Equity Research Institute, cerca de 100 mil universitarios en California carecen de estatus migratorio permanente, y 3.3 millones de personas en el estado viven en hogares con estatus mixto. Karisma Ramos Ayala, estudiante de escritura creativa en CSUN, cont\u00f3 su experiencia: \u201cNo creo que ICE deba estar cerca de escuelas o universidades. La gente est\u00e1 aqu\u00ed para educarse, y no podemos permitir que nos lo arrebaten\u201d. En enero, la administraci\u00f3n Trump derog\u00f3 una pol\u00edtica que prohib\u00eda arrestos migratorios en escuelas, iglesias y otros lugares considerados \u201csensibles\u201d. Aunque a\u00fan no se han reportado operativos en campus universitarios, los estudiantes viven en incertidumbre. foto: Fred Greaves for CalMatters Por otro lado, el fiscal general de California, Rob Bonta, emiti\u00f3 directrices claras sobre\u00a0 esta situaci\u00f3n: ICE puede ingresar en \u00e1reas p\u00fablicas como parques y bibliotecas, no as\u00ed en espacios privados como viviendas estudiantiles o aulas restringidas. Para ello es necesaria una orden judicial. Asimismo, las universidades han reforzado sus protocolos. La UC, la CSU y colegios comunitarios proh\u00edben a sus polic\u00edas colaborar con ICE, de acuerdo con la ley estatal de 2017. Adem\u00e1s, los Centros \u201cDream\u201d ubicados en los diferentes campus universitarios ofrecen asesor\u00eda legal, salud mental y recursos financieros para estudiantes. Por su parte, los estudiantes tienen tres exigencias clave: Declarar los campus como \u201csantuarios\u201d y prohibir el acceso a ICE Mayor financiamiento para recursos legales y apoyo a estudiantes indocumentados Sistemas de alerta ante la presencia de agentes migratorios \u00a0 Aditi Hariharan, presidenta de la Asociaci\u00f3n de Estudiantes de la UC, critic\u00f3 la falta de empleo en campus para indocumentados: \u201cLa UC debe demostrar su apoyo, o ser\u00e1 dif\u00edcil crear un ambiente seguro\u201d Asimismo, Amy Bentley-Smith, portavoz de Cal State, afirm\u00f3 que \u201cNuestros campus est\u00e1n comprometidos con la seguridad de todos los estudiantes, sin importar su estatus\u201d. Mientras, la UC destac\u00f3 sus programas de asesor\u00eda legal y apoyo financiero. Algunos grupos conservadores, como en Cal State Long Beach, respaldan las deportaciones, argumentando que las universidades no deben ser santuarios. Este debate ha generado tensiones, con enfrentamientos entre manifestantes y contramanifestantes La profesora Rosa Rivera Furumoto de CSUN destac\u00f3 la importancia de la resistencia estudiantil: \u201cEstamos en una situaci\u00f3n aterradora, y necesitamos levantarnos\u201d. Con el aumento de las pol\u00edticas migratorias restrictivas, las universidades de California se convierten en un frente clave para la defensa de los derechos de los migrantes. BIBLIOGRAF\u00cdA CAL MATTERS https:\/\/calmatters.org\/calmatters-en-espanol\/2025\/03\/universidades-estudiantes-migrantes-recursos-autoridades-migratorias\/ KQED https:\/\/www.kqed.org\/news\/12032339\/students-call-on-california-colleges-to-protect-campuses-from-immigration-enforcement<\/p>","protected":false},"author":13,"featured_media":60645,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[13,3432,10],"tags":[],"class_list":["post-60644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","category-destacada","category-noticias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Estudiantes se han manifestado en diversas universidades de California por temor a deportaciones. Ante el anuncio de posibles deportaciones masivas durante el segundo mandato del presidente Donald Trump, estudiantes en California han alzado la voz para exigir mayor protecci\u00f3n en sus campus. Manifestaciones en universidades como UC Berkeley, Sacramento State y Cal State Northridge demuestran\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Noticias\"\/>\n\t<meta name=\"google-site-verification\" content=\"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE\" \/>\n\t<meta name=\"keywords\" content=\"educaci\u00f3n,noticia destacada,noticias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias\" \/>\n\t\t<meta property=\"og:description\" content=\"Estudiantes se han manifestado en diversas universidades de California por temor a deportaciones. Ante el anuncio de posibles deportaciones masivas durante el segundo mandato del presidente Donald Trump, estudiantes en California han alzado la voz para exigir mayor protecci\u00f3n en sus campus. Manifestaciones en universidades como UC Berkeley, Sacramento State y Cal State Northridge demuestran\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-04-07T16:31:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-11-19T00:38:11+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Estudiantes se han manifestado en diversas universidades de California por temor a deportaciones. Ante el anuncio de posibles deportaciones masivas durante el segundo mandato del presidente Donald Trump, estudiantes en California han alzado la voz para exigir mayor protecci\u00f3n en sus campus. Manifestaciones en universidades como UC Berkeley, Sacramento State y Cal State Northridge demuestran\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/destacada\\\/#blogposting\",\"name\":\"Estudiantes en California piden mayor protecci\\u00f3n contra autoridades migratorias\",\"headline\":\"Estudiantes en California piden mayor protecci\\u00f3n contra autoridades migratorias\",\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg\",\"width\":1020,\"height\":680,\"caption\":\"Estudiantes de diversas universidades de California piden mayor proteccio\\u0301n contra autoridades migratorias.\"},\"datePublished\":\"2025-04-07T10:31:11-06:00\",\"dateModified\":\"2025-11-18T18:38:11-06:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/destacada\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/destacada\\\/#webpage\"},\"articleSection\":\"Educaci\\u00f3n, Noticia Destacada, Noticias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/destacada\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/destacada\\\/#listItem\",\"name\":\"Estudiantes en California piden mayor protecci\\u00f3n contra autoridades migratorias\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/destacada\\\/#listItem\",\"position\":3,\"name\":\"Estudiantes en California piden mayor protecci\\u00f3n contra autoridades migratorias\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/destacada\\\/#organizationLogo\",\"width\":240,\"height\":40},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/destacada\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/\",\"name\":\"Noticias\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/destacada\\\/#webpage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/destacada\\\/\",\"name\":\"Estudiantes en California piden mayor protecci\\u00f3n contra autoridades migratorias\",\"description\":\"Estudiantes se han manifestado en diversas universidades de California por temor a deportaciones. Ante el anuncio de posibles deportaciones masivas durante el segundo mandato del presidente Donald Trump, estudiantes en California han alzado la voz para exigir mayor protecci\\u00f3n en sus campus. Manifestaciones en universidades como UC Berkeley, Sacramento State y Cal State Northridge demuestran\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/destacada\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/destacada\\\/#mainImage\",\"width\":1020,\"height\":680,\"caption\":\"Estudiantes de diversas universidades de California piden mayor proteccio\\u0301n contra autoridades migratorias.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/destacada\\\/#mainImage\"},\"datePublished\":\"2025-04-07T10:31:11-06:00\",\"dateModified\":\"2025-11-18T18:38:11-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias","description":"Estudiantes se han manifestado en diversas universidades de California por temor a deportaciones. Ante el anuncio de posibles deportaciones masivas durante el segundo mandato del presidente Donald Trump, estudiantes en California han alzado la voz para exigir mayor protecci\u00f3n en sus campus. Manifestaciones en universidades como UC Berkeley, Sacramento State y Cal State Northridge demuestran","canonical_url":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/","robots":"max-image-preview:large","keywords":"educaci\u00f3n,noticia destacada,noticias","webmasterTools":{"google-site-verification":"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/#blogposting","name":"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias","headline":"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias","author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/04\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg","width":1020,"height":680,"caption":"Estudiantes de diversas universidades de California piden mayor proteccio\u0301n contra autoridades migratorias."},"datePublished":"2025-04-07T10:31:11-06:00","dateModified":"2025-11-18T18:38:11-06:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/#webpage"},"isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/#webpage"},"articleSection":"Educaci\u00f3n, Noticia Destacada, Noticias"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","position":1,"name":"Home","item":"https:\/\/accesolatino.org\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/en\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/#listItem","name":"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias"},"previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/#listItem","position":3,"name":"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias","previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/en\/#organization","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","@id":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/#organizationLogo","width":240,"height":40},"image":{"@id":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author","url":"https:\/\/accesolatino.org\/en\/author\/noticias\/","name":"Noticias"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/#webpage","url":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/","name":"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias","description":"Estudiantes se han manifestado en diversas universidades de California por temor a deportaciones. Ante el anuncio de posibles deportaciones masivas durante el segundo mandato del presidente Donald Trump, estudiantes en California han alzado la voz para exigir mayor protecci\u00f3n en sus campus. Manifestaciones en universidades como UC Berkeley, Sacramento State y Cal State Northridge demuestran","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/#breadcrumblist"},"author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"creator":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/04\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg","@id":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/#mainImage","width":1020,"height":680,"caption":"Estudiantes de diversas universidades de California piden mayor proteccio\u0301n contra autoridades migratorias."},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/#mainImage"},"datePublished":"2025-04-07T10:31:11-06:00","dateModified":"2025-11-18T18:38:11-06:00"},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/en\/#website","url":"https:\/\/accesolatino.org\/en\/","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","inLanguage":"en-US","publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim","og:type":"article","og:title":"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias","og:description":"Estudiantes se han manifestado en diversas universidades de California por temor a deportaciones. Ante el anuncio de posibles deportaciones masivas durante el segundo mandato del presidente Donald Trump, estudiantes en California han alzado la voz para exigir mayor protecci\u00f3n en sus campus. Manifestaciones en universidades como UC Berkeley, Sacramento State y Cal State Northridge demuestran","og:url":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/","article:published_time":"2025-04-07T16:31:11+00:00","article:modified_time":"2025-11-19T00:38:11+00:00","twitter:card":"summary_large_image","twitter:title":"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias","twitter:description":"Estudiantes se han manifestado en diversas universidades de California por temor a deportaciones. Ante el anuncio de posibles deportaciones masivas durante el segundo mandato del presidente Donald Trump, estudiantes en California han alzado la voz para exigir mayor protecci\u00f3n en sus campus. Manifestaciones en universidades como UC Berkeley, Sacramento State y Cal State Northridge demuestran"},"aioseo_meta_data":{"post_id":"60644","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-04-07 16:29:05","updated":"2025-11-19 00:38:14","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEstudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/accesolatino.org\/en"},{"label":"Noticias","link":"https:\/\/accesolatino.org\/en\/category\/noticias\/"},{"label":"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias","link":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/destacada\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceso Latino | Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias<\/title>\n<meta name=\"description\" content=\"Estudiantes de diversas universidades de California piden mayor protecci\u00f3n contra autoridades migratorias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Estudiantes de diversas universidades de California piden mayor protecci\u00f3n contra autoridades migratorias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-07T16:31:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T00:38:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/04\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1020\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\"},\"headline\":\"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias\",\"datePublished\":\"2025-04-07T16:31:11+00:00\",\"dateModified\":\"2025-11-19T00:38:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/noticias\\\/\"},\"wordCount\":562,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg\",\"articleSection\":[\"Educaci\u00f3n\",\"Noticia Destacada\",\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/noticias\\\/\",\"name\":\"Acceso Latino | Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg\",\"datePublished\":\"2025-04-07T16:31:11+00:00\",\"dateModified\":\"2025-11-19T00:38:11+00:00\",\"description\":\"Estudiantes de diversas universidades de California piden mayor protecci\u00f3n contra autoridades migratorias.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg\",\"width\":1020,\"height\":680,\"caption\":\"Estudiantes de diversas universidades de California piden mayor proteccio\u0301n contra autoridades migratorias.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticia Destacada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/destacada\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceso Latino | Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias","description":"Estudiantes de diversas universidades de California piden mayor protecci\u00f3n contra autoridades migratorias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias | Acceso Latino","og_description":"Estudiantes de diversas universidades de California piden mayor protecci\u00f3n contra autoridades migratorias.","og_url":"https:\/\/accesolatino.org\/en\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-04-07T16:31:11+00:00","article_modified_time":"2025-11-19T00:38:11+00:00","og_image":[{"width":1020,"height":680,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/04\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg","type":"image\/jpeg"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905"},"headline":"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias","datePublished":"2025-04-07T16:31:11+00:00","dateModified":"2025-11-19T00:38:11+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/"},"wordCount":562,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/04\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg","articleSection":["Educaci\u00f3n","Noticia Destacada","Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/","url":"https:\/\/accesolatino.org\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/","name":"Acceso Latino | Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/04\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg","datePublished":"2025-04-07T16:31:11+00:00","dateModified":"2025-11-19T00:38:11+00:00","description":"Estudiantes de diversas universidades de California piden mayor protecci\u00f3n contra autoridades migratorias.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/04\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/04\/Estudiantes-de-diversas-universidades-de-California-piden-mayor-proteccion-contra-autoridades-migratorias.jpg","width":1020,"height":680,"caption":"Estudiantes de diversas universidades de California piden mayor proteccio\u0301n contra autoridades migratorias."},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/estudiantes-en-california-piden-mayor-proteccion-contra-autoridades-migratorias\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticia Destacada","item":"https:\/\/accesolatino.org\/category\/destacada\/"},{"@type":"ListItem","position":3,"name":"Estudiantes en California piden mayor protecci\u00f3n contra autoridades migratorias"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/60644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=60644"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/60644\/revisions"}],"predecessor-version":[{"id":68852,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/60644\/revisions\/68852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/60645"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=60644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=60644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=60644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}