{"id":58946,"date":"2025-01-29T10:18:45","date_gmt":"2025-01-29T16:18:45","guid":{"rendered":"https:\/\/accesolatino.org\/?p=58946"},"modified":"2025-01-29T10:29:27","modified_gmt":"2025-01-29T16:29:27","slug":"empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/","title":{"rendered":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"58946\" class=\"elementor elementor-58946\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53b9bde8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"53b9bde8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27c852cd\" data-id=\"27c852cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70203735 elementor-widget elementor-widget-heading\" data-id=\"70203735\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Samuel S\u00e1nchez, due\u00f1o de restaurantes en Chicago, lidera esfuerzos para buscar soluciones migratorias de sentido com\u00fan en Estados Unidos.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b90fa2e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5b90fa2e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7811ecfb\" data-id=\"7811ecfb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31e6e18 elementor-widget elementor-widget-text-editor\" data-id=\"31e6e18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Samuel S\u00e1nchez, hijo de un inmigrante mexicano deportado cuando \u00e9l ten\u00eda 14 a\u00f1os, ha convertido su historia familiar en una lucha por un camino hacia la ciudadan\u00eda para los Dreamers y los trabajadores esenciales en Estados Unidos. Como miembro del Comit\u00e9 de 100, una coalici\u00f3n de empresarios latinos, S\u00e1nchez busca soluciones migratorias que protejan a quienes han contribuido al desarrollo econ\u00f3mico del pa\u00eds.<\/p><p>Samuel S\u00e1nchez creci\u00f3 en Texas mientras su padre trabajaba en los campos de algod\u00f3n hasta ser deportado. A\u00f1os despu\u00e9s, su padre regres\u00f3 con una visa de trabajo, dejando una marca en la perspectiva de S\u00e1nchez sobre la inmigraci\u00f3n. Ahora, como due\u00f1o de siete restaurantes en Chicago, utiliza su posici\u00f3n para abogar por quienes est\u00e1n en riesgo de deportaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22fcb44e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"22fcb44e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4617c747\" data-id=\"4617c747\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a1201b0 elementor-widget elementor-widget-image\" data-id=\"4a1201b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1316\" height=\"740\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png\" class=\"attachment-full size-full wp-image-58948\" alt=\"El 30% de los trabajadores agri\u0301colas de EE.UU. son mexicanos inmigrantes. Cre\u0301dito- Rebecca Blackwell | AP\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png 1316w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP-300x169.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP-1024x576.png 1024w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP-768x432.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP-18x10.png 18w\" sizes=\"(max-width: 1316px) 100vw, 1316px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">El 30% de los trabajadores agri\u0301colas de EE.UU. son mexicanos inmigrantes. Cre\u0301dito- Rebecca Blackwell | AP<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ce7762e\" data-id=\"7ce7762e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-205c3333 elementor-widget elementor-widget-text-editor\" data-id=\"205c3333\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cMucha gente que est\u00e1 aqu\u00ed merece una oportunidad. No pueden ver m\u00e1s all\u00e1 porque est\u00e1n encerrados en un estado\u201d, expres\u00f3 S\u00e1nchez en entrevista con Univisi\u00f3n. Tambi\u00e9n destac\u00f3 la importancia de proteger a quienes han vivido a\u00f1os en Estados Unidos sin una situaci\u00f3n migratoria regular: \u201cEs importante que salgamos a luchar por aquellos que corren riesgo de deportaci\u00f3n y son los que tienen a\u00f1os de estar aqu\u00ed\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66371ea4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"66371ea4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1418c424\" data-id=\"1418c424\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54543942 elementor-widget elementor-widget-text-editor\" data-id=\"54543942\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Comit\u00e9 de 100, al que S\u00e1nchez pertenece, re\u00fane a empresarios latinos de diversos sectores, como la restauraci\u00f3n, la construcci\u00f3n y la hoteler\u00eda. Su objetivo es proponer lo que ellos denominan \u201csoluciones migratorias de sentido com\u00fan\u201d que beneficien tanto a los inmigrantes como a la econom\u00eda estadounidense.<\/p><p>En este sentido, la coalici\u00f3n busca negociar los siguientes objetivos principales en el Congreso:<\/p><ol><li>Ciudadan\u00eda para los Dreamers: S\u00e1nchez reconoce que este tema es complejo en las negociaciones pol\u00edticas, pero considera esencial avanzar<\/li><li>Protecci\u00f3n para los trabajadores esenciales: S\u00e1nchez enfatiza que deportar a los trabajadores indocumentados, como empleados agr\u00edcolas y de restaurantes, tendr\u00eda un impacto negativo en la econom\u00eda<\/li><li>Estatus para c\u00f3nyuges de ciudadanos: S\u00e1nchez aboga especialmente por las familias con estatus mixto.<\/li><\/ol><p>Por su parte, George Carrillo, presidente de la C\u00e1mara Hispana de la Construcci\u00f3n, y tambi\u00e9n miembro del Comit\u00e9 100, explica que las deportaciones masivas podr\u00edan provocar una escasez de trabajadores. Carrillo, hijo de padres ecuatorianos, menciona que abrir un camino a la ciudadan\u00eda para cientos migrantes es posible y cree que as\u00ed contribuir\u00edan m\u00e1s a la econom\u00eda del pa\u00eds, como han reportado diversas organizaciones. Por ejemplo, el American Immigration Council (AIC) public\u00f3 un informe que detalla la importancia de los trabajadores inmigrantes en el sector agr\u00edcola y de la construcci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-547fab44 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"547fab44\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d0c1c70\" data-id=\"6d0c1c70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1aca2c9a elementor-widget elementor-widget-toggle\" data-id=\"1aca2c9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4491\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-4491\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-4491\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-4491\"><p><strong>UNIVISI\u00d3N<\/strong><\/p><p><a href=\"https:\/\/www.univision.com\/noticias\/inmigracion\/empresarios-evitar-deportaciones-dreamers-trabajadores-esenciales\">https:\/\/www.univision.com\/noticias\/inmigracion\/empresarios-evitar-deportaciones-dreamers-trabajadores-esenciales<\/a><\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Samuel S\u00e1nchez, due\u00f1o de restaurantes en Chicago, lidera esfuerzos para buscar soluciones migratorias de sentido com\u00fan en Estados Unidos. Samuel S\u00e1nchez, hijo de un inmigrante mexicano deportado cuando \u00e9l ten\u00eda 14 a\u00f1os, ha convertido su historia familiar en una lucha por un camino hacia la ciudadan\u00eda para los Dreamers y los trabajadores esenciales en Estados Unidos. Como miembro del Comit\u00e9 de 100, una coalici\u00f3n de empresarios latinos, S\u00e1nchez busca soluciones migratorias que protejan a quienes han contribuido al desarrollo econ\u00f3mico del pa\u00eds. Samuel S\u00e1nchez creci\u00f3 en Texas mientras su padre trabajaba en los campos de algod\u00f3n hasta ser deportado. A\u00f1os despu\u00e9s, su padre regres\u00f3 con una visa de trabajo, dejando una marca en la perspectiva de S\u00e1nchez sobre la inmigraci\u00f3n. Ahora, como due\u00f1o de siete restaurantes en Chicago, utiliza su posici\u00f3n para abogar por quienes est\u00e1n en riesgo de deportaci\u00f3n. Foto: La Opini\u00f3n | Rebecca Blackwell | AP \u201cMucha gente que est\u00e1 aqu\u00ed merece una oportunidad. No pueden ver m\u00e1s all\u00e1 porque est\u00e1n encerrados en un estado\u201d, expres\u00f3 S\u00e1nchez en entrevista con Univisi\u00f3n. Tambi\u00e9n destac\u00f3 la importancia de proteger a quienes han vivido a\u00f1os en Estados Unidos sin una situaci\u00f3n migratoria regular: \u201cEs importante que salgamos a luchar por aquellos que corren riesgo de deportaci\u00f3n y son los que tienen a\u00f1os de estar aqu\u00ed\u201d. El Comit\u00e9 de 100, al que S\u00e1nchez pertenece, re\u00fane a empresarios latinos de diversos sectores, como la restauraci\u00f3n, la construcci\u00f3n y la hoteler\u00eda. Su objetivo es proponer lo que ellos denominan \u201csoluciones migratorias de sentido com\u00fan\u201d que beneficien tanto a los inmigrantes como a la econom\u00eda estadounidense. En este sentido, la coalici\u00f3n busca negociar los siguientes objetivos principales en el Congreso: Ciudadan\u00eda para los Dreamers: S\u00e1nchez reconoce que este tema es complejo en las negociaciones pol\u00edticas, pero considera esencial avanzar Protecci\u00f3n para los trabajadores esenciales: S\u00e1nchez enfatiza que deportar a los trabajadores indocumentados, como empleados agr\u00edcolas y de restaurantes, tendr\u00eda un impacto negativo en la econom\u00eda Estatus para c\u00f3nyuges de ciudadanos: S\u00e1nchez aboga especialmente por las familias con estatus mixto. Por su parte, George Carrillo, presidente de la C\u00e1mara Hispana de la Construcci\u00f3n, y tambi\u00e9n miembro del Comit\u00e9 100, explica que las deportaciones masivas podr\u00edan provocar una escasez de trabajadores. Carrillo, hijo de padres ecuatorianos, menciona que abrir un camino a la ciudadan\u00eda para cientos migrantes es posible y cree que as\u00ed contribuir\u00edan m\u00e1s a la econom\u00eda del pa\u00eds, como han reportado diversas organizaciones. Por ejemplo, el American Immigration Council (AIC) public\u00f3 un informe que detalla la importancia de los trabajadores inmigrantes en el sector agr\u00edcola y de la construcci\u00f3n. BIBLIOGRAF\u00cdA UNIVISI\u00d3N https:\/\/www.univision.com\/noticias\/inmigracion\/empresarios-evitar-deportaciones-dreamers-trabajadores-esenciales \u00a0<\/p>","protected":false},"author":13,"featured_media":58948,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[3432,10],"tags":[2306,61,3466,443,3465],"class_list":["post-58946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacada","category-noticias","tag-camino-a-la-ciudadania","tag-dreamers","tag-empresarios-latinos","tag-indocumentados","tag-trabajadores-esenciales"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Samuel S\u00e1nchez, due\u00f1o de restaurantes en Chicago, lidera esfuerzos para buscar soluciones migratorias de sentido com\u00fan en Estados Unidos. Samuel S\u00e1nchez, hijo de un inmigrante mexicano deportado cuando \u00e9l ten\u00eda 14 a\u00f1os, ha convertido su historia familiar en una lucha por un camino hacia la ciudadan\u00eda para los Dreamers y los trabajadores esenciales en Estados\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Noticias\"\/>\n\t<meta name=\"google-site-verification\" content=\"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE\" \/>\n\t<meta name=\"keywords\" content=\"camino a la ciudadan\u00eda,dreamers,empresarios latinos,indocumentados,trabajadores esenciales,noticia destacada,noticias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales\" \/>\n\t\t<meta property=\"og:description\" content=\"Samuel S\u00e1nchez, due\u00f1o de restaurantes en Chicago, lidera esfuerzos para buscar soluciones migratorias de sentido com\u00fan en Estados Unidos. Samuel S\u00e1nchez, hijo de un inmigrante mexicano deportado cuando \u00e9l ten\u00eda 14 a\u00f1os, ha convertido su historia familiar en una lucha por un camino hacia la ciudadan\u00eda para los Dreamers y los trabajadores esenciales en Estados\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-01-29T16:18:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-01-29T16:29:27+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Samuel S\u00e1nchez, due\u00f1o de restaurantes en Chicago, lidera esfuerzos para buscar soluciones migratorias de sentido com\u00fan en Estados Unidos. Samuel S\u00e1nchez, hijo de un inmigrante mexicano deportado cuando \u00e9l ten\u00eda 14 a\u00f1os, ha convertido su historia familiar en una lucha por un camino hacia la ciudadan\u00eda para los Dreamers y los trabajadores esenciales en Estados\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#blogposting\",\"name\":\"Empresarios latinos abogan por un camino a la ciudadan\\u00eda para Dreamers y trabajadores esenciales\",\"headline\":\"Empresarios latinos abogan por un camino a la ciudadan\\u00eda para Dreamers y trabajadores esenciales\",\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png\",\"width\":1316,\"height\":740,\"caption\":\"El 30% de los trabajadores agri\\u0301colas de EE.UU. son mexicanos inmigrantes. Cre\\u0301dito- Rebecca Blackwell | AP\"},\"datePublished\":\"2025-01-29T10:18:45-06:00\",\"dateModified\":\"2025-01-29T10:29:27-06:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#webpage\"},\"articleSection\":\"Noticia Destacada, Noticias, Camino a la ciudadan\\u00eda, Dreamers, Empresarios latinos, Indocumentados, Trabajadores esenciales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#listItem\",\"name\":\"Empresarios latinos abogan por un camino a la ciudadan\\u00eda para Dreamers y trabajadores esenciales\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#listItem\",\"position\":3,\"name\":\"Empresarios latinos abogan por un camino a la ciudadan\\u00eda para Dreamers y trabajadores esenciales\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#organizationLogo\",\"width\":240,\"height\":40},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/\",\"name\":\"Noticias\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#webpage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/\",\"name\":\"Empresarios latinos abogan por un camino a la ciudadan\\u00eda para Dreamers y trabajadores esenciales\",\"description\":\"Samuel S\\u00e1nchez, due\\u00f1o de restaurantes en Chicago, lidera esfuerzos para buscar soluciones migratorias de sentido com\\u00fan en Estados Unidos. Samuel S\\u00e1nchez, hijo de un inmigrante mexicano deportado cuando \\u00e9l ten\\u00eda 14 a\\u00f1os, ha convertido su historia familiar en una lucha por un camino hacia la ciudadan\\u00eda para los Dreamers y los trabajadores esenciales en Estados\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#mainImage\",\"width\":1316,\"height\":740,\"caption\":\"El 30% de los trabajadores agri\\u0301colas de EE.UU. son mexicanos inmigrantes. Cre\\u0301dito- Rebecca Blackwell | AP\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#mainImage\"},\"datePublished\":\"2025-01-29T10:18:45-06:00\",\"dateModified\":\"2025-01-29T10:29:27-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales","description":"Samuel S\u00e1nchez, due\u00f1o de restaurantes en Chicago, lidera esfuerzos para buscar soluciones migratorias de sentido com\u00fan en Estados Unidos. Samuel S\u00e1nchez, hijo de un inmigrante mexicano deportado cuando \u00e9l ten\u00eda 14 a\u00f1os, ha convertido su historia familiar en una lucha por un camino hacia la ciudadan\u00eda para los Dreamers y los trabajadores esenciales en Estados","canonical_url":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/","robots":"max-image-preview:large","keywords":"camino a la ciudadan\u00eda,dreamers,empresarios latinos,indocumentados,trabajadores esenciales,noticia destacada,noticias","webmasterTools":{"google-site-verification":"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#blogposting","name":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales","headline":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales","author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png","width":1316,"height":740,"caption":"El 30% de los trabajadores agri\u0301colas de EE.UU. son mexicanos inmigrantes. Cre\u0301dito- Rebecca Blackwell | AP"},"datePublished":"2025-01-29T10:18:45-06:00","dateModified":"2025-01-29T10:29:27-06:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#webpage"},"isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#webpage"},"articleSection":"Noticia Destacada, Noticias, Camino a la ciudadan\u00eda, Dreamers, Empresarios latinos, Indocumentados, Trabajadores esenciales"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","position":1,"name":"Home","item":"https:\/\/accesolatino.org\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/en\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#listItem","name":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales"},"previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#listItem","position":3,"name":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales","previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/en\/#organization","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#organizationLogo","width":240,"height":40},"image":{"@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author","url":"https:\/\/accesolatino.org\/en\/author\/noticias\/","name":"Noticias"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#webpage","url":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/","name":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales","description":"Samuel S\u00e1nchez, due\u00f1o de restaurantes en Chicago, lidera esfuerzos para buscar soluciones migratorias de sentido com\u00fan en Estados Unidos. Samuel S\u00e1nchez, hijo de un inmigrante mexicano deportado cuando \u00e9l ten\u00eda 14 a\u00f1os, ha convertido su historia familiar en una lucha por un camino hacia la ciudadan\u00eda para los Dreamers y los trabajadores esenciales en Estados","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#breadcrumblist"},"author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"creator":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png","@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#mainImage","width":1316,"height":740,"caption":"El 30% de los trabajadores agri\u0301colas de EE.UU. son mexicanos inmigrantes. Cre\u0301dito- Rebecca Blackwell | AP"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#mainImage"},"datePublished":"2025-01-29T10:18:45-06:00","dateModified":"2025-01-29T10:29:27-06:00"},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/en\/#website","url":"https:\/\/accesolatino.org\/en\/","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","inLanguage":"en-US","publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim","og:type":"article","og:title":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales","og:description":"Samuel S\u00e1nchez, due\u00f1o de restaurantes en Chicago, lidera esfuerzos para buscar soluciones migratorias de sentido com\u00fan en Estados Unidos. Samuel S\u00e1nchez, hijo de un inmigrante mexicano deportado cuando \u00e9l ten\u00eda 14 a\u00f1os, ha convertido su historia familiar en una lucha por un camino hacia la ciudadan\u00eda para los Dreamers y los trabajadores esenciales en Estados","og:url":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/","article:published_time":"2025-01-29T16:18:45+00:00","article:modified_time":"2025-01-29T16:29:27+00:00","twitter:card":"summary_large_image","twitter:title":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales","twitter:description":"Samuel S\u00e1nchez, due\u00f1o de restaurantes en Chicago, lidera esfuerzos para buscar soluciones migratorias de sentido com\u00fan en Estados Unidos. Samuel S\u00e1nchez, hijo de un inmigrante mexicano deportado cuando \u00e9l ten\u00eda 14 a\u00f1os, ha convertido su historia familiar en una lucha por un camino hacia la ciudadan\u00eda para los Dreamers y los trabajadores esenciales en Estados"},"aioseo_meta_data":{"post_id":"58946","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-01-29 16:18:45","updated":"2025-06-06 09:28:40","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEmpresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/accesolatino.org\/en"},{"label":"Noticias","link":"https:\/\/accesolatino.org\/en\/category\/noticias\/"},{"label":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales","link":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales<\/title>\n<meta name=\"description\" content=\"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y protecciones para trabajadores esenciales indocumentados.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y protecciones para trabajadores esenciales indocumentados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-29T16:18:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-29T16:29:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1316\" \/>\n\t<meta property=\"og:image:height\" content=\"740\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\"},\"headline\":\"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales\",\"datePublished\":\"2025-01-29T16:18:45+00:00\",\"dateModified\":\"2025-01-29T16:29:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/\"},\"wordCount\":504,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png\",\"keywords\":[\"Camino a la ciudadan\u00eda\",\"Dreamers\",\"Empresarios latinos\",\"Indocumentados\",\"Trabajadores esenciales\"],\"articleSection\":[\"Noticia Destacada\",\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/\",\"name\":\"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png\",\"datePublished\":\"2025-01-29T16:18:45+00:00\",\"dateModified\":\"2025-01-29T16:29:27+00:00\",\"description\":\"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y protecciones para trabajadores esenciales indocumentados.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png\",\"width\":1316,\"height\":740,\"caption\":\"El 30% de los trabajadores agri\u0301colas de EE.UU. son mexicanos inmigrantes. Cre\u0301dito- Rebecca Blackwell | AP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\\\/destacada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticia Destacada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/destacada\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales","description":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y protecciones para trabajadores esenciales indocumentados.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/","og_locale":"en_US","og_type":"article","og_title":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales | Acceso Latino","og_description":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y protecciones para trabajadores esenciales indocumentados.","og_url":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-01-29T16:18:45+00:00","article_modified_time":"2025-01-29T16:29:27+00:00","og_image":[{"width":1316,"height":740,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905"},"headline":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales","datePublished":"2025-01-29T16:18:45+00:00","dateModified":"2025-01-29T16:29:27+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/"},"wordCount":504,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png","keywords":["Camino a la ciudadan\u00eda","Dreamers","Empresarios latinos","Indocumentados","Trabajadores esenciales"],"articleSection":["Noticia Destacada","Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/","url":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/","name":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png","datePublished":"2025-01-29T16:18:45+00:00","dateModified":"2025-01-29T16:29:27+00:00","description":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y protecciones para trabajadores esenciales indocumentados.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/El-30-de-los-trabajadores-agricolas-de-EE.UU_.-son-mexicanos-inmigrantes.-Credito-Rebecca-Blackwell-AP.png","width":1316,"height":740,"caption":"El 30% de los trabajadores agri\u0301colas de EE.UU. son mexicanos inmigrantes. Cre\u0301dito- Rebecca Blackwell | AP"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/empresarios-latinos-abogan-por-un-camino-a-la-ciudadania-para-dreamers-y-trabajadores-esenciales\/destacada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticia Destacada","item":"https:\/\/accesolatino.org\/category\/destacada\/"},{"@type":"ListItem","position":3,"name":"Empresarios latinos abogan por un camino a la ciudadan\u00eda para Dreamers y trabajadores esenciales"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/58946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=58946"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/58946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/58948"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=58946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=58946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=58946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}