{"id":57995,"date":"2025-01-16T08:35:00","date_gmt":"2025-01-16T14:35:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=57995"},"modified":"2025-01-16T19:27:01","modified_gmt":"2025-01-17T01:27:01","slug":"dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/","title":{"rendered":"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"57995\" class=\"elementor elementor-57995\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e21bab7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6e21bab7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6254eca1\" data-id=\"6254eca1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71919bc8 elementor-widget elementor-widget-heading\" data-id=\"71919bc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Esta nueva medida beneficiar\u00eda a unos 600 mil venezolanos elegibles en Estados Unidos.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-924f8f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"924f8f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-360226a2\" data-id=\"360226a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32a7c658 elementor-widget elementor-widget-text-editor\" data-id=\"32a7c658\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Departamento de Seguridad Nacional (DHS) anunci\u00f3 la extensi\u00f3n del Estatus de Protecci\u00f3n Temporal (TPS) para ciudadanos venezolanos por un per\u00edodo de 18 meses, desde el 3 de abril de 2025 hasta el 2 de octubre de 2026. Esta decisi\u00f3n responde a las condiciones extraordinarias y temporales que hacen inseguro el retorno de estas personas a su pa\u00eds de origen debido a la crisis humanitaria en Venezuela.<\/p><p>El TPS para Venezuela fue extendido tras una evaluaci\u00f3n detallada de la situaci\u00f3n en el pa\u00eds sudamericano, que enfrenta una grave emergencia humanitaria ocasionada por la crisis pol\u00edtica y econ\u00f3mica. Factores como el acceso limitado a alimentos, medicamentos, servicios de salud, agua potable, electricidad y combustibles, adem\u00e1s de altos niveles de violencia, respaldaron esta decisi\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b6aa642 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6b6aa642\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-28c111e4\" data-id=\"28c111e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52e57207 elementor-widget elementor-widget-image\" data-id=\"52e57207\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"553\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela.png\" class=\"attachment-full size-full wp-image-57996\" alt=\"DHS extiende el Estatus de Proteccio\u0301n Temporal para Venezuela\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela.png 553w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela-18x9.png 18w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1988ba4a\" data-id=\"1988ba4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52cd1e12 elementor-widget elementor-widget-text-editor\" data-id=\"52cd1e12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La medida permitir\u00e1 a venezolanos que hayan residido continuamente en Estados Unidos hasta el 31 de julio de 2023, mantener su TPS y su documento de autorizaci\u00f3n de empleo (EAD), siempre que cumplan con los requisitos de elegibilidad y se vuelvan a registrar en el per\u00edodo establecido. Sin embargo, aquellos que ingresaron al pa\u00eds despu\u00e9s de esa fecha o no lo hicieron mediante un proceso legal, no son elegibles para este beneficio y estar\u00e1n sujetos a medidas de cumplimiento de las leyes de inmigraci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53d7fcb0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"53d7fcb0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d58a299\" data-id=\"5d58a299\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16722c79 elementor-widget elementor-widget-text-editor\" data-id=\"16722c79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El DHS anunci\u00f3 que todos los beneficiarios pasan por un proceso de evaluaci\u00f3n de seguridad nacional y p\u00fablica durante su solicitud inicial y en la reinscripci\u00f3n. Aquellos que representen una amenaza o tengan antecedentes criminales significativos no podr\u00e1n acceder al TPS y podr\u00edan enfrentar detenci\u00f3n o deportaci\u00f3n.<\/p><p>Asimismo, la extensi\u00f3n tambi\u00e9n garantiza la validez autom\u00e1tica de ciertos EAD hasta el 2 de abril de 2026, para asegurar la continuidad laboral mientras se procesan las renovaciones.<\/p><p>Con esta extensi\u00f3n, cerca de 600 mil venezolanos elegibles en Estados Unidos podr\u00e1n mantener su protecci\u00f3n temporal y permisos de trabajo. El DHS hizo un llamado a los beneficiarios actuales a volver a registrarse dentro del per\u00edodo que se establecer\u00e1 en el pr\u00f3ximo aviso del Registro Federal, asegurando que puedan seguir benefici\u00e1ndose de este programa y mantener la protecci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74f14980 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"74f14980\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79367de4\" data-id=\"79367de4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe0b863 elementor-widget elementor-widget-toggle\" data-id=\"fe0b863\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2661\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2661\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2661\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2661\"><p><strong>DHS<\/strong><\/p><p><a href=\"https:\/\/www.dhs.gov\/news\/2025\/01\/10\/dhs-extend-temporary-protected-status-venezuela\">https:\/\/www.dhs.gov\/news\/2025\/01\/10\/dhs-extend-temporary-protected-status-venezuela<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Esta nueva medida beneficiar\u00eda a unos 600 mil venezolanos elegibles en Estados Unidos. El Departamento de Seguridad Nacional (DHS) anunci\u00f3 la extensi\u00f3n del Estatus de Protecci\u00f3n Temporal (TPS) para ciudadanos venezolanos por un per\u00edodo de 18 meses, desde el 3 de abril de 2025 hasta el 2 de octubre de 2026. Esta decisi\u00f3n responde a las condiciones extraordinarias y temporales que hacen inseguro el retorno de estas personas a su pa\u00eds de origen debido a la crisis humanitaria en Venezuela. El TPS para Venezuela fue extendido tras una evaluaci\u00f3n detallada de la situaci\u00f3n en el pa\u00eds sudamericano, que enfrenta una grave emergencia humanitaria ocasionada por la crisis pol\u00edtica y econ\u00f3mica. Factores como el acceso limitado a alimentos, medicamentos, servicios de salud, agua potable, electricidad y combustibles, adem\u00e1s de altos niveles de violencia, respaldaron esta decisi\u00f3n. La medida permitir\u00e1 a venezolanos que hayan residido continuamente en Estados Unidos hasta el 31 de julio de 2023, mantener su TPS y su documento de autorizaci\u00f3n de empleo (EAD), siempre que cumplan con los requisitos de elegibilidad y se vuelvan a registrar en el per\u00edodo establecido. Sin embargo, aquellos que ingresaron al pa\u00eds despu\u00e9s de esa fecha o no lo hicieron mediante un proceso legal, no son elegibles para este beneficio y estar\u00e1n sujetos a medidas de cumplimiento de las leyes de inmigraci\u00f3n. El DHS anunci\u00f3 que todos los beneficiarios pasan por un proceso de evaluaci\u00f3n de seguridad nacional y p\u00fablica durante su solicitud inicial y en la reinscripci\u00f3n. Aquellos que representen una amenaza o tengan antecedentes criminales significativos no podr\u00e1n acceder al TPS y podr\u00edan enfrentar detenci\u00f3n o deportaci\u00f3n. Asimismo, la extensi\u00f3n tambi\u00e9n garantiza la validez autom\u00e1tica de ciertos EAD hasta el 2 de abril de 2026, para asegurar la continuidad laboral mientras se procesan las renovaciones. Con esta extensi\u00f3n, cerca de 600 mil venezolanos elegibles en Estados Unidos podr\u00e1n mantener su protecci\u00f3n temporal y permisos de trabajo. El DHS hizo un llamado a los beneficiarios actuales a volver a registrarse dentro del per\u00edodo que se establecer\u00e1 en el pr\u00f3ximo aviso del Registro Federal, asegurando que puedan seguir benefici\u00e1ndose de este programa y mantener la protecci\u00f3n. BIBLIOGRAF\u00cdA DHS https:\/\/www.dhs.gov\/news\/2025\/01\/10\/dhs-extend-temporary-protected-status-venezuela<\/p>","protected":false},"author":13,"featured_media":57996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[3432],"tags":[283,1010,315,80,3431],"class_list":["post-57995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacada","tag-dhs","tag-ead","tag-estatus-de-proteccion-temporal","tag-tps","tag-venezuela"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela<\/title>\n<meta name=\"description\" content=\"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela y permitir\u00e1 a miles de venezolanos trabajar y evitar la deportaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela\" \/>\n<meta property=\"og:description\" content=\"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela y permitir\u00e1 a miles de venezolanos trabajar y evitar la deportaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-16T14:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-17T01:27:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\\\/destacada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\\\/destacada\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\"},\"headline\":\"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela\",\"datePublished\":\"2025-01-16T14:35:00+00:00\",\"dateModified\":\"2025-01-17T01:27:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\\\/destacada\\\/\"},\"wordCount\":397,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\\\/destacada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela.png\",\"keywords\":[\"DHS\",\"EAD\",\"Estatus de Protecci\u00f3n Temporal\",\"TPS\",\"Venezuela\"],\"articleSection\":[\"Noticia Destacada\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\\\/destacada\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\\\/destacada\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\\\/destacada\\\/\",\"name\":\"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\\\/destacada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\\\/destacada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela.png\",\"datePublished\":\"2025-01-16T14:35:00+00:00\",\"dateModified\":\"2025-01-17T01:27:01+00:00\",\"description\":\"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela y permitir\u00e1 a miles de venezolanos trabajar y evitar la deportaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\\\/destacada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\\\/destacada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\\\/destacada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela.png\",\"width\":553,\"height\":267,\"caption\":\"DHS extiende el Estatus de Proteccio\u0301n Temporal para Venezuela\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\\\/destacada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela","description":"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela y permitir\u00e1 a miles de venezolanos trabajar y evitar la deportaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/","og_locale":"en_US","og_type":"article","og_title":"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela","og_description":"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela y permitir\u00e1 a miles de venezolanos trabajar y evitar la deportaci\u00f3n.","og_url":"https:\/\/accesolatino.org\/en\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-01-16T14:35:00+00:00","article_modified_time":"2025-01-17T01:27:01+00:00","og_image":[{"width":553,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b"},"headline":"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela","datePublished":"2025-01-16T14:35:00+00:00","dateModified":"2025-01-17T01:27:01+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/"},"wordCount":397,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela.png","keywords":["DHS","EAD","Estatus de Protecci\u00f3n Temporal","TPS","Venezuela"],"articleSection":["Noticia Destacada"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/","url":"https:\/\/accesolatino.org\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/","name":"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela.png","datePublished":"2025-01-16T14:35:00+00:00","dateModified":"2025-01-17T01:27:01+00:00","description":"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela y permitir\u00e1 a miles de venezolanos trabajar y evitar la deportaci\u00f3n.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/DHS-extiende-el-Estatus-de-Proteccion-Temporal-para-Venezuela.png","width":553,"height":267,"caption":"DHS extiende el Estatus de Proteccio\u0301n Temporal para Venezuela"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/dhs-extiende-el-estatus-de-proteccion-temporal-para-venezuela\/destacada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"DHS extiende el Estatus de Protecci\u00f3n Temporal para Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/57995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=57995"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/57995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/57996"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=57995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=57995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=57995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}