{"id":57409,"date":"2025-01-02T10:23:36","date_gmt":"2025-01-02T16:23:36","guid":{"rendered":"https:\/\/accesolatino.org\/?p=57409"},"modified":"2025-01-02T10:38:01","modified_gmt":"2025-01-02T16:38:01","slug":"nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/","title":{"rendered":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"57409\" class=\"elementor elementor-57409\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-690b2096 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"690b2096\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-544596f\" data-id=\"544596f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19ff7d3 elementor-widget elementor-widget-heading\" data-id=\"19ff7d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ciertos trabajadores inmigrantes con permiso de trabajo vencido podr\u00e1n seguir trabajando mientras esperan el proceso de renovaci\u00f3n. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e6f422f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1e6f422f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-349290d7\" data-id=\"349290d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ebc33b0 elementor-widget elementor-widget-text-editor\" data-id=\"6ebc33b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n (USCIS) y el Departamento de Seguridad Nacional (DHS), publicaron una nueva regla que detalla el incremento del periodo de extensi\u00f3n autom\u00e1tica para ciertos trabajadores inmigrantes. La norma final modifica los reglamentos del DHS para aumentar de forma permanente el per\u00edodo de extensi\u00f3n autom\u00e1tica de la autorizaci\u00f3n de empleo que expira y\/o Documentos de Autorizaci\u00f3n de Empleo (EA) para ciertos solicitantes de renovaci\u00f3n que han presentado a tiempo el Formulario I-765, Solicitud de Autorizaci\u00f3n de Empleo, de hasta 180 d\u00edas a hasta 540 d\u00edas.<\/p><p>Luego de dos normas temporales, el DHS finalmente increment\u00f3 esta extensi\u00f3n autom\u00e1tica de manera permanente para prevenir que los solicitantes elegibles de renovaci\u00f3n EAD experimenten un lapso en la autorizaci\u00f3n de empleo y\/o la validez de su EAD como resultado de los largos tiempos de procesamiento de USCIS.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6be9617c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6be9617c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-37da817a\" data-id=\"37da817a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c4d0153 elementor-widget elementor-widget-image\" data-id=\"4c4d0153\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"552\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/extensiondepermisodetrabajo.png\" class=\"attachment-full size-full wp-image-57411\" alt=\"extensi\u00f3n de permiso de trabajo\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/extensiondepermisodetrabajo.png 552w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/extensiondepermisodetrabajo-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/extensiondepermisodetrabajo-18x9.png 18w\" sizes=\"(max-width: 552px) 100vw, 552px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5a618b34\" data-id=\"5a618b34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-234f429b elementor-widget elementor-widget-text-editor\" data-id=\"234f429b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esta regla fue publicada el 13 de diciembre de 2024, y ser\u00e1 efectiva 30 d\u00edas despu\u00e9s de publicaci\u00f3n em el Registro Federal, es decir el 13 de enero de 2024. De esta manera, gracias a esta regla final, los inmigrantes con permiso de trabajo expirado podr\u00e1n continuar trabajando 18 meses mientras esperan por la renovaci\u00f3n de su permiso.\u00a0 Los aplicantes que presentaron su renovaci\u00f3n de EAD el 4 de mayo de 2022 o antes son elegibles por esta nueva regla.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28e704bd elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"28e704bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b3b3b0a\" data-id=\"6b3b3b0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ce0db4e elementor-widget elementor-widget-text-editor\" data-id=\"3ce0db4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cDesde enero de 2021, la econom\u00eda estadounidense ha creado m\u00e1s de 16 millones de puestos de trabajo, y el DHS se ha comprometido a ayudar a las empresas a cubrirlos\u201d, expres\u00f3 el secretario de Seguridad Nacional, Alejandro N. Mayorkas. \u201cAumentar el per\u00edodo de extensi\u00f3n autom\u00e1tica para ciertos documentos de autorizaci\u00f3n de empleo ayudar\u00e1 a eliminar la burocracia que agobia a los empleadores, asegurar\u00e1 que cientos de miles de personas elegibles para el empleo puedan seguir contribuyendo a nuestras comunidades y fortalecer\u00e1 a\u00fan m\u00e1s la robusta econom\u00eda de nuestra naci\u00f3n\u201d, agreg\u00f3.<\/p><p>Esta no es la \u00fanica medida realizada por el gobierno estadounidense para apoyar a las capacidades de los trabajadores inmigrantes. Para reducir los tiempos de procesamiento de EAD, han reducido los plazos de tr\u00e1mite de solicitudes de EAD para solicitantes de asilo y ciertas personas en libertad condicional. Asimismo, han ampliado la presentaci\u00f3n en l\u00ednea de las solicitudes de EAD a solicitantes de asilo. De esta manera, USCIS ha logrado reducir los tiempos de procesamiento de EAD para personas con solitudes pendientes de ajuste de estatus desde el A\u00f1o Fiscal 2021 a la fecha.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a723d92 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5a723d92\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-207d56c\" data-id=\"207d56c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4817f8cb elementor-widget elementor-widget-toggle\" data-id=\"4817f8cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1201\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1201\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1201\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1201\"><p><strong>PUBLIC INSPECTION<\/strong><\/p><p><a href=\"https:\/\/public-inspection.federalregister.gov\/2024-28584.pdf\">https:\/\/public-inspection.federalregister.gov\/2024-28584.pdf<\/a><\/p><p><strong>DHS<\/strong><\/p><p><a href=\"https:\/\/www.dhs.gov\/news\/2024\/12\/10\/dhs-announces-permanent-increase-automatic-extension-period-certain-employment\">https:\/\/www.dhs.gov\/news\/2024\/12\/10\/dhs-announces-permanent-increase-automatic-extension-period-certain-employment<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ciertos trabajadores inmigrantes con permiso de trabajo vencido podr\u00e1n seguir trabajando mientras esperan el proceso de renovaci\u00f3n. El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n (USCIS) y el Departamento de Seguridad Nacional (DHS), publicaron una nueva regla que detalla el incremento del periodo de extensi\u00f3n autom\u00e1tica para ciertos trabajadores inmigrantes. La norma final modifica los reglamentos del DHS para aumentar de forma permanente el per\u00edodo de extensi\u00f3n autom\u00e1tica de la autorizaci\u00f3n de empleo que expira y\/o Documentos de Autorizaci\u00f3n de Empleo (EA) para ciertos solicitantes de renovaci\u00f3n que han presentado a tiempo el Formulario I-765, Solicitud de Autorizaci\u00f3n de Empleo, de hasta 180 d\u00edas a hasta 540 d\u00edas. Luego de dos normas temporales, el DHS finalmente increment\u00f3 esta extensi\u00f3n autom\u00e1tica de manera permanente para prevenir que los solicitantes elegibles de renovaci\u00f3n EAD experimenten un lapso en la autorizaci\u00f3n de empleo y\/o la validez de su EAD como resultado de los largos tiempos de procesamiento de USCIS. Esta regla fue publicada el 13 de diciembre de 2024, y ser\u00e1 efectiva 30 d\u00edas despu\u00e9s de publicaci\u00f3n em el Registro Federal, es decir el 13 de enero de 2024. De esta manera, gracias a esta regla final, los inmigrantes con permiso de trabajo expirado podr\u00e1n continuar trabajando 18 meses mientras esperan por la renovaci\u00f3n de su permiso.\u00a0 Los aplicantes que presentaron su renovaci\u00f3n de EAD el 4 de mayo de 2022 o antes son elegibles por esta nueva regla. \u201cDesde enero de 2021, la econom\u00eda estadounidense ha creado m\u00e1s de 16 millones de puestos de trabajo, y el DHS se ha comprometido a ayudar a las empresas a cubrirlos\u201d, expres\u00f3 el secretario de Seguridad Nacional, Alejandro N. Mayorkas. \u201cAumentar el per\u00edodo de extensi\u00f3n autom\u00e1tica para ciertos documentos de autorizaci\u00f3n de empleo ayudar\u00e1 a eliminar la burocracia que agobia a los empleadores, asegurar\u00e1 que cientos de miles de personas elegibles para el empleo puedan seguir contribuyendo a nuestras comunidades y fortalecer\u00e1 a\u00fan m\u00e1s la robusta econom\u00eda de nuestra naci\u00f3n\u201d, agreg\u00f3. Esta no es la \u00fanica medida realizada por el gobierno estadounidense para apoyar a las capacidades de los trabajadores inmigrantes. Para reducir los tiempos de procesamiento de EAD, han reducido los plazos de tr\u00e1mite de solicitudes de EAD para solicitantes de asilo y ciertas personas en libertad condicional. Asimismo, han ampliado la presentaci\u00f3n en l\u00ednea de las solicitudes de EAD a solicitantes de asilo. De esta manera, USCIS ha logrado reducir los tiempos de procesamiento de EAD para personas con solitudes pendientes de ajuste de estatus desde el A\u00f1o Fiscal 2021 a la fecha. BIBLIOGRAF\u00cdA PUBLIC INSPECTION https:\/\/public-inspection.federalregister.gov\/2024-28584.pdf DHS https:\/\/www.dhs.gov\/news\/2024\/12\/10\/dhs-announces-permanent-increase-automatic-extension-period-certain-employment<\/p>","protected":false},"author":13,"featured_media":57411,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,12,1934],"tags":[3403,1010,3401,3402,1028],"class_list":["post-57409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-tramites","category-tramites-y-permisos","tag-18-meses","tag-ead","tag-extension-automatica","tag-nueva-regla","tag-trabajadores"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ciertos trabajadores inmigrantes con permiso de trabajo vencido podr\u00e1n seguir trabajando mientras esperan el proceso de renovaci\u00f3n. El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n (USCIS) y el Departamento de Seguridad Nacional (DHS), publicaron una nueva regla que detalla el incremento del periodo de extensi\u00f3n autom\u00e1tica para ciertos trabajadores inmigrantes. La norma final modifica los reglamentos del\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Noticias\"\/>\n\t<meta name=\"google-site-verification\" content=\"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE\" \/>\n\t<meta name=\"keywords\" content=\"18 meses,ead,extensi\u00f3n autom\u00e1tica,nueva regla,trabajadores,noticias,tr\u00e1mites,tr\u00e1mites y permisos\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes\" \/>\n\t\t<meta property=\"og:description\" content=\"Ciertos trabajadores inmigrantes con permiso de trabajo vencido podr\u00e1n seguir trabajando mientras esperan el proceso de renovaci\u00f3n. El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n (USCIS) y el Departamento de Seguridad Nacional (DHS), publicaron una nueva regla que detalla el incremento del periodo de extensi\u00f3n autom\u00e1tica para ciertos trabajadores inmigrantes. La norma final modifica los reglamentos del\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-01-02T16:23:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-01-02T16:38:01+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ciertos trabajadores inmigrantes con permiso de trabajo vencido podr\u00e1n seguir trabajando mientras esperan el proceso de renovaci\u00f3n. El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n (USCIS) y el Departamento de Seguridad Nacional (DHS), publicaron una nueva regla que detalla el incremento del periodo de extensi\u00f3n autom\u00e1tica para ciertos trabajadores inmigrantes. La norma final modifica los reglamentos del\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#blogposting\",\"name\":\"Nueva regla incrementa el periodo de extensi\\u00f3n autom\\u00e1tica para trabajadores inmigrantes\",\"headline\":\"Nueva regla incrementa el periodo de extensi\\u00f3n autom\\u00e1tica para trabajadores inmigrantes\",\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/extensiondepermisodetrabajo.png\",\"width\":552,\"height\":267,\"caption\":\"extensi\\u00f3n de permiso de trabajo\"},\"datePublished\":\"2025-01-02T10:23:36-06:00\",\"dateModified\":\"2025-01-02T10:38:01-06:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#webpage\"},\"articleSection\":\"Noticias, Tr\\u00e1mites, Tr\\u00e1mites y Permisos, 18 meses, EAD, Extensi\\u00f3n autom\\u00e1tica, Nueva regla, Trabajadores\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#listItem\",\"name\":\"Nueva regla incrementa el periodo de extensi\\u00f3n autom\\u00e1tica para trabajadores inmigrantes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#listItem\",\"position\":3,\"name\":\"Nueva regla incrementa el periodo de extensi\\u00f3n autom\\u00e1tica para trabajadores inmigrantes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#organizationLogo\",\"width\":240,\"height\":40},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/\",\"name\":\"Noticias\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#webpage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/\",\"name\":\"Nueva regla incrementa el periodo de extensi\\u00f3n autom\\u00e1tica para trabajadores inmigrantes\",\"description\":\"Ciertos trabajadores inmigrantes con permiso de trabajo vencido podr\\u00e1n seguir trabajando mientras esperan el proceso de renovaci\\u00f3n. El Servicio de Ciudadan\\u00eda e Inmigraci\\u00f3n (USCIS) y el Departamento de Seguridad Nacional (DHS), publicaron una nueva regla que detalla el incremento del periodo de extensi\\u00f3n autom\\u00e1tica para ciertos trabajadores inmigrantes. La norma final modifica los reglamentos del\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/extensiondepermisodetrabajo.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#mainImage\",\"width\":552,\"height\":267,\"caption\":\"extensi\\u00f3n de permiso de trabajo\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#mainImage\"},\"datePublished\":\"2025-01-02T10:23:36-06:00\",\"dateModified\":\"2025-01-02T10:38:01-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes","description":"Ciertos trabajadores inmigrantes con permiso de trabajo vencido podr\u00e1n seguir trabajando mientras esperan el proceso de renovaci\u00f3n. El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n (USCIS) y el Departamento de Seguridad Nacional (DHS), publicaron una nueva regla que detalla el incremento del periodo de extensi\u00f3n autom\u00e1tica para ciertos trabajadores inmigrantes. La norma final modifica los reglamentos del","canonical_url":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/","robots":"max-image-preview:large","keywords":"18 meses,ead,extensi\u00f3n autom\u00e1tica,nueva regla,trabajadores,noticias,tr\u00e1mites,tr\u00e1mites y permisos","webmasterTools":{"google-site-verification":"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#blogposting","name":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes","headline":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes","author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/extensiondepermisodetrabajo.png","width":552,"height":267,"caption":"extensi\u00f3n de permiso de trabajo"},"datePublished":"2025-01-02T10:23:36-06:00","dateModified":"2025-01-02T10:38:01-06:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#webpage"},"isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#webpage"},"articleSection":"Noticias, Tr\u00e1mites, Tr\u00e1mites y Permisos, 18 meses, EAD, Extensi\u00f3n autom\u00e1tica, Nueva regla, Trabajadores"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","position":1,"name":"Home","item":"https:\/\/accesolatino.org\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/en\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#listItem","name":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#listItem","position":3,"name":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes","previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/en\/#organization","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#organizationLogo","width":240,"height":40},"image":{"@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author","url":"https:\/\/accesolatino.org\/en\/author\/noticias\/","name":"Noticias"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#webpage","url":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/","name":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes","description":"Ciertos trabajadores inmigrantes con permiso de trabajo vencido podr\u00e1n seguir trabajando mientras esperan el proceso de renovaci\u00f3n. El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n (USCIS) y el Departamento de Seguridad Nacional (DHS), publicaron una nueva regla que detalla el incremento del periodo de extensi\u00f3n autom\u00e1tica para ciertos trabajadores inmigrantes. La norma final modifica los reglamentos del","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#breadcrumblist"},"author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"creator":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/extensiondepermisodetrabajo.png","@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#mainImage","width":552,"height":267,"caption":"extensi\u00f3n de permiso de trabajo"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#mainImage"},"datePublished":"2025-01-02T10:23:36-06:00","dateModified":"2025-01-02T10:38:01-06:00"},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/en\/#website","url":"https:\/\/accesolatino.org\/en\/","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","inLanguage":"en-US","publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim","og:type":"article","og:title":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes","og:description":"Ciertos trabajadores inmigrantes con permiso de trabajo vencido podr\u00e1n seguir trabajando mientras esperan el proceso de renovaci\u00f3n. El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n (USCIS) y el Departamento de Seguridad Nacional (DHS), publicaron una nueva regla que detalla el incremento del periodo de extensi\u00f3n autom\u00e1tica para ciertos trabajadores inmigrantes. La norma final modifica los reglamentos del","og:url":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/","article:published_time":"2025-01-02T16:23:36+00:00","article:modified_time":"2025-01-02T16:38:01+00:00","twitter:card":"summary_large_image","twitter:title":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes","twitter:description":"Ciertos trabajadores inmigrantes con permiso de trabajo vencido podr\u00e1n seguir trabajando mientras esperan el proceso de renovaci\u00f3n. El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n (USCIS) y el Departamento de Seguridad Nacional (DHS), publicaron una nueva regla que detalla el incremento del periodo de extensi\u00f3n autom\u00e1tica para ciertos trabajadores inmigrantes. La norma final modifica los reglamentos del"},"aioseo_meta_data":{"post_id":"57409","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-01-02 16:23:36","updated":"2025-06-06 09:24:40","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/accesolatino.org\/en"},{"label":"Noticias","link":"https:\/\/accesolatino.org\/en\/category\/noticias\/"},{"label":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes","link":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes<\/title>\n<meta name=\"description\" content=\"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes y podr\u00e1n trabajar hasta 18 meses con EAD vencido.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes y podr\u00e1n trabajar hasta 18 meses con EAD vencido.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-02T16:23:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-02T16:38:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/extensiondepermisodetrabajo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"552\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\"},\"headline\":\"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes\",\"datePublished\":\"2025-01-02T16:23:36+00:00\",\"dateModified\":\"2025-01-02T16:38:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/\"},\"wordCount\":476,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/extensiondepermisodetrabajo.png\",\"keywords\":[\"18 meses\",\"EAD\",\"Extensi\u00f3n autom\u00e1tica\",\"Nueva regla\",\"Trabajadores\"],\"articleSection\":[\"Noticias\",\"Tr\u00e1mites\",\"Tr\u00e1mites y Permisos\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/\",\"name\":\"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/extensiondepermisodetrabajo.png\",\"datePublished\":\"2025-01-02T16:23:36+00:00\",\"dateModified\":\"2025-01-02T16:38:01+00:00\",\"description\":\"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes y podr\u00e1n trabajar hasta 18 meses con EAD vencido.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/extensiondepermisodetrabajo.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/extensiondepermisodetrabajo.png\",\"width\":552,\"height\":267,\"caption\":\"extensi\u00f3n de permiso de trabajo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes","description":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes y podr\u00e1n trabajar hasta 18 meses con EAD vencido.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes | Acceso Latino","og_description":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes y podr\u00e1n trabajar hasta 18 meses con EAD vencido.","og_url":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2025-01-02T16:23:36+00:00","article_modified_time":"2025-01-02T16:38:01+00:00","og_image":[{"width":552,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/extensiondepermisodetrabajo.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905"},"headline":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes","datePublished":"2025-01-02T16:23:36+00:00","dateModified":"2025-01-02T16:38:01+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/"},"wordCount":476,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/extensiondepermisodetrabajo.png","keywords":["18 meses","EAD","Extensi\u00f3n autom\u00e1tica","Nueva regla","Trabajadores"],"articleSection":["Noticias","Tr\u00e1mites","Tr\u00e1mites y Permisos"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/","url":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/","name":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/extensiondepermisodetrabajo.png","datePublished":"2025-01-02T16:23:36+00:00","dateModified":"2025-01-02T16:38:01+00:00","description":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes y podr\u00e1n trabajar hasta 18 meses con EAD vencido.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/extensiondepermisodetrabajo.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2025\/01\/extensiondepermisodetrabajo.png","width":552,"height":267,"caption":"extensi\u00f3n de permiso de trabajo"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/nueva-regla-incrementa-el-periodo-de-extension-automatica-para-trabajadores-inmigrantes\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Nueva regla incrementa el periodo de extensi\u00f3n autom\u00e1tica para trabajadores inmigrantes"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/57409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=57409"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/57409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/57411"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=57409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=57409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=57409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}