{"id":56643,"date":"2024-11-29T05:24:00","date_gmt":"2024-11-29T11:24:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=56643"},"modified":"2024-11-28T17:42:52","modified_gmt":"2024-11-28T23:42:52","slug":"el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/","title":{"rendered":"El destacado trabajo de MALDEF por los inmigrantes latinos en Estados Unidos"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"56643\" class=\"elementor elementor-56643\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a9f07ba elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1a9f07ba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5fb037bd\" data-id=\"5fb037bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-246b3a9c elementor-widget elementor-widget-heading\" data-id=\"246b3a9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MALDEF es una de las organizaciones de defensa y representaci\u00f3n legal m\u00e1s importantes para la comunidad hispana en Estados Unidos.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f1f2109 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7f1f2109\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7aadeea5\" data-id=\"7aadeea5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ade0de4 elementor-widget elementor-widget-text-editor\" data-id=\"5ade0de4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Mexican American Legal Defense and Educational Fund o MALDEF es una organizaci\u00f3n sin fines de lucro dedicada a proteger los derechos civiles de los latinos en Estados Unidos. Fundada en 1968, MALDEF se centra en temas como la educaci\u00f3n, el empleo, los derechos de los inmigrantes y la participaci\u00f3n pol\u00edtica, a trav\u00e9s de litigios, promoci\u00f3n de pol\u00edticas p\u00fablicas y educaci\u00f3n p\u00fablica.<\/p><p>En este sentido, se trata de una organizaci\u00f3n especializada en la litigaci\u00f3n de derechos civiles, especialmente de los inmigrantes latinos. MALDEF se ha involucrado en importantes casos legales para proteger los derechos de los inmigrantes, luchando contra leyes discriminatorias y pr\u00e1cticas que afectan negativamente a las comunidades latinas. Han defendido a individuos y grupos en tribunales para asegurar que sus derechos sean respetados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77d5c779 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"77d5c779\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2da1908b\" data-id=\"2da1908b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76fb0e8 elementor-widget elementor-widget-image\" data-id=\"76fb0e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"552\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/MALDEF.png\" class=\"attachment-full size-full wp-image-56645\" alt=\"MALDEF\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/MALDEF.png 552w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/MALDEF-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/MALDEF-18x9.png 18w\" sizes=\"(max-width: 552px) 100vw, 552px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3a879624\" data-id=\"3a879624\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59505cef elementor-widget elementor-widget-text-editor\" data-id=\"59505cef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Actualmente, MALDEF representa a los beneficiarios de DACA y ha presentado recursos e impugnaciones en la <a href=\"https:\/\/accesolatino.org\/en\/daca\/como-avanza-el-caso-daca-en-la-corte-de-apelaciones-del-5o-distrito\/\">Corte de Apelaciones del Quinto Circuito<\/a>, para la defensa del programa. Uno de los argumentos dentro de la apelaci\u00f3n explica que los beneficiarios de DACA han construido sus vidas alrededor de su presencia en Estados Unidos, y la mayor\u00eda han desarrollado carreras profesionales en el pa\u00eds y han formado lazos en sus comunidades locales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-604a1eb6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"604a1eb6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-486dddf7\" data-id=\"486dddf7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7561e8ef elementor-widget elementor-widget-text-editor\" data-id=\"7561e8ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En este sentido, MALDEF tambi\u00e9n apoya los esfuerzos por aprobar una reforma migratoria. MALDEF aboga por pol\u00edticas de inmigraci\u00f3n que sean justas y humanitarias y adem\u00e1s miembros de la organizaci\u00f3n participan activamente en la promoci\u00f3n de cambios legislativos que permitan a los inmigrantes tener mejores oportunidades para regularizar su estatus.<\/p><p>Por otro lado, MALDEF tambi\u00e9n trabaja para garantizar la igualdad de acceso a la educaci\u00f3n, enfrent\u00e1ndose a pol\u00edticas que intentan limitar las oportunidades educativas para estudiantes inmigrantes o latinos. Han litigado casos relacionados con el acceso a la educaci\u00f3n superior y la financiaci\u00f3n equitativa de las escuelas p\u00fablicas.<\/p><p>De esta forma, MALDEF proporciona informaci\u00f3n legal y recursos educativos a la comunidad inmigrante, explicando sus derechos y las opciones legales disponibles. Tambi\u00e9n ofrecen talleres y programas educativos para empoderar a los inmigrantes y sus familias.<\/p><p>Para cada ciclo acad\u00e9mico MALDEF crea una gu\u00eda de recursos gratuita para estudiantes, padres y educadores, con una lista de becas disponibles que no requieren un estatus migratorio. Consulta el recurso para el ciclo 2025-2026 en el siguiente enlace: <a href=\"https:\/\/www.maldef.org\/resources\/scholarship-resource-guide-2025-2026\/\">https:\/\/www.maldef.org\/resources\/scholarship-resource-guide-2025-2026\/<\/a><\/p><p>Asimismo, la organizaci\u00f3n tambi\u00e9n trabaja por los derechos laborales. MALDEF apoya a trabajadores inmigrantes que enfrentan explotaci\u00f3n laboral, promoviendo condiciones de trabajo justas y asegurando que se respeten sus derechos laborales, incluyendo temas de salarios, seguridad laboral y discriminaci\u00f3n en el lugar de trabajo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42cceee7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"42cceee7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-167d34e7\" data-id=\"167d34e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e910714 elementor-widget elementor-widget-toggle\" data-id=\"2e910714\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7811\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-7811\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7811\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-7811\"><p><strong>MALDEF<\/strong><\/p><p><a href=\"https:\/\/www.maldef.org\/wp-content\/uploads\/2024\/01\/70-Brief-of-Intervenor-Defendants-Appellants-Alvarez.pdf\">https:\/\/www.maldef.org\/wp-content\/uploads\/2024\/01\/70-Brief-of-Intervenor-Defendants-Appellants-Alvarez.pdf<\/a><\/p><p><a href=\"https:\/\/www.maldef.org\/about\/\">https:\/\/www.maldef.org\/about\/<\/a><\/p><p><a href=\"https:\/\/www.maldef.org\/public-policy\/education\/\">https:\/\/www.maldef.org\/public-policy\/education\/<\/a><\/p><p><a href=\"https:\/\/www.maldef.org\/court-cases\/employment\/\">https:\/\/www.maldef.org\/court-cases\/employment\/<\/a><\/p><p><a href=\"https:\/\/www.maldef.org\/resources\/scholarship-resources\/\">https:\/\/www.maldef.org\/resources\/scholarship-resources\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>MALDEF es una de las organizaciones de defensa y representaci\u00f3n legal m\u00e1s importantes para la comunidad hispana en Estados Unidos. El Mexican American Legal Defense and Educational Fund o MALDEF es una organizaci\u00f3n sin fines de lucro dedicada a proteger los derechos civiles de los latinos en Estados Unidos. Fundada en 1968, MALDEF se centra en temas como la educaci\u00f3n, el empleo, los derechos de los inmigrantes y la participaci\u00f3n pol\u00edtica, a trav\u00e9s de litigios, promoci\u00f3n de pol\u00edticas p\u00fablicas y educaci\u00f3n p\u00fablica. En este sentido, se trata de una organizaci\u00f3n especializada en la litigaci\u00f3n de derechos civiles, especialmente de los inmigrantes latinos. MALDEF se ha involucrado en importantes casos legales para proteger los derechos de los inmigrantes, luchando contra leyes discriminatorias y pr\u00e1cticas que afectan negativamente a las comunidades latinas. Han defendido a individuos y grupos en tribunales para asegurar que sus derechos sean respetados. Actualmente, MALDEF representa a los beneficiarios de DACA y ha presentado recursos e impugnaciones en la Corte de Apelaciones del Quinto Circuito, para la defensa del programa. Uno de los argumentos dentro de la apelaci\u00f3n explica que los beneficiarios de DACA han construido sus vidas alrededor de su presencia en Estados Unidos, y la mayor\u00eda han desarrollado carreras profesionales en el pa\u00eds y han formado lazos en sus comunidades locales. En este sentido, MALDEF tambi\u00e9n apoya los esfuerzos por aprobar una reforma migratoria. MALDEF aboga por pol\u00edticas de inmigraci\u00f3n que sean justas y humanitarias y adem\u00e1s miembros de la organizaci\u00f3n participan activamente en la promoci\u00f3n de cambios legislativos que permitan a los inmigrantes tener mejores oportunidades para regularizar su estatus. Por otro lado, MALDEF tambi\u00e9n trabaja para garantizar la igualdad de acceso a la educaci\u00f3n, enfrent\u00e1ndose a pol\u00edticas que intentan limitar las oportunidades educativas para estudiantes inmigrantes o latinos. Han litigado casos relacionados con el acceso a la educaci\u00f3n superior y la financiaci\u00f3n equitativa de las escuelas p\u00fablicas. De esta forma, MALDEF proporciona informaci\u00f3n legal y recursos educativos a la comunidad inmigrante, explicando sus derechos y las opciones legales disponibles. Tambi\u00e9n ofrecen talleres y programas educativos para empoderar a los inmigrantes y sus familias. Para cada ciclo acad\u00e9mico MALDEF crea una gu\u00eda de recursos gratuita para estudiantes, padres y educadores, con una lista de becas disponibles que no requieren un estatus migratorio. Consulta el recurso para el ciclo 2025-2026 en el siguiente enlace: https:\/\/www.maldef.org\/resources\/scholarship-resource-guide-2025-2026\/ Asimismo, la organizaci\u00f3n tambi\u00e9n trabaja por los derechos laborales. MALDEF apoya a trabajadores inmigrantes que enfrentan explotaci\u00f3n laboral, promoviendo condiciones de trabajo justas y asegurando que se respeten sus derechos laborales, incluyendo temas de salarios, seguridad laboral y discriminaci\u00f3n en el lugar de trabajo. BIBLIOGRAF\u00cdA MALDEF https:\/\/www.maldef.org\/wp-content\/uploads\/2024\/01\/70-Brief-of-Intervenor-Defendants-Appellants-Alvarez.pdf https:\/\/www.maldef.org\/about\/ https:\/\/www.maldef.org\/public-policy\/education\/ https:\/\/www.maldef.org\/court-cases\/employment\/ https:\/\/www.maldef.org\/resources\/scholarship-resources\/<\/p>","protected":false},"author":13,"featured_media":56645,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10],"tags":[87,2805,34,2342,3341],"class_list":["post-56643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-inmigrantes","tag-justicia","tag-latinos","tag-maldef","tag-mexican-american-legal-defense-and-educational-fund"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El destacado trabajo de MALDEF por los inmigrantes latinos en Estados Unidos<\/title>\n<meta name=\"description\" content=\"El Mexican American Legal Defense and Educational Fund o MALDEF realiza un destacado trabajo por los inmigrantes latinos en Estados Unidos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El destacado trabajo de MALDEF por los inmigrantes latinos en Estados Unidos | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"El Mexican American Legal Defense and Educational Fund o MALDEF realiza un destacado trabajo por los inmigrantes latinos en Estados Unidos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-29T11:24:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/MALDEF.png\" \/>\n\t<meta property=\"og:image:width\" content=\"552\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\"},\"headline\":\"El destacado trabajo de MALDEF por los inmigrantes latinos en Estados Unidos\",\"datePublished\":\"2024-11-29T11:24:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\\\/noticias\\\/\"},\"wordCount\":523,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MALDEF.png\",\"keywords\":[\"Inmigrantes\",\"Justicia\",\"latinos\",\"MALDEF\",\"Mexican American Legal Defense and Educational Fund\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\\\/noticias\\\/\",\"name\":\"El destacado trabajo de MALDEF por los inmigrantes latinos en Estados Unidos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MALDEF.png\",\"datePublished\":\"2024-11-29T11:24:00+00:00\",\"description\":\"El Mexican American Legal Defense and Educational Fund o MALDEF realiza un destacado trabajo por los inmigrantes latinos en Estados Unidos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MALDEF.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MALDEF.png\",\"width\":552,\"height\":267,\"caption\":\"MALDEF\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El destacado trabajo de MALDEF por los inmigrantes latinos en Estados Unidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El destacado trabajo de MALDEF por los inmigrantes latinos en Estados Unidos","description":"El Mexican American Legal Defense and Educational Fund o MALDEF realiza un destacado trabajo por los inmigrantes latinos en Estados Unidos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"El destacado trabajo de MALDEF por los inmigrantes latinos en Estados Unidos | Acceso Latino","og_description":"El Mexican American Legal Defense and Educational Fund o MALDEF realiza un destacado trabajo por los inmigrantes latinos en Estados Unidos.","og_url":"https:\/\/accesolatino.org\/en\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2024-11-29T11:24:00+00:00","og_image":[{"width":552,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/MALDEF.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b"},"headline":"El destacado trabajo de MALDEF por los inmigrantes latinos en Estados Unidos","datePublished":"2024-11-29T11:24:00+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/"},"wordCount":523,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/MALDEF.png","keywords":["Inmigrantes","Justicia","latinos","MALDEF","Mexican American Legal Defense and Educational Fund"],"articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/","url":"https:\/\/accesolatino.org\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/","name":"El destacado trabajo de MALDEF por los inmigrantes latinos en Estados Unidos","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/MALDEF.png","datePublished":"2024-11-29T11:24:00+00:00","description":"El Mexican American Legal Defense and Educational Fund o MALDEF realiza un destacado trabajo por los inmigrantes latinos en Estados Unidos.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/MALDEF.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/MALDEF.png","width":552,"height":267,"caption":"MALDEF"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/el-destacado-trabajo-de-maldef-por-los-inmigrantes-latinos-en-estados-unidos\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"El destacado trabajo de MALDEF por los inmigrantes latinos en Estados Unidos"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/56643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=56643"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/56643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/56645"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=56643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=56643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=56643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}