{"id":56411,"date":"2024-11-12T11:48:53","date_gmt":"2024-11-12T17:48:53","guid":{"rendered":"https:\/\/accesolatino.org\/?p=56411"},"modified":"2024-11-12T12:00:50","modified_gmt":"2024-11-12T18:00:50","slug":"organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/","title":{"rendered":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"56411\" class=\"elementor elementor-56411\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c4a4eb8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4c4a4eb8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b79b4b4\" data-id=\"1b79b4b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5937bf8 elementor-widget elementor-widget-heading\" data-id=\"5937bf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fundada en 1977, Progreso Latino es la organizaci\u00f3n comunitaria a favor de inmigrantes y latinos m\u00e1s importante de Rhode Island.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-214f0316 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"214f0316\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7de96810\" data-id=\"7de96810\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f6c7be6 elementor-widget elementor-widget-text-editor\" data-id=\"4f6c7be6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Progreso Latino es una organizaci\u00f3n fundada por l\u00edderes hispanos locales en 1977 con el prop\u00f3sito de servir a la comunidad latina y comunidades inmigrantes de Rhode Island. Desde entonces, Progreso Latino ha crecido hasta convertirse en la organizaci\u00f3n comunitaria latina m\u00e1s grande del estado, al ofrecer diversos programas y servicios.<\/p><p>La misi\u00f3n de esta organizaci\u00f3n es ayudar a los inmigrantes del estado para alcanzar la autosuficiencia y el progreso socioecon\u00f3mico por medio de programas que apoyar el crecimiento personal y el cambio social.<\/p><p>Progreso Latino realiza anualmente una gala para la recaudaci\u00f3n de fondos para cubrir sus diversos programas, que incluyen becas, ense\u00f1anza del ingl\u00e9s y un banco de alimentos que sirve a 450 personas a la semana. En este sentido, durante la gala de este a\u00f1o, Progreso Latino celebr\u00f3 su 47 aniversario.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4774ff91 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4774ff91\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3bf9a1b6\" data-id=\"3bf9a1b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69b1f224 elementor-widget elementor-widget-image\" data-id=\"69b1f224\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"551\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png\" class=\"attachment-full size-full wp-image-56418\" alt=\"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png 551w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland-18x9.png 18w\" sizes=\"(max-width: 551px) 100vw, 551px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-29e39c4d\" data-id=\"29e39c4d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13e1f128 elementor-widget elementor-widget-text-editor\" data-id=\"13e1f128\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El tema de este a\u00f1o fue una fiesta de m\u00e1scaras, que tambi\u00e9n sirvi\u00f3 para rendir tributo a las v\u00edctimas de violencia dom\u00e9stica cuando los asistentes revelaron su rostro retirando las m\u00e1scaras.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a872614 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1a872614\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7092f406\" data-id=\"7092f406\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59258b99 elementor-widget elementor-widget-text-editor\" data-id=\"59258b99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Adem\u00e1s de los programas sobre educaci\u00f3n y alimentaci\u00f3n, Progreso Latino destaca por su labor en servicios sociales, protecci\u00f3n de v\u00edctimas de violencia dom\u00e9stica, procesamiento de deducci\u00f3n de impuestos, educaci\u00f3n financiera y capacitaci\u00f3n para el empleo.<\/p><p>Conoce m\u00e1s sobre los programas disponibles en el siguiente enlace: <a href=\"https:\/\/progresolatino.org\/\">https:\/\/progresolatino.org\/<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f7bc50d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6f7bc50d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e01f507\" data-id=\"4e01f507\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1028ca48 elementor-widget elementor-widget-toggle\" data-id=\"1028ca48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2711\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2711\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2711\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2711\"><p><strong>PROGRESO LATINO<\/strong><\/p><p><a href=\"https:\/\/progresolatino.org\/about-us\">https:\/\/progresolatino.org\/about-us<\/a><\/p><p><strong>WPRI<\/strong><\/p><p><a href=\"https:\/\/www.wpri.com\/12-informa\/comunidad\/progreso-latino-celebro-su-47-aniversario-de-servicio-a-la-comunidad\/\">https:\/\/www.wpri.com\/12-informa\/comunidad\/progreso-latino-celebro-su-47-aniversario-de-servicio-a-la-comunidad\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Fundada en 1977, Progreso Latino es la organizaci\u00f3n comunitaria a favor de inmigrantes y latinos m\u00e1s importante de Rhode Island. Progreso Latino es una organizaci\u00f3n fundada por l\u00edderes hispanos locales en 1977 con el prop\u00f3sito de servir a la comunidad latina y comunidades inmigrantes de Rhode Island. Desde entonces, Progreso Latino ha crecido hasta convertirse en la organizaci\u00f3n comunitaria latina m\u00e1s grande del estado, al ofrecer diversos programas y servicios. La misi\u00f3n de esta organizaci\u00f3n es ayudar a los inmigrantes del estado para alcanzar la autosuficiencia y el progreso socioecon\u00f3mico por medio de programas que apoyar el crecimiento personal y el cambio social. Progreso Latino realiza anualmente una gala para la recaudaci\u00f3n de fondos para cubrir sus diversos programas, que incluyen becas, ense\u00f1anza del ingl\u00e9s y un banco de alimentos que sirve a 450 personas a la semana. En este sentido, durante la gala de este a\u00f1o, Progreso Latino celebr\u00f3 su 47 aniversario. El tema de este a\u00f1o fue una fiesta de m\u00e1scaras, que tambi\u00e9n sirvi\u00f3 para rendir tributo a las v\u00edctimas de violencia dom\u00e9stica cuando los asistentes revelaron su rostro retirando las m\u00e1scaras. Adem\u00e1s de los programas sobre educaci\u00f3n y alimentaci\u00f3n, Progreso Latino destaca por su labor en servicios sociales, protecci\u00f3n de v\u00edctimas de violencia dom\u00e9stica, procesamiento de deducci\u00f3n de impuestos, educaci\u00f3n financiera y capacitaci\u00f3n para el empleo. Conoce m\u00e1s sobre los programas disponibles en el siguiente enlace: https:\/\/progresolatino.org\/ BIBLIOGRAF\u00cdA PROGRESO LATINO https:\/\/progresolatino.org\/about-us WPRI https:\/\/www.wpri.com\/12-informa\/comunidad\/progreso-latino-celebro-su-47-aniversario-de-servicio-a-la-comunidad\/<\/p>","protected":false},"author":6,"featured_media":56418,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[90],"tags":[73,28,165,68,61,228,87,100,86,173],"class_list":["post-56411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apoyo-social","tag-biden","tag-ciudadania","tag-ciudadania-estadounidense","tag-daca","tag-dreamers","tag-estados-unidos","tag-inmigrantes","tag-joe-biden","tag-migrantes","tag-uscis"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Fundada en 1977, Progreso Latino es la organizaci\u00f3n comunitaria a favor de inmigrantes y latinos m\u00e1s importante de Rhode Island. Progreso Latino es una organizaci\u00f3n fundada por l\u00edderes hispanos locales en 1977 con el prop\u00f3sito de servir a la comunidad latina y comunidades inmigrantes de Rhode Island. Desde entonces, Progreso Latino ha crecido hasta convertirse\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Apoyos Sociales Apoyos Sociales\"\/>\n\t<meta name=\"google-site-verification\" content=\"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE\" \/>\n\t<meta name=\"keywords\" content=\"biden,ciudadan\u00eda,ciudadan\u00eda estadounidense,daca,dreamers,estados unidos,inmigrantes,joe biden,migrantes,uscis,apoyo social\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island\" \/>\n\t\t<meta property=\"og:description\" content=\"Fundada en 1977, Progreso Latino es la organizaci\u00f3n comunitaria a favor de inmigrantes y latinos m\u00e1s importante de Rhode Island. Progreso Latino es una organizaci\u00f3n fundada por l\u00edderes hispanos locales en 1977 con el prop\u00f3sito de servir a la comunidad latina y comunidades inmigrantes de Rhode Island. Desde entonces, Progreso Latino ha crecido hasta convertirse\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-11-12T17:48:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-11-12T18:00:50+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Fundada en 1977, Progreso Latino es la organizaci\u00f3n comunitaria a favor de inmigrantes y latinos m\u00e1s importante de Rhode Island. Progreso Latino es una organizaci\u00f3n fundada por l\u00edderes hispanos locales en 1977 con el prop\u00f3sito de servir a la comunidad latina y comunidades inmigrantes de Rhode Island. Desde entonces, Progreso Latino ha crecido hasta convertirse\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#blogposting\",\"name\":\"Organizaci\\u00f3n Progreso Latino celebra 47 a\\u00f1os de servir a la comunidad en Rhode Island\",\"headline\":\"Organizaci\\u00f3n Progreso Latino celebra 47 a\\u00f1os de servir a la comunidad en Rhode Island\",\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/apoyos-sociales\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png\",\"width\":551,\"height\":267,\"caption\":\"Organizaci\\u00f3n Progreso Latino celebra 47 a\\u00f1os de servir a la comunidad en Rhode Island\"},\"datePublished\":\"2024-11-12T11:48:53-06:00\",\"dateModified\":\"2024-11-12T12:00:50-06:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#webpage\"},\"articleSection\":\"Apoyo Social, Biden, ciudadan\\u00eda, Ciudadan\\u00eda estadounidense, DACA, Dreamers, Estados Unidos, Inmigrantes, Joe Biden, Migrantes, USCIS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/apoyo-social\\\/#listItem\",\"name\":\"Apoyo Social\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/apoyo-social\\\/#listItem\",\"position\":2,\"name\":\"Apoyo Social\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/apoyo-social\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#listItem\",\"name\":\"Organizaci\\u00f3n Progreso Latino celebra 47 a\\u00f1os de servir a la comunidad en Rhode Island\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#listItem\",\"position\":3,\"name\":\"Organizaci\\u00f3n Progreso Latino celebra 47 a\\u00f1os de servir a la comunidad en Rhode Island\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/apoyo-social\\\/#listItem\",\"name\":\"Apoyo Social\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#organizationLogo\",\"width\":240,\"height\":40},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/apoyos-sociales\\\/#author\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/apoyos-sociales\\\/\",\"name\":\"Apoyos Sociales Apoyos Sociales\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#webpage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/\",\"name\":\"Organizaci\\u00f3n Progreso Latino celebra 47 a\\u00f1os de servir a la comunidad en Rhode Island\",\"description\":\"Fundada en 1977, Progreso Latino es la organizaci\\u00f3n comunitaria a favor de inmigrantes y latinos m\\u00e1s importante de Rhode Island. Progreso Latino es una organizaci\\u00f3n fundada por l\\u00edderes hispanos locales en 1977 con el prop\\u00f3sito de servir a la comunidad latina y comunidades inmigrantes de Rhode Island. Desde entonces, Progreso Latino ha crecido hasta convertirse\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/apoyos-sociales\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/apoyos-sociales\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#mainImage\",\"width\":551,\"height\":267,\"caption\":\"Organizaci\\u00f3n Progreso Latino celebra 47 a\\u00f1os de servir a la comunidad en Rhode Island\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#mainImage\"},\"datePublished\":\"2024-11-12T11:48:53-06:00\",\"dateModified\":\"2024-11-12T12:00:50-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island","description":"Fundada en 1977, Progreso Latino es la organizaci\u00f3n comunitaria a favor de inmigrantes y latinos m\u00e1s importante de Rhode Island. Progreso Latino es una organizaci\u00f3n fundada por l\u00edderes hispanos locales en 1977 con el prop\u00f3sito de servir a la comunidad latina y comunidades inmigrantes de Rhode Island. Desde entonces, Progreso Latino ha crecido hasta convertirse","canonical_url":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/","robots":"max-image-preview:large","keywords":"biden,ciudadan\u00eda,ciudadan\u00eda estadounidense,daca,dreamers,estados unidos,inmigrantes,joe biden,migrantes,uscis,apoyo social","webmasterTools":{"google-site-verification":"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#blogposting","name":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island","headline":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island","author":{"@id":"https:\/\/accesolatino.org\/en\/author\/apoyos-sociales\/#author"},"publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png","width":551,"height":267,"caption":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island"},"datePublished":"2024-11-12T11:48:53-06:00","dateModified":"2024-11-12T12:00:50-06:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#webpage"},"isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#webpage"},"articleSection":"Apoyo Social, Biden, ciudadan\u00eda, Ciudadan\u00eda estadounidense, DACA, Dreamers, Estados Unidos, Inmigrantes, Joe Biden, Migrantes, USCIS"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","position":1,"name":"Home","item":"https:\/\/accesolatino.org\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/apoyo-social\/#listItem","name":"Apoyo Social"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/apoyo-social\/#listItem","position":2,"name":"Apoyo Social","item":"https:\/\/accesolatino.org\/en\/category\/apoyo-social\/","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#listItem","name":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island"},"previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#listItem","position":3,"name":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island","previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/apoyo-social\/#listItem","name":"Apoyo Social"}}]},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/en\/#organization","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#organizationLogo","width":240,"height":40},"image":{"@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/accesolatino.org\/en\/author\/apoyos-sociales\/#author","url":"https:\/\/accesolatino.org\/en\/author\/apoyos-sociales\/","name":"Apoyos Sociales Apoyos Sociales"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#webpage","url":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/","name":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island","description":"Fundada en 1977, Progreso Latino es la organizaci\u00f3n comunitaria a favor de inmigrantes y latinos m\u00e1s importante de Rhode Island. Progreso Latino es una organizaci\u00f3n fundada por l\u00edderes hispanos locales en 1977 con el prop\u00f3sito de servir a la comunidad latina y comunidades inmigrantes de Rhode Island. Desde entonces, Progreso Latino ha crecido hasta convertirse","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#breadcrumblist"},"author":{"@id":"https:\/\/accesolatino.org\/en\/author\/apoyos-sociales\/#author"},"creator":{"@id":"https:\/\/accesolatino.org\/en\/author\/apoyos-sociales\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png","@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#mainImage","width":551,"height":267,"caption":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#mainImage"},"datePublished":"2024-11-12T11:48:53-06:00","dateModified":"2024-11-12T12:00:50-06:00"},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/en\/#website","url":"https:\/\/accesolatino.org\/en\/","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","inLanguage":"en-US","publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim","og:type":"article","og:title":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island","og:description":"Fundada en 1977, Progreso Latino es la organizaci\u00f3n comunitaria a favor de inmigrantes y latinos m\u00e1s importante de Rhode Island. Progreso Latino es una organizaci\u00f3n fundada por l\u00edderes hispanos locales en 1977 con el prop\u00f3sito de servir a la comunidad latina y comunidades inmigrantes de Rhode Island. Desde entonces, Progreso Latino ha crecido hasta convertirse","og:url":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/","article:published_time":"2024-11-12T17:48:53+00:00","article:modified_time":"2024-11-12T18:00:50+00:00","twitter:card":"summary_large_image","twitter:title":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island","twitter:description":"Fundada en 1977, Progreso Latino es la organizaci\u00f3n comunitaria a favor de inmigrantes y latinos m\u00e1s importante de Rhode Island. Progreso Latino es una organizaci\u00f3n fundada por l\u00edderes hispanos locales en 1977 con el prop\u00f3sito de servir a la comunidad latina y comunidades inmigrantes de Rhode Island. Desde entonces, Progreso Latino ha crecido hasta convertirse"},"aioseo_meta_data":{"post_id":"56411","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-11-12 17:48:54","updated":"2025-06-06 09:18:40","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\/category\/apoyo-social\/\" title=\"Apoyo Social\">Apoyo Social<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tOrganizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/accesolatino.org\/en"},{"label":"Apoyo Social","link":"https:\/\/accesolatino.org\/en\/category\/apoyo-social\/"},{"label":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island","link":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island<\/title>\n<meta name=\"description\" content=\"La organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad latina e inmigrante en el estado de Rhode Island.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"La organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad latina e inmigrante en el estado de Rhode Island.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-12T17:48:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-12T18:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png\" \/>\n\t<meta property=\"og:image:width\" content=\"551\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Apoyos Sociales Apoyos Sociales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Apoyos Sociales Apoyos Sociales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/\"},\"author\":{\"name\":\"Apoyos Sociales Apoyos Sociales\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/7dcf8193a1bb4eef76a38e855d85c72c\"},\"headline\":\"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island\",\"datePublished\":\"2024-11-12T17:48:53+00:00\",\"dateModified\":\"2024-11-12T18:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/\"},\"wordCount\":290,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png\",\"keywords\":[\"Biden\",\"ciudadan\u00eda\",\"Ciudadan\u00eda estadounidense\",\"DACA\",\"Dreamers\",\"Estados Unidos\",\"Inmigrantes\",\"Joe Biden\",\"Migrantes\",\"USCIS\"],\"articleSection\":[\"Apoyo Social\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/\",\"name\":\"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png\",\"datePublished\":\"2024-11-12T17:48:53+00:00\",\"dateModified\":\"2024-11-12T18:00:50+00:00\",\"description\":\"La organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad latina e inmigrante en el estado de Rhode Island.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png\",\"width\":551,\"height\":267,\"caption\":\"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\\\/apoyo-social\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apoyo Social\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/apoyo-social\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/7dcf8193a1bb4eef76a38e855d85c72c\",\"name\":\"Apoyos Sociales Apoyos Sociales\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island","description":"La organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad latina e inmigrante en el estado de Rhode Island.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/","og_locale":"en_US","og_type":"article","og_title":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island | Acceso Latino","og_description":"La organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad latina e inmigrante en el estado de Rhode Island.","og_url":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2024-11-12T17:48:53+00:00","article_modified_time":"2024-11-12T18:00:50+00:00","og_image":[{"width":551,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png","type":"image\/png"}],"author":"Apoyos Sociales Apoyos Sociales","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Apoyos Sociales Apoyos Sociales","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/"},"author":{"name":"Apoyos Sociales Apoyos Sociales","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/7dcf8193a1bb4eef76a38e855d85c72c"},"headline":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island","datePublished":"2024-11-12T17:48:53+00:00","dateModified":"2024-11-12T18:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/"},"wordCount":290,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png","keywords":["Biden","ciudadan\u00eda","Ciudadan\u00eda estadounidense","DACA","Dreamers","Estados Unidos","Inmigrantes","Joe Biden","Migrantes","USCIS"],"articleSection":["Apoyo Social"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/","url":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/","name":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png","datePublished":"2024-11-12T17:48:53+00:00","dateModified":"2024-11-12T18:00:50+00:00","description":"La organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad latina e inmigrante en el estado de Rhode Island.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/11\/OrganizacionProgresoLatinocelebra47anosdeserviralacomunidadenRhodeIsland.png","width":551,"height":267,"caption":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/organizacion-progreso-latino-celebra-47-anos-de-servir-a-la-comunidad-en-rhode-island\/apoyo-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Apoyo Social","item":"https:\/\/accesolatino.org\/en\/category\/apoyo-social\/"},{"@type":"ListItem","position":3,"name":"Organizaci\u00f3n Progreso Latino celebra 47 a\u00f1os de servir a la comunidad en Rhode Island"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/7dcf8193a1bb4eef76a38e855d85c72c","name":"Apoyos Sociales Apoyos Sociales"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/56411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=56411"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/56411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/56418"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=56411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=56411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=56411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}