{"id":56227,"date":"2024-10-25T05:04:00","date_gmt":"2024-10-25T11:04:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=56227"},"modified":"2024-10-24T17:21:28","modified_gmt":"2024-10-24T23:21:28","slug":"universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/","title":{"rendered":"Universidad de Colima firma convenio para seguir recibiendo Dreamers"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"56227\" class=\"elementor elementor-56227\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-510d437b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"510d437b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ec12004\" data-id=\"1ec12004\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e7d5536 elementor-widget elementor-widget-heading\" data-id=\"5e7d5536\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La Universidad de Coima y la Red de Liderazgo del Sureste firmaron un convenio para recibir a Dreamers y ayudarlos a regularizar su estatus migratorio.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-786d9976 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"786d9976\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73190e59\" data-id=\"73190e59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5040d038 elementor-widget elementor-widget-text-editor\" data-id=\"5040d038\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Universidad de Colima (UdeC) firm\u00f3 un convenio con la Red de Liderazgo del Sureste para fomentar la internacionalizaci\u00f3n solidaria, cuyo objetivo es ayudar a Dreamers, es decir, j\u00f3venes que llegaron a Estados Unidos sin documentos cuando eran menores, a regularizar su estatus migratorio. A trav\u00e9s de esta iniciativita, la UdeC recibir\u00e1 grupos de Dreamers cada a\u00f1o para favorecer experiencias educativas y culturales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7937d98d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7937d98d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1728bdce\" data-id=\"1728bdce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40b3c4b9 elementor-widget elementor-widget-image\" data-id=\"40b3c4b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"551\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/10\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico.png\" class=\"attachment-full size-full wp-image-56228\" alt=\"Universidad de Colima firma convenio para seguir recibiendo Dreamers\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/10\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico.png 551w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/10\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/10\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico-18x9.png 18w\" sizes=\"(max-width: 551px) 100vw, 551px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-55228d2c\" data-id=\"55228d2c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68466924 elementor-widget elementor-widget-text-editor\" data-id=\"68466924\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los Dreamers que participan en esta clase de programas, son adem\u00e1s beneficiarios de Acci\u00f3n Diferida para los Llegados en la Infancia o DACA, el programa que brinda protecci\u00f3n contra la deportaci\u00f3n y ofrece un permiso de trabajo. Al tramitar un permiso especial de viaje o Advance Parole, los Dreamers pueden salir de Estados Unidos de manera legal, lo cual no solo es la \u00fanica manera que pueden salir del pa\u00eds sin perder sus beneficios de DACA, sino que, al regresar a Estados Unidos, se elimina su entrada ilegal y se registra su entrada de manera regular, lo cual a futuro les puede permitir regularizar su estatus migratorio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-592a5fee elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"592a5fee\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31030d62\" data-id=\"31030d62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e507c52 elementor-widget elementor-widget-text-editor\" data-id=\"5e507c52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>De esta forma, la UdeC, organizar\u00e1 regularmente grupos de Dreamers que llegan a M\u00e9xico para reconectar con su cultura y poder reencontrarse con sus familiares y en algunos casos verlos por primera vez. <a href=\"https:\/\/accesolatino.org\/en\/noticias\/universidad-de-colima-recibio-a-dreamers-mexicanos\/\">Hace un a\u00f1o se llev\u00f3 a cabo la primera actividad con Dreamers en la UdeC<\/a>, que cont\u00f3 con el apoyo de la entonces diputada local de Colima, Fernanda Salazar. Esta actividad permite a Dreamers recibir cursos y clases en la Facultad de Ciencias Pol\u00edticas y los estudiantes de la Facultad de Turismo ayudaros a gestionar visitas guiadas en diversos puntos del estado.<\/p><p>Recientemente, un nuevo grupo de 32 Dreamers fue recibido en el auditorio de la Direcci\u00f3n General de Desarrollo de Personal Docente de la UdeC. Los Dreamers, 10 hombres y 22 mujeres, tomaron el curso \u201cPol\u00edtica y Cultura Mexicana\u201d, que abord\u00f3 temas de pol\u00edtica, turismo, cultura y literatura de M\u00e9xico. Del 11 al 20 de octubre, los 32 Dreamers, permanecieron en Colima para participar en las actividades del curso.<\/p><p>Salazar, que ahora es consultora en M\u00e1sMex Consultores, expres\u00f3 que este tipo de actividades son clave para que los Dreamers mexicanos vuelvan a conectar con su pa\u00eds. \u201cEs algo que cambia vidas. \u201cMuchos de nosotros tenemos a un familiar que vive cerca de nosotros y no lo visitamos; en cambio, los dreamers, los migrantes, tratan de hablarles todos los d\u00edas, de estar al pendiente, y el que puedan venir a su pa\u00eds es algo que les cambiar\u00e1 la vida\u201d, expres\u00f3.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2da5d2ca elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2da5d2ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa69e9f\" data-id=\"fa69e9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7722785e elementor-widget elementor-widget-toggle\" data-id=\"7722785e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1991\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1991\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1991\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1991\"><p><strong>EL COMENTARIO UCOL<\/strong><\/p><p><a href=\"https:\/\/elcomentario.ucol.mx\/?p=142976\">https:\/\/elcomentario.ucol.mx\/?p=142976<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La Universidad de Coima y la Red de Liderazgo del Sureste firmaron un convenio para recibir a Dreamers y ayudarlos a regularizar su estatus migratorio. La Universidad de Colima (UdeC) firm\u00f3 un convenio con la Red de Liderazgo del Sureste para fomentar la internacionalizaci\u00f3n solidaria, cuyo objetivo es ayudar a Dreamers, es decir, j\u00f3venes que llegaron a Estados Unidos sin documentos cuando eran menores, a regularizar su estatus migratorio. A trav\u00e9s de esta iniciativita, la UdeC recibir\u00e1 grupos de Dreamers cada a\u00f1o para favorecer experiencias educativas y culturales. Los Dreamers que participan en esta clase de programas, son adem\u00e1s beneficiarios de Acci\u00f3n Diferida para los Llegados en la Infancia o DACA, el programa que brinda protecci\u00f3n contra la deportaci\u00f3n y ofrece un permiso de trabajo. Al tramitar un permiso especial de viaje o Advance Parole, los Dreamers pueden salir de Estados Unidos de manera legal, lo cual no solo es la \u00fanica manera que pueden salir del pa\u00eds sin perder sus beneficios de DACA, sino que, al regresar a Estados Unidos, se elimina su entrada ilegal y se registra su entrada de manera regular, lo cual a futuro les puede permitir regularizar su estatus migratorio. De esta forma, la UdeC, organizar\u00e1 regularmente grupos de Dreamers que llegan a M\u00e9xico para reconectar con su cultura y poder reencontrarse con sus familiares y en algunos casos verlos por primera vez. Hace un a\u00f1o se llev\u00f3 a cabo la primera actividad con Dreamers en la UdeC, que cont\u00f3 con el apoyo de la entonces diputada local de Colima, Fernanda Salazar. Esta actividad permite a Dreamers recibir cursos y clases en la Facultad de Ciencias Pol\u00edticas y los estudiantes de la Facultad de Turismo ayudaros a gestionar visitas guiadas en diversos puntos del estado. Recientemente, un nuevo grupo de 32 Dreamers fue recibido en el auditorio de la Direcci\u00f3n General de Desarrollo de Personal Docente de la UdeC. Los Dreamers, 10 hombres y 22 mujeres, tomaron el curso \u201cPol\u00edtica y Cultura Mexicana\u201d, que abord\u00f3 temas de pol\u00edtica, turismo, cultura y literatura de M\u00e9xico. Del 11 al 20 de octubre, los 32 Dreamers, permanecieron en Colima para participar en las actividades del curso. Salazar, que ahora es consultora en M\u00e1sMex Consultores, expres\u00f3 que este tipo de actividades son clave para que los Dreamers mexicanos vuelvan a conectar con su pa\u00eds. \u201cEs algo que cambia vidas. \u201cMuchos de nosotros tenemos a un familiar que vive cerca de nosotros y no lo visitamos; en cambio, los dreamers, los migrantes, tratan de hablarles todos los d\u00edas, de estar al pendiente, y el que puedan venir a su pa\u00eds es algo que les cambiar\u00e1 la vida\u201d, expres\u00f3. BIBLIOGRAF\u00cdA EL COMENTARIO UCOL https:\/\/elcomentario.ucol.mx\/?p=142976<\/p>","protected":false},"author":13,"featured_media":56228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10],"tags":[68,61,143,2568,2567],"class_list":["post-56227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-daca","tag-dreamers","tag-estatus-migratorio","tag-udec","tag-universidad-de-colima"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Universidad de Colima firma convenio para seguir recibiendo Dreamers<\/title>\n<meta name=\"description\" content=\"La Universidad de Colima firm\u00f3 un convenio para seguir recibiendo Dreamers y ayudarles a regularizar su estatus migratorio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Universidad de Colima firma convenio para seguir recibiendo Dreamers | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"La Universidad de Colima firm\u00f3 un convenio para seguir recibiendo Dreamers y ayudarles a regularizar su estatus migratorio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-25T11:04:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/10\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico.png\" \/>\n\t<meta property=\"og:image:width\" content=\"551\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Universidad de Colima firma convenio para seguir recibiendo Dreamers\",\"datePublished\":\"2024-10-25T11:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\\\/noticias\\\/\"},\"wordCount\":471,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico.png\",\"keywords\":[\"DACA\",\"Dreamers\",\"Estatus migratorio\",\"UdeC\",\"Universidad de Colima\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\\\/noticias\\\/\",\"name\":\"Universidad de Colima firma convenio para seguir recibiendo Dreamers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico.png\",\"datePublished\":\"2024-10-25T11:04:00+00:00\",\"description\":\"La Universidad de Colima firm\u00f3 un convenio para seguir recibiendo Dreamers y ayudarles a regularizar su estatus migratorio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico.png\",\"width\":551,\"height\":267,\"caption\":\"Universidad de Colima firma convenio para seguir recibiendo Dreamers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Universidad de Colima firma convenio para seguir recibiendo Dreamers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Universidad de Colima firma convenio para seguir recibiendo Dreamers","description":"La Universidad de Colima firm\u00f3 un convenio para seguir recibiendo Dreamers y ayudarles a regularizar su estatus migratorio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Universidad de Colima firma convenio para seguir recibiendo Dreamers | Acceso Latino","og_description":"La Universidad de Colima firm\u00f3 un convenio para seguir recibiendo Dreamers y ayudarles a regularizar su estatus migratorio.","og_url":"https:\/\/accesolatino.org\/en\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2024-10-25T11:04:00+00:00","og_image":[{"width":551,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/10\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Universidad de Colima firma convenio para seguir recibiendo Dreamers","datePublished":"2024-10-25T11:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/"},"wordCount":471,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/10\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico.png","keywords":["DACA","Dreamers","Estatus migratorio","UdeC","Universidad de Colima"],"articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/","url":"https:\/\/accesolatino.org\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/","name":"Universidad de Colima firma convenio para seguir recibiendo Dreamers","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/10\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico.png","datePublished":"2024-10-25T11:04:00+00:00","description":"La Universidad de Colima firm\u00f3 un convenio para seguir recibiendo Dreamers y ayudarles a regularizar su estatus migratorio.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/10\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/10\/FirmaUdeCconvenioparaquemasdreamerspuedanvisitarMexico.png","width":551,"height":267,"caption":"Universidad de Colima firma convenio para seguir recibiendo Dreamers"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/universidad-de-colima-firma-convenio-para-seguir-recibiendo-dreamers\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Universidad de Colima firma convenio para seguir recibiendo Dreamers"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/56227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=56227"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/56227\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/56228"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=56227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=56227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=56227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}