{"id":55941,"date":"2024-09-27T02:56:00","date_gmt":"2024-09-27T08:56:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=55941"},"modified":"2024-09-25T15:09:38","modified_gmt":"2024-09-25T21:09:38","slug":"como-presentar-el-formulario-ds-160-en-grupos-familiares","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/","title":{"rendered":"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"55941\" class=\"elementor elementor-55941\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25896c32 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"25896c32\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64401d73\" data-id=\"64401d73\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6726723a elementor-widget elementor-widget-heading\" data-id=\"6726723a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conoce las opciones para presentar el formulario DS-160 en grupos o familia.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-773c95aa elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"773c95aa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-744a23dc\" data-id=\"744a23dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c8b34ef elementor-widget elementor-widget-text-editor\" data-id=\"7c8b34ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El formulario DS-160 es un documento electr\u00f3nico necesario para solicitar visas de no inmigrante en Estados Unidos, por ejemplo, visas B1\/B2 de turista, visas H-1B de trabajadores especializados o visas F-1 de estudiantes. Este formulario recopila informaci\u00f3n detallada sobre el solicitante, incluyendo datos como detalles del viaje, historial de empleo, educaci\u00f3n, antecedentes familiares, entre otros. El formulario se completa \u00fanicamente l\u00ednea y tiene una tarifa de presentaci\u00f3n de 160 d\u00f3lares.<\/p><p>Para facilitar el proceso, el Departamento de Estado (DOS) permite las aplicaciones en grupos o en familia. De esta manera, las personas que planean viajar en familia o grupo a Estados Unidos, pueden presentar las aplicaciones en conjunto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b38a5b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1b38a5b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6242d103\" data-id=\"6242d103\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ae3f6ed elementor-widget elementor-widget-image\" data-id=\"3ae3f6ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"551\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/09\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png\" class=\"attachment-full size-full wp-image-55942\" alt=\"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares?\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/09\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png 551w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/09\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/09\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia-18x9.png 18w\" sizes=\"(max-width: 551px) 100vw, 551px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1ad4f3b4\" data-id=\"1ad4f3b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b6cac72 elementor-widget elementor-widget-text-editor\" data-id=\"4b6cac72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Al seleccionar la opci\u00f3n \u201cemail confirmation \u201cen la p\u00e1gina de confirmaci\u00f3n, el usuario ser\u00e1 redirigido a la p\u00e1gina \u201cThank You\u201d, en donde aparece una opci\u00f3n para crear una aplicaci\u00f3n familiar o en grupo. Al seleccionar esta opci\u00f3n, cierta informaci\u00f3n de la primera aplicaci\u00f3n, como el destino, serpa autom\u00e1ticamente importada y mostrada en la nueva o en las nuevas aplicaciones. Cabe destacar que para acceder a esta opci\u00f3n es necesario llenar primero una aplicaci\u00f3n individual para cada miembro de la familia o grupo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66ddcb7c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"66ddcb7c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f8f49c3\" data-id=\"f8f49c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fc04af4 elementor-widget elementor-widget-text-editor\" data-id=\"5fc04af4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Al utilizar esta opci\u00f3n, tambi\u00e9n es posible modificar los datos que se importaron autom\u00e1ticamente por el sistema, es decir, si alguno de los miembros del grupo tiene un apellido distinto u otra nacionalidad, es posible cambiar la informaci\u00f3n antes de enviar la aplicaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2113df0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2113df0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-339ae8da\" data-id=\"339ae8da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c7d3176 elementor-widget elementor-widget-toggle\" data-id=\"4c7d3176\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1281\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1281\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1281\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1281\"><p><strong>DOS<\/strong><\/p><p><a href=\"https:\/\/travel.state.gov\/content\/travel\/en\/us-visas\/visa-information-resources\/forms\/ds-160-online-nonimmigrant-visa-application\/ds-160-faqs.html\">https:\/\/travel.state.gov\/content\/travel\/en\/us-visas\/visa-information-resources\/forms\/ds-160-online-nonimmigrant-visa-application\/ds-160-faqs.html<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Conoce las opciones para presentar el formulario DS-160 en grupos o familia. El formulario DS-160 es un documento electr\u00f3nico necesario para solicitar visas de no inmigrante en Estados Unidos, por ejemplo, visas B1\/B2 de turista, visas H-1B de trabajadores especializados o visas F-1 de estudiantes. Este formulario recopila informaci\u00f3n detallada sobre el solicitante, incluyendo datos como detalles del viaje, historial de empleo, educaci\u00f3n, antecedentes familiares, entre otros. El formulario se completa \u00fanicamente l\u00ednea y tiene una tarifa de presentaci\u00f3n de 160 d\u00f3lares. Para facilitar el proceso, el Departamento de Estado (DOS) permite las aplicaciones en grupos o en familia. De esta manera, las personas que planean viajar en familia o grupo a Estados Unidos, pueden presentar las aplicaciones en conjunto. Al seleccionar la opci\u00f3n \u201cemail confirmation \u201cen la p\u00e1gina de confirmaci\u00f3n, el usuario ser\u00e1 redirigido a la p\u00e1gina \u201cThank You\u201d, en donde aparece una opci\u00f3n para crear una aplicaci\u00f3n familiar o en grupo. Al seleccionar esta opci\u00f3n, cierta informaci\u00f3n de la primera aplicaci\u00f3n, como el destino, serpa autom\u00e1ticamente importada y mostrada en la nueva o en las nuevas aplicaciones. Cabe destacar que para acceder a esta opci\u00f3n es necesario llenar primero una aplicaci\u00f3n individual para cada miembro de la familia o grupo. Al utilizar esta opci\u00f3n, tambi\u00e9n es posible modificar los datos que se importaron autom\u00e1ticamente por el sistema, es decir, si alguno de los miembros del grupo tiene un apellido distinto u otra nacionalidad, es posible cambiar la informaci\u00f3n antes de enviar la aplicaci\u00f3n. BIBLIOGRAF\u00cdA DOS https:\/\/travel.state.gov\/content\/travel\/en\/us-visas\/visa-information-resources\/forms\/ds-160-online-nonimmigrant-visa-application\/ds-160-faqs.html<\/p>","protected":false},"author":13,"featured_media":55942,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[12,1934],"tags":[3216,105,1692,3215,1594],"class_list":["post-55941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tramites","category-tramites-y-permisos","tag-aplicaciones-en-grupo","tag-ds-160","tag-formulario","tag-grupos-familiares","tag-visa-de-turista"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares?<\/title>\n<meta name=\"description\" content=\"Conoce la opci\u00f3n para presentar el formulario DS-160 en grupos familiares para la presentaci\u00f3n de solicitudes de visa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares? | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Conoce la opci\u00f3n para presentar el formulario DS-160 en grupos familiares para la presentaci\u00f3n de solicitudes de visa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-27T08:56:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/09\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"551\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares? | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Conoce la opci\u00f3n para presentar el formulario DS-160 en grupos familiares para la presentaci\u00f3n de solicitudes de visa.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/09\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/como-presentar-el-formulario-ds-160-en-grupos-familiares\\\/tramites\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/como-presentar-el-formulario-ds-160-en-grupos-familiares\\\/tramites\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares?\",\"datePublished\":\"2024-09-27T08:56:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/como-presentar-el-formulario-ds-160-en-grupos-familiares\\\/tramites\\\/\"},\"wordCount\":296,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/como-presentar-el-formulario-ds-160-en-grupos-familiares\\\/tramites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png\",\"keywords\":[\"Aplicaciones en grupo\",\"ds-160\",\"Formulario\",\"Grupos familiares\",\"Visa de turista\"],\"articleSection\":[\"Tr\u00e1mites\",\"Tr\u00e1mites y Permisos\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/como-presentar-el-formulario-ds-160-en-grupos-familiares\\\/tramites\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/como-presentar-el-formulario-ds-160-en-grupos-familiares\\\/tramites\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/como-presentar-el-formulario-ds-160-en-grupos-familiares\\\/tramites\\\/\",\"name\":\"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/como-presentar-el-formulario-ds-160-en-grupos-familiares\\\/tramites\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/como-presentar-el-formulario-ds-160-en-grupos-familiares\\\/tramites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png\",\"datePublished\":\"2024-09-27T08:56:00+00:00\",\"description\":\"Conoce la opci\u00f3n para presentar el formulario DS-160 en grupos familiares para la presentaci\u00f3n de solicitudes de visa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/como-presentar-el-formulario-ds-160-en-grupos-familiares\\\/tramites\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/como-presentar-el-formulario-ds-160-en-grupos-familiares\\\/tramites\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/como-presentar-el-formulario-ds-160-en-grupos-familiares\\\/tramites\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png\",\"width\":551,\"height\":267,\"caption\":\"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/como-presentar-el-formulario-ds-160-en-grupos-familiares\\\/tramites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tr\u00e1mites\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/tramites\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares?","description":"Conoce la opci\u00f3n para presentar el formulario DS-160 en grupos familiares para la presentaci\u00f3n de solicitudes de visa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares? | Acceso Latino","og_description":"Conoce la opci\u00f3n para presentar el formulario DS-160 en grupos familiares para la presentaci\u00f3n de solicitudes de visa.","og_url":"https:\/\/accesolatino.org\/en\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2024-09-27T08:56:00+00:00","og_image":[{"width":551,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/09\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_title":"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares? | Acceso Latino","twitter_description":"Conoce la opci\u00f3n para presentar el formulario DS-160 en grupos familiares para la presentaci\u00f3n de solicitudes de visa.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/09\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares?","datePublished":"2024-09-27T08:56:00+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/"},"wordCount":296,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/09\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png","keywords":["Aplicaciones en grupo","ds-160","Formulario","Grupos familiares","Visa de turista"],"articleSection":["Tr\u00e1mites","Tr\u00e1mites y Permisos"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/","url":"https:\/\/accesolatino.org\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/","name":"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares?","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/09\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png","datePublished":"2024-09-27T08:56:00+00:00","description":"Conoce la opci\u00f3n para presentar el formulario DS-160 en grupos familiares para la presentaci\u00f3n de solicitudes de visa.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/09\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/09\/EstoesloquedicelaEmbajadadeEstadosUnidossipiensasviajarcontufamilia.png","width":551,"height":267,"caption":"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares?"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/como-presentar-el-formulario-ds-160-en-grupos-familiares\/tramites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Tr\u00e1mites","item":"https:\/\/accesolatino.org\/category\/tramites\/"},{"@type":"ListItem","position":3,"name":"\u00bfC\u00f3mo presentar el formulario DS-160 en grupos familiares?"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/55941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=55941"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/55941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/55942"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=55941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=55941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=55941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}