{"id":54978,"date":"2024-06-27T08:58:00","date_gmt":"2024-06-27T14:58:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=54978"},"modified":"2024-06-26T11:08:10","modified_gmt":"2024-06-26T17:08:10","slug":"conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/","title":{"rendered":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"54978\" class=\"elementor elementor-54978\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45e9751e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"45e9751e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ad8bfd5\" data-id=\"4ad8bfd5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6451a9e3 elementor-widget elementor-widget-heading\" data-id=\"6451a9e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CLEAP es un programa binacional que capacita a l\u00edderes latinos en la intersecci\u00f3n de las pol\u00edticas p\u00fablicas de Estados Unidos y M\u00e9xico.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-634aff48 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"634aff48\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c956f96\" data-id=\"4c956f96\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a423ba7 elementor-widget elementor-widget-text-editor\" data-id=\"6a423ba7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos (CLEAP), organizado por la organizaci\u00f3n Voces Unidas de las Monta\u00f1as, es una iniciativa educativa y de defensa que busca empoderar a los l\u00edderes latinos en Colorado. Este programa ofrece una comprensi\u00f3n profunda de las pol\u00edticas p\u00fablicas de Estados Unidos y M\u00e9xico, abordando c\u00f3mo estas afectan a los inmigrantes, migrantes y la di\u00e1spora mexicana en Estados Unidos.<\/p><p>El CLEAP proporciona oportunidades educativas para que los participantes adquieran un conocimiento integral de las pol\u00edticas p\u00fablicas actuales e hist\u00f3ricas de ambos pa\u00edses. Adem\u00e1s, el programa sumerge a los l\u00edderes en el contexto cultural, c\u00edvico y pol\u00edtico de M\u00e9xico, permiti\u00e9ndoles desarrollar y practicar habilidades de defensa durante su estancia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55d716cb elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"55d716cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-60387491\" data-id=\"60387491\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e9d2ef elementor-widget elementor-widget-text-editor\" data-id=\"1e9d2ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El programa se fundamenta en tres principios clave:<\/p><ul><li>Teor\u00eda del aprendizaje de adultos: Sugiere que los adultos aprenden mejor a trav\u00e9s de la pr\u00e1ctica y necesitan ver la aplicaci\u00f3n inmediata de habilidades o conocimientos<\/li><li>M\u00e9todo socr\u00e1tico: Fomenta un di\u00e1logo cooperativo entre los participantes mediante preguntas que estimulan el pensamiento cr\u00edtico<\/li><li>Investigaci\u00f3n-acci\u00f3n participativa: Una metodolog\u00eda cualitativa donde investigadores y participantes colaboran para comprender problemas sociales y emprender acciones que promuevan el cambio social<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c5a5935\" data-id=\"2c5a5935\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-648729c9 elementor-widget elementor-widget-image\" data-id=\"648729c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1104\" height=\"533\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png\" class=\"attachment-full size-full wp-image-54981\" alt=\"CLEAP\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png 1104w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos-1024x494.png 1024w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos-768x371.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos-18x9.png 18w\" sizes=\"(max-width: 1104px) 100vw, 1104px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">CLEAP<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-611f30c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"611f30c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6de7560e\" data-id=\"6de7560e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11ef3a5b elementor-widget elementor-widget-text-editor\" data-id=\"11ef3a5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Este a\u00f1o, CLEAP reuni\u00f3 a 11 l\u00edderes en Ciudad de M\u00e9xico, donde se encontraron con expertos universitarios y pol\u00edticos tanto mexicanos como estadounidenses. Alex S\u00e1nchez, presidente y fundador de Voces Unidas de las Monta\u00f1as, destaca la importancia de traer el talento y la experiencia de los mexicanos en el extranjero para influir en la creaci\u00f3n de mejores pol\u00edticas migratorias.<\/p><p>Una prioridad fundamental del programa es apoyar a los beneficiarios de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA) y a los Dreamers en su proceso de regularizaci\u00f3n de estatus migratorio. Actualmente, hay alrededor de 12 mil personas con DACA en Colorado y m\u00e1s de 600 mil a nivel nacional. Estos j\u00f3venes profesionales, en riesgo de perder su protecci\u00f3n, enfrentan la posibilidad de deportaci\u00f3n a pa\u00edses que apenas conocen. Esta situaci\u00f3n no solo afecta a los individuos, sino tambi\u00e9n a la econom\u00eda y la comunidad migrante en Estados Unidos.<\/p><p>Luz Galaviz, una de las l\u00edderes de CLEAP 2024, enfatiza que su trabajo va m\u00e1s all\u00e1 de DACA, abarcando a los 11 millones de latinos indocumentados en Estados Unidos. Abogan por pol\u00edticas en ambos pa\u00edses que eliminen la necesidad de emigrar, protejan los derechos humanos de los migrantes y establezcan procesos dignos para la legalizaci\u00f3n.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3566a0f6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3566a0f6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-913d1c6\" data-id=\"913d1c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4641c567 elementor-widget elementor-widget-toggle\" data-id=\"4641c567\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1171\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1171\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1171\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1171\"><p><strong>VOCES UNIDAS<\/strong><\/p><p><a href=\"https:\/\/www.vocesunidas.org\/civic-leader-education-advocacy-program\">https:\/\/www.vocesunidas.org\/civic-leader-education-advocacy-program<\/a><\/p><p><strong>YAHOO<\/strong><\/p><p><a href=\"https:\/\/es-us.finanzas.yahoo.com\/noticias\/cleap-programa-binacional-busca-incluir-223048941.html\">https:\/\/es-us.finanzas.yahoo.com\/noticias\/cleap-programa-binacional-busca-incluir-223048941.html<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>CLEAP es un programa binacional que capacita a l\u00edderes latinos en la intersecci\u00f3n de las pol\u00edticas p\u00fablicas de Estados Unidos y M\u00e9xico.<\/p>","protected":false},"author":13,"featured_media":54981,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10],"tags":[3053,68,61,3052,3051],"class_list":["post-54978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-cleap","tag-daca","tag-dreamers","tag-politicas-publicas","tag-programa-de-educacion-y-defensa-de-lideres-civicos"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"CLEAP es un programa binacional que capacita a l\u00edderes latinos en la intersecci\u00f3n de las pol\u00edticas p\u00fablicas de Estados Unidos y M\u00e9xico.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Noticias\"\/>\n\t<meta name=\"google-site-verification\" content=\"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE\" \/>\n\t<meta name=\"keywords\" content=\"cleap,daca,dreamers,pol\u00edticas p\u00fablicas,programa de educaci\u00f3n y defensa de l\u00edderes c\u00edvicos,noticias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers\" \/>\n\t\t<meta property=\"og:description\" content=\"CLEAP es un programa binacional que capacita a l\u00edderes latinos en la intersecci\u00f3n de las pol\u00edticas p\u00fablicas de Estados Unidos y M\u00e9xico.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-06-27T14:58:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-06-26T17:08:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers\" \/>\n\t\t<meta name=\"twitter:description\" content=\"CLEAP es un programa binacional que capacita a l\u00edderes latinos en la intersecci\u00f3n de las pol\u00edticas p\u00fablicas de Estados Unidos y M\u00e9xico.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#blogposting\",\"name\":\"Conoce el Programa de Educaci\\u00f3n y Defensa de L\\u00edderes C\\u00edvicos y su labor en la defensa de DACA y los Dreamers\",\"headline\":\"Conoce el Programa de Educaci\\u00f3n y Defensa de L\\u00edderes C\\u00edvicos y su labor en la defensa de DACA y los Dreamers\",\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png\",\"width\":1104,\"height\":533,\"caption\":\"CLEAP\"},\"datePublished\":\"2024-06-27T08:58:00-06:00\",\"dateModified\":\"2024-06-26T11:08:10-06:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#webpage\"},\"articleSection\":\"Noticias, CLEAP, DACA, Dreamers, Pol\\u00edticas p\\u00fablicas, Programa de Educaci\\u00f3n y Defensa de L\\u00edderes C\\u00edvicos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#listItem\",\"name\":\"Conoce el Programa de Educaci\\u00f3n y Defensa de L\\u00edderes C\\u00edvicos y su labor en la defensa de DACA y los Dreamers\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#listItem\",\"position\":3,\"name\":\"Conoce el Programa de Educaci\\u00f3n y Defensa de L\\u00edderes C\\u00edvicos y su labor en la defensa de DACA y los Dreamers\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#organizationLogo\",\"width\":240,\"height\":40},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/\",\"name\":\"Noticias\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#webpage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/\",\"name\":\"Conoce el Programa de Educaci\\u00f3n y Defensa de L\\u00edderes C\\u00edvicos y su labor en la defensa de DACA y los Dreamers\",\"description\":\"CLEAP es un programa binacional que capacita a l\\u00edderes latinos en la intersecci\\u00f3n de las pol\\u00edticas p\\u00fablicas de Estados Unidos y M\\u00e9xico.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#mainImage\",\"width\":1104,\"height\":533,\"caption\":\"CLEAP\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#mainImage\"},\"datePublished\":\"2024-06-27T08:58:00-06:00\",\"dateModified\":\"2024-06-26T11:08:10-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers","description":"CLEAP es un programa binacional que capacita a l\u00edderes latinos en la intersecci\u00f3n de las pol\u00edticas p\u00fablicas de Estados Unidos y M\u00e9xico.","canonical_url":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/","robots":"max-image-preview:large","keywords":"cleap,daca,dreamers,pol\u00edticas p\u00fablicas,programa de educaci\u00f3n y defensa de l\u00edderes c\u00edvicos,noticias","webmasterTools":{"google-site-verification":"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#blogposting","name":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers","headline":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers","author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png","width":1104,"height":533,"caption":"CLEAP"},"datePublished":"2024-06-27T08:58:00-06:00","dateModified":"2024-06-26T11:08:10-06:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#webpage"},"isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#webpage"},"articleSection":"Noticias, CLEAP, DACA, Dreamers, Pol\u00edticas p\u00fablicas, Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","position":1,"name":"Home","item":"https:\/\/accesolatino.org\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/en\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#listItem","name":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers"},"previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#listItem","position":3,"name":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers","previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/en\/#organization","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","@id":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#organizationLogo","width":240,"height":40},"image":{"@id":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author","url":"https:\/\/accesolatino.org\/en\/author\/noticias\/","name":"Noticias"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#webpage","url":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/","name":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers","description":"CLEAP es un programa binacional que capacita a l\u00edderes latinos en la intersecci\u00f3n de las pol\u00edticas p\u00fablicas de Estados Unidos y M\u00e9xico.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#breadcrumblist"},"author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"creator":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png","@id":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#mainImage","width":1104,"height":533,"caption":"CLEAP"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#mainImage"},"datePublished":"2024-06-27T08:58:00-06:00","dateModified":"2024-06-26T11:08:10-06:00"},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/en\/#website","url":"https:\/\/accesolatino.org\/en\/","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","inLanguage":"en-US","publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim","og:type":"article","og:title":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers","og:description":"CLEAP es un programa binacional que capacita a l\u00edderes latinos en la intersecci\u00f3n de las pol\u00edticas p\u00fablicas de Estados Unidos y M\u00e9xico.","og:url":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/","article:published_time":"2024-06-27T14:58:00+00:00","article:modified_time":"2024-06-26T17:08:10+00:00","twitter:card":"summary_large_image","twitter:title":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers","twitter:description":"CLEAP es un programa binacional que capacita a l\u00edderes latinos en la intersecci\u00f3n de las pol\u00edticas p\u00fablicas de Estados Unidos y M\u00e9xico."},"aioseo_meta_data":{"post_id":"54978","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-06-26 17:01:58","updated":"2025-06-06 08:59:38","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tConoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/accesolatino.org\/en"},{"label":"Noticias","link":"https:\/\/accesolatino.org\/en\/category\/noticias\/"},{"label":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers","link":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers<\/title>\n<meta name=\"description\" content=\"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos CLEAP y su labor en la defensa de DACA, los Dreamers y pol\u00edticas migratorias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos CLEAP y su labor en la defensa de DACA, los Dreamers y pol\u00edticas migratorias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-27T14:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1104\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos CLEAP y su labor en la defensa de DACA, los Dreamers y pol\u00edticas migratorias.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\"},\"headline\":\"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers\",\"datePublished\":\"2024-06-27T14:58:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/\"},\"wordCount\":513,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png\",\"keywords\":[\"CLEAP\",\"DACA\",\"Dreamers\",\"Pol\u00edticas p\u00fablicas\",\"Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/\",\"name\":\"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png\",\"datePublished\":\"2024-06-27T14:58:00+00:00\",\"description\":\"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos CLEAP y su labor en la defensa de DACA, los Dreamers y pol\u00edticas migratorias.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png\",\"width\":1104,\"height\":533,\"caption\":\"CLEAP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers","description":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos CLEAP y su labor en la defensa de DACA, los Dreamers y pol\u00edticas migratorias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers | Acceso Latino","og_description":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos CLEAP y su labor en la defensa de DACA, los Dreamers y pol\u00edticas migratorias.","og_url":"https:\/\/accesolatino.org\/en\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2024-06-27T14:58:00+00:00","og_image":[{"width":1104,"height":533,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_title":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers | Acceso Latino","twitter_description":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos CLEAP y su labor en la defensa de DACA, los Dreamers y pol\u00edticas migratorias.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905"},"headline":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers","datePublished":"2024-06-27T14:58:00+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/"},"wordCount":513,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png","keywords":["CLEAP","DACA","Dreamers","Pol\u00edticas p\u00fablicas","Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos"],"articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/","url":"https:\/\/accesolatino.org\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/","name":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png","datePublished":"2024-06-27T14:58:00+00:00","description":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos CLEAP y su labor en la defensa de DACA, los Dreamers y pol\u00edticas migratorias.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/CLEAP_elprogramabinacionalquebuscaincluirenlaspoliticaenprodelosmigranteslatinos.png","width":1104,"height":533,"caption":"CLEAP"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/conoce-el-programa-de-educacion-y-defensa-de-lideres-civicos-y-su-labor-en-la-defensa-de-daca-y-los-dreamers\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Conoce el Programa de Educaci\u00f3n y Defensa de L\u00edderes C\u00edvicos y su labor en la defensa de DACA y los Dreamers"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/54978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=54978"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/54978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/54981"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=54978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=54978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=54978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}