{"id":54769,"date":"2024-06-10T17:44:18","date_gmt":"2024-06-10T23:44:18","guid":{"rendered":"https:\/\/accesolatino.org\/?p=54769"},"modified":"2024-06-10T17:50:05","modified_gmt":"2024-06-10T23:50:05","slug":"como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/","title":{"rendered":"\u00bfC\u00f3mo ha beneficiado la Prop 308 a los Dreamers de Arizona?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"54769\" class=\"elementor elementor-54769\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ffae077 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2ffae077\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e9e8160\" data-id=\"6e9e8160\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bc92de3 elementor-widget elementor-widget-heading\" data-id=\"6bc92de3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gracias al voto popular, en diciembre de 2022 fue aprobada la Proposition 308 o Prop 308, que le brinda acceso a la matricula estatal a los Dreamers de Arizona.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dc42296 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5dc42296\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4318a701\" data-id=\"4318a701\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2941e74b elementor-widget elementor-widget-text-editor\" data-id=\"2941e74b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Proposition 308, mejor conocida como Prop 308, es una iniciativa legislativa en Arizona que beneficia a los Dreamers en t\u00e9rminos de su acceso y asequibilidad a la educaci\u00f3n superior. Esta iniciativa fue aprobada en las elecciones de noviembre de 2022 gracias al voto popular. Esta medida permite a ciertos estudiantes indocumentados pagar matr\u00edculas universitarias estatales en lugar de tarifas mucho m\u00e1s elevadas para estudiantes de fuera del estado.<\/p><p>Antes de la aprobaci\u00f3n de la Prop 308, los estudiantes indocumentados en Arizona estaban obligados a pagar matr\u00edculas m\u00e1s altas, similar a las tarifas para estudiantes for\u00e1neos, independientemente de cu\u00e1nto tiempo hubieran vivido en el estado. Esto limitaba el acceso a la educaci\u00f3n superior para los j\u00f3venes indocumentados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ccc6823 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3ccc6823\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6bf40b93\" data-id=\"6bf40b93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6837fbf3 elementor-widget elementor-widget-image\" data-id=\"6837fbf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"551\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/Prop308dreamersarizona.png\" class=\"attachment-full size-full wp-image-54770\" alt=\"dreamers arizona\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/Prop308dreamersarizona.png 551w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/Prop308dreamersarizona-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/Prop308dreamersarizona-18x9.png 18w\" sizes=\"(max-width: 551px) 100vw, 551px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1e6ca7f0\" data-id=\"1e6ca7f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fc77c2 elementor-widget elementor-widget-text-editor\" data-id=\"5fc77c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gracias a la Prop 308 esta situaci\u00f3n cambi\u00f3 y ahora los estudiantes indocumentados que se hayan graduado de una high school en Arizona, despu\u00e9s de haber asistido al menos dos a\u00f1os, son elegibles para pagar las tarifas de matr\u00edcula estatales en las universidades p\u00fablicas del estado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-493f0610 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"493f0610\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20975c80\" data-id=\"20975c80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-228f3d48 elementor-widget elementor-widget-text-editor\" data-id=\"228f3d48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un caso de \u00e9xito generado en parte gracias a la Prop 308 es el de la Dreamers Mar\u00eda Le\u00f3n. Le\u00f3n se gradu\u00f3 de high school en 2015 y atendi\u00f3 a Paradise Valley Community College, un colegio comunitario p\u00fablico en Phoenix. Gracias a su estatus como beneficiarios de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA), Le\u00f3n tuvo acceso a la matr\u00edcula estatal.<\/p><p>Sin embargo, en 2017, la administraci\u00f3n de Donald Trump a trav\u00e9s del Departamento de Justicia (DOJ) anunci\u00f3 el final de DACA. Un a\u00f1o despu\u00e9s la Superna Corte de Arizona aprob\u00f3 una ley que restring\u00eda los servicios y beneficios financiados por el estado a las personas sin estatus legal. De esta forma, Le\u00f3n, al igual que miles de beneficiarios de DACA en el estado de Arizona, perdieron la oportunidad de acceder a una tarifa m\u00e1s asequible para su educaci\u00f3n universitaria.<\/p><p>Tras esa experiencia, Le\u00f3n se acerc\u00f3 a Aliento AZ, una organizaci\u00f3n comunitaria en el estado que trabaja por el bienestar de los j\u00f3venes indocumentados, por los beneficiarios DACA y por las familias de estatus mixto. Cabe destacar que Aliento y sus colaboradores fueron un pilar importante para la aprobaci\u00f3n de la Prop 308.<\/p><p>Tras las noticias positivas sobre la matr\u00edcula estatal en 2022, Le\u00f3n pudo ser aceptada en un programa competitivo. \u201cComo latina orgullosa y estudiante de enfermer\u00eda que luch\u00f3 para inscribirse en la universidad con el sue\u00f1o de convertirse en m\u00e9dico, aprend\u00ed la importancia de que organizaciones como Aliento usen su propia voz y se unan a conversaciones para garantizar que m\u00e1s estudiantes j\u00f3venes reciban oportunidades como estas que establece la Proposici\u00f3n 308\u201d, escribi\u00f3 en un art\u00edculo donde cuenta su experiencia.<\/p><p>Gracias a esta nueva ley a su esfuerzo, Le\u00f3n obtuvo la Future Fellowship of Aliento de Arizona, un programa que la impulsa a continuar con sus estudios.<\/p><p>\u201cCapacitar a m\u00e1s estudiantes para que se matriculen en la universidad puede traducirse en enormes beneficios para Arizona y nuestro pa\u00eds. Es el esfuerzo de nuestro estado para abordar los desaf\u00edos educativos de la sociedad y brindar caminos hacia el \u00e9xito para estudiantes de todos los or\u00edgenes. Nuestro objetivo es solidificar el progreso que se logr\u00f3 para los estudiantes\u201d, declar\u00f3 Le\u00f3n acerca de la importancia de los avances recientes en el acceso a la educaci\u00f3n superior para los Dreamers en Arizona.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7effa6b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7effa6b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2689e7f7\" data-id=\"2689e7f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2170783f elementor-widget elementor-widget-toggle\" data-id=\"2170783f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5611\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-5611\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5611\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-5611\"><p><strong>YAHOO\/THE ARIZONA REPUBLIC<\/strong><\/p><p><a href=\"https:\/\/ca.news.yahoo.com\/im-undocumented-college-story-more-091226547.html?guce%5C_referrer=aHR0cHM6Ly90LmNvL25PS0hYdmNPbEg&amp;guce%5C_referrer%5C_sig=AQAAAE-jyjUmHT5m4iicGqFNPFUsTTgnmKmp36okJIv3Td7V4PnDEXX9SiK3f0Teep02vaL1Eq%5C_hXtDFNF5q3m0KrMx7ezhaf6ze1TL8AH%5C_E0uTqfFpaY8p1zZv8G-qAZXHc%5C_z5uvATF5im83ahsPgm0ZCK4HnbqOdxPyTmXzbL9yMN_&amp;guccounter=2\">https:\/\/ca.news.yahoo.com\/im-undocumented-college-story-more-091226547.html?guce%5C_referrer=aHR0cHM6Ly90LmNvL25PS0hYdmNPbEg&amp;guce%5C_referrer%5C_sig=AQAAAE-jyjUmHT5m4iicGqFNPFUsTTgnmKmp36okJIv3Td7V4PnDEXX9SiK3f0Teep02vaL1Eq%5C_hXtDFNF5q3m0KrMx7ezhaf6ze1TL8AH%5C_E0uTqfFpaY8p1zZv8G-qAZXHc%5C_z5uvATF5im83ahsPgm0ZCK4HnbqOdxPyTmXzbL9yMN_&amp;guccounter=2<\/a><\/p><p><strong>ALIENTO AZ<\/strong><\/p><p><a href=\"https:\/\/www.alientoaz.org\/instate-tuition\">https:\/\/www.alientoaz.org\/instate-tuition<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Gracias al voto popular, en diciembre de 2022 fue aprobada la Proposition 308 o Prop 308, que le brinda acceso a la matricula estatal a los Dreamers de Arizona.<\/p>","protected":false},"author":6,"featured_media":54770,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[90],"tags":[3005,61,3007,1407,3006],"class_list":["post-54769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apoyo-social","tag-aliento-az","tag-dreamers","tag-maria-leon","tag-matricula-estatal","tag-prop-308-2"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo ha beneficiado la Prop 308 a los Dreamers de Arizona?<\/title>\n<meta name=\"description\" content=\"Conoce la historia de Mar\u00eda Le\u00f3n y c\u00f3mo ha beneficiado la Prop 308 y el acceso a matr\u00edcula estatal a los Dreamers de Arizona.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo ha beneficiado la Prop 308 a los Dreamers de Arizona? | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Conoce la historia de Mar\u00eda Le\u00f3n y c\u00f3mo ha beneficiado la Prop 308 y el acceso a matr\u00edcula estatal a los Dreamers de Arizona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-10T23:44:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-10T23:50:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/Prop308dreamersarizona.png\" \/>\n\t<meta property=\"og:image:width\" content=\"551\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Apoyos Sociales Apoyos Sociales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00bfC\u00f3mo ha beneficiado la Prop 308 a los Dreamers de Arizona? | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Conoce la historia de Mar\u00eda Le\u00f3n y c\u00f3mo ha beneficiado la Prop 308 y el acceso a matr\u00edcula estatal a los Dreamers de Arizona.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/Prop308dreamersarizona.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Apoyos Sociales Apoyos Sociales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\\\/apoyo-social\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\\\/apoyo-social\\\/\"},\"author\":{\"name\":\"Apoyos Sociales Apoyos Sociales\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2d4cfb2c54accad189944e54dc18182a\"},\"headline\":\"\u00bfC\u00f3mo ha beneficiado la Prop 308 a los Dreamers de Arizona?\",\"datePublished\":\"2024-06-10T23:44:18+00:00\",\"dateModified\":\"2024-06-10T23:50:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\\\/apoyo-social\\\/\"},\"wordCount\":694,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\\\/apoyo-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Prop308dreamersarizona.png\",\"keywords\":[\"Aliento AZ\",\"Dreamers\",\"Mar\u00eda Le\u00f3n\",\"Matr\u00edcula estatal\",\"Prop 308\"],\"articleSection\":[\"Apoyo Social\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\\\/apoyo-social\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\\\/apoyo-social\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\\\/apoyo-social\\\/\",\"name\":\"\u00bfC\u00f3mo ha beneficiado la Prop 308 a los Dreamers de Arizona?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\\\/apoyo-social\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\\\/apoyo-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Prop308dreamersarizona.png\",\"datePublished\":\"2024-06-10T23:44:18+00:00\",\"dateModified\":\"2024-06-10T23:50:05+00:00\",\"description\":\"Conoce la historia de Mar\u00eda Le\u00f3n y c\u00f3mo ha beneficiado la Prop 308 y el acceso a matr\u00edcula estatal a los Dreamers de Arizona.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\\\/apoyo-social\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\\\/apoyo-social\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\\\/apoyo-social\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Prop308dreamersarizona.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Prop308dreamersarizona.png\",\"width\":551,\"height\":267,\"caption\":\"dreamers arizona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\\\/apoyo-social\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apoyo Social\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/apoyo-social\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfC\u00f3mo ha beneficiado la Prop 308 a los Dreamers de Arizona?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2d4cfb2c54accad189944e54dc18182a\",\"name\":\"Apoyos Sociales Apoyos Sociales\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo ha beneficiado la Prop 308 a los Dreamers de Arizona?","description":"Conoce la historia de Mar\u00eda Le\u00f3n y c\u00f3mo ha beneficiado la Prop 308 y el acceso a matr\u00edcula estatal a los Dreamers de Arizona.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfC\u00f3mo ha beneficiado la Prop 308 a los Dreamers de Arizona? | Acceso Latino","og_description":"Conoce la historia de Mar\u00eda Le\u00f3n y c\u00f3mo ha beneficiado la Prop 308 y el acceso a matr\u00edcula estatal a los Dreamers de Arizona.","og_url":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2024-06-10T23:44:18+00:00","article_modified_time":"2024-06-10T23:50:05+00:00","og_image":[{"width":551,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/Prop308dreamersarizona.png","type":"image\/png"}],"author":"Apoyos Sociales Apoyos Sociales","twitter_card":"summary_large_image","twitter_title":"\u00bfC\u00f3mo ha beneficiado la Prop 308 a los Dreamers de Arizona? | Acceso Latino","twitter_description":"Conoce la historia de Mar\u00eda Le\u00f3n y c\u00f3mo ha beneficiado la Prop 308 y el acceso a matr\u00edcula estatal a los Dreamers de Arizona.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/Prop308dreamersarizona.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Apoyos Sociales Apoyos Sociales","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/"},"author":{"name":"Apoyos Sociales Apoyos Sociales","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2d4cfb2c54accad189944e54dc18182a"},"headline":"\u00bfC\u00f3mo ha beneficiado la Prop 308 a los Dreamers de Arizona?","datePublished":"2024-06-10T23:44:18+00:00","dateModified":"2024-06-10T23:50:05+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/"},"wordCount":694,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/Prop308dreamersarizona.png","keywords":["Aliento AZ","Dreamers","Mar\u00eda Le\u00f3n","Matr\u00edcula estatal","Prop 308"],"articleSection":["Apoyo Social"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/","url":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/","name":"\u00bfC\u00f3mo ha beneficiado la Prop 308 a los Dreamers de Arizona?","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/Prop308dreamersarizona.png","datePublished":"2024-06-10T23:44:18+00:00","dateModified":"2024-06-10T23:50:05+00:00","description":"Conoce la historia de Mar\u00eda Le\u00f3n y c\u00f3mo ha beneficiado la Prop 308 y el acceso a matr\u00edcula estatal a los Dreamers de Arizona.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/Prop308dreamersarizona.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/06\/Prop308dreamersarizona.png","width":551,"height":267,"caption":"dreamers arizona"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/como-ha-beneficiado-la-prop-308-a-los-dreamers-de-arizona\/apoyo-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Apoyo Social","item":"https:\/\/accesolatino.org\/en\/category\/apoyo-social\/"},{"@type":"ListItem","position":3,"name":"\u00bfC\u00f3mo ha beneficiado la Prop 308 a los Dreamers de Arizona?"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2d4cfb2c54accad189944e54dc18182a","name":"Apoyos Sociales Apoyos Sociales"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/54769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=54769"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/54769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/54770"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=54769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=54769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=54769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}