{"id":54520,"date":"2024-05-15T14:20:02","date_gmt":"2024-05-15T20:20:02","guid":{"rendered":"https:\/\/accesolatino.org\/?p=54520"},"modified":"2024-05-15T14:25:08","modified_gmt":"2024-05-15T20:25:08","slug":"en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/","title":{"rendered":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"54520\" class=\"elementor elementor-54520\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2d7b39 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"b2d7b39\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60250c5a\" data-id=\"60250c5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6825cbef elementor-widget elementor-widget-heading\" data-id=\"6825cbef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El Servicio de Impuestos Internos ofrece diversas modalidades para acceder a una pr\u00f3rroga en la declaraci\u00f3n de impuestos anuales.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-207b8639 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"207b8639\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d504036\" data-id=\"7d504036\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ca7e988 elementor-widget elementor-widget-text-editor\" data-id=\"1ca7e988\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aun despu\u00e9s de que pase la fecha l\u00edmite de presentaci\u00f3n de la declaraci\u00f3n de impuestos de los Servicios de Impuestos Internos (IRS) es posible solicitar una pr\u00f3rroga o extensi\u00f3n al presentar el Formulario 4868. Esto permitir\u00eda obtener una extensi\u00f3n autom\u00e1tica hasta el 15 de octubre de 2024.<\/p><p>No obstante, es importante tener en cuenta que esta pr\u00f3rroga solo se aplica al tiempo para presentar la declaraci\u00f3n, no al tiempo para pagar los impuestos adeudados. En caso de tener impuestos pendientes, es necesario pagarlos antes de la fecha l\u00edmite original para evitar multas e intereses adicionales.<\/p><p>La informaci\u00f3n proporcionada por el IRS explica c\u00f3mo solicitar una pr\u00f3rroga de tiempo para presentar la declaraci\u00f3n de impuestos federales. Aqu\u00ed hay algunos puntos clave a tener en cuenta:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74fdb624 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"74fdb624\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aaf725e\" data-id=\"aaf725e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fd9172 elementor-widget elementor-widget-image\" data-id=\"8fd9172\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"601\" height=\"338\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg\" class=\"attachment-full size-full wp-image-20020\" alt=\"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg 601w, https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos-300x169.jpg 300w\" sizes=\"(max-width: 601px) 100vw, 601px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3b1dbf3e\" data-id=\"3b1dbf3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59b9ec49 elementor-widget elementor-widget-text-editor\" data-id=\"59b9ec49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En primer lugar, como se mencion\u00f3 anteriormente, una pr\u00f3rroga de tiempo para presentar la declaraci\u00f3n no aplaza el plazo para pagar los impuestos adeudados. Debes estimar y pagar cualquier impuesto adeudado para la fecha de vencimiento regular para evitar multas.<\/p><p>Otro dato importante es que debes presentar tu solicitud de pr\u00f3rroga a m\u00e1s tardar en la fecha de vencimiento regular para presentar tu declaraci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-438553be elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"438553be\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b0a07a8\" data-id=\"1b0a07a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c60e0e8 elementor-widget elementor-widget-text-editor\" data-id=\"3c60e0e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La presentaci\u00f3n electr\u00f3nica es gratuita. Los contribuyentes individuales pueden utilizar Free File del IRS para solicitar electr\u00f3nicamente una pr\u00f3rroga autom\u00e1tica para la presentaci\u00f3n de los impuestos. Esto te otorga hasta el 15 de octubre para presentar la declaraci\u00f3n.<\/p><p>Finalmente, tambi\u00e9n puedes obtener una pr\u00f3rroga al pagar electr\u00f3nicamente todo o parte de tu impuesto sobre los ingresos estimados adeudados e indicar que el pago es para una pr\u00f3rroga.<\/p><p>Por otro lado, cabe destacar la importancia de los formularios de pr\u00f3rroga seg\u00fan el estado civil.\u00a0 Es decir, existen diferentes formularios de pr\u00f3rroga dependiendo del estado civil para efectos de la declaraci\u00f3n, como el Formulario 4868 para individuos o el Formulario 7004 para negocios y sociedades an\u00f3nimas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-636436af elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"636436af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-590f5a29\" data-id=\"590f5a29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-586de5b elementor-widget elementor-widget-toggle\" data-id=\"586de5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9271\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-9271\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-9271\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-9271\"><p><strong>IRS<\/strong><\/p><p><a href=\"https:\/\/www.irs.gov\/es\/forms-pubs\/extension-of-time-to-file-your-tax-return\">https:\/\/www.irs.gov\/es\/forms-pubs\/extension-of-time-to-file-your-tax-return<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El Servicio de Impuestos Internos ofrece diversas modalidades para acceder a una prorroga en la declaraci\u00f3n de impuestos anuales.<\/p>","protected":false},"author":13,"featured_media":20020,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10],"tags":[1234,1390,320,321,2946],"class_list":["post-54520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-declaracion-de-impuestos","tag-extension","tag-impuestos","tag-irs","tag-prorroga-2"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Servicio de Impuestos Internos ofrece diversas modalidades para acceder a una prorroga en la declaraci\u00f3n de impuestos anuales.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Noticias\"\/>\n\t<meta name=\"google-site-verification\" content=\"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE\" \/>\n\t<meta name=\"keywords\" content=\"declaraci\u00f3n de impuestos,extensi\u00f3n,impuestos,irs,pr\u00f3rroga,noticias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?\" \/>\n\t\t<meta property=\"og:description\" content=\"El Servicio de Impuestos Internos ofrece diversas modalidades para acceder a una prorroga en la declaraci\u00f3n de impuestos anuales.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-05-15T20:20:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-05-15T20:25:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Servicio de Impuestos Internos ofrece diversas modalidades para acceder a una prorroga en la declaraci\u00f3n de impuestos anuales.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#blogposting\",\"name\":\"\\u00bfEn qu\\u00e9 consiste la pr\\u00f3rroga para la declaraci\\u00f3n de impuestos en EE.UU.?\",\"headline\":\"\\u00bfEn qu\\u00e9 consiste la pr\\u00f3rroga para la declaraci\\u00f3n de impuestos en EE.UU.?\",\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\\u00f3n-de-impuestos.jpg\",\"width\":601,\"height\":338,\"caption\":\"Inmigrantes e indocumentados deben presentar su declaraci\\u00f3n de impuestos\"},\"datePublished\":\"2024-05-15T14:20:02-06:00\",\"dateModified\":\"2024-05-15T14:25:08-06:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#webpage\"},\"articleSection\":\"Noticias, Declaraci\\u00f3n de impuestos, Extensi\\u00f3n, Impuestos, IRS, Pr\\u00f3rroga\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#listItem\",\"name\":\"\\u00bfEn qu\\u00e9 consiste la pr\\u00f3rroga para la declaraci\\u00f3n de impuestos en EE.UU.?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#listItem\",\"position\":3,\"name\":\"\\u00bfEn qu\\u00e9 consiste la pr\\u00f3rroga para la declaraci\\u00f3n de impuestos en EE.UU.?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#organizationLogo\",\"width\":240,\"height\":40},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/\",\"name\":\"Noticias\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#webpage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/\",\"name\":\"\\u00bfEn qu\\u00e9 consiste la pr\\u00f3rroga para la declaraci\\u00f3n de impuestos en EE.UU.?\",\"description\":\"El Servicio de Impuestos Internos ofrece diversas modalidades para acceder a una prorroga en la declaraci\\u00f3n de impuestos anuales.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\\u00f3n-de-impuestos.jpg\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#mainImage\",\"width\":601,\"height\":338,\"caption\":\"Inmigrantes e indocumentados deben presentar su declaraci\\u00f3n de impuestos\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#mainImage\"},\"datePublished\":\"2024-05-15T14:20:02-06:00\",\"dateModified\":\"2024-05-15T14:25:08-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?","description":"El Servicio de Impuestos Internos ofrece diversas modalidades para acceder a una prorroga en la declaraci\u00f3n de impuestos anuales.","canonical_url":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/","robots":"max-image-preview:large","keywords":"declaraci\u00f3n de impuestos,extensi\u00f3n,impuestos,irs,pr\u00f3rroga,noticias","webmasterTools":{"google-site-verification":"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#blogposting","name":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?","headline":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?","author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg","width":601,"height":338,"caption":"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos"},"datePublished":"2024-05-15T14:20:02-06:00","dateModified":"2024-05-15T14:25:08-06:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#webpage"},"isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#webpage"},"articleSection":"Noticias, Declaraci\u00f3n de impuestos, Extensi\u00f3n, Impuestos, IRS, Pr\u00f3rroga"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","position":1,"name":"Home","item":"https:\/\/accesolatino.org\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/en\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#listItem","name":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#listItem","position":3,"name":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?","previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/en\/#organization","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","@id":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#organizationLogo","width":240,"height":40},"image":{"@id":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author","url":"https:\/\/accesolatino.org\/en\/author\/noticias\/","name":"Noticias"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#webpage","url":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/","name":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?","description":"El Servicio de Impuestos Internos ofrece diversas modalidades para acceder a una prorroga en la declaraci\u00f3n de impuestos anuales.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#breadcrumblist"},"author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"creator":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg","@id":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#mainImage","width":601,"height":338,"caption":"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#mainImage"},"datePublished":"2024-05-15T14:20:02-06:00","dateModified":"2024-05-15T14:25:08-06:00"},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/en\/#website","url":"https:\/\/accesolatino.org\/en\/","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","inLanguage":"en-US","publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim","og:type":"article","og:title":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?","og:description":"El Servicio de Impuestos Internos ofrece diversas modalidades para acceder a una prorroga en la declaraci\u00f3n de impuestos anuales.","og:url":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/","article:published_time":"2024-05-15T20:20:02+00:00","article:modified_time":"2024-05-15T20:25:08+00:00","twitter:card":"summary_large_image","twitter:title":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?","twitter:description":"El Servicio de Impuestos Internos ofrece diversas modalidades para acceder a una prorroga en la declaraci\u00f3n de impuestos anuales."},"aioseo_meta_data":{"post_id":"54520","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-05-15 20:20:02","updated":"2025-06-06 08:53:38","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/accesolatino.org\/en"},{"label":"Noticias","link":"https:\/\/accesolatino.org\/en\/category\/noticias\/"},{"label":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?","link":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?<\/title>\n<meta name=\"description\" content=\"Conoce c\u00f3mo solicitarla y en qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos ante el Servicio de Impuestos Internos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.? | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Conoce c\u00f3mo solicitarla y en qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos ante el Servicio de Impuestos Internos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-15T20:20:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-15T20:25:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"601\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.? | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Conoce c\u00f3mo solicitarla y en qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos ante el Servicio de Impuestos Internos.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\"},\"headline\":\"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?\",\"datePublished\":\"2024-05-15T20:20:02+00:00\",\"dateModified\":\"2024-05-15T20:25:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/\"},\"wordCount\":379,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg\",\"keywords\":[\"Declaraci\u00f3n de impuestos\",\"Extensi\u00f3n\",\"Impuestos\",\"IRS\",\"Pr\u00f3rroga\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/\",\"name\":\"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg\",\"datePublished\":\"2024-05-15T20:20:02+00:00\",\"dateModified\":\"2024-05-15T20:25:08+00:00\",\"description\":\"Conoce c\u00f3mo solicitarla y en qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos ante el Servicio de Impuestos Internos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg\",\"width\":601,\"height\":338,\"caption\":\"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?","description":"Conoce c\u00f3mo solicitarla y en qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos ante el Servicio de Impuestos Internos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.? | Acceso Latino","og_description":"Conoce c\u00f3mo solicitarla y en qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos ante el Servicio de Impuestos Internos.","og_url":"https:\/\/accesolatino.org\/en\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2024-05-15T20:20:02+00:00","article_modified_time":"2024-05-15T20:25:08+00:00","og_image":[{"width":601,"height":338,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg","type":"image\/jpeg"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_title":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.? | Acceso Latino","twitter_description":"Conoce c\u00f3mo solicitarla y en qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos ante el Servicio de Impuestos Internos.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905"},"headline":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?","datePublished":"2024-05-15T20:20:02+00:00","dateModified":"2024-05-15T20:25:08+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/"},"wordCount":379,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg","keywords":["Declaraci\u00f3n de impuestos","Extensi\u00f3n","Impuestos","IRS","Pr\u00f3rroga"],"articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/","url":"https:\/\/accesolatino.org\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/","name":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg","datePublished":"2024-05-15T20:20:02+00:00","dateModified":"2024-05-15T20:25:08+00:00","description":"Conoce c\u00f3mo solicitarla y en qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos ante el Servicio de Impuestos Internos.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg","width":601,"height":338,"caption":"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en-que-consiste-la-prorroga-para-la-declaracion-de-impuestos-en-ee-uu\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"\u00bfEn qu\u00e9 consiste la pr\u00f3rroga para la declaraci\u00f3n de impuestos en EE.UU.?"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/54520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=54520"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/54520\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/20020"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=54520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=54520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=54520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}