{"id":54048,"date":"2024-03-27T08:26:00","date_gmt":"2024-03-27T14:26:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=54048"},"modified":"2024-03-25T18:36:34","modified_gmt":"2024-03-26T00:36:34","slug":"soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/","title":{"rendered":"Soy inmigrante en EE.UU. y tengo hijos menores de edad, \u00bfc\u00f3mo puedo inscribirlos a la escuela?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"54048\" class=\"elementor elementor-54048\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1e72ab elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"c1e72ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2420a45c\" data-id=\"2420a45c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54048dc6 elementor-widget elementor-widget-heading\" data-id=\"54048dc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conoce qu\u00e9 necesitas saber para inscribir a tu hijo a una escuela en Estados Unidos.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e445318 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3e445318\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f85d273\" data-id=\"6f85d273\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d0baa4 elementor-widget elementor-widget-text-editor\" data-id=\"6d0baa4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Buscar, encontrar e inscribir a tus hijos a la escuela es un paso muy importante como inmigrante reci\u00e9n llegado a Estados Unidos. Este proceso es importante, ya que no solo garantiza el acceso a la educaci\u00f3n, sino que tambi\u00e9n brinda estabilidad y oportunidades para el desarrollo acad\u00e9mico y personal de tus hijos. La educaci\u00f3n formal para los ni\u00f1os no solo les proporciona conocimientos fundamentales, sino que tambi\u00e9n les ayuda a integrarse en la sociedad, aprender ingl\u00e9s y adaptarse a su nuevo entorno.<\/p><p>El primer paso es investigar acerca de las escuelas m\u00e1s cercanas a tu lugar de residencia y la que mejor se adapte a las necesidades de tus hijos y a su nivel grado acad\u00e9mico, esta informaci\u00f3n la puedes encontrar directamente en la oficina del distrito escolar correspondiente.<\/p><p>En Estados Unidos se utiliza el t\u00e9rmino K-12, para clasificar a la educaci\u00f3n gratuita, la K hace referencia al kindergarten que comienza a los cinco a\u00f1os de edad y a 12, que es el \u00faltimo grado de escolarizaci\u00f3n y que concluye generalmente a los 18 a\u00f1os.<\/p><p>En el sistema educativo estadounidense existen tres categor\u00edas principales: Elementary School generalmente equivale a cinco a\u00f1os, de 1\u00ba a 5\u00ba grado; middle school que equivale a tres a\u00f1os, de 6\u00ba a 8\u00ba grado; y finalmente cuatro a\u00f1os de high school de 9\u00ba a 12\u00ba grado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ad18370 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6ad18370\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4ebb285f\" data-id=\"4ebb285f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38be96a1 elementor-widget elementor-widget-image\" data-id=\"38be96a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"553\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png\" class=\"attachment-full size-full wp-image-54051\" alt=\"escuela migrante menor de edad\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png 553w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela-18x9.png 18w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-28170be1\" data-id=\"28170be1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5206d8c elementor-widget elementor-widget-text-editor\" data-id=\"5206d8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Documentaci\u00f3n necesaria<\/strong><\/p><p>Al encontrar una escuela, es necesario reunir la documentaci\u00f3n requerida. Por lo general, necesitar\u00e1s ciertos documentos para inscribir a tus hijos en la escuela, como certificado de nacimiento, registros de vacunaci\u00f3n, comprobante de residencia, comprobantes de ingresos, entre otros. Los requisitos en la documentaci\u00f3n pueden variar dependiendo del estado, la escuela y el grado que estudie tu hijo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71a3bf7a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"71a3bf7a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf79445\" data-id=\"cf79445\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ad17f7 elementor-widget elementor-widget-text-editor\" data-id=\"6ad17f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Education for all<\/strong><\/p><p>Muchos inmigrantes, especialmente quienes se encuentran en situaci\u00f3n irregular pueden tener dudas acerca de la inscripci\u00f3n de sus hijos a una escuela p\u00fablica. En este caso, cabe destacar, que, en 1982, la Corte Suprema de Estados Unidos dictamin\u00f3 en el caso Plyler v. Doe que los ni\u00f1os indocumentados tienen derecho a recibir educaci\u00f3n p\u00fablica gratuita en Estados Unidos.<\/p><p>La Corte consider\u00f3 que negar la educaci\u00f3n a los ni\u00f1os indocumentados violaba la Cl\u00e1usula de Protecci\u00f3n Igualitaria de la Decimocuarta Enmienda de la Constituci\u00f3n, que establece que ninguna persona dentro de la jurisdicci\u00f3n de un estado puede ser privada de igual protecci\u00f3n de las leyes. Este fallo estableci\u00f3 que <strong>los ni\u00f1os, independientemente de su estatus migratorio, tienen derecho a recibir educaci\u00f3n p\u00fablica gratuita en Estados Unidos.<\/strong><\/p><p><strong>Mi hijo no habla ingl\u00e9s<\/strong><\/p><p>Para los ni\u00f1os inmigrantes, el idioma es uno de los principales desaf\u00edos, sin embargo, es una situaci\u00f3n regulada por el gobierno. El discreto escolar est\u00e1 obligado a proveer educaci\u00f3n gratuita del idioma ingl\u00e9s a tu hijo para acelerar su regularizaci\u00f3n.<\/p><p>Finalmente, es importante que, aunque el a\u00f1o escolar comienza entre agosto y septiembre, inscribas a tu hijo a la escuela lo antes posible.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5018a74b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5018a74b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4814fa8c\" data-id=\"4814fa8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59d451f4 elementor-widget elementor-widget-toggle\" data-id=\"59d451f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1501\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1501\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1501\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1501\"><p><strong>IMMIGREAT<\/strong><\/p><p><a href=\"https:\/\/www.inmigreat.com\/blogs-en\/como-inscribir-a-tus-hijos-en-la-escuela-publica-en-estados-unidos\">https:\/\/www.inmigreat.com\/blogs-en\/como-inscribir-a-tus-hijos-en-la-escuela-publica-en-estados-unidos<\/a><\/p><p><strong>US IMMIGRATION APPLICATION<\/strong><\/p><p><a href=\"https:\/\/www.usimmigrationapplication.org\/immigration-news\/how-enroll-child-school-usa\">https:\/\/www.usimmigrationapplication.org\/immigration-news\/how-enroll-child-school-usa<\/a><\/p><p><strong>USA HELLO<\/strong><\/p><p><a href=\"https:\/\/usahello.org\/education\/children\/register-child-in-school\/\">https:\/\/usahello.org\/education\/children\/register-child-in-school\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Conoce qu\u00e9 necesitas saber para inscribir a tu hijo a una escuela en Estados Unidos.<\/p>","protected":false},"author":13,"featured_media":54051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1933,13,157,1],"tags":[2877,2219,2876,2696,87],"class_list":["post-54048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-becas-y-educacion","category-educacion","category-red-de-apoyo","category-temas-de-interes","tag-distrito-escolar","tag-documentacion","tag-escuela","tag-hijos","tag-inmigrantes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soy inmigrante en EE.UU. y tengo hijos menores de edad, \u00bfc\u00f3mo puedo inscribirlos a la escuela?<\/title>\n<meta name=\"description\" content=\"Soy inmigrante en Estados Unidos y tengo hijos menores de edad, c\u00f3mo puedo inscribirlos a la escuela y cu\u00e1les son los requisitos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soy inmigrante en EE.UU. y tengo hijos menores de edad, \u00bfc\u00f3mo puedo inscribirlos a la escuela? | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Soy inmigrante en Estados Unidos y tengo hijos menores de edad, c\u00f3mo puedo inscribirlos a la escuela y cu\u00e1les son los requisitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-27T14:26:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Soy inmigrante en EE.UU. y tengo hijos menores de edad, \u00bfc\u00f3mo puedo inscribirlos a la escuela? | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Soy inmigrante en Estados Unidos y tengo hijos menores de edad, c\u00f3mo puedo inscribirlos a la escuela y cu\u00e1les son los requisitos.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\\\/becas-y-educacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\\\/becas-y-educacion\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\"},\"headline\":\"Soy inmigrante en EE.UU. y tengo hijos menores de edad, \u00bfc\u00f3mo puedo inscribirlos a la escuela?\",\"datePublished\":\"2024-03-27T14:26:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\\\/becas-y-educacion\\\/\"},\"wordCount\":575,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\\\/becas-y-educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png\",\"keywords\":[\"Distrito Escolar\",\"Documentaci\u00f3n\",\"Escuela\",\"Hijos\",\"Inmigrantes\"],\"articleSection\":[\"Becas y Educaci\u00f3n\",\"Educaci\u00f3n\",\"Red de apoyo\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\\\/becas-y-educacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\\\/becas-y-educacion\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\\\/becas-y-educacion\\\/\",\"name\":\"Soy inmigrante en EE.UU. y tengo hijos menores de edad, \u00bfc\u00f3mo puedo inscribirlos a la escuela?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\\\/becas-y-educacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\\\/becas-y-educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png\",\"datePublished\":\"2024-03-27T14:26:00+00:00\",\"description\":\"Soy inmigrante en Estados Unidos y tengo hijos menores de edad, c\u00f3mo puedo inscribirlos a la escuela y cu\u00e1les son los requisitos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\\\/becas-y-educacion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\\\/becas-y-educacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\\\/becas-y-educacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png\",\"width\":553,\"height\":267,\"caption\":\"escuela migrante menor de edad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\\\/becas-y-educacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Becas y Educaci\u00f3n\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/becas-y-educacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Soy inmigrante en EE.UU. y tengo hijos menores de edad, \u00bfc\u00f3mo puedo inscribirlos a la escuela?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soy inmigrante en EE.UU. y tengo hijos menores de edad, \u00bfc\u00f3mo puedo inscribirlos a la escuela?","description":"Soy inmigrante en Estados Unidos y tengo hijos menores de edad, c\u00f3mo puedo inscribirlos a la escuela y cu\u00e1les son los requisitos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/","og_locale":"en_US","og_type":"article","og_title":"Soy inmigrante en EE.UU. y tengo hijos menores de edad, \u00bfc\u00f3mo puedo inscribirlos a la escuela? | Acceso Latino","og_description":"Soy inmigrante en Estados Unidos y tengo hijos menores de edad, c\u00f3mo puedo inscribirlos a la escuela y cu\u00e1les son los requisitos.","og_url":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2024-03-27T14:26:00+00:00","og_image":[{"width":553,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_title":"Soy inmigrante en EE.UU. y tengo hijos menores de edad, \u00bfc\u00f3mo puedo inscribirlos a la escuela? | Acceso Latino","twitter_description":"Soy inmigrante en Estados Unidos y tengo hijos menores de edad, c\u00f3mo puedo inscribirlos a la escuela y cu\u00e1les son los requisitos.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b"},"headline":"Soy inmigrante en EE.UU. y tengo hijos menores de edad, \u00bfc\u00f3mo puedo inscribirlos a la escuela?","datePublished":"2024-03-27T14:26:00+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/"},"wordCount":575,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png","keywords":["Distrito Escolar","Documentaci\u00f3n","Escuela","Hijos","Inmigrantes"],"articleSection":["Becas y Educaci\u00f3n","Educaci\u00f3n","Red de apoyo","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/","url":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/","name":"Soy inmigrante en EE.UU. y tengo hijos menores de edad, \u00bfc\u00f3mo puedo inscribirlos a la escuela?","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png","datePublished":"2024-03-27T14:26:00+00:00","description":"Soy inmigrante en Estados Unidos y tengo hijos menores de edad, c\u00f3mo puedo inscribirlos a la escuela y cu\u00e1les son los requisitos.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/soy_migrante_y_tengo_ninos_menores_de_edad_como_puedo_meterlos_a_la_escuela.png","width":553,"height":267,"caption":"escuela migrante menor de edad"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/soy-inmigrante-en-ee-uu-y-tengo-hijos-menores-de-edad-como-puedo-inscribirlos-a-la-escuela\/becas-y-educacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Becas y Educaci\u00f3n","item":"https:\/\/accesolatino.org\/category\/becas-y-educacion\/"},{"@type":"ListItem","position":3,"name":"Soy inmigrante en EE.UU. y tengo hijos menores de edad, \u00bfc\u00f3mo puedo inscribirlos a la escuela?"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/54048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=54048"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/54048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/54051"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=54048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=54048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=54048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}