{"id":53892,"date":"2024-03-08T12:02:05","date_gmt":"2024-03-08T18:02:05","guid":{"rendered":"https:\/\/accesolatino.org\/?p=53892"},"modified":"2024-03-08T12:05:47","modified_gmt":"2024-03-08T18:05:47","slug":"puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/","title":{"rendered":"\u00bfPuede un menor de edad con padre o madre estadounidense solicitar la residencia?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"53892\" class=\"elementor elementor-53892\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8c5635 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"e8c5635\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f536308\" data-id=\"6f536308\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52f2c57c elementor-widget elementor-widget-heading\" data-id=\"52f2c57c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La residencia legal en Estados Unidos est\u00e1 disponible para cualquier persona con al menos un padre estadounidense. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-332c6553 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"332c6553\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad6911b\" data-id=\"ad6911b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3644a6e1 elementor-widget elementor-widget-text-editor\" data-id=\"3644a6e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si eres menor de edad y tu madre o padre es ciudadano estadounidense, puedes ser elegible para obtener la residencia en Estados Unidos. Como hijo o hija de ciudadano estadounidense, puedes calificar para la Green Card a trav\u00e9s del proceso de petici\u00f3n de familiar inmediato. Las hijas o hijos solteros de un ciudadano o ciudadana estadounidense que sean menores de 21 a\u00f1os son elegibles para obtener la residencia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31a40c46 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"31a40c46\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-776f5685\" data-id=\"776f5685\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2822a236 elementor-widget elementor-widget-image\" data-id=\"2822a236\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"553\" height=\"267\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/ciudadania_con_padres.png\" class=\"attachment-full size-full wp-image-53894\" alt=\"ciudadania con padres\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/ciudadania_con_padres.png 553w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/ciudadania_con_padres-300x145.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/ciudadania_con_padres-18x9.png 18w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-13a4219\" data-id=\"13a4219\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18263cb9 elementor-widget elementor-widget-text-editor\" data-id=\"18263cb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Este proceso var\u00eda dependiendo de si est\u00e1s dentro o fuera de Estados Unidos al momento de solicitar la residencia. Si est\u00e1s fuera de Estados Unidos, tu padre debe presentar el Formulario I-130, Petici\u00f3n para Familiar Extranjero, ante el Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos (USCIS). Una vez aprobada la petici\u00f3n, generalmente se env\u00eda al Centro Nacional de Visas (NVC) y luego a la embajada o consulado de Estados Unidos en tu pa\u00eds de origen para continuar el proceso de visa de inmigrante.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d0cf78 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2d0cf78\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6125b294\" data-id=\"6125b294\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b2dd70d elementor-widget elementor-widget-text-editor\" data-id=\"1b2dd70d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En cuanto a los formularios necesarios para iniciar y completar este proceso se encuentran los siguientes:<\/p><ul><li>Formulario I-130, Petici\u00f3n para Familiar Extranjero: Este formulario debe ser completado por el padre o madre que es ciudadano estadounidense y se presenta ante USCIS.<\/li><li>Formulario DS-260: Si est\u00e1s fuera de Estados Unidos, este formulario es necesario para solicitar la visa de inmigrante en la embajada o consulado de Estados Unidos en tu pa\u00eds de origen.<\/li><\/ul><p>Es posible que se requieran otros formularios, pero esto depende de la situaci\u00f3n particular de cada caso. Asimismo, suelen ser necesarios documentos como certificados de nacimiento, pasaportes, fotograf\u00edas, evidencia de la relaci\u00f3n familiar, entre otros.<\/p><p>Para evitar el \u201caging out\u201d, es decir, cuando los menores cumplen la mayor\u00eda de edad despu\u00e9s de presentar su solicitud y antes de recibir su LPR, existe la Ley de Protecci\u00f3n del Estatus del Menor (CPSA) ley que \u201ccongela\u201d la edad de los menores solicitantes de LPR, para evitar que se vean afectados por retrasos en tiempos de procesamiento de las solicitudes.<\/p><p>Por ejemplo, un padre que present\u00f3 la solicitud para su hija de 17 a\u00f1os, podr\u00eda recibir su Green Card, a\u00f1os despu\u00e9s, incluso cuando ella haya cumplido la mayor\u00eda de edad.\u00a0 En estos casos, la CSPA, permite que los j\u00f3venes sigan siendo elegibles al congelar su edad y tomar en cuenta la edad que ten\u00edan al momento de presentar la solicitud.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-664b3412 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"664b3412\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20ec8916\" data-id=\"20ec8916\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3403360b elementor-widget elementor-widget-toggle\" data-id=\"3403360b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8721\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8721\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8721\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8721\"><p><strong>USCIS<\/strong><\/p><p><a href=\"https:\/\/www.uscis.gov\/es\/residencia-permanente-tarjeta-verde\/procesos-y-procedimientos-para-la-residencia-permanente\/ley-de-proteccion-del-estatus-del-menor\">https:\/\/www.uscis.gov\/es\/residencia-permanente-tarjeta-verde\/procesos-y-procedimientos-para-la-residencia-permanente\/ley-de-proteccion-del-estatus-del-menor<\/a><\/p><p><a href=\"https:\/\/www.uscis.gov\/es\/ciudadania\/aprenda-sobre-ciudadania\/soy-hijo-de-un-ciudadano-estadounidense\">https:\/\/www.uscis.gov\/es\/ciudadania\/aprenda-sobre-ciudadania\/soy-hijo-de-un-ciudadano-estadounidense<\/a><\/p><p><a href=\"https:\/\/www.uscis.gov\/es\/i-130\">https:\/\/www.uscis.gov\/es\/i-130<\/a><\/p><p><a href=\"https:\/\/www.uscis.gov\/es\/residencia-permanente-tarjeta-verde\/categorias-de-elegibilidad-a-la-residencia-permanente\/residencia-permanente-para-familiares-inmediatos-de-un-ciudadano-estadounidense\">https:\/\/www.uscis.gov\/es\/residencia-permanente-tarjeta-verde\/categorias-de-elegibilidad-a-la-residencia-permanente\/residencia-permanente-para-familiares-inmediatos-de-un-ciudadano-estadounidense<\/a><\/p><p><strong>DEPARTMENT OF STATE<\/strong><\/p><p><a href=\"https:\/\/travel.state.gov\/content\/travel\/en\/us-visas\/inmigracion\/preguntas-frecuentes---solicitud-electronica-de-visa-de-inmigrante-ds-260.html\">https:\/\/travel.state.gov\/content\/travel\/en\/us-visas\/inmigracion\/preguntas-frecuentes&#8212;solicitud-electronica-de-visa-de-inmigrante-ds-260.html<\/a><\/p><p><strong>USA GOV<\/strong><\/p><p><a href=\"https:\/\/www.usa.gov\/es\/solicitar-residencia-permanente-para-familiar\">https:\/\/www.usa.gov\/es\/solicitar-residencia-permanente-para-familiar<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La residencia legal en Estados Unidos est\u00e1 disponible para cualquier persona con al menos un padre estadounidense. <\/p>","protected":false},"author":13,"featured_media":53894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[90,157,12,1934],"tags":[133,2850,2481,2849,62],"class_list":["post-53892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apoyo-social","category-red-de-apoyo","category-tramites","category-tramites-y-permisos","tag-green-card","tag-hijos-menores","tag-i-130-2","tag-padres-estadounidenses","tag-residencia"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPuede un menor de edad con padre o madre estadounidense solicitar la residencia?<\/title>\n<meta name=\"description\" content=\"Puede un menor de edad con padre o madre estadounidense solicitar la residencia permanente legal; conoce c\u00f3mo funciona el proceso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPuede un menor de edad con padre o madre estadounidense solicitar la residencia? | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Puede un menor de edad con padre o madre estadounidense solicitar la residencia permanente legal; conoce c\u00f3mo funciona el proceso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-08T18:02:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-08T18:05:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/ciudadania_con_padres.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00bfPuede un menor de edad con padre o madre estadounidense solicitar la residencia? | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Puede un menor de edad con padre o madre estadounidense solicitar la residencia permanente legal; conoce c\u00f3mo funciona el proceso.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/ciudadania_con_padres.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\\\/tramites\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\\\/tramites\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"\u00bfPuede un menor de edad con padre o madre estadounidense solicitar la residencia?\",\"datePublished\":\"2024-03-08T18:02:05+00:00\",\"dateModified\":\"2024-03-08T18:05:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\\\/tramites\\\/\"},\"wordCount\":493,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\\\/tramites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ciudadania_con_padres.png\",\"keywords\":[\"Green Card\",\"Hijos menores\",\"I-130\",\"Padres estadounidenses\",\"Residencia\"],\"articleSection\":[\"Apoyo Social\",\"Red de apoyo\",\"Tr\u00e1mites\",\"Tr\u00e1mites y Permisos\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\\\/tramites\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\\\/tramites\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\\\/tramites\\\/\",\"name\":\"\u00bfPuede un menor de edad con padre o madre estadounidense solicitar la residencia?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\\\/tramites\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\\\/tramites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ciudadania_con_padres.png\",\"datePublished\":\"2024-03-08T18:02:05+00:00\",\"dateModified\":\"2024-03-08T18:05:47+00:00\",\"description\":\"Puede un menor de edad con padre o madre estadounidense solicitar la residencia permanente legal; conoce c\u00f3mo funciona el proceso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\\\/tramites\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\\\/tramites\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\\\/tramites\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ciudadania_con_padres.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ciudadania_con_padres.png\",\"width\":553,\"height\":267,\"caption\":\"ciudadania con padres\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\\\/tramites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tr\u00e1mites\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/tramites\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfPuede un menor de edad con padre o madre estadounidense solicitar la residencia?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPuede un menor de edad con padre o madre estadounidense solicitar la residencia?","description":"Puede un menor de edad con padre o madre estadounidense solicitar la residencia permanente legal; conoce c\u00f3mo funciona el proceso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfPuede un menor de edad con padre o madre estadounidense solicitar la residencia? | Acceso Latino","og_description":"Puede un menor de edad con padre o madre estadounidense solicitar la residencia permanente legal; conoce c\u00f3mo funciona el proceso.","og_url":"https:\/\/accesolatino.org\/en\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2024-03-08T18:02:05+00:00","article_modified_time":"2024-03-08T18:05:47+00:00","og_image":[{"width":553,"height":267,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/ciudadania_con_padres.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_title":"\u00bfPuede un menor de edad con padre o madre estadounidense solicitar la residencia? | Acceso Latino","twitter_description":"Puede un menor de edad con padre o madre estadounidense solicitar la residencia permanente legal; conoce c\u00f3mo funciona el proceso.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/ciudadania_con_padres.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"\u00bfPuede un menor de edad con padre o madre estadounidense solicitar la residencia?","datePublished":"2024-03-08T18:02:05+00:00","dateModified":"2024-03-08T18:05:47+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/"},"wordCount":493,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/ciudadania_con_padres.png","keywords":["Green Card","Hijos menores","I-130","Padres estadounidenses","Residencia"],"articleSection":["Apoyo Social","Red de apoyo","Tr\u00e1mites","Tr\u00e1mites y Permisos"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/","url":"https:\/\/accesolatino.org\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/","name":"\u00bfPuede un menor de edad con padre o madre estadounidense solicitar la residencia?","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/ciudadania_con_padres.png","datePublished":"2024-03-08T18:02:05+00:00","dateModified":"2024-03-08T18:05:47+00:00","description":"Puede un menor de edad con padre o madre estadounidense solicitar la residencia permanente legal; conoce c\u00f3mo funciona el proceso.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/ciudadania_con_padres.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/03\/ciudadania_con_padres.png","width":553,"height":267,"caption":"ciudadania con padres"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/puede-un-menor-de-edad-con-padre-o-madre-estadounidense-solicitar-la-residencia\/tramites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Tr\u00e1mites","item":"https:\/\/accesolatino.org\/category\/tramites\/"},{"@type":"ListItem","position":3,"name":"\u00bfPuede un menor de edad con padre o madre estadounidense solicitar la residencia?"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/53892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=53892"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/53892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/53894"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=53892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=53892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=53892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}