{"id":53692,"date":"2024-03-01T08:57:00","date_gmt":"2024-03-01T14:57:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=53692"},"modified":"2024-02-28T13:02:53","modified_gmt":"2024-02-28T19:02:53","slug":"conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/","title":{"rendered":"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"53692\" class=\"elementor elementor-53692\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-163b70ed elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"163b70ed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33339682\" data-id=\"33339682\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1c23f6 elementor-widget elementor-widget-heading\" data-id=\"b1c23f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Erica Alfaro es una escritora y oradora hija de trabajadores agr\u00edcolas inmigrantes originarios de Oaxaca, M\u00e9xico.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bde098b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7bde098b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59421eb6\" data-id=\"59421eb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73d9d00 elementor-widget elementor-widget-text-editor\" data-id=\"73d9d00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En 2019, Erica Alfaro salt\u00f3 a la fama luego de que se tomar\u00e1 fotos de graduaci\u00f3n con sus padres en los campos donde trabajaban sus padres en California. Ese a\u00f1o, a los 29 a\u00f1os, Alfaro obtuvo su maestr\u00eda en educaci\u00f3n por Universidad Estatal de San Diego, sin embargo, antes tuvo un largo recorrido que incluy\u00f3 abandonar su educaci\u00f3n a los 15 a\u00f1os.<\/p><p>Erica naci\u00f3 en Fresno, California, pero creci\u00f3 en Tijuana, Baja California. Durante esa \u00e9poca cruzaba la frontera diariamente para asistir a la escuela, sin embargo, cuando cumpli\u00f3 13 a\u00f1os se mud\u00f3 a Oceanside, California con su familia. Tanto ella como su hermano trabajaban en los campos agr\u00edcolas con sus padres durante las vacaciones de verano. Sus padres de origen mixteco nacieron en Oaxaca y emigraron a Estados Unidos por separado, y fue ah\u00ed donde se conocieron.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-289d82fe elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"289d82fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3188b249\" data-id=\"3188b249\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ad4a843 elementor-widget elementor-widget-image\" data-id=\"2ad4a843\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"460\" height=\"259\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/02\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg\" class=\"attachment-full size-full wp-image-53693\" alt=\"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/02\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg 460w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/02\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169-300x169.jpg 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/02\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169-18x10.jpg 18w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3cdfb796\" data-id=\"3cdfb796\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66d69ec4 elementor-widget elementor-widget-text-editor\" data-id=\"66d69ec4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cuando ten\u00eda 15 a\u00f1os, Alfaro qued\u00f3 embarazada y tuvo que abandonar sus estudios Posteriormente comenz\u00f3 a vivir con su pareja que ejerci\u00f3 violencia dom\u00e9stica sobre ella, situaci\u00f3n por la cual, despu\u00e9s de dar a luz, decidi\u00f3 regresar a casa con sus padres. A los 17 a\u00f1os retom\u00f3 sus estudios, pero ahora a trav\u00e9s de un programa de educaci\u00f3n en el hogar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64726e47 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"64726e47\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6cee07bd\" data-id=\"6cee07bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ca27c92 elementor-widget elementor-widget-text-editor\" data-id=\"7ca27c92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A\u00f1os despu\u00e9s, en 2017, logr\u00f3 graduarse de la universidad y obtener su t\u00edtulo de psicolog\u00eda y, adem\u00e1s, fue oradora en su ceremonia de graduaci\u00f3n. En 2019, una serie de fotograf\u00edas, donde aparec\u00eda Erica con toga y birrete acompa\u00f1ada de sus padres, en los campos de cultivo donde trabajaban, se viralizaron en internet. Esta sesi\u00f3n de fotos fue realizada con motivo de su graduaci\u00f3n de su maestr\u00eda en educaci\u00f3n con especializaci\u00f3n en consejer\u00eda.<\/p><p>Actualmente, Alfaro es escritora y oradora. Su libro <em>Harvesting Dreams<\/em> or <em>Cosechando Sue\u00f1os<\/em> obtuvo en 2022 el International Latino Book Award en la categor\u00eda Most Inspirational Young Adult. En dicho t\u00edtulo explora los desaf\u00edos y adversidades que enfrent\u00f3 como hija de inmigrantes para alcanzar el sue\u00f1o americano.<\/p><p>Por otra parte, entre los temas de sus conferencias destacan la educaci\u00f3n, resiliencia, liderazgo y \u00e9xito educativo. \u201cDurante mis conferencias y charlas siempre enfatiz\u00f3 que para que nuestras vidas cambien nosotros tenemos que tomar control de ella. Con mi historia motiva a mi audiencia a que tome 100% responsabilidad de su vida\u201d, expres\u00f3. Adem\u00e1s, mencion\u00f3 que siempre termina sus charlas con la siguiente frase: \u201cT\u00fa puedes usar tus adversidades como una excusa para detenerte, o como una raz\u00f3n para salir adelante\u201d.<\/p><p>Su reconocimiento ahora a nivel internacional le ha permitido obtener diversos premios como Latina Leadership Award por The City of Oceanside, una carta de reconocimiento firmada por la vicepresidenta Kamala Harris e incluso la proclamaci\u00f3n del d\u00eda 5 de octubre como Erica Alfaro&#8217;s Day por el Condado de San Diego.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-647b3f7b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"647b3f7b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-21636d63\" data-id=\"21636d63\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e42fdc8 elementor-widget elementor-widget-toggle\" data-id=\"5e42fdc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1581\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1581\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1581\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1581\"><p><strong>CNN EN ESPA\u00d1OL<\/strong><\/p><p><a href=\"https:\/\/cnnespanol.cnn.com\/2019\/05\/27\/fotos-que-inspiran-universitaria-se-toma-la-foto-de-su-graduacion-en-los-campos-donde-trabajan-sus-padres-inmigrantes\/\">https:\/\/cnnespanol.cnn.com\/2019\/05\/27\/fotos-que-inspiran-universitaria-se-toma-la-foto-de-su-graduacion-en-los-campos-donde-trabajan-sus-padres-inmigrantes\/<\/a><\/p><p><strong>ERICA ALFARO<\/strong><\/p><p><a href=\"https:\/\/ericaalfaro.com\/books\">https:\/\/ericaalfaro.com\/books<\/a><\/p><p><a href=\"https:\/\/ericaalfaro.com\/\">https:\/\/ericaalfaro.com\/<\/a><\/p><p><strong>INMIGRACI\u00d3N Y VISAS<\/strong><\/p><p><a href=\"https:\/\/www.inmigracionyvisas.com\/a4190-erica-alfaro-orgullosa-de-ser-hija-de-inmigrantes.html\">https:\/\/www.inmigracionyvisas.com\/a4190-erica-alfaro-orgullosa-de-ser-hija-de-inmigrantes.html<\/a><\/p><p><strong>EL LATINO ONLINE<\/strong><\/p><p><a href=\"https:\/\/ellatinoonline.com\/2024\/02\/08\/como-una-razon-para-salir-adelante-consejo-de-erica-alfaro\/\">https:\/\/ellatinoonline.com\/2024\/02\/08\/como-una-razon-para-salir-adelante-consejo-de-erica-alfaro\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Erica Alfaro es una escritora y oradora hija de trabajadores agr\u00edcolas inmigrantes originarios de Oaxaca, M\u00e9xico.<\/p>","protected":false},"author":14,"featured_media":53693,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9,30],"tags":[2834,2835,1858,2836,1008],"class_list":["post-53692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orgullo-latino","category-testimoniales","tag-erica-alfaro","tag-escritora","tag-latina","tag-oradora","tag-trabajadores-inmigrantes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas<\/title>\n<meta name=\"description\" content=\"Conoce la historia de Erica Alfaro, oradora y escritora premiada latina hija de trabajadores agr\u00edcolas inmigrantes de Oaxaca.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Conoce la historia de Erica Alfaro, oradora y escritora premiada latina hija de trabajadores agr\u00edcolas inmigrantes de Oaxaca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-01T14:57:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/02\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Testimoniales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Conoce la historia de Erica Alfaro, oradora y escritora premiada latina hija de trabajadores agr\u00edcolas inmigrantes de Oaxaca.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/02\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Testimoniales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\\\/orgullo-latino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\\\/orgullo-latino\\\/\"},\"author\":{\"name\":\"Testimoniales\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/f91b6c00888ce85395cb05edc01e916d\"},\"headline\":\"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas\",\"datePublished\":\"2024-03-01T14:57:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\\\/orgullo-latino\\\/\"},\"wordCount\":552,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\\\/orgullo-latino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg\",\"keywords\":[\"Erica Alfaro\",\"Escritora\",\"Latina\",\"Oradora\",\"Trabajadores inmigrantes\"],\"articleSection\":[\"Orgullo Latino\",\"Testimoniales\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\\\/orgullo-latino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\\\/orgullo-latino\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\\\/orgullo-latino\\\/\",\"name\":\"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\\\/orgullo-latino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\\\/orgullo-latino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg\",\"datePublished\":\"2024-03-01T14:57:00+00:00\",\"description\":\"Conoce la historia de Erica Alfaro, oradora y escritora premiada latina hija de trabajadores agr\u00edcolas inmigrantes de Oaxaca.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\\\/orgullo-latino\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\\\/orgullo-latino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\\\/orgullo-latino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg\",\"width\":460,\"height\":259,\"caption\":\"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\\\/orgullo-latino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Orgullo Latino\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/orgullo-latino\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/f91b6c00888ce85395cb05edc01e916d\",\"name\":\"Testimoniales\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas","description":"Conoce la historia de Erica Alfaro, oradora y escritora premiada latina hija de trabajadores agr\u00edcolas inmigrantes de Oaxaca.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/","og_locale":"en_US","og_type":"article","og_title":"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas | Acceso Latino","og_description":"Conoce la historia de Erica Alfaro, oradora y escritora premiada latina hija de trabajadores agr\u00edcolas inmigrantes de Oaxaca.","og_url":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2024-03-01T14:57:00+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/02\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg","type":"image\/jpeg"}],"author":"Testimoniales","twitter_card":"summary_large_image","twitter_title":"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas | Acceso Latino","twitter_description":"Conoce la historia de Erica Alfaro, oradora y escritora premiada latina hija de trabajadores agr\u00edcolas inmigrantes de Oaxaca.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/02\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Testimoniales","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/"},"author":{"name":"Testimoniales","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/f91b6c00888ce85395cb05edc01e916d"},"headline":"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas","datePublished":"2024-03-01T14:57:00+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/"},"wordCount":552,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/02\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg","keywords":["Erica Alfaro","Escritora","Latina","Oradora","Trabajadores inmigrantes"],"articleSection":["Orgullo Latino","Testimoniales"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/","url":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/","name":"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/02\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg","datePublished":"2024-03-01T14:57:00+00:00","description":"Conoce la historia de Erica Alfaro, oradora y escritora premiada latina hija de trabajadores agr\u00edcolas inmigrantes de Oaxaca.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/02\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2024\/02\/190526182709-03-graduation-photo-honors-immigrant-parents-trnd-0526-large-169.jpg","width":460,"height":259,"caption":"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/conoce-la-historia-de-erica-alfaro-oradora-y-escritora-latina-hija-de-trabajadores-agricolas\/orgullo-latino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Orgullo Latino","item":"https:\/\/accesolatino.org\/category\/orgullo-latino\/"},{"@type":"ListItem","position":3,"name":"Conoce la historia de Erica Alfaro, oradora y escritora latina hija de trabajadores agr\u00edcolas"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/f91b6c00888ce85395cb05edc01e916d","name":"Testimonials"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/53692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=53692"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/53692\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/53693"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=53692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=53692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=53692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}