{"id":51825,"date":"2023-11-01T15:09:29","date_gmt":"2023-11-01T21:09:29","guid":{"rendered":"https:\/\/accesolatino.org\/?p=51825"},"modified":"2023-11-01T15:12:48","modified_gmt":"2023-11-01T21:12:48","slug":"razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/","title":{"rendered":"Razones por las cuales puedes perder tus beneficios de DACA"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"51825\" class=\"elementor elementor-51825\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-619210ca elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"619210ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18b0d5ab\" data-id=\"18b0d5ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ca3d0d elementor-widget elementor-widget-image\" data-id=\"4ca3d0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"2349\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/infografia-Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png\" class=\"attachment-full size-full wp-image-51829\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/infografia-Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png 1080w, https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/infografia-Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA-138x300.png 138w, https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/infografia-Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA-471x1024.png 471w, https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/infografia-Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA-768x1670.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/infografia-Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA-706x1536.png 706w, https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/infografia-Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA-942x2048.png 942w, https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/infografia-Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA-6x12.png 6w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29ada7a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"29ada7a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf359a3\" data-id=\"bf359a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-223ec10e elementor-widget elementor-widget-toggle\" data-id=\"223ec10e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5741\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-5741\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5741\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-5741\"><p><strong>USCIS<\/strong><\/p><p><a href=\"https:\/\/www.uscis.gov\/es\/programas-humanitarios\/consideracion-de-accion-diferida-para-los-llegados-en-la-infancia-daca\/preguntas-frecuentes\">https:\/\/www.uscis.gov\/es\/programas-humanitarios\/consideracion-de-accion-diferida-para-los-llegados-en-la-infancia-daca\/preguntas-frecuentes<\/a><\/p><p>\u00a0<\/p><p><a href=\"https:\/\/www.uscis.gov\/es\/i-131\">https:\/\/www.uscis.gov\/es\/i-131<\/a><\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La Acci\u00f3n Diferida para los Llegados en Infancia (DACA) es un programa que protege a ciertos inmigrantes indocumentados que llegaron siendo ni\u00f1os a Estados Unidos. DACA protege a los inmigrantes elegibles de ser deportados y adem\u00e1s les ofrece la oportunidad de obtener un documento de autorizaci\u00f3n de empleo (EAD) para trabajar legalmente y permanecer en Estados Unidos. <\/p>","protected":false},"author":13,"featured_media":51827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[73,28,165,68,87,86,173],"class_list":["post-51825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-temas-de-interes","tag-biden","tag-ciudadania","tag-ciudadania-estadounidense","tag-daca","tag-inmigrantes","tag-migrantes","tag-uscis"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Razones por las cuales puedes perder tus beneficios de DACA<\/title>\n<meta name=\"description\" content=\"Existen ciertas situaciones que pueden poner en peligro estos beneficios a las personas que cuentan con la protecci\u00f3n de DACA. Tres situaciones en concreto afectan directamente a los beneficiarios de DACA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Razones por las cuales puedes perder tus beneficios de DACA | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Existen ciertas situaciones que pueden poner en peligro estos beneficios a las personas que cuentan con la protecci\u00f3n de DACA. Tres situaciones en concreto afectan directamente a los beneficiarios de DACA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-01T21:09:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-01T21:12:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1081\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Razones por las cuales puedes perder tus beneficios de DACA | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Existen ciertas situaciones que pueden poner en peligro estos beneficios a las personas que cuentan con la protecci\u00f3n de DACA. Tres situaciones en concreto afectan directamente a los beneficiarios de DACA\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\\\/temas-de-interes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\\\/temas-de-interes\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Razones por las cuales puedes perder tus beneficios de DACA\",\"datePublished\":\"2023-11-01T21:09:29+00:00\",\"dateModified\":\"2023-11-01T21:12:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\\\/temas-de-interes\\\/\"},\"wordCount\":27,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png\",\"keywords\":[\"Biden\",\"ciudadan\u00eda\",\"Ciudadan\u00eda estadounidense\",\"DACA\",\"Inmigrantes\",\"Migrantes\",\"USCIS\"],\"articleSection\":[\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\\\/temas-de-interes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\\\/temas-de-interes\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\\\/temas-de-interes\\\/\",\"name\":\"Razones por las cuales puedes perder tus beneficios de DACA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\\\/temas-de-interes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png\",\"datePublished\":\"2023-11-01T21:09:29+00:00\",\"dateModified\":\"2023-11-01T21:12:48+00:00\",\"description\":\"Existen ciertas situaciones que pueden poner en peligro estos beneficios a las personas que cuentan con la protecci\u00f3n de DACA. Tres situaciones en concreto afectan directamente a los beneficiarios de DACA\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\\\/temas-de-interes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\\\/temas-de-interes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\\\/temas-de-interes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png\",\"width\":1080,\"height\":1081},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\\\/temas-de-interes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temas de inter\u00e9s\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/temas-de-interes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Razones por las cuales puedes perder tus beneficios de DACA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Razones por las cuales puedes perder tus beneficios de DACA","description":"Existen ciertas situaciones que pueden poner en peligro estos beneficios a las personas que cuentan con la protecci\u00f3n de DACA. Tres situaciones en concreto afectan directamente a los beneficiarios de DACA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/","og_locale":"en_US","og_type":"article","og_title":"Razones por las cuales puedes perder tus beneficios de DACA | Acceso Latino","og_description":"Existen ciertas situaciones que pueden poner en peligro estos beneficios a las personas que cuentan con la protecci\u00f3n de DACA. Tres situaciones en concreto afectan directamente a los beneficiarios de DACA","og_url":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2023-11-01T21:09:29+00:00","article_modified_time":"2023-11-01T21:12:48+00:00","og_image":[{"width":1080,"height":1081,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_title":"Razones por las cuales puedes perder tus beneficios de DACA | Acceso Latino","twitter_description":"Existen ciertas situaciones que pueden poner en peligro estos beneficios a las personas que cuentan con la protecci\u00f3n de DACA. Tres situaciones en concreto afectan directamente a los beneficiarios de DACA","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Razones por las cuales puedes perder tus beneficios de DACA","datePublished":"2023-11-01T21:09:29+00:00","dateModified":"2023-11-01T21:12:48+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/"},"wordCount":27,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png","keywords":["Biden","ciudadan\u00eda","Ciudadan\u00eda estadounidense","DACA","Inmigrantes","Migrantes","USCIS"],"articleSection":["Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/","url":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/","name":"Razones por las cuales puedes perder tus beneficios de DACA","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png","datePublished":"2023-11-01T21:09:29+00:00","dateModified":"2023-11-01T21:12:48+00:00","description":"Existen ciertas situaciones que pueden poner en peligro estos beneficios a las personas que cuentan con la protecci\u00f3n de DACA. Tres situaciones en concreto afectan directamente a los beneficiarios de DACA","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/11\/Razones_por_las_cuales_puedes_perder_tus_beneficios_de_DACA.png","width":1080,"height":1081},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/razones-por-las-cuales-puedes-perder-tus-beneficios-de-daca-2\/temas-de-interes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Temas de inter\u00e9s","item":"https:\/\/accesolatino.org\/category\/temas-de-interes\/"},{"@type":"ListItem","position":3,"name":"Razones por las cuales puedes perder tus beneficios de DACA"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/51825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=51825"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/51825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/51827"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=51825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=51825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=51825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}