{"id":49998,"date":"2023-07-21T08:38:00","date_gmt":"2023-07-21T14:38:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=49998"},"modified":"2023-07-19T12:40:22","modified_gmt":"2023-07-19T18:40:22","slug":"dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/","title":{"rendered":"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para cuatro pa\u00edses"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"49998\" class=\"elementor elementor-49998\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55ab3581 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"55ab3581\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41b8d8f\" data-id=\"41b8d8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42d0cc08 elementor-widget elementor-widget-heading\" data-id=\"42d0cc08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Los nuevos procesos para la reunificaci\u00f3n familiar beneficiar\u00e1n a migrantes de Colombia, El Salvador, Guatemala y Honduras.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5190a2a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5190a2a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71c82b20\" data-id=\"71c82b20\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f10a562 elementor-widget elementor-widget-text-editor\" data-id=\"6f10a562\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Departamento de Seguridad Nacional (DHS) anunci\u00f3 la creaci\u00f3n de un nuevo proceso para la reunificaci\u00f3n familiar denominado family reunification parole (FRP). Esta nueva estrategia de reunificaci\u00f3n familiar est\u00e1 destinada a migrantes de Colombia, El Salvador, Guatemala y Honduras. El FRP busca ofrecer una nueva alternativa para la migraci\u00f3n legal y para reducir la migraci\u00f3n irregular.<\/p><p>Este nuevo proceso fue dise\u00f1ado para nacionales de los pa\u00edses mencionados cuyos familiares son ciudadanos estadounidenses o residentes permanentes y que han recibido aprobaci\u00f3n para reunirse con su familia en Estados Unidas. El DHS explica que los ciudadanos de estos pa\u00edses pueden ser considerados para el parole, por un periodo de hasta tres a\u00f1os, mientras esperan para solicitar la residencia permanente.<\/p><p>Alrededor de 70 mil personas podr\u00edan ser elegibles para este programa de manera inmediata, sin embargo, la administraci\u00f3n de Joe Biden tiene como objetivo recibir hasta 100 mil migrantes a trav\u00e9s de esta iniciativa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ba073c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2ba073c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2897c048\" data-id=\"2897c048\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16891553 elementor-widget elementor-widget-image\" data-id=\"16891553\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"694\" height=\"1048\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/07\/Reunificacion-familiar-1.png\" class=\"attachment-full size-full wp-image-49999\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/07\/Reunificacion-familiar-1.png 694w, https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/07\/Reunificacion-familiar-1-199x300.png 199w, https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/07\/Reunificacion-familiar-1-678x1024.png 678w, https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/07\/Reunificacion-familiar-1-8x12.png 8w\" sizes=\"(max-width: 694px) 100vw, 694px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ed0e6a0\" data-id=\"7ed0e6a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ce1edbe elementor-widget elementor-widget-text-editor\" data-id=\"4ce1edbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cEl Departamento ha demostrado que la expansi\u00f3n de v\u00edas seguras, ordenadas y legales, combinada con una fuerte aplicaci\u00f3n de la ley, es efectiva para reducir la migraci\u00f3n irregular y peligrosa a los Estados Unidos\u201d, explic\u00f3 Alejandro N. Mayorkas, secretario de seguridad nacional. Asimismo, resalt\u00f3 que estos nuevos procesos promueven la unidad familiar y adem\u00e1s brindan v\u00edas legales que son consistentes con las leyes estadounidenses.<\/p><p>De esta forma, ciudadanos de estos pa\u00edses que son beneficiarios de un Formulario I-130, Petici\u00f3n de familiar extranjero aprobado, son elegibles para aplicar al FRP. Para ello deben cumplir requisitos como: estar fuera de Estados Unidos, requisitos m\u00e9dicos, no contar con visa de inmigrante.<\/p><p>El Departamento de Estado es el encargado de emitir una invitaci\u00f3n a trav\u00e9s del formulario I-130 al ciudadano o residente permanente a nombre de un familiar. Posteriormente, el peticionario invitado puede comenzar el proceso presentando una solicitud en nombre del beneficiario y los miembros de la familia elegibles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71c369e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"71c369e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1dcb9582\" data-id=\"1dcb9582\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3843d257 elementor-widget elementor-widget-text-editor\" data-id=\"3843d257\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durante el proceso, las solicitudes se revisan caso por caso, y las autoridades migratorias determinan si estas demuestran razones humanitarias urgentes o un beneficio significativo. Quienes completen el proceso tendr\u00e1n un parole de hasta tres a\u00f1os y ser\u00e1n elegibles para obtener una autorizaci\u00f3n de empleo mientras esperan obtener su visa de inmigrante. Una vez que obtenga su visa de inmigrante, los beneficiarios de este programa pueden solicitar la residencia permanente.<\/p><p>Este programa busca reducir los cruces ilegales en la frontera entre Estados Unidos y M\u00e9xico y promover v\u00edas legales y ordenadas para la migraci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bf8a284 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6bf8a284\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3005f707\" data-id=\"3005f707\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ed2dbb0 elementor-widget elementor-widget-toggle\" data-id=\"5ed2dbb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1591\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1591\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1591\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1591\"><p><strong>DHS<\/strong><\/p><p><a href=\"https:\/\/www.dhs.gov\/news\/2023\/07\/07\/dhs-announces-family-reunification-parole-processes-colombia-el-salvador-guatemala\">https:\/\/www.dhs.gov\/news\/2023\/07\/07\/dhs-announces-family-reunification-parole-processes-colombia-el-salvador-guatemala<\/a><\/p><p><a href=\"https:\/\/www.dhs.gov\/family-reunification-task-force\">https:\/\/www.dhs.gov\/family-reunification-task-force<\/a><\/p><p><strong>BOUNDLESS<\/strong><\/p><p><a href=\"https:\/\/www.boundless.com\/blog\/family-reunification-parole-process\/\">https:\/\/www.boundless.com\/blog\/family-reunification-parole-process\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Los nuevos procesos para la reunificaci\u00f3n familiar beneficiar\u00e1n a migrantes de Colombia, El Salvador, Guatemala y Honduras.<\/p>","protected":false},"author":13,"featured_media":49999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[90,10],"tags":[2356,283,754,1090,293],"class_list":["post-49998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apoyo-social","category-noticias","tag-ciudadanos","tag-dhs","tag-parole","tag-residentes","tag-reunificacion-familiar"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para cuatro pa\u00edses<\/title>\n<meta name=\"description\" content=\"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para migrantes de Colombia, El Salvador, Guatemala y Honduras con familiares en EE.UU.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para cuatro pa\u00edses | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para migrantes de Colombia, El Salvador, Guatemala y Honduras con familiares en EE.UU.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-21T14:38:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/07\/Reunificacion-familiar-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"694\" \/>\n\t<meta property=\"og:image:height\" content=\"1048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para cuatro pa\u00edses | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para migrantes de Colombia, El Salvador, Guatemala y Honduras con familiares en EE.UU.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/07\/Reunificacion-familiar-1.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\\\/apoyo-social\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\\\/apoyo-social\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para cuatro pa\u00edses\",\"datePublished\":\"2023-07-21T14:38:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\\\/apoyo-social\\\/\"},\"wordCount\":482,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\\\/apoyo-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Reunificacion-familiar-1.png\",\"keywords\":[\"Ciudadanos\",\"DHS\",\"Parole\",\"Residentes\",\"Reunificaci\u00f3n familiar\"],\"articleSection\":[\"Apoyo Social\",\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\\\/apoyo-social\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\\\/apoyo-social\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\\\/apoyo-social\\\/\",\"name\":\"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para cuatro pa\u00edses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\\\/apoyo-social\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\\\/apoyo-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Reunificacion-familiar-1.png\",\"datePublished\":\"2023-07-21T14:38:00+00:00\",\"description\":\"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para migrantes de Colombia, El Salvador, Guatemala y Honduras con familiares en EE.UU.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\\\/apoyo-social\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\\\/apoyo-social\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\\\/apoyo-social\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Reunificacion-familiar-1.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Reunificacion-familiar-1.png\",\"width\":694,\"height\":1048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\\\/apoyo-social\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apoyo Social\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/apoyo-social\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para cuatro pa\u00edses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para cuatro pa\u00edses","description":"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para migrantes de Colombia, El Salvador, Guatemala y Honduras con familiares en EE.UU.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/","og_locale":"en_US","og_type":"article","og_title":"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para cuatro pa\u00edses | Acceso Latino","og_description":"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para migrantes de Colombia, El Salvador, Guatemala y Honduras con familiares en EE.UU.","og_url":"https:\/\/accesolatino.org\/en\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2023-07-21T14:38:00+00:00","og_image":[{"width":694,"height":1048,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/07\/Reunificacion-familiar-1.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_title":"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para cuatro pa\u00edses | Acceso Latino","twitter_description":"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para migrantes de Colombia, El Salvador, Guatemala y Honduras con familiares en EE.UU.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/07\/Reunificacion-familiar-1.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para cuatro pa\u00edses","datePublished":"2023-07-21T14:38:00+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/"},"wordCount":482,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/07\/Reunificacion-familiar-1.png","keywords":["Ciudadanos","DHS","Parole","Residentes","Reunificaci\u00f3n familiar"],"articleSection":["Apoyo Social","Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/","url":"https:\/\/accesolatino.org\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/","name":"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para cuatro pa\u00edses","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/07\/Reunificacion-familiar-1.png","datePublished":"2023-07-21T14:38:00+00:00","description":"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para migrantes de Colombia, El Salvador, Guatemala y Honduras con familiares en EE.UU.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/07\/Reunificacion-familiar-1.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/07\/Reunificacion-familiar-1.png","width":694,"height":1048},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/dhs-anuncia-nuevo-plan-de-reunificacion-familiar-para-cuatro-paises\/apoyo-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Apoyo Social","item":"https:\/\/accesolatino.org\/en\/category\/apoyo-social\/"},{"@type":"ListItem","position":3,"name":"DHS anuncia nuevo plan de Reunificaci\u00f3n Familiar para cuatro pa\u00edses"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/49998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=49998"}],"version-history":[{"count":0,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/49998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/49999"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=49998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=49998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=49998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}