{"id":49497,"date":"2023-06-12T09:02:39","date_gmt":"2023-06-12T15:02:39","guid":{"rendered":"https:\/\/accesolatino.org\/?p=49497"},"modified":"2025-10-20T13:19:57","modified_gmt":"2025-10-20T19:19:57","slug":"legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/","title":{"rendered":"Legislators from Mexico meet with the Mexican community in California"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"49497\" class=\"elementor elementor-49497\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52799fd elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"52799fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62dcc2de\" data-id=\"62dcc2de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c9d0cfb elementor-widget elementor-widget-heading\" data-id=\"3c9d0cfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Legislators and representatives of the Congress of the Union met with Mexican migrants in California and to present a work agenda in favor of the migrant community.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab297d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"ab297d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4dfb0758\" data-id=\"4dfb0758\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c828fbe elementor-widget elementor-widget-text-editor\" data-id=\"5c828fbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Deputies and senators from Mexico met with migrants from the state of Jalisco, with Dreamers, with former braceros and with members of the Association of Jaliscienses in Action (AJUA). In addition, California state senators, assemblymen and mayors of cities in southern California also participated in this meeting. The objective of this meeting was to strengthen the collaboration between the people of Jalisco in California and the Congress of the Union.<\/p><p>On the other hand, the congressmen held a meeting with Dreamers through the Coalition of Mexican Migrants, in which Linda S\u00e1nchez, a member of the Hispanic Caucus in the House of Representatives, and a member of the committee participated \"<em>Ways and Means<\/em>\u201c, which provides social security programs, unemployment insurance and other support.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c8a3ec2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7c8a3ec2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-37cf2518\" data-id=\"37cf2518\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6323f454 elementor-widget elementor-widget-image\" data-id=\"6323f454\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"850\" height=\"565\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm.jpg\" class=\"attachment-full size-full wp-image-49498\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm.jpg 850w, https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm-300x199.jpg 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm-768x510.jpg 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm-18x12.jpg 18w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Foto: comunicacionsocial.diputados.gob.mx<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9733731\" data-id=\"9733731\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c8214ac elementor-widget elementor-widget-text-editor\" data-id=\"7c8214ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>As reported by the Chamber of Deputies in its press release, the population of Jalisco in the state of California is over 2 million people, which is why they seek to promote legislation in favor of this population.<\/p><p>On the other hand, there was also a meeting with the Federation of Zacatecanos from southern California, who expressed their needs and who wanted to support families and communities in Mexico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1eb8532c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1eb8532c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1af19766\" data-id=\"1af19766\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dd25b6e elementor-widget elementor-widget-text-editor\" data-id=\"1dd25b6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Finally, the work agenda included the creation of the first Cultural Festival \"Mexico in the Heart\", which previously only took place in the state of Jalisco, and now it will also take place in southern California, with the aim of expanding the sides of coordination with the Mexican community in said region.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a69803 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2a69803\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b550ee4\" data-id=\"6b550ee4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63ac0669 elementor-widget elementor-widget-toggle\" data-id=\"63ac0669\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1671\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1671\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1671\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1671\"><p><strong>C\u00c1MARA DE DIPUTADOS<\/strong><\/p><p><a href=\"https:\/\/comunicacionsocial.diputados.gob.mx\/index.php\/notilegis\/sostiene-jorge-lvarez-maynez-agenda-de-trabajo-con-la-comunidad-migrante-v\">https:\/\/comunicacionsocial.diputados.gob.mx\/index.php\/notilegis\/sostiene-jorge-lvarez-maynez-agenda-de-trabajo-con-la-comunidad-migrante-v<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Legislators and representatives of the Congress of the Union met with Mexican migrants in California and to present a work agenda in favor of the migrant community.<\/p>","protected":false},"author":13,"featured_media":49498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10],"tags":[1946,2268,61,2269,2270,2266,2267],"class_list":["post-49497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-1946","tag-comunidad-mexicana-2","tag-dreamers","tag-jaliscienses","tag-legisladores","tag-mexicanos-en-california","tag-sur-de-california"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Legisladores y representantes del Congreso de la Uni\u00f3n se reunieron con migrantes mexicanos en California y para presentar una agenda de trabajo a favor de la comunidad migrante.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Noticias\"\/>\n\t<meta name=\"google-site-verification\" content=\"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE\" \/>\n\t<meta name=\"keywords\" content=\"\u2022,comunidad mexicana \u2022,dreamers,jaliscienses \u2022,legisladores \u2022,mexicanos en california,sur de california \u2022,noticias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California\" \/>\n\t\t<meta property=\"og:description\" content=\"Legisladores y representantes del Congreso de la Uni\u00f3n se reunieron con migrantes mexicanos en California y para presentar una agenda de trabajo a favor de la comunidad migrante.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-12T15:02:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-20T19:19:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Legisladores y representantes del Congreso de la Uni\u00f3n se reunieron con migrantes mexicanos en California y para presentar una agenda de trabajo a favor de la comunidad migrante.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#blogposting\",\"name\":\"Legisladores de M\\u00e9xico se re\\u00fanen con comunidad de mexicanos en California\",\"headline\":\"Legisladores de M\\u00e9xico se re\\u00fanen con comunidad de mexicanos en California\",\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/2023_05_29__02_15_53pm.jpg\",\"width\":850,\"height\":565,\"caption\":\"Foto: comunicacionsocial.diputados.gob.mx\"},\"datePublished\":\"2023-06-12T09:02:39-06:00\",\"dateModified\":\"2025-10-20T13:19:57-06:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#webpage\"},\"articleSection\":\"Noticias, \\u2022, Comunidad mexicana \\u2022, Dreamers, Jaliscienses \\u2022, Legisladores \\u2022, Mexicanos en California, Sur de California \\u2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#listItem\",\"name\":\"Legisladores de M\\u00e9xico se re\\u00fanen con comunidad de mexicanos en California\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#listItem\",\"position\":3,\"name\":\"Legisladores de M\\u00e9xico se re\\u00fanen con comunidad de mexicanos en California\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#organizationLogo\",\"width\":240,\"height\":40},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/\",\"name\":\"Noticias\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#webpage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/\",\"name\":\"Legisladores de M\\u00e9xico se re\\u00fanen con comunidad de mexicanos en California\",\"description\":\"Legisladores y representantes del Congreso de la Uni\\u00f3n se reunieron con migrantes mexicanos en California y para presentar una agenda de trabajo a favor de la comunidad migrante.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/2023_05_29__02_15_53pm.jpg\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#mainImage\",\"width\":850,\"height\":565,\"caption\":\"Foto: comunicacionsocial.diputados.gob.mx\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#mainImage\"},\"datePublished\":\"2023-06-12T09:02:39-06:00\",\"dateModified\":\"2025-10-20T13:19:57-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Legislators from Mexico meet with the Mexican community in California","description":"Legislators and representatives of the Congress of the Union met with Mexican migrants in California and to present a work agenda in favor of the migrant community.","canonical_url":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/","robots":"max-image-preview:large","keywords":"\u2022,comunidad mexicana \u2022,dreamers,jaliscienses \u2022,legisladores \u2022,mexicanos en california,sur de california \u2022,noticias","webmasterTools":{"google-site-verification":"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#blogposting","name":"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California","headline":"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California","author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm.jpg","width":850,"height":565,"caption":"Foto: comunicacionsocial.diputados.gob.mx"},"datePublished":"2023-06-12T09:02:39-06:00","dateModified":"2025-10-20T13:19:57-06:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#webpage"},"isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#webpage"},"articleSection":"Noticias, \u2022, Comunidad mexicana \u2022, Dreamers, Jaliscienses \u2022, Legisladores \u2022, Mexicanos en California, Sur de California \u2022"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","position":1,"name":"Home","item":"https:\/\/accesolatino.org\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/en\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#listItem","name":"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California"},"previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#listItem","position":3,"name":"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California","previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/en\/#organization","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","@id":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#organizationLogo","width":240,"height":40},"image":{"@id":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author","url":"https:\/\/accesolatino.org\/en\/author\/noticias\/","name":"Noticias"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#webpage","url":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/","name":"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California","description":"Legisladores y representantes del Congreso de la Uni\u00f3n se reunieron con migrantes mexicanos en California y para presentar una agenda de trabajo a favor de la comunidad migrante.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#breadcrumblist"},"author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"creator":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm.jpg","@id":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#mainImage","width":850,"height":565,"caption":"Foto: comunicacionsocial.diputados.gob.mx"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#mainImage"},"datePublished":"2023-06-12T09:02:39-06:00","dateModified":"2025-10-20T13:19:57-06:00"},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/en\/#website","url":"https:\/\/accesolatino.org\/en\/","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","inLanguage":"en-US","publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim","og:type":"article","og:title":"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California","og:description":"Legisladores y representantes del Congreso de la Uni\u00f3n se reunieron con migrantes mexicanos en California y para presentar una agenda de trabajo a favor de la comunidad migrante.","og:url":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/","article:published_time":"2023-06-12T15:02:39+00:00","article:modified_time":"2025-10-20T19:19:57+00:00","twitter:card":"summary_large_image","twitter:title":"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California","twitter:description":"Legisladores y representantes del Congreso de la Uni\u00f3n se reunieron con migrantes mexicanos en California y para presentar una agenda de trabajo a favor de la comunidad migrante."},"aioseo_meta_data":{"post_id":"49497","title":"#post_title","description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-07-14 08:20:15","updated":"2025-10-20 19:20:41","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLegisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/accesolatino.org\/en"},{"label":"Noticias","link":"https:\/\/accesolatino.org\/en\/category\/noticias\/"},{"label":"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California","link":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California<\/title>\n<meta name=\"description\" content=\"Legisladores de M\u00e9xico realizaron una reuni\u00f3n con miembros de la comunidad de mexicanos y funcionarios del sur de California.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Legisladores de M\u00e9xico realizaron una reuni\u00f3n con miembros de la comunidad de mexicanos y funcionarios del sur de California.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-12T15:02:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-20T19:19:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Legisladores de M\u00e9xico realizaron una reuni\u00f3n con miembros de la comunidad de mexicanos y funcionarios del sur de California.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\"},\"headline\":\"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California\",\"datePublished\":\"2023-06-12T15:02:39+00:00\",\"dateModified\":\"2025-10-20T19:19:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/\"},\"wordCount\":333,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/2023_05_29__02_15_53pm.jpg\",\"keywords\":[\"\u2022\",\"Comunidad mexicana \u2022\",\"Dreamers\",\"Jaliscienses \u2022\",\"Legisladores \u2022\",\"Mexicanos en California\",\"Sur de California \u2022\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/\",\"name\":\"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/2023_05_29__02_15_53pm.jpg\",\"datePublished\":\"2023-06-12T15:02:39+00:00\",\"dateModified\":\"2025-10-20T19:19:57+00:00\",\"description\":\"Legisladores de M\u00e9xico realizaron una reuni\u00f3n con miembros de la comunidad de mexicanos y funcionarios del sur de California.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/2023_05_29__02_15_53pm.jpg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/2023_05_29__02_15_53pm.jpg\",\"width\":850,\"height\":565,\"caption\":\"Foto: comunicacionsocial.diputados.gob.mx\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Legislators from Mexico meet with the Mexican community in California","description":"Legisladores de M\u00e9xico realizaron una reuni\u00f3n con miembros de la comunidad de mexicanos y funcionarios del sur de California.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California | Acceso Latino","og_description":"Legisladores de M\u00e9xico realizaron una reuni\u00f3n con miembros de la comunidad de mexicanos y funcionarios del sur de California.","og_url":"https:\/\/accesolatino.org\/en\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2023-06-12T15:02:39+00:00","article_modified_time":"2025-10-20T19:19:57+00:00","og_image":[{"width":850,"height":565,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm.jpg","type":"image\/jpeg"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_title":"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California | Acceso Latino","twitter_description":"Legisladores de M\u00e9xico realizaron una reuni\u00f3n con miembros de la comunidad de mexicanos y funcionarios del sur de California.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm.jpg","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905"},"headline":"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California","datePublished":"2023-06-12T15:02:39+00:00","dateModified":"2025-10-20T19:19:57+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/"},"wordCount":333,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm.jpg","keywords":["\u2022","Comunidad mexicana \u2022","Dreamers","Jaliscienses \u2022","Legisladores \u2022","Mexicanos en California","Sur de California \u2022"],"articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/","url":"https:\/\/accesolatino.org\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/","name":"Legislators from Mexico meet with the Mexican community in California","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm.jpg","datePublished":"2023-06-12T15:02:39+00:00","dateModified":"2025-10-20T19:19:57+00:00","description":"Legisladores de M\u00e9xico realizaron una reuni\u00f3n con miembros de la comunidad de mexicanos y funcionarios del sur de California.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm.jpg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2023\/06\/2023_05_29__02_15_53pm.jpg","width":850,"height":565,"caption":"Foto: comunicacionsocial.diputados.gob.mx"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/legisladores-de-mexico-se-reunen-con-comunidad-de-mexicanos-en-california\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Legisladores de M\u00e9xico se re\u00fanen con comunidad de mexicanos en California"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/49497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=49497"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/49497\/revisions"}],"predecessor-version":[{"id":64349,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/49497\/revisions\/64349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/49498"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=49497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=49497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=49497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}