{"id":42651,"date":"2022-06-28T06:13:00","date_gmt":"2022-06-28T11:13:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=42651"},"modified":"2025-10-22T00:42:55","modified_gmt":"2025-10-22T06:42:55","slug":"cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/","title":{"rendered":"\u00bfCu\u00e1les son las opciones de los graduados que no tienen DACA?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"42651\" class=\"elementor elementor-42651\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b1190c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3b1190c0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29162963\" data-id=\"29162963\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc02d7c elementor-widget elementor-widget-heading\" data-id=\"bc02d7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Los estudiantes graduados de la nueva generaci\u00f3n de inmigrantes indocumentados no cuentan con permiso de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA), por lo tanto, no pueden trabajar de manera legal.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-718594a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"718594a4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1623b43f\" data-id=\"1623b43f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17a951e0 elementor-widget elementor-widget-text-editor\" data-id=\"17a951e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para ser elegible a DACA, los inmigrantes deben cumplir diversos criterios como haber sido menores de 31 a\u00f1os el 15 de junio de 2012, cuando se implement\u00f3 DACA; haber llegado a Estados Unidos siendo menores de 16 a\u00f1os y haber residido continuamente en el pa\u00eds desde el 15 de junio de 2007.<\/p><p>De esta forma, los j\u00f3venes que ingresaron a Estados Unidos despu\u00e9s de junio de 2007, y que ahora han concluido sus estudios universitarios o de preparatoria, no pueden ingresar al campo laboral debido a su estatus de inmigrante sin documentos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-146e273c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"146e273c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4e6f1902\" data-id=\"4e6f1902\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7566795b elementor-widget elementor-widget-image\" data-id=\"7566795b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png\" class=\"attachment-full size-full wp-image-42652\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png 1000w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU--300x210.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU--768x538.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU--18x12.png 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b21516a\" data-id=\"2b21516a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74037252 elementor-widget elementor-widget-text-editor\" data-id=\"74037252\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cientos de miles de estudiantes de la nueva generaci\u00f3n de inmigrantes se grad\u00faan cada a\u00f1o de la preparatoria sin tener la oportunidad de ingresar al mercado laboral, y mucho menos al programa DACA que les brinda protecci\u00f3n contra la deportaci\u00f3n y autorizaci\u00f3n de empleo.<\/p><p>A pesar de no poder aplicar tampoco a beneficios federales para pagar la universidad, los inmigrantes indocumentados post DACA pueden acceder a beneficios estatales como el California Dream Act, que ofrece ayuda financiera a j\u00f3venes para que contin\u00faen sus estudios universitarios sin importar su estatus migratorio. El requisito principal es haber formado parte del sistema escolar de California.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44d9a7d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"44d9a7d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64596d5f\" data-id=\"64596d5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d5b301d elementor-widget elementor-widget-text-editor\" data-id=\"4d5b301d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Colorado tambi\u00e9n implement\u00f3 la ley ASSET, que permite que estudiantes indocumentados sin importar si tienen DACA o no, puedan acceder a la matr\u00edcula estatal y pagar menores tarifas en la universidad. Desde el 2013 m\u00e1s de 3 mil estudiantes se han beneficiado de esta ley.<\/p><p>En total son 21 estados, que permiten que estudiantes sin documentos puedan acceder a beneficios de financiamiento estatal para pagar continuar sus estudios universitarios. Aunque las reglas y requerimientos var\u00edan en cada estado, los estudiantes tienen la oportunidad de seguir estudiando y con suerte lograr emprender un negocio, a falta de un permiso para trabajar.<\/p><p>Adicionalmente, la organizaci\u00f3n pro migrante FWD estima que existen m\u00e1s de 600 mil dreamers de nueva generaci\u00f3n que se encuentran inscritos en el sistema educativo, de los cuales solo 21 mil cuentan con DACA.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-325e6248 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"325e6248\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-200cde80\" data-id=\"200cde80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f5ecdda elementor-widget elementor-widget-toggle\" data-id=\"6f5ecdda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1861\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1861\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1861\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1861\"><p><strong>FWD<\/strong><\/p><p><a href=\"https:\/\/www.fwd.us\/news\/undocumented-high-school-graduates\/\">https:\/\/www.fwd.us\/news\/undocumented-high-school-graduates\/<\/a><\/p><p><strong>NILC <\/strong><\/p><p><a href=\"https:\/\/www.nilc.org\/issues\/education\/basic-facts-instate\/\">https:\/\/www.nilc.org\/issues\/education\/basic-facts-instate\/<\/a><\/p><p><strong>TELEMUNDO 20<\/strong><\/p><p><a href=\"https:\/\/www.telemundo20.com\/noticias\/local\/que-pasa-con-los-graduados-indocumentados-en-eeuu\/2208835\/\">https:\/\/www.telemundo20.com\/noticias\/local\/que-pasa-con-los-graduados-indocumentados-en-eeuu\/2208835\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Los estudiantes graduados de la nueva generaci\u00f3n de inmigrantes indocumentados no cuentan con permiso de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA), por lo tanto, no pueden trabajar de manera legal.<\/p>","protected":false},"author":7,"featured_media":42652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[13],"tags":[68,775,1518,221,1454],"class_list":["post-42651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-daca","tag-estudiantes-indocumentados","tag-graduados","tag-high-school","tag-preparatoria"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfCu\u00e1les son las opciones de los graduados que no tienen DACA?<\/title>\n<meta name=\"description\" content=\"Los estudiantes indocumentados graduados de preparatoria que no tienen acceso a DACA cuentan con opciones para continuar sus estudios universitarios.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1les son las opciones de los graduados que no tienen DACA? | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Los estudiantes indocumentados graduados de preparatoria que no tienen acceso a DACA cuentan con opciones para continuar sus estudios universitarios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-28T11:13:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T06:42:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Educacion Educacion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00bfCu\u00e1les son las opciones de los graduados que no tienen DACA? | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Los estudiantes indocumentados graduados de preparatoria que no tienen acceso a DACA cuentan con opciones para continuar sus estudios universitarios.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Educacion Educacion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\\\/educacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\\\/educacion\\\/\"},\"author\":{\"name\":\"Educacion Educacion\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/c646484d487fbb885a5279d51e9d225d\"},\"headline\":\"\u00bfCu\u00e1les son las opciones de los graduados que no tienen DACA?\",\"datePublished\":\"2022-06-28T11:13:00+00:00\",\"dateModified\":\"2025-10-22T06:42:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\\\/educacion\\\/\"},\"wordCount\":408,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\\\/educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png\",\"keywords\":[\"DACA\",\"Estudiantes indocumentados\",\"Graduados\",\"High School\",\"Preparatoria\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\\\/educacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\\\/educacion\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\\\/educacion\\\/\",\"name\":\"\u00bfCu\u00e1les son las opciones de los graduados que no tienen DACA?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\\\/educacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\\\/educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png\",\"datePublished\":\"2022-06-28T11:13:00+00:00\",\"dateModified\":\"2025-10-22T06:42:55+00:00\",\"description\":\"Los estudiantes indocumentados graduados de preparatoria que no tienen acceso a DACA cuentan con opciones para continuar sus estudios universitarios.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\\\/educacion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\\\/educacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\\\/educacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png\",\"width\":1000,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\\\/educacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Educaci\u00f3n\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/educacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfCu\u00e1les son las opciones de los graduados que no tienen DACA?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/c646484d487fbb885a5279d51e9d225d\",\"name\":\"Educacion Educacion\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1les son las opciones de los graduados que no tienen DACA?","description":"Los estudiantes indocumentados graduados de preparatoria que no tienen acceso a DACA cuentan con opciones para continuar sus estudios universitarios.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfCu\u00e1les son las opciones de los graduados que no tienen DACA? | Acceso Latino","og_description":"Los estudiantes indocumentados graduados de preparatoria que no tienen acceso a DACA cuentan con opciones para continuar sus estudios universitarios.","og_url":"https:\/\/accesolatino.org\/en\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2022-06-28T11:13:00+00:00","article_modified_time":"2025-10-22T06:42:55+00:00","og_image":[{"width":1000,"height":700,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png","type":"image\/png"}],"author":"Educacion Educacion","twitter_card":"summary_large_image","twitter_title":"\u00bfCu\u00e1les son las opciones de los graduados que no tienen DACA? | Acceso Latino","twitter_description":"Los estudiantes indocumentados graduados de preparatoria que no tienen acceso a DACA cuentan con opciones para continuar sus estudios universitarios.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Educacion Educacion","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/"},"author":{"name":"Educacion Educacion","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/c646484d487fbb885a5279d51e9d225d"},"headline":"\u00bfCu\u00e1les son las opciones de los graduados que no tienen DACA?","datePublished":"2022-06-28T11:13:00+00:00","dateModified":"2025-10-22T06:42:55+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/"},"wordCount":408,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png","keywords":["DACA","Estudiantes indocumentados","Graduados","High School","Preparatoria"],"articleSection":["Educaci\u00f3n"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/","url":"https:\/\/accesolatino.org\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/","name":"\u00bfCu\u00e1les son las opciones de los graduados que no tienen DACA?","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png","datePublished":"2022-06-28T11:13:00+00:00","dateModified":"2025-10-22T06:42:55+00:00","description":"Los estudiantes indocumentados graduados de preparatoria que no tienen acceso a DACA cuentan con opciones para continuar sus estudios universitarios.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-\u00bfQue\u0301-pasa-con-los-graduados-indocumentados-en-EEUU-.png","width":1000,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/cuales-son-las-opciones-de-los-graduados-que-no-tienen-daca\/educacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Educaci\u00f3n","item":"https:\/\/accesolatino.org\/category\/educacion\/"},{"@type":"ListItem","position":3,"name":"\u00bfCu\u00e1les son las opciones de los graduados que no tienen DACA?"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/c646484d487fbb885a5279d51e9d225d","name":"Educacion Educacion"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/42651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=42651"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/42651\/revisions"}],"predecessor-version":[{"id":64845,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/42651\/revisions\/64845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/42652"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=42651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=42651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=42651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}