{"id":42643,"date":"2022-06-27T08:54:00","date_gmt":"2022-06-27T13:54:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=42643"},"modified":"2025-10-22T00:43:16","modified_gmt":"2025-10-22T06:43:16","slug":"el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/","title":{"rendered":"On July 1, the call for the first generation of one of the HACU scholarships for Hispanic students closes"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"42643\" class=\"elementor elementor-42643\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59c253a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"59c253a4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-77e8ebdb\" data-id=\"77e8ebdb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61c28883 elementor-widget elementor-widget-heading\" data-id=\"61c28883\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Five scholarships will be awarded to students from institutions belonging to the Hispanic Association of Colleges and Universities (HACU).<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-375d6ae6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"375d6ae6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41f95428\" data-id=\"41f95428\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a8e21ba elementor-widget elementor-widget-text-editor\" data-id=\"6a8e21ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>First Generation Scholarship de Coca-Cola<\/strong>, is geared toward full-time undergraduate or graduate students studying at a HACU member institution. It is also aimed at first-generation students, that is, students of Hispanic descent who are the first members of their immediate family to attend college. The total amount of the scholarship is $2,500.<\/p><p>It is worth mentioning that to be eligible for this scholarship, students must be US citizens or have legal permanent residence in the United States.<\/p><p>The scholarship is open to students who meet the requirements mentioned above, regardless of the university degree they are studying. However, a GPA of 2.5 or higher is also required. July 1 at 5 PM CST is the deadline to apply for this scholarship.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-691857e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"691857e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1cc14c7\" data-id=\"1cc14c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70b25fce elementor-widget elementor-widget-image\" data-id=\"70b25fce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png\" class=\"attachment-full size-full wp-image-42644\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png 1000w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola-300x210.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola-768x538.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola-18x12.png 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-96edd26\" data-id=\"96edd26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f985e80 elementor-widget elementor-widget-text-editor\" data-id=\"5f985e80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Other scholarships available to Hispanic students from HACU affiliated institutions are:<\/p><ul><li><strong>Miller Lite Brewed to Be Bright Scholarships<\/strong>, which offers 31 scholarships of $2,500 and eight of $5,000. Unlike the Coca-Cola scholarship, this one does offer an opportunity to apply to undocumented students, as long as their Deferred Action (DACA) permit is valid.<\/li><li><strong>Cafe Bustelo El Cafe Del Futuro Scholarship,<\/strong> offers the opportunity to 25 students with employment authorization and a GPA of 2.0, to receive a support of 5 thousand dollars.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66475080 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"66475080\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6efe104a\" data-id=\"6efe104a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68a86d6e elementor-widget elementor-widget-text-editor\" data-id=\"68a86d6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Learn more scholarships for students of Hispanic origin at the following link: <a href=\"https:\/\/www.hacu.net\/hacu\/Scholarships.asp\">https:\/\/www.hacu.net\/hacu\/Scholarships.asp<\/a>. All scholarships have a deadline to apply on July 1.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53d1a91b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"53d1a91b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5950f5ff\" data-id=\"5950f5ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5423f809 elementor-widget elementor-widget-toggle\" data-id=\"5423f809\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1411\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1411\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1411\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1411\"><p><strong>HACU<\/strong><\/p><p><a href=\"https:\/\/www.hacu.net\/hacu\/Scholarships.asp\">https:\/\/www.hacu.net\/hacu\/Scholarships.asp<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Five scholarships will be awarded to students from institutions belonging to the Hispanic Association of Colleges and Universities (HACU).<\/p>","protected":false},"author":7,"featured_media":42644,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[13],"tags":[1515,1516,1517,543,945],"class_list":["post-42643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-beca","tag-coca-cola","tag-hacu","tag-hispanos","tag-universidad"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El 1\u00ba de julio cierra la convocatoria de la primera generaci\u00f3n de una de las becas de HACU para estudiantes hispanos<\/title>\n<meta name=\"description\" content=\"El 1 de julio cierra la convocatoria de la primera generaci\u00f3n de la beca Coca-Cola para estudiantes hispanos del HACU.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El 1\u00ba de julio cierra la convocatoria de la primera generaci\u00f3n de una de las becas de HACU para estudiantes hispanos | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Se otorgar\u00e1n cinco becas a estudiantes de instituciones pertenecientes a Hispanic Association of Colleges and Universities (HACU).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-27T13:54:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T06:43:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Educacion Educacion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"El 1\u00ba de julio cierra la convocatoria de la primera generaci\u00f3n de una de las becas de HACU para estudiantes hispanos | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Se otorgar\u00e1n cinco becas a estudiantes de instituciones pertenecientes a Hispanic Association of Colleges and Universities (HACU).\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Educacion Educacion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\\\/educacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\\\/educacion\\\/\"},\"author\":{\"name\":\"Educacion Educacion\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/c646484d487fbb885a5279d51e9d225d\"},\"headline\":\"El 1\u00ba de julio cierra la convocatoria de la primera generaci\u00f3n de una de las becas de HACU para estudiantes hispanos\",\"datePublished\":\"2022-06-27T13:54:00+00:00\",\"dateModified\":\"2025-10-22T06:43:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\\\/educacion\\\/\"},\"wordCount\":311,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\\\/educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png\",\"keywords\":[\"Beca\",\"Coca-Cola\",\"HACU\",\"hispanos\",\"Universidad\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\\\/educacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\\\/educacion\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\\\/educacion\\\/\",\"name\":\"El 1\u00ba de julio cierra la convocatoria de la primera generaci\u00f3n de una de las becas de HACU para estudiantes hispanos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\\\/educacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\\\/educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png\",\"datePublished\":\"2022-06-27T13:54:00+00:00\",\"dateModified\":\"2025-10-22T06:43:16+00:00\",\"description\":\"El 1 de julio cierra la convocatoria de la primera generaci\u00f3n de la beca Coca-Cola para estudiantes hispanos del HACU.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\\\/educacion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\\\/educacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\\\/educacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png\",\"width\":1000,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\\\/educacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Educaci\u00f3n\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/educacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El 1\u00ba de julio cierra la convocatoria de la primera generaci\u00f3n de una de las becas de HACU para estudiantes hispanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/c646484d487fbb885a5279d51e9d225d\",\"name\":\"Educacion Educacion\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"On July 1, the call for the first generation of one of the HACU scholarships for Hispanic students closes","description":"El 1 de julio cierra la convocatoria de la primera generaci\u00f3n de la beca Coca-Cola para estudiantes hispanos del HACU.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/","og_locale":"en_US","og_type":"article","og_title":"El 1\u00ba de julio cierra la convocatoria de la primera generaci\u00f3n de una de las becas de HACU para estudiantes hispanos | Acceso Latino","og_description":"Se otorgar\u00e1n cinco becas a estudiantes de instituciones pertenecientes a Hispanic Association of Colleges and Universities (HACU).","og_url":"https:\/\/accesolatino.org\/en\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2022-06-27T13:54:00+00:00","article_modified_time":"2025-10-22T06:43:16+00:00","og_image":[{"width":1000,"height":700,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png","type":"image\/png"}],"author":"Educacion Educacion","twitter_card":"summary_large_image","twitter_title":"El 1\u00ba de julio cierra la convocatoria de la primera generaci\u00f3n de una de las becas de HACU para estudiantes hispanos | Acceso Latino","twitter_description":"Se otorgar\u00e1n cinco becas a estudiantes de instituciones pertenecientes a Hispanic Association of Colleges and Universities (HACU).","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Educacion Educacion","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/"},"author":{"name":"Educacion Educacion","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/c646484d487fbb885a5279d51e9d225d"},"headline":"El 1\u00ba de julio cierra la convocatoria de la primera generaci\u00f3n de una de las becas de HACU para estudiantes hispanos","datePublished":"2022-06-27T13:54:00+00:00","dateModified":"2025-10-22T06:43:16+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/"},"wordCount":311,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png","keywords":["Beca","Coca-Cola","HACU","hispanos","Universidad"],"articleSection":["Educaci\u00f3n"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/","url":"https:\/\/accesolatino.org\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/","name":"On July 1, the call for the first generation of one of the HACU scholarships for Hispanic students closes","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png","datePublished":"2022-06-27T13:54:00+00:00","dateModified":"2025-10-22T06:43:16+00:00","description":"El 1 de julio cierra la convocatoria de la primera generaci\u00f3n de la beca Coca-Cola para estudiantes hispanos del HACU.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/06\/Beca-de-Primera-Generacio\u0301n-de-Coca-Cola.png","width":1000,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/el-1o-de-julio-cierra-la-convocatoria-de-la-primera-generacion-de-una-de-las-becas-de-hacu-para-estudiantes-hispanos\/educacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Educaci\u00f3n","item":"https:\/\/accesolatino.org\/category\/educacion\/"},{"@type":"ListItem","position":3,"name":"El 1\u00ba de julio cierra la convocatoria de la primera generaci\u00f3n de una de las becas de HACU para estudiantes hispanos"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/c646484d487fbb885a5279d51e9d225d","name":"Educacion Educacion"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/42643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=42643"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/42643\/revisions"}],"predecessor-version":[{"id":64848,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/42643\/revisions\/64848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/42644"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=42643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=42643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=42643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}