{"id":41539,"date":"2022-04-08T08:01:00","date_gmt":"2022-04-08T13:01:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=41539"},"modified":"2025-10-22T13:02:54","modified_gmt":"2025-10-22T19:02:54","slug":"isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/","title":{"rendered":"Isaret Jeffers la mexicana que apoya a mujeres inmigrantes en condiciones vulnerables a trav\u00e9s de Colectivo \u00c1rbol"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"41539\" class=\"elementor elementor-41539\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61ee85b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"61ee85b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f349b6f\" data-id=\"2f349b6f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6981f084 elementor-widget elementor-widget-heading\" data-id=\"6981f084\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Isaret Jeffers, dirige desde el 2017 el Colectivo \u00c1rbol, que apoya a familias de inmigrantes que se dedican a la agricultura en los campos de Florida y a mujeres inmigrantes v\u00edctimas de violencia.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40915882 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"40915882\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16b237a5\" data-id=\"16b237a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5895ac6e elementor-widget elementor-widget-text-editor\" data-id=\"5895ac6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cPaisanita Carri\u00f3n\u201d, como se le conoce a Isaret Jeffers, la fundadora de Colectivo \u00c1rbol, naci\u00f3 en Le\u00f3n Guanajuato y a los 22 a\u00f1os emigr\u00f3 a Atlanta, Georgia, donde logr\u00f3 establecerse y conseguir trabajo en una tienda de art\u00edculos de piel.<\/p><p>Durante diez a\u00f1os, Isaret, sufri\u00f3 de violencia dom\u00e9stica de parte del padre de sus hijas, situaci\u00f3n que la motiv\u00f3 a apoyar a mujeres inmigrantes en la misma situaci\u00f3n. Fue cuando acudi\u00f3 al Consulado de M\u00e9xico en Orlando y conoci\u00f3 a muchas mujeres que hab\u00edan vivido o estaban viviendo lo mismo que ella.<\/p><p>De esta forma comenz\u00f3 a ayudar a mujeres inmigrantes en condiciones vulnerables y recibi\u00f3 apoyo a trav\u00e9s de donaciones de ropa y comida. De esta forma, en 2017 naci\u00f3 Colectivo \u00c1rbol, que inici\u00f3 sus actividades ofreciendo clases de ingl\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-847556e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"847556e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-46007919\" data-id=\"46007919\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-606cf491 elementor-widget elementor-widget-image\" data-id=\"606cf491\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"463\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/04\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png\" class=\"attachment-full size-full wp-image-41540\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/04\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png 1000w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/04\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n--300x139.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/04\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n--768x356.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/04\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n--18x8.png 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-61c7bf4b\" data-id=\"61c7bf4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3be27396 elementor-widget elementor-widget-text-editor\" data-id=\"3be27396\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Actualmente el colectivo est\u00e1 enfocado en el apoyo comunitario a las mujeres inmigrantes que se dedican a la agricultura. El colectivo ha realizado ferias de salud y campa\u00f1as sociales donde brindaron asesor\u00eda legal, clases de ingl\u00e9s, entre otras actividades.<\/p><p>\u201cLas mujeres trabajadoras del campo son la columna vertebral de las familias que traen las frutas y verduras a nuestras mesas, son parte muy importante de nuestra comunidad y por eso deben ser mujeres fuertes en todos sentidos, no solo f\u00edsicamente sino emocionalmente\u201d, explic\u00f3 Jeffers al medio Sentinel de Orlando.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14a9814a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"14a9814a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-545455ff\" data-id=\"545455ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bf82113 elementor-widget elementor-widget-text-editor\" data-id=\"4bf82113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Asimismo, gracias a la labor de Jeffers y el Colectivo \u00c1rbol, han logrado colabora con el Club Migrante Guanajuatense, el Gobierno de Guanajuato, la Secretar\u00eda del Migrante y Enlace Internacional de Guanajuato, para realizar un programa de reunificaci\u00f3n familiar. A trav\u00e9s de este programa lograron entregar visas a 36 padres mayores de 60 a\u00f1os que no hab\u00edan visto a sus hijos inmigrantes por diez a\u00f1os.<\/p><p>No obstante, la labor del Colectivo no solo se limita a apoyar a inmigrantes mexicanas: \u201cElla (Jeffers) no distingue nacionalidades, no tienen que ser mexicanos, ayuda a la gente de cualquier pa\u00eds, colombianos, ecuatorianos, venezolanos. Es una mujer entregada al servicio de la comunidad, colabora con juguetes para los ni\u00f1os, organiza eventos educativos y mantiene informada a la comunidad\u201d, explic\u00f3 la inmigrante colombiana Carolina Estrada, que ha sido beneficiada por las acciones del colectivo.<\/p><p>Learn more at:<\/p><ul><li><a href=\"https:\/\/facebook.com\/Feedingfamilies2020\">https:\/\/facebook.com\/Feedingfamilies2020<\/a><\/li><li><a href=\"https:\/\/facebook.com\/14isa\">https:\/\/facebook.com\/14isa<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a6b8ca8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7a6b8ca8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72c1ba12\" data-id=\"72c1ba12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-510bcf28 elementor-widget elementor-widget-toggle\" data-id=\"510bcf28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1351\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1351\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1351\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1351\"><p><strong>ORLANDO SENTINEL<\/strong><\/p><p><a href=\"https:\/\/www.orlandosentinel.com\/elsentinel\/comunidad\/os-es-colectivo-arbol-pide-ayuda-lugar-clases-ingles-20180829-story.html\">https:\/\/www.orlandosentinel.com\/elsentinel\/comunidad\/os-es-colectivo-arbol-pide-ayuda-lugar-clases-ingles-20180829-story.html<\/a><\/p><p><a href=\"https:\/\/www.orlandosentinel.com\/elsentinel\/comunidad\/os-es-isaret-jeffers-paisanita-carrion-ayuda-mujeres-campo-20190115-story.html\">https:\/\/www.orlandosentinel.com\/elsentinel\/comunidad\/os-es-isaret-jeffers-paisanita-carrion-ayuda-mujeres-campo-20190115-story.html<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Isaret Jeffers, dirige desde el 2017 el Colectivo \u00c1rbol, que apoya a familias de inmigrantes que se dedican a la agricultura en los campos de Florida y a mujeres inmigrantes v\u00edctimas de violencia.<\/p>","protected":false},"author":14,"featured_media":41540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9,30],"tags":[1303,1304,1148,1301,1305],"class_list":["post-41539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orgullo-latino","category-testimoniales","tag-agricultura","tag-colectivo-arbol","tag-florida","tag-mujeres-inmigrantes","tag-orlando"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Isaret Jeffers la mexicana que apoya a mujeres inmigrantes en condiciones vulnerables a trav\u00e9s de Colectivo \u00c1rbol<\/title>\n<meta name=\"description\" content=\"Isaret Jeffers es una mexicana que ha logrado apoyar a cientos de mujeres inmigrantes en condiciones vulnerables a trav\u00e9s del Colectivo \u00c1rbol.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isaret Jeffers la mexicana que apoya a mujeres inmigrantes en condiciones vulnerables a trav\u00e9s de Colectivo \u00c1rbol | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Isaret Jeffers es una mexicana que ha logrado apoyar a cientos de mujeres inmigrantes en condiciones vulnerables a trav\u00e9s del Colectivo \u00c1rbol.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-08T13:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T19:02:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/04\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"463\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Testimoniales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Isaret Jeffers la mexicana que apoya a mujeres inmigrantes en condiciones vulnerables a trav\u00e9s de Colectivo \u00c1rbol | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Isaret Jeffers es una mexicana que ha logrado apoyar a cientos de mujeres inmigrantes en condiciones vulnerables a trav\u00e9s del Colectivo \u00c1rbol.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/04\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Testimoniales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\\\/orgullo-latino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\\\/orgullo-latino\\\/\"},\"author\":{\"name\":\"Testimoniales\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/f91b6c00888ce85395cb05edc01e916d\"},\"headline\":\"Isaret Jeffers la mexicana que apoya a mujeres inmigrantes en condiciones vulnerables a trav\u00e9s de Colectivo \u00c1rbol\",\"datePublished\":\"2022-04-08T13:01:00+00:00\",\"dateModified\":\"2025-10-22T19:02:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\\\/orgullo-latino\\\/\"},\"wordCount\":464,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\\\/orgullo-latino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png\",\"keywords\":[\"Agricultura\",\"Colectivo \u00c1rbol\",\"Florida\",\"Mujeres inmigrantes\",\"Orlando\"],\"articleSection\":[\"Orgullo Latino\",\"Testimoniales\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\\\/orgullo-latino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\\\/orgullo-latino\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\\\/orgullo-latino\\\/\",\"name\":\"Isaret Jeffers la mexicana que apoya a mujeres inmigrantes en condiciones vulnerables a trav\u00e9s de Colectivo \u00c1rbol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\\\/orgullo-latino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\\\/orgullo-latino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png\",\"datePublished\":\"2022-04-08T13:01:00+00:00\",\"dateModified\":\"2025-10-22T19:02:54+00:00\",\"description\":\"Isaret Jeffers es una mexicana que ha logrado apoyar a cientos de mujeres inmigrantes en condiciones vulnerables a trav\u00e9s del Colectivo \u00c1rbol.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\\\/orgullo-latino\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\\\/orgullo-latino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\\\/orgullo-latino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png\",\"width\":1000,\"height\":463},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\\\/orgullo-latino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Orgullo Latino\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/orgullo-latino\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Isaret Jeffers la mexicana que apoya a mujeres inmigrantes en condiciones vulnerables a trav\u00e9s de Colectivo \u00c1rbol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/f91b6c00888ce85395cb05edc01e916d\",\"name\":\"Testimoniales\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Isaret Jeffers la mexicana que apoya a mujeres inmigrantes en condiciones vulnerables a trav\u00e9s de Colectivo \u00c1rbol","description":"Isaret Jeffers es una mexicana que ha logrado apoyar a cientos de mujeres inmigrantes en condiciones vulnerables a trav\u00e9s del Colectivo \u00c1rbol.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/","og_locale":"en_US","og_type":"article","og_title":"Isaret Jeffers la mexicana que apoya a mujeres inmigrantes en condiciones vulnerables a trav\u00e9s de Colectivo \u00c1rbol | Acceso Latino","og_description":"Isaret Jeffers es una mexicana que ha logrado apoyar a cientos de mujeres inmigrantes en condiciones vulnerables a trav\u00e9s del Colectivo \u00c1rbol.","og_url":"https:\/\/accesolatino.org\/en\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2022-04-08T13:01:00+00:00","article_modified_time":"2025-10-22T19:02:54+00:00","og_image":[{"width":1000,"height":463,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/04\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png","type":"image\/png"}],"author":"Testimoniales","twitter_card":"summary_large_image","twitter_title":"Isaret Jeffers la mexicana que apoya a mujeres inmigrantes en condiciones vulnerables a trav\u00e9s de Colectivo \u00c1rbol | Acceso Latino","twitter_description":"Isaret Jeffers es una mexicana que ha logrado apoyar a cientos de mujeres inmigrantes en condiciones vulnerables a trav\u00e9s del Colectivo \u00c1rbol.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/04\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Testimoniales","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/"},"author":{"name":"Testimoniales","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/f91b6c00888ce85395cb05edc01e916d"},"headline":"Isaret Jeffers la mexicana que apoya a mujeres inmigrantes en condiciones vulnerables a trav\u00e9s de Colectivo \u00c1rbol","datePublished":"2022-04-08T13:01:00+00:00","dateModified":"2025-10-22T19:02:54+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/"},"wordCount":464,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/04\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png","keywords":["Agricultura","Colectivo \u00c1rbol","Florida","Mujeres inmigrantes","Orlando"],"articleSection":["Orgullo Latino","Testimoniales"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/","url":"https:\/\/accesolatino.org\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/","name":"Isaret Jeffers la mexicana que apoya a mujeres inmigrantes en condiciones vulnerables a trav\u00e9s de Colectivo \u00c1rbol","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/04\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png","datePublished":"2022-04-08T13:01:00+00:00","dateModified":"2025-10-22T19:02:54+00:00","description":"Isaret Jeffers es una mexicana que ha logrado apoyar a cientos de mujeres inmigrantes en condiciones vulnerables a trav\u00e9s del Colectivo \u00c1rbol.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/04\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/04\/PW-orgullo-latino-_-La-Paisanita-Carrio\u0301n-.png","width":1000,"height":463},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/isaret-jeffers-la-mexicana-que-apoya-a-mujeres-inmigrantes-en-condiciones-vulnerables-a-traves-de-colectivo-arbol\/orgullo-latino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Orgullo Latino","item":"https:\/\/accesolatino.org\/category\/orgullo-latino\/"},{"@type":"ListItem","position":3,"name":"Isaret Jeffers la mexicana que apoya a mujeres inmigrantes en condiciones vulnerables a trav\u00e9s de Colectivo \u00c1rbol"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/f91b6c00888ce85395cb05edc01e916d","name":"Testimonials"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/41539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=41539"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/41539\/revisions"}],"predecessor-version":[{"id":64966,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/41539\/revisions\/64966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/41540"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=41539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=41539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=41539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}