{"id":41339,"date":"2022-03-23T09:00:00","date_gmt":"2022-03-23T15:00:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=41339"},"modified":"2025-10-22T13:57:55","modified_gmt":"2025-10-22T19:57:55","slug":"para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/","title":{"rendered":"To go to any Mexican consulate you must schedule an appointment"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"41339\" class=\"elementor elementor-41339\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e99297f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2e99297f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad30eab\" data-id=\"ad30eab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47f05bbc elementor-widget elementor-widget-heading\" data-id=\"47f05bbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">All services of the Mexican Consular Network in North America require scheduling an appointment by phone or online.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-363e755e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"363e755e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-605b13d7\" data-id=\"605b13d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-284e66d5 elementor-widget elementor-widget-text-editor\" data-id=\"284e66d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>MiConsulado is the new telephone attention and appointment scheduling service that replaced Mexitel as of March 1 of this year. The General Directorate of Consular Services (DGSC) has promised a more efficient service due to the use of better technology and more telephone operators.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6612214b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6612214b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34c4d717\" data-id=\"34c4d717\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb60497 elementor-widget elementor-widget-image\" data-id=\"eb60497\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png\" class=\"attachment-full size-full wp-image-41340\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png 1000w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita-300x210.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita-768x538.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita-18x12.png 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2375299f\" data-id=\"2375299f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70f15b89 elementor-widget elementor-widget-text-editor\" data-id=\"70f15b89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In this sense, it is necessary to schedule appointments at the consulates in advance. Appointments can be scheduled by calling the new enabled number 1-424-309-0009 or on the new website <a href=\"https:\/\/citas.sre.gob.mx\/\">citas.sre.gob.mx<\/a>.<\/p><p>To schedule an appointment to process a passport, consular registration, voter identification card, dual nationality, among others, it is necessary to do so at least two weeks in advance.<\/p><p>On the other hand, for procedures such as wills, public faith, power of attorney, or repudiation of hereditary rights, it is necessary to schedule the appointment up to four weeks in advance.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55ade69f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"55ade69f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33ea1cc6\" data-id=\"33ea1cc6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3287147c elementor-widget elementor-widget-text-editor\" data-id=\"3287147c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>On the other hand, for any procedure in Mobile Consulates, the appointments open three weeks before the indicated date of each location.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-744892cf elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"744892cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7bea8577\" data-id=\"7bea8577\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4929b5 elementor-widget elementor-widget-toggle\" data-id=\"e4929b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2391\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2391\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2391\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2391\"><p><strong>Secretary of Foreign Relations<\/strong><\/p><p><a href=\"https:\/\/citas.sre.gob.mx\/\">https:\/\/citas.sre.gob.mx\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>All services of the Mexican Consular Network in North America require scheduling an appointment by phone or online.<\/p>","protected":false},"author":10,"featured_media":41340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[518,562,1245,572,148],"class_list":["post-41339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-temas-de-interes","tag-citas","tag-consulado","tag-miconsulado","tag-pasaporte","tag-tramites"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Para acudir a cualquier consulado mexicano debes agendar una cita<\/title>\n<meta name=\"description\" content=\"Depende del tr\u00e1mite una cita en Consulados debe programarse con dos, tres o hasta cuatro semanas de anticipaci\u00f3n v\u00eda telef\u00f3nica o en l\u00ednea.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para acudir a cualquier consulado mexicano debes agendar una cita | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Depende del tr\u00e1mite una cita en Consulados debe programarse con dos, tres o hasta cuatro semanas de anticipaci\u00f3n v\u00eda telef\u00f3nica o en l\u00ednea.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-23T15:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T19:57:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Documentos Documentos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Para acudir a cualquier consulado mexicano debes agendar una cita | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Depende del tr\u00e1mite una cita en Consulados debe programarse con dos, tres o hasta cuatro semanas de anticipaci\u00f3n v\u00eda telef\u00f3nica o en l\u00ednea.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Documentos Documentos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\\\/temas-de-interes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\\\/temas-de-interes\\\/\"},\"author\":{\"name\":\"Documentos Documentos\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/826c76fb759dc85d58f8218f7637a1a9\"},\"headline\":\"Para acudir a cualquier consulado mexicano debes agendar una cita\",\"datePublished\":\"2022-03-23T15:00:00+00:00\",\"dateModified\":\"2025-10-22T19:57:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\\\/temas-de-interes\\\/\"},\"wordCount\":225,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png\",\"keywords\":[\"Citas\",\"Consulado\",\"MiConsulado\",\"pasaporte\",\"Tr\u00e1mites\"],\"articleSection\":[\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\\\/temas-de-interes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\\\/temas-de-interes\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\\\/temas-de-interes\\\/\",\"name\":\"Para acudir a cualquier consulado mexicano debes agendar una cita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\\\/temas-de-interes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\\\/temas-de-interes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png\",\"datePublished\":\"2022-03-23T15:00:00+00:00\",\"dateModified\":\"2025-10-22T19:57:55+00:00\",\"description\":\"Depende del tr\u00e1mite una cita en Consulados debe programarse con dos, tres o hasta cuatro semanas de anticipaci\u00f3n v\u00eda telef\u00f3nica o en l\u00ednea.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\\\/temas-de-interes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\\\/temas-de-interes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\\\/temas-de-interes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png\",\"width\":1000,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\\\/temas-de-interes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temas de inter\u00e9s\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/temas-de-interes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Para acudir a cualquier consulado mexicano debes agendar una cita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/826c76fb759dc85d58f8218f7637a1a9\",\"name\":\"Documentos Documentos\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"To go to any Mexican consulate you must schedule an appointment","description":"Depende del tr\u00e1mite una cita en Consulados debe programarse con dos, tres o hasta cuatro semanas de anticipaci\u00f3n v\u00eda telef\u00f3nica o en l\u00ednea.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/","og_locale":"en_US","og_type":"article","og_title":"Para acudir a cualquier consulado mexicano debes agendar una cita | Acceso Latino","og_description":"Depende del tr\u00e1mite una cita en Consulados debe programarse con dos, tres o hasta cuatro semanas de anticipaci\u00f3n v\u00eda telef\u00f3nica o en l\u00ednea.","og_url":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2022-03-23T15:00:00+00:00","article_modified_time":"2025-10-22T19:57:55+00:00","og_image":[{"width":1000,"height":700,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png","type":"image\/png"}],"author":"Documentos Documentos","twitter_card":"summary_large_image","twitter_title":"Para acudir a cualquier consulado mexicano debes agendar una cita | Acceso Latino","twitter_description":"Depende del tr\u00e1mite una cita en Consulados debe programarse con dos, tres o hasta cuatro semanas de anticipaci\u00f3n v\u00eda telef\u00f3nica o en l\u00ednea.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Documentos Documentos","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/"},"author":{"name":"Documentos Documentos","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/826c76fb759dc85d58f8218f7637a1a9"},"headline":"Para acudir a cualquier consulado mexicano debes agendar una cita","datePublished":"2022-03-23T15:00:00+00:00","dateModified":"2025-10-22T19:57:55+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/"},"wordCount":225,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png","keywords":["Citas","Consulado","MiConsulado","pasaporte","Tr\u00e1mites"],"articleSection":["Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/","url":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/","name":"To go to any Mexican consulate you must schedule an appointment","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png","datePublished":"2022-03-23T15:00:00+00:00","dateModified":"2025-10-22T19:57:55+00:00","description":"Depende del tr\u00e1mite una cita en Consulados debe programarse con dos, tres o hasta cuatro semanas de anticipaci\u00f3n v\u00eda telef\u00f3nica o en l\u00ednea.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/Cuanto-debo-esperar-para-ser-atendido-en-el-consulado-mexicano-despues-de-agendar-una-cita.png","width":1000,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/para-acudir-a-cualquier-consulado-mexicano-debes-agendar-una-cita\/temas-de-interes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Temas de inter\u00e9s","item":"https:\/\/accesolatino.org\/category\/temas-de-interes\/"},{"@type":"ListItem","position":3,"name":"Para acudir a cualquier consulado mexicano debes agendar una cita"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/826c76fb759dc85d58f8218f7637a1a9","name":"Documentos Documentos"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/41339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=41339"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/41339\/revisions"}],"predecessor-version":[{"id":64991,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/41339\/revisions\/64991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/41340"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=41339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=41339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=41339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}