{"id":41178,"date":"2022-03-08T09:18:00","date_gmt":"2022-03-08T15:18:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=41178"},"modified":"2025-10-23T12:22:38","modified_gmt":"2025-10-23T18:22:38","slug":"thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/","title":{"rendered":"TheDream.US ha apoyado a m\u00e1s de 6 mil dreamers a cursar la universidad"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"41178\" class=\"elementor elementor-41178\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-182dfa17 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"182dfa17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-594389bf\" data-id=\"594389bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-772826de elementor-widget elementor-widget-heading\" data-id=\"772826de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TheDream.US ha brindado la oportunidad a miles de estudiantes indocumentados de escasos recursos a cursar y graduarse de la universidad, gracias a sus dos becas Opportunity Scholarship y National Scholarship.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b367781 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1b367781\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ca81dbb\" data-id=\"7ca81dbb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cb2d21c elementor-widget elementor-widget-text-editor\" data-id=\"2cb2d21c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En 2013 naci\u00f3 TheDream.US, el programa privado de becas universitarias para dreamers m\u00e1s grande de Estados Unidos. Desde su creaci\u00f3n han brindado m\u00e1s de 6 mil 500 becas en 70 universidades en 19 estados y Washington D.C. Adem\u00e1s, tan solo hasta el 2020, m\u00e1s de mil 700 becarios concluyeron sus estudios universitarios y lograron graduarse.<\/p><p>De los 6 mil 500 becarios totales hasta 2021, 5 mil 900 recibieron la beca National, que brinda hasta 37 mil d\u00f3lares para un <em>bachelor&#8217;s degree<\/em> en una universidad que forme parte del programa y 600 la beca Opportunity que ofrece hasta 80 mil d\u00f3lares a estudiantes de bachelor&#8217;s degree en universidades alejadas de su estado de origen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-289db9f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"289db9f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-571fedb8\" data-id=\"571fedb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f015e50 elementor-widget elementor-widget-image\" data-id=\"7f015e50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"463\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/PW-Educacio\u0301n-_-The-DreamUS.png\" class=\"attachment-full size-full wp-image-41179\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/PW-Educacio\u0301n-_-The-DreamUS.png 1000w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/PW-Educacio\u0301n-_-The-DreamUS-300x139.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/PW-Educacio\u0301n-_-The-DreamUS-768x356.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/PW-Educacio\u0301n-_-The-DreamUS-18x8.png 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2afabc54\" data-id=\"2afabc54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4477ee0e elementor-widget elementor-widget-text-editor\" data-id=\"4477ee0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Asimismo, los m\u00e1s de 6 mil estudiantes en su totalidad, pertenec\u00edan a familias de bajos ingresos, en este sentido el 83% de los becarios se convirtieron en los primeros miembros de su familia en asistir la universidad.<\/p><p>La edad promedio en la que los becarios llegaron a Estados Unidos es a los cuatro a\u00f1os, por lo que son personas que crecieron y pasaron la mayor parte de su vida en el pa\u00eds.\u00a0 Otro dato relevante es el origen de los becarios, ya que TheDream.US ha logrado otorgar becas a estudiantes de m\u00e1s de 90 pa\u00edses.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f711b17 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4f711b17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5bdba5b0\" data-id=\"5bdba5b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6067932 elementor-widget elementor-widget-text-editor\" data-id=\"6067932\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los beneficiarios de Acci\u00f3n Diferida, representan el 79% del total de los becarios y el 3 y 18% corresponden estudiantes con Estatus de Protecci\u00f3n Temporal (TPS) y estudiantes indocumentados sin DACA ni TPS, respectivamente.<\/p><p>Existe una gran variedad de sectores laborales en los que los antiguos becarios y ahora profesionales se encuentran trabajando, por ejemplo, en servicios p\u00fablicos y sociales, negocios, ciencia y tecnolog\u00eda, medios y ciencias sociales, medicina y salud, servicios personales y arte, entretenimiento y deportes.<\/p><p>El \u00e9xito del programa tambi\u00e9n radica en el alto porcentaje de graduados que se encuentran trabajando (85%), adem\u00e1s el 76% trabajan en industrias consideradas esenciales o de primera l\u00ednea.<\/p><p>Asimismo, el 67% de los graduados encontraron un trabajo que cumple con sus intereses profesionales, 48% ya ha recibido un aumento o una promoci\u00f3n, 74% cuenta con beneficios de empleo y el 6% trabajan por su propia cuenta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4dd6e113 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4dd6e113\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-718aa2e0\" data-id=\"718aa2e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c069f19 elementor-widget elementor-widget-toggle\" data-id=\"c069f19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2011\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2011\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2011\"><p><strong>THEDREAM.US <\/strong><\/p><p><a href=\"https:\/\/impactreport.thedream.us\/\">https:\/\/impactreport.thedream.us\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>TheDream.US ha brindado la oportunidad a miles de estudiantes indocumentados de escasos recursos a cursar y graduarse de la universidad, gracias a sus dos becas Opportunity Scholarship y National Scholarship.<\/p>","protected":false},"author":7,"featured_media":41179,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-41178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TheDream.US ha apoyado a m\u00e1s de 6 mil dreamers a cursar la universidad<\/title>\n<meta name=\"description\" content=\"TheDream.US, el programa de becas para dreamers m\u00e1s grande de Estados Unidos ha apoyado a m\u00e1s de 6 mil estudiantes indocumentados a cursar la universidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TheDream.US ha apoyado a m\u00e1s de 6 mil dreamers a cursar la universidad | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"TheDream.US, el programa de becas para dreamers m\u00e1s grande de Estados Unidos ha apoyado a m\u00e1s de 6 mil estudiantes indocumentados a cursar la universidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-08T15:18:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-23T18:22:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/PW-Educacio\u0301n-_-The-DreamUS.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"463\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Educacion Educacion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"TheDream.US ha apoyado a m\u00e1s de 6 mil dreamers a cursar la universidad | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"TheDream.US, el programa de becas para dreamers m\u00e1s grande de Estados Unidos ha apoyado a m\u00e1s de 6 mil estudiantes indocumentados a cursar la universidad.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/PW-Educacio\u0301n-_-The-DreamUS.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Educacion Educacion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\\\/educacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\\\/educacion\\\/\"},\"author\":{\"name\":\"Educacion Educacion\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/c646484d487fbb885a5279d51e9d225d\"},\"headline\":\"TheDream.US ha apoyado a m\u00e1s de 6 mil dreamers a cursar la universidad\",\"datePublished\":\"2022-03-08T15:18:00+00:00\",\"dateModified\":\"2025-10-23T18:22:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\\\/educacion\\\/\"},\"wordCount\":406,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\\\/educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/PW-Educacio\u0301n-_-The-DreamUS.png\",\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\\\/educacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\\\/educacion\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\\\/educacion\\\/\",\"name\":\"TheDream.US ha apoyado a m\u00e1s de 6 mil dreamers a cursar la universidad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\\\/educacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\\\/educacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/PW-Educacio\u0301n-_-The-DreamUS.png\",\"datePublished\":\"2022-03-08T15:18:00+00:00\",\"dateModified\":\"2025-10-23T18:22:38+00:00\",\"description\":\"TheDream.US, el programa de becas para dreamers m\u00e1s grande de Estados Unidos ha apoyado a m\u00e1s de 6 mil estudiantes indocumentados a cursar la universidad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\\\/educacion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\\\/educacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\\\/educacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/PW-Educacio\u0301n-_-The-DreamUS.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/PW-Educacio\u0301n-_-The-DreamUS.png\",\"width\":1000,\"height\":463},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\\\/educacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Educaci\u00f3n\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/educacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TheDream.US ha apoyado a m\u00e1s de 6 mil dreamers a cursar la universidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/c646484d487fbb885a5279d51e9d225d\",\"name\":\"Educacion Educacion\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TheDream.US ha apoyado a m\u00e1s de 6 mil dreamers a cursar la universidad","description":"TheDream.US, el programa de becas para dreamers m\u00e1s grande de Estados Unidos ha apoyado a m\u00e1s de 6 mil estudiantes indocumentados a cursar la universidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/","og_locale":"en_US","og_type":"article","og_title":"TheDream.US ha apoyado a m\u00e1s de 6 mil dreamers a cursar la universidad | Acceso Latino","og_description":"TheDream.US, el programa de becas para dreamers m\u00e1s grande de Estados Unidos ha apoyado a m\u00e1s de 6 mil estudiantes indocumentados a cursar la universidad.","og_url":"https:\/\/accesolatino.org\/en\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2022-03-08T15:18:00+00:00","article_modified_time":"2025-10-23T18:22:38+00:00","og_image":[{"width":1000,"height":463,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/PW-Educacio\u0301n-_-The-DreamUS.png","type":"image\/png"}],"author":"Educacion Educacion","twitter_card":"summary_large_image","twitter_title":"TheDream.US ha apoyado a m\u00e1s de 6 mil dreamers a cursar la universidad | Acceso Latino","twitter_description":"TheDream.US, el programa de becas para dreamers m\u00e1s grande de Estados Unidos ha apoyado a m\u00e1s de 6 mil estudiantes indocumentados a cursar la universidad.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/PW-Educacio\u0301n-_-The-DreamUS.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Educacion Educacion","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/"},"author":{"name":"Educacion Educacion","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/c646484d487fbb885a5279d51e9d225d"},"headline":"TheDream.US ha apoyado a m\u00e1s de 6 mil dreamers a cursar la universidad","datePublished":"2022-03-08T15:18:00+00:00","dateModified":"2025-10-23T18:22:38+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/"},"wordCount":406,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/PW-Educacio\u0301n-_-The-DreamUS.png","articleSection":["Educaci\u00f3n"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/","url":"https:\/\/accesolatino.org\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/","name":"TheDream.US ha apoyado a m\u00e1s de 6 mil dreamers a cursar la universidad","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/PW-Educacio\u0301n-_-The-DreamUS.png","datePublished":"2022-03-08T15:18:00+00:00","dateModified":"2025-10-23T18:22:38+00:00","description":"TheDream.US, el programa de becas para dreamers m\u00e1s grande de Estados Unidos ha apoyado a m\u00e1s de 6 mil estudiantes indocumentados a cursar la universidad.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/PW-Educacio\u0301n-_-The-DreamUS.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2022\/03\/PW-Educacio\u0301n-_-The-DreamUS.png","width":1000,"height":463},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/thedream-us-ha-apoyado-a-mas-de-6-mil-dreamers-a-cursar-la-universidad\/educacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Educaci\u00f3n","item":"https:\/\/accesolatino.org\/category\/educacion\/"},{"@type":"ListItem","position":3,"name":"TheDream.US ha apoyado a m\u00e1s de 6 mil dreamers a cursar la universidad"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/c646484d487fbb885a5279d51e9d225d","name":"Educacion Educacion"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/41178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=41178"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/41178\/revisions"}],"predecessor-version":[{"id":65024,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/41178\/revisions\/65024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/41179"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=41178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=41178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=41178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}