{"id":39893,"date":"2021-11-17T06:50:00","date_gmt":"2021-11-17T12:50:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=39893"},"modified":"2025-10-24T13:39:59","modified_gmt":"2025-10-24T19:39:59","slug":"conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/","title":{"rendered":"Learn about the main reasons for deportation of foreigners in the United States"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"39893\" class=\"elementor elementor-39893\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e9284d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1e9284d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c27fa0b\" data-id=\"6c27fa0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ff4b4a5 elementor-widget elementor-widget-heading\" data-id=\"4ff4b4a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The main reasons why an undocumented immigrant is deported are directly related to the commission of a crime or the violation of immigration laws.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43ace6ce elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"43ace6ce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12676217\" data-id=\"12676217\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a470182 elementor-widget elementor-widget-text-editor\" data-id=\"7a470182\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Immigration and Nationality Law in section 237 describes each and every one of the reasons why a foreigner can be deported from the United States, you can consult them <a href=\"https:\/\/uscode.house.gov\/view.xhtml?req=granuleid:USC-prelim-title8-section1227&amp;num=0&amp;edition=prelim\">here<\/a>. The agency responsible for carrying out immigration-related deportations and detentions is the Immigration and Customs Enforcement Service (ICE).<\/p><p>The main reason a foreign national can be deported from the United States, regardless of their immigration status (even if they are a permanent resident), is the commission of a felony.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32e0a879 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"32e0a879\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-718f057d\" data-id=\"718f057d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b46378c elementor-widget elementor-widget-image\" data-id=\"b46378c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/11\/causas-de-deportacion-mas-comunes.png\" class=\"attachment-full size-full wp-image-39894\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/11\/causas-de-deportacion-mas-comunes.png 1000w, https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/11\/causas-de-deportacion-mas-comunes-300x210.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/11\/causas-de-deportacion-mas-comunes-768x538.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/11\/causas-de-deportacion-mas-comunes-18x12.png 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Photo: prensalibre.com<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34cd1364\" data-id=\"34cd1364\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68a36da1 elementor-widget elementor-widget-text-editor\" data-id=\"68a36da1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Some of the serious crimes are foreign trafficking, document fraud, domestic violence, drug-related crimes, firearm trafficking, money laundering, terrorism, rape or murder.<\/p><p>Although each state classifies crimes differently, either as serious or minor, ICE carries out its own judgment on the crime, so it can even lead to deportation for crimes considered minor.<\/p><p>Another case that could possibly end in deportation is the violation of immigration laws, for example, falsification of documents, fraudulent marriages, among others.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c5a3ef7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6c5a3ef7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41215767\" data-id=\"41215767\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ff8962f elementor-widget elementor-widget-text-editor\" data-id=\"1ff8962f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>On the other hand, tourists, non-immigrant workers and students can be deported if they do not comply with the conditions of their visa. For example, if an exchange student gets a job, she would be at risk of being deported because she does not have the permits to carry out commercial activities in the country.<\/p><p>Similarly, Green Card holders can be deported if they do not send notifications to the Citizenship and Immigration Services (USCIS), about changes of address or if they do not prove not to be a \"public charge\" five years after receiving the certificate. permanent residence.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7355d946 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7355d946\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef73384\" data-id=\"ef73384\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62b23abf elementor-widget elementor-widget-toggle\" data-id=\"62b23abf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1651\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1651\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1651\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1651\"><p><strong>CONEXI\u00d3N MIGRANTE<\/strong><\/p><p><a href=\"https:\/\/conexionmigrante.com\/2021-\/01-\/10\/estas-son-las-causas-mas-comunes-por-los-que-se-puedes-ser-deportado-de-usa\/\">https:\/\/conexionmigrante.com\/2021-\/01-\/10\/estas-son-las-causas-mas-comunes-por-los-que-se-puedes-ser-deportado-de-usa\/<\/a><\/p><p><strong>ALL LAW<\/strong><\/p><p><a href=\"https:\/\/www.alllaw.com\/articles\/nolo\/us-immigration\/legal-reasons-immigrant-may-be-deported.html\">https:\/\/www.alllaw.com\/articles\/nolo\/us-immigration\/legal-reasons-immigrant-may-be-deported.html<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>The main reasons why an undocumented immigrant is deported are directly related to the commission of a crime or the violation of immigration laws.<\/p>","protected":false},"author":13,"featured_media":39894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[312,12],"tags":[73,247,640,800,61,551,133,139,87,86],"class_list":["post-39893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asesoria-legal","category-tramites","tag-biden","tag-deportacion","tag-deportacion-migrantes","tag-deportaciones","tag-dreamers","tag-extranjeros","tag-green-card","tag-ice","tag-inmigrantes","tag-migrantes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conoce cu\u00e1les son las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos<\/title>\n<meta name=\"description\" content=\"Las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos son la comisi\u00f3n de delitos o la violaci\u00f3n de las leyes de inmigraci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conoce cu\u00e1les son las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"Las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos son la comisi\u00f3n de delitos o la violaci\u00f3n de las leyes de inmigraci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-17T12:50:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-24T19:39:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/11\/causas-de-deportacion-mas-comunes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Conoce cu\u00e1les son las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"Las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos son la comisi\u00f3n de delitos o la violaci\u00f3n de las leyes de inmigraci\u00f3n.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/11\/causas-de-deportacion-mas-comunes.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\\\/tramites\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\\\/tramites\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Conoce cu\u00e1les son las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos\",\"datePublished\":\"2021-11-17T12:50:00+00:00\",\"dateModified\":\"2025-10-24T19:39:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\\\/tramites\\\/\"},\"wordCount\":362,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\\\/tramites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/causas-de-deportacion-mas-comunes.png\",\"keywords\":[\"Biden\",\"Deportaci\u00f3n\",\"deportacion migrantes\",\"deportaciones\",\"Dreamers\",\"Extranjeros\",\"Green Card\",\"ICE\",\"Inmigrantes\",\"Migrantes\"],\"articleSection\":[\"Asesor\u00eda Legal\",\"Tr\u00e1mites\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\\\/tramites\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\\\/tramites\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\\\/tramites\\\/\",\"name\":\"Conoce cu\u00e1les son las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\\\/tramites\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\\\/tramites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/causas-de-deportacion-mas-comunes.png\",\"datePublished\":\"2021-11-17T12:50:00+00:00\",\"dateModified\":\"2025-10-24T19:39:59+00:00\",\"description\":\"Las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos son la comisi\u00f3n de delitos o la violaci\u00f3n de las leyes de inmigraci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\\\/tramites\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\\\/tramites\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\\\/tramites\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/causas-de-deportacion-mas-comunes.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/causas-de-deportacion-mas-comunes.png\",\"width\":1000,\"height\":700,\"caption\":\"Foto: prensalibre.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\\\/tramites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tr\u00e1mites\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/tramites\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conoce cu\u00e1les son las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Learn about the main reasons for deportation of foreigners in the United States","description":"Las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos son la comisi\u00f3n de delitos o la violaci\u00f3n de las leyes de inmigraci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/","og_locale":"en_US","og_type":"article","og_title":"Conoce cu\u00e1les son las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos | Acceso Latino","og_description":"Las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos son la comisi\u00f3n de delitos o la violaci\u00f3n de las leyes de inmigraci\u00f3n.","og_url":"https:\/\/accesolatino.org\/en\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2021-11-17T12:50:00+00:00","article_modified_time":"2025-10-24T19:39:59+00:00","og_image":[{"width":1000,"height":700,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/11\/causas-de-deportacion-mas-comunes.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_title":"Conoce cu\u00e1les son las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos | Acceso Latino","twitter_description":"Las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos son la comisi\u00f3n de delitos o la violaci\u00f3n de las leyes de inmigraci\u00f3n.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/11\/causas-de-deportacion-mas-comunes.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Conoce cu\u00e1les son las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos","datePublished":"2021-11-17T12:50:00+00:00","dateModified":"2025-10-24T19:39:59+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/"},"wordCount":362,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/11\/causas-de-deportacion-mas-comunes.png","keywords":["Biden","Deportaci\u00f3n","deportacion migrantes","deportaciones","Dreamers","Extranjeros","Green Card","ICE","Inmigrantes","Migrantes"],"articleSection":["Asesor\u00eda Legal","Tr\u00e1mites"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/","url":"https:\/\/accesolatino.org\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/","name":"Learn about the main reasons for deportation of foreigners in the United States","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/11\/causas-de-deportacion-mas-comunes.png","datePublished":"2021-11-17T12:50:00+00:00","dateModified":"2025-10-24T19:39:59+00:00","description":"Las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos son la comisi\u00f3n de delitos o la violaci\u00f3n de las leyes de inmigraci\u00f3n.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/11\/causas-de-deportacion-mas-comunes.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/11\/causas-de-deportacion-mas-comunes.png","width":1000,"height":700,"caption":"Foto: prensalibre.com"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/conoce-cuales-son-las-principales-razones-de-deportacion-de-extranjeros-en-estados-unidos\/tramites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Tr\u00e1mites","item":"https:\/\/accesolatino.org\/category\/tramites\/"},{"@type":"ListItem","position":3,"name":"Conoce cu\u00e1les son las principales razones de deportaci\u00f3n de extranjeros en Estados Unidos"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/39893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=39893"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/39893\/revisions"}],"predecessor-version":[{"id":65202,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/39893\/revisions\/65202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/39894"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=39893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=39893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=39893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}