{"id":39251,"date":"2021-10-07T09:00:00","date_gmt":"2021-10-07T14:00:00","guid":{"rendered":"https:\/\/accesolatino.org\/?p=39251"},"modified":"2025-10-24T14:25:32","modified_gmt":"2025-10-24T20:25:32","slug":"que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/","title":{"rendered":"What is and how does the Joe Biden government proposal to change the DACA rule work?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"39251\" class=\"elementor elementor-39251\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73a9ddbb elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"73a9ddbb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e98c96a\" data-id=\"3e98c96a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91c43b5 elementor-widget elementor-widget-heading\" data-id=\"91c43b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">On September 27, the Department of Homeland Security (DHS) announced a proposed rulemaking that would prevent the deportation of Deferred Action for Childhood Arrivals (DACA) beneficiaries.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2045fd72 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2045fd72\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28391891\" data-id=\"28391891\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52aca07b elementor-widget elementor-widget-text-editor\" data-id=\"52aca07b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>On July 16 of this year, a federal judge in the state of Texas declared the DACA program illegal, and initial applications for this program have been suspended. However, the DHS with the Notice of Proposed Rulemaking (NPRM) on DACA, hopes that progress will be made in the defense and protection of the <em>dreamers<\/em>.<\/p><p>\"The Biden-Harris Administration continues to take steps to protect Dreamers and recognize their contributions to this country,\" said Homeland Security Secretary Alejandro Mayorkas. The secretary explained that the notice of proposed rulemaking announced by DHS is only one step towards achieving the protection of immigrants. However, he recognized that only through Congress will it be possible to provide permanent protection to this population.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-780146e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"780146e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f2fa9b3\" data-id=\"f2fa9b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e9a0947 elementor-widget elementor-widget-image\" data-id=\"7e9a0947\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png\" class=\"attachment-full size-full wp-image-39252\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png 1000w, https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion-300x210.png 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion-768x538.png 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion-16x12.png 16w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4276213a\" data-id=\"4276213a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f9c5ab5 elementor-widget elementor-widget-text-editor\" data-id=\"3f9c5ab5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>DACA, which was announced in 2012 under the practices of the US Citizenship and Immigration Services (USCIS), considers that its beneficiaries should not be a priority for deportation. And this is precisely what the new regulation proposed by the Joe Biden government seeks.<\/p><p>\u201cDHS continues to accept and process DACA renewal applications under the terms of DACA policy, as permitted by court order. The Biden-Harris Administration appealed the Texas court's ruling. The issuance of the NPRM does not affect the court order or DHS's obligations under the order, \u201dDHS explained in a statement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f7b4e00 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1f7b4e00\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-77a4dd2b\" data-id=\"77a4dd2b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f67a14 elementor-widget elementor-widget-toggle\" data-id=\"7f67a14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1331\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1331\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1331\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1331\"><p><strong>DHS<\/strong><\/p><p><a href=\"https:\/\/www.dhs.gov\/news\/2021\/09\/27\/dhs-publish-notice-proposed-rulemaking-daca\">https:\/\/www.dhs.gov\/news\/2021\/09\/27\/dhs-publish-notice-proposed-rulemaking-daca<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>On September 27, the Department of Homeland Security (DHS) announced a proposed rulemaking that would prevent the deportation of Deferred Action for Childhood Arrivals (DACA) beneficiaries.<\/p>","protected":false},"author":13,"featured_media":39252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[168,198],"tags":[309,73,167,679,61],"class_list":["post-39251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biden","category-plan-biden","tag-alejandro-mayorkas","tag-biden","tag-departamento-de-seguridad-nacional","tag-deportacion-de-migrantes","tag-dreamers"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El 27 de septiembre el Departamento de Seguridad Nacional (DHS, en ingl\u00e9s) anunci\u00f3 una propuesta de reglamentaci\u00f3n que evitar\u00eda la deportaci\u00f3n de beneficiarios de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA).\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Noticias\"\/>\n\t<meta name=\"google-site-verification\" content=\"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE\" \/>\n\t<meta name=\"keywords\" content=\"alejandro mayorkas,biden,departamento de seguridad nacional,deportaci\u00f3n de migrantes,dreamers,plan biden\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?\" \/>\n\t\t<meta property=\"og:description\" content=\"El 27 de septiembre el Departamento de Seguridad Nacional (DHS, en ingl\u00e9s) anunci\u00f3 una propuesta de reglamentaci\u00f3n que evitar\u00eda la deportaci\u00f3n de beneficiarios de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA).\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-10-07T14:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-24T20:25:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El 27 de septiembre el Departamento de Seguridad Nacional (DHS, en ingl\u00e9s) anunci\u00f3 una propuesta de reglamentaci\u00f3n que evitar\u00eda la deportaci\u00f3n de beneficiarios de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA).\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#blogposting\",\"name\":\"\\u00bfQu\\u00e9 es y c\\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\\u00f3n de DACA?\",\"headline\":\"\\u00bfQu\\u00e9 es y c\\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\\u00f3n de DACA?\",\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/\\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png\",\"width\":1000,\"height\":700,\"caption\":\"Foto: washingtonpost.com\"},\"datePublished\":\"2021-10-07T09:00:00-05:00\",\"dateModified\":\"2025-10-24T14:25:32-06:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#webpage\"},\"articleSection\":\"Biden, Plan Biden, Alejandro Mayorkas, Biden, Departamento de Seguridad Nacional, deportaci\\u00f3n de migrantes, Dreamers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/biden\\\/#listItem\",\"name\":\"Biden\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/biden\\\/#listItem\",\"position\":2,\"name\":\"Biden\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/biden\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#listItem\",\"name\":\"\\u00bfQu\\u00e9 es y c\\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\\u00f3n de DACA?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#listItem\",\"position\":3,\"name\":\"\\u00bfQu\\u00e9 es y c\\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\\u00f3n de DACA?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/category\\\/biden\\\/#listItem\",\"name\":\"Biden\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#organizationLogo\",\"width\":240,\"height\":40},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/\",\"name\":\"Noticias\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#webpage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/\",\"name\":\"\\u00bfQu\\u00e9 es y c\\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\\u00f3n de DACA?\",\"description\":\"El 27 de septiembre el Departamento de Seguridad Nacional (DHS, en ingl\\u00e9s) anunci\\u00f3 una propuesta de reglamentaci\\u00f3n que evitar\\u00eda la deportaci\\u00f3n de beneficiarios de Acci\\u00f3n Diferida para los Llegados en la Infancia (DACA).\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/author\\\/noticias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/\\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#mainImage\",\"width\":1000,\"height\":700,\"caption\":\"Foto: washingtonpost.com\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#mainImage\"},\"datePublished\":\"2021-10-07T09:00:00-05:00\",\"dateModified\":\"2025-10-24T14:25:32-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/\",\"name\":\"Acceso Latino\",\"description\":\"Fundaci\\u00f3n Carlos Slim\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"What is and how does the Joe Biden government proposal to change the DACA rule work?","description":"On September 27, the Department of Homeland Security (DHS) announced a proposed rulemaking that would prevent the deportation of Deferred Action for Childhood Arrivals (DACA) beneficiaries.","canonical_url":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/","robots":"max-image-preview:large","keywords":"alejandro mayorkas,biden,departamento de seguridad nacional,deportaci\u00f3n de migrantes,dreamers,plan biden","webmasterTools":{"google-site-verification":"Z_-BGsTuwqZx0Xdr6iQS0vlsm11t7p4fBNFDiXbmAZE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#blogposting","name":"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?","headline":"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?","author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png","width":1000,"height":700,"caption":"Foto: washingtonpost.com"},"datePublished":"2021-10-07T09:00:00-05:00","dateModified":"2025-10-24T14:25:32-06:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#webpage"},"isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#webpage"},"articleSection":"Biden, Plan Biden, Alejandro Mayorkas, Biden, Departamento de Seguridad Nacional, deportaci\u00f3n de migrantes, Dreamers"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","position":1,"name":"Home","item":"https:\/\/accesolatino.org\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/biden\/#listItem","name":"Biden"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/biden\/#listItem","position":2,"name":"Biden","item":"https:\/\/accesolatino.org\/en\/category\/biden\/","nextItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#listItem","name":"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#listItem","position":3,"name":"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?","previousItem":{"@type":"ListItem","@id":"https:\/\/accesolatino.org\/en\/category\/biden\/#listItem","name":"Biden"}}]},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/en\/#organization","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#organizationLogo","width":240,"height":40},"image":{"@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author","url":"https:\/\/accesolatino.org\/en\/author\/noticias\/","name":"Noticias"},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#webpage","url":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/","name":"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?","description":"El 27 de septiembre el Departamento de Seguridad Nacional (DHS, en ingl\u00e9s) anunci\u00f3 una propuesta de reglamentaci\u00f3n que evitar\u00eda la deportaci\u00f3n de beneficiarios de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA).","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#breadcrumblist"},"author":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"creator":{"@id":"https:\/\/accesolatino.org\/en\/author\/noticias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png","@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#mainImage","width":1000,"height":700,"caption":"Foto: washingtonpost.com"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#mainImage"},"datePublished":"2021-10-07T09:00:00-05:00","dateModified":"2025-10-24T14:25:32-06:00"},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/en\/#website","url":"https:\/\/accesolatino.org\/en\/","name":"Acceso Latino","description":"Fundaci\u00f3n Carlos Slim","inLanguage":"en-US","publisher":{"@id":"https:\/\/accesolatino.org\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Acceso Latino \u00bb Fundaci\u00f3n Carlos Slim","og:type":"article","og:title":"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?","og:description":"El 27 de septiembre el Departamento de Seguridad Nacional (DHS, en ingl\u00e9s) anunci\u00f3 una propuesta de reglamentaci\u00f3n que evitar\u00eda la deportaci\u00f3n de beneficiarios de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA).","og:url":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/","article:published_time":"2021-10-07T14:00:00+00:00","article:modified_time":"2025-10-24T20:25:32+00:00","twitter:card":"summary_large_image","twitter:title":"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?","twitter:description":"El 27 de septiembre el Departamento de Seguridad Nacional (DHS, en ingl\u00e9s) anunci\u00f3 una propuesta de reglamentaci\u00f3n que evitar\u00eda la deportaci\u00f3n de beneficiarios de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA)."},"aioseo_meta_data":{"post_id":"39251","title":"#post_title","description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-07-14 06:55:07","updated":"2025-10-24 20:26:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/accesolatino.org\/en\/category\/biden\/\" title=\"Biden\">Biden<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/accesolatino.org\/en"},{"label":"Biden","link":"https:\/\/accesolatino.org\/en\/category\/biden\/"},{"label":"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?","link":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?<\/title>\n<meta name=\"description\" content=\"El Departamento de Seguridad Nacional ha propuesto un cambio de reglamentaci\u00f3n de DACA, para evitar la deportaci\u00f3n de sus beneficiarios.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA? | Acceso Latino\" \/>\n<meta property=\"og:description\" content=\"El Departamento de Seguridad Nacional ha propuesto un cambio de reglamentaci\u00f3n de DACA, para evitar la deportaci\u00f3n de sus beneficiarios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-07T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-24T20:25:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA? | Acceso Latino\" \/>\n<meta name=\"twitter:description\" content=\"El Departamento de Seguridad Nacional ha propuesto un cambio de reglamentaci\u00f3n de DACA, para evitar la deportaci\u00f3n de sus beneficiarios.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\"},\"headline\":\"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?\",\"datePublished\":\"2021-10-07T14:00:00+00:00\",\"dateModified\":\"2025-10-24T20:25:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/\"},\"wordCount\":328,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png\",\"keywords\":[\"Alejandro Mayorkas\",\"Biden\",\"Departamento de Seguridad Nacional\",\"deportaci\u00f3n de migrantes\",\"Dreamers\"],\"articleSection\":[\"Biden\",\"Plan Biden\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/\",\"name\":\"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png\",\"datePublished\":\"2021-10-07T14:00:00+00:00\",\"dateModified\":\"2025-10-24T20:25:32+00:00\",\"description\":\"El Departamento de Seguridad Nacional ha propuesto un cambio de reglamentaci\u00f3n de DACA, para evitar la deportaci\u00f3n de sus beneficiarios.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png\",\"width\":1000,\"height\":700,\"caption\":\"Foto: washingtonpost.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\\\/biden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biden\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/biden\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/2ab87d8d821c5dd6fc56121eb4758905\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"What is and how does the Joe Biden government proposal to change the DACA rule work?","description":"El Departamento de Seguridad Nacional ha propuesto un cambio de reglamentaci\u00f3n de DACA, para evitar la deportaci\u00f3n de sus beneficiarios.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA? | Acceso Latino","og_description":"El Departamento de Seguridad Nacional ha propuesto un cambio de reglamentaci\u00f3n de DACA, para evitar la deportaci\u00f3n de sus beneficiarios.","og_url":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2021-10-07T14:00:00+00:00","article_modified_time":"2025-10-24T20:25:32+00:00","og_image":[{"width":1000,"height":700,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_title":"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA? | Acceso Latino","twitter_description":"El Departamento de Seguridad Nacional ha propuesto un cambio de reglamentaci\u00f3n de DACA, para evitar la deportaci\u00f3n de sus beneficiarios.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905"},"headline":"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?","datePublished":"2021-10-07T14:00:00+00:00","dateModified":"2025-10-24T20:25:32+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/"},"wordCount":328,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png","keywords":["Alejandro Mayorkas","Biden","Departamento de Seguridad Nacional","deportaci\u00f3n de migrantes","Dreamers"],"articleSection":["Biden","Plan Biden"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/","url":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/","name":"What is and how does the Joe Biden government proposal to change the DACA rule work?","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png","datePublished":"2021-10-07T14:00:00+00:00","dateModified":"2025-10-24T20:25:32+00:00","description":"El Departamento de Seguridad Nacional ha propuesto un cambio de reglamentaci\u00f3n de DACA, para evitar la deportaci\u00f3n de sus beneficiarios.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/10\/\u00bfQue-es-y-como-funciona-la-propuesta-de-Joe-Biden-para-proteger-a-los-dreamers-de-la-deportacion.png","width":1000,"height":700,"caption":"Foto: washingtonpost.com"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/que-es-y-como-funciona-la-propuesta-del-gobierno-de-joe-biden-para-cambiar-la-reglamentacion-de-daca\/biden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Biden","item":"https:\/\/accesolatino.org\/category\/biden\/"},{"@type":"ListItem","position":3,"name":"\u00bfQu\u00e9 es y c\u00f3mo funciona la propuesta del gobierno de Joe Biden para cambiar la reglamentaci\u00f3n de DACA?"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/2ab87d8d821c5dd6fc56121eb4758905","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/39251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=39251"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/39251\/revisions"}],"predecessor-version":[{"id":65258,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/39251\/revisions\/65258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/39252"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=39251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=39251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=39251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}