{"id":38221,"date":"2021-07-26T09:00:00","date_gmt":"2021-07-26T14:00:00","guid":{"rendered":"https:\/\/accesolatino.org\/noticias\/que-dice-la-ley-de-vivienda-justa-y-como-protege-a-los-inmigrantes-copy\/"},"modified":"2025-10-24T15:48:20","modified_gmt":"2025-10-24T21:48:20","slug":"la-ley-de-vivienda-justa-y-los-inmigrantes","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/","title":{"rendered":"The Fair Housing Act and immigrants"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"38221\" class=\"elementor elementor-38221\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e5aa982 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6e5aa982\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23f0ea21\" data-id=\"23f0ea21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-334a74aa elementor-widget elementor-widget-heading\" data-id=\"334a74aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fair Housing Act, or Fair Housing Act, a law that protects the population from discrimination when renting or purchasing a home in the United States.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-117375cc elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"117375cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6995cf70\" data-id=\"6995cf70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-255a9b28 elementor-widget elementor-widget-text-editor\" data-id=\"255a9b28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Law establishes the prohibition of acts of discrimination when selling, renting or financing a home, based on race, religion, nationality, sex, disability or family status.\u00a0<\/p><p>This law dates from 1968, during the administration of Democratic President Lyndon B. Johnson, when he signed the Civil Rights Act. which currently covers most of the homes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bda815 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1bda815\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1413ef12\" data-id=\"1413ef12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31ef994b elementor-widget elementor-widget-image\" data-id=\"31ef994b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/07\/vivienda-justa.jpg\" class=\"attachment-full size-full wp-image-38223\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/07\/vivienda-justa.jpg 1000w, https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/07\/vivienda-justa-300x200.jpg 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/07\/vivienda-justa-768x512.jpg 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/07\/vivienda-justa-16x12.jpg 16w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2be4f814\" data-id=\"2be4f814\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3af2dd8e elementor-widget elementor-widget-text-editor\" data-id=\"3af2dd8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cIn very limited circumstances, the Act exempts owner-occupied buildings with no more than four units, single-family homes sold or rented by the owner without the use of an agent, and homes operated by religious organizations and private clubs that limit the occupation to the members \u201d, as explained by the Department of Housing and Urban Development of the United States.<\/p><p><strong>What does the law prohibit? <\/strong><\/p><p>Fair Housing Law, considers discrimination related to the aforementioned reasons illegal (based on race, color, religion, sex, disability, family status or national origin) when renting or selling a home, in situations such as the following:\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f8a1ead elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1f8a1ead\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6986c77\" data-id=\"6986c77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6adc02cd elementor-widget elementor-widget-text-editor\" data-id=\"6adc02cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Refusing to rent or sell a home<\/li><li>Refusing to negotiate a home<\/li><li>Establish different terms, conditions or privileges for the sale or rental of a home<\/li><li>Providing a person with different housing services or facilities<\/li><li>Falsely denying that the home is available for inspection, sale, or rental<\/li><li>Make, print, or post any notice, statement, or advertisement regarding the sale or rental of a home that indicates any preference, limitation, or discrimination<\/li><li>Impose different sales prices or rental charges for the sale or rental of a home<\/li><li>Utilice diferentes criterios de calificaci\u00f3n o aplicaciones, o est\u00e1ndares o procedimientos de venta o alquiler, como est\u00e1ndares de ingresos, requisitos de solicitud, tarifas de solicitud, an\u00e1lisis de cr\u00e9dito, procedimientos de aprobaci\u00f3n de venta o alquiler u otros requisitos<\/li><li>Evicting a tenant or a tenant's guest, among others.<\/li><\/ul><p>The Law also protects the population from discrimination when applying for a mortgage loan, for example, refusing to provide information on mortgage loans, conditioning them or not providing the assistance required for any of the aforementioned discrimination grounds.<\/p><p>Learn more at the following link:\u00a0<a style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\" href=\"https:\/\/www.hud.gov\/program_offices\/fair_housing_equal_opp\/fair_housing_act_overview\">https:\/\/www.hud.gov\/program_offices\/fair_housing_equal_opp\/fair_housing_act_overview<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b49c127 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2b49c127\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5faff873\" data-id=\"5faff873\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-466b1d20 elementor-widget elementor-widget-toggle\" data-id=\"466b1d20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1181\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1181\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1181\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1181\"><p><strong>US DEPARTMENT OF HOUSING AND URBAN DEVELOPMENT <\/strong><\/p><p><a href=\"https:\/\/www.hud.gov\/program_offices\/fair_housing_equal_opp\/fair_housing_act_overview\">https:\/\/www.hud.gov\/program_offices\/fair_housing_equal_opp\/fair_housing_act_overview<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Conoce  sobre la ley de vivienda justa en Estados Unidos y c\u00f3mo protege a la poblaci\u00f3n de ser discriminados al rentar o adquirir una casa.<\/p>","protected":false},"author":13,"featured_media":38223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[149],"tags":[165,110,228,109,87,86,47],"class_list":["post-38221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vivienda","tag-ciudadania-estadounidense","tag-discriminacion","tag-estados-unidos","tag-fair-housing-act","tag-inmigrantes","tag-migrantes","tag-vivienda"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Ley de Vivienda Justa y los inmigrantes<\/title>\n<meta name=\"description\" content=\"Conoce sobre la ley de vivienda justa en Estados Unidos y c\u00f3mo protege a la poblaci\u00f3n de ser discriminados al rentar o adquirir una casa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acceso Latino | La Ley de Vivienda Justa y los inmigrantes\" \/>\n<meta property=\"og:description\" content=\"Conoce m\u00e1s sobre la ley de vivienda justa en Estados Unidos y c\u00f3mo protege a la poblaci\u00f3n de ser discriminados al rentar o adquirir una casa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-26T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-24T21:48:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/07\/vivienda-justa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Acceso Latino | La Ley de Vivienda Justa y los inmigrantes\" \/>\n<meta name=\"twitter:description\" content=\"Conoce m\u00e1s sobre la ley de vivienda justa en Estados Unidos y c\u00f3mo protege a la poblaci\u00f3n de ser discriminados al rentar o adquirir una casa.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/04\/vivienda_justa.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-ley-de-vivienda-justa-y-los-inmigrantes\\\/vivienda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-ley-de-vivienda-justa-y-los-inmigrantes\\\/vivienda\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\"},\"headline\":\"La Ley de Vivienda Justa y los inmigrantes\",\"datePublished\":\"2021-07-26T14:00:00+00:00\",\"dateModified\":\"2025-10-24T21:48:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-ley-de-vivienda-justa-y-los-inmigrantes\\\/vivienda\\\/\"},\"wordCount\":457,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-ley-de-vivienda-justa-y-los-inmigrantes\\\/vivienda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/vivienda-justa.jpg\",\"keywords\":[\"Ciudadan\u00eda estadounidense\",\"Discriminaci\u00f3n\",\"Estados Unidos\",\"Fair Housing Act\",\"Inmigrantes\",\"Migrantes\",\"VIVIENDA\"],\"articleSection\":[\"Vivienda\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/la-ley-de-vivienda-justa-y-los-inmigrantes\\\/vivienda\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-ley-de-vivienda-justa-y-los-inmigrantes\\\/vivienda\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/la-ley-de-vivienda-justa-y-los-inmigrantes\\\/vivienda\\\/\",\"name\":\"La Ley de Vivienda Justa y los inmigrantes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-ley-de-vivienda-justa-y-los-inmigrantes\\\/vivienda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-ley-de-vivienda-justa-y-los-inmigrantes\\\/vivienda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/vivienda-justa.jpg\",\"datePublished\":\"2021-07-26T14:00:00+00:00\",\"dateModified\":\"2025-10-24T21:48:20+00:00\",\"description\":\"Conoce sobre la ley de vivienda justa en Estados Unidos y c\u00f3mo protege a la poblaci\u00f3n de ser discriminados al rentar o adquirir una casa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-ley-de-vivienda-justa-y-los-inmigrantes\\\/vivienda\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/la-ley-de-vivienda-justa-y-los-inmigrantes\\\/vivienda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-ley-de-vivienda-justa-y-los-inmigrantes\\\/vivienda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/vivienda-justa.jpg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/vivienda-justa.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/la-ley-de-vivienda-justa-y-los-inmigrantes\\\/vivienda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vivienda\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/vivienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La Ley de Vivienda Justa y los inmigrantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Fair Housing Act and immigrants","description":"Conoce sobre la ley de vivienda justa en Estados Unidos y c\u00f3mo protege a la poblaci\u00f3n de ser discriminados al rentar o adquirir una casa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/","og_locale":"en_US","og_type":"article","og_title":"Acceso Latino | La Ley de Vivienda Justa y los inmigrantes","og_description":"Conoce m\u00e1s sobre la ley de vivienda justa en Estados Unidos y c\u00f3mo protege a la poblaci\u00f3n de ser discriminados al rentar o adquirir una casa.","og_url":"https:\/\/accesolatino.org\/en\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2021-07-26T14:00:00+00:00","article_modified_time":"2025-10-24T21:48:20+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/07\/vivienda-justa.jpg","type":"image\/jpeg"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_title":"Acceso Latino | La Ley de Vivienda Justa y los inmigrantes","twitter_description":"Conoce m\u00e1s sobre la ley de vivienda justa en Estados Unidos y c\u00f3mo protege a la poblaci\u00f3n de ser discriminados al rentar o adquirir una casa.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/04\/vivienda_justa.jpg","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b"},"headline":"La Ley de Vivienda Justa y los inmigrantes","datePublished":"2021-07-26T14:00:00+00:00","dateModified":"2025-10-24T21:48:20+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/"},"wordCount":457,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/07\/vivienda-justa.jpg","keywords":["Ciudadan\u00eda estadounidense","Discriminaci\u00f3n","Estados Unidos","Fair Housing Act","Inmigrantes","Migrantes","VIVIENDA"],"articleSection":["Vivienda"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/","url":"https:\/\/accesolatino.org\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/","name":"The Fair Housing Act and immigrants","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/07\/vivienda-justa.jpg","datePublished":"2021-07-26T14:00:00+00:00","dateModified":"2025-10-24T21:48:20+00:00","description":"Conoce sobre la ley de vivienda justa en Estados Unidos y c\u00f3mo protege a la poblaci\u00f3n de ser discriminados al rentar o adquirir una casa.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/07\/vivienda-justa.jpg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/07\/vivienda-justa.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/la-ley-de-vivienda-justa-y-los-inmigrantes\/vivienda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Vivienda","item":"https:\/\/accesolatino.org\/category\/vivienda\/"},{"@type":"ListItem","position":3,"name":"La Ley de Vivienda Justa y los inmigrantes"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/38221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=38221"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/38221\/revisions"}],"predecessor-version":[{"id":65361,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/38221\/revisions\/65361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/38223"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=38221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=38221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=38221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}