{"id":36967,"date":"2021-05-24T09:10:13","date_gmt":"2021-05-24T14:10:13","guid":{"rendered":"https:\/\/accesolatino.org\/?p=36967"},"modified":"2025-10-24T18:48:19","modified_gmt":"2025-10-25T00:48:19","slug":"conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/","title":{"rendered":"Get to know Ciudadan\u00edzate, the support portal for migrants"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"36967\" class=\"elementor elementor-36967\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-606b38bf elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"606b38bf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6bdff9dc\" data-id=\"6bdff9dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37c63822 elementor-widget elementor-widget-heading\" data-id=\"37c63822\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ciudadan\u00edzate is a portal that has educational and support tools for migrants in their process of obtaining US citizenship.  <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-616ca3a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"616ca3a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76b5b58f\" data-id=\"76b5b58f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-339d82f7 elementor-widget elementor-widget-text-editor\" data-id=\"339d82f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>All immigrants living in U.S. territory seek to have a peaceful life; to work and enjoy the rights and obligations that any U.S. resident has, but the harsh immigration policies that were implemented during the last few years have made the situation difficult.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c525ac2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2c525ac2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-709c2a51\" data-id=\"709c2a51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4448e812 elementor-widget elementor-widget-image\" data-id=\"4448e812\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1350\" height=\"900\" src=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate.jpeg\" class=\"attachment-full size-full wp-image-36968\" alt=\"\" srcset=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate.jpeg 1350w, https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate-300x200.jpeg 300w, https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate-1024x683.jpeg 1024w, https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate-768x512.jpeg 768w, https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate-16x12.jpeg 16w\" sizes=\"(max-width: 1350px) 100vw, 1350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-28e85759\" data-id=\"28e85759\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64e62401 elementor-widget elementor-widget-text-editor\" data-id=\"64e62401\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>However, the plans of the current administration have been clear from the beginning, the search for a comprehensive immigration reform is one of the priorities. In this way, 11 million undocumented people in the United States will be able to obtain their residency. <\/p><p>Acceso Latino has a support section called Citizenship, which redirects you to a specialized site that seeks to facilitate the path to becoming a legal resident in the United States.<\/p><p><a href=\"https:\/\/ciudadanizate.accesolatino.org\">\"Citizenship\" (Ciudadan\u00edzate in english)<\/a> is a tool that guides applicants through the process and shows how simple obtaining U.S. citizenship can be.<\/p><p>Acceso Latino your immigration support portal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d536d13 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2d536d13\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-77d492f\" data-id=\"77d492f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bef67fd elementor-widget elementor-widget-toggle\" data-id=\"bef67fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2001\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2001\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2001\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2001\"><p><strong>CITIZENSHIP<\/strong><\/p><p><a href=\"https:\/\/ciudadanizate.accesolatino.org\">https:\/\/ciudadanizate.accesolatino.org<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ciudadan\u00edzate es un portal que cuenta con herramientas educativas y de apoyo para migrantes en su proceso de obtenci\u00f3n de ciudadan\u00eda estadounidense. Todos los inmigrantes que viven en territorio norteamericano buscan tener una vida pacifica; trabajar y gozar de los derechos y obligaciones que tiene cualquier residente estadounidense pero las duras pol\u00edticas migratorias que fueron implementadas durante los \u00faltimos a\u00f1os dificultaron la situaci\u00f3n. No obstante, los planes de la actual administraci\u00f3n desde su comienzo han sido claros, la b\u00fasqueda de una reforma migratoria integral es una de las prioridades. De esta forma se intenta que 11 millones de personas indocumentadas en Estados Unidos, obtengan su residencia. Acceso Latino cuenta con una secci\u00f3n de apoyo llamada Ciudadan\u00eda, la cual te redirige a un sitio especializado que busca facilitar el camino a ser un residente legal en los Estados Unidos. Ciudadan\u00edzate es una herramienta que gu\u00eda a los solicitantes en su proceso y muestra lo sencillo que puede ser la obtenci\u00f3n de la ciudadan\u00eda estadounidense. Acceso Latino tu portal de apoyo migratorio. BIBLIOGRAF\u00cdA CIUDADAN\u00cdZATE https:\/\/ciudadanizate.accesolatino.org<\/p>","protected":false},"author":13,"featured_media":36968,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[27,220],"tags":[166,164,86],"class_list":["post-36967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudadania","category-ciudadanizate","tag-acceso-latino","tag-ciudadanizate","tag-migrantes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conoce Ciudadan\u00edzate, el portal de apoyo para migrantes<\/title>\n<meta name=\"description\" content=\"Ciudadan\u00edzate es un portal que apoya a migrantes en su proceso de obtenci\u00f3n de ciudadan\u00eda americana.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acceso Latino | Conoce Ciudadan\u00edzate, el portal de apoyo para migrantes\" \/>\n<meta property=\"og:description\" content=\"Ciudadan\u00edzate es un portal que apoya a migrantes en su proceso de obtenci\u00f3n de ciudadan\u00eda americana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-24T14:10:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-25T00:48:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Acceso Latino | Conoce Ciudadan\u00edzate, el portal de apoyo para migrantes\" \/>\n<meta name=\"twitter:description\" content=\"Ciudadan\u00edzate es un portal que apoya a migrantes en su proceso de obtenci\u00f3n de ciudadan\u00eda americana.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate.jpeg\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\\\/ciudadania\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\\\/ciudadania\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Conoce Ciudadan\u00edzate, el portal de apoyo para migrantes\",\"datePublished\":\"2021-05-24T14:10:13+00:00\",\"dateModified\":\"2025-10-25T00:48:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\\\/ciudadania\\\/\"},\"wordCount\":200,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\\\/ciudadania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Ciudadanizate.jpeg\",\"keywords\":[\"Acceso Latino\",\"Ciudadan\u00edzate\",\"Migrantes\"],\"articleSection\":[\"Ciudadan\u00eda\",\"Ciudadan\u00edzate\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\\\/ciudadania\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\\\/ciudadania\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\\\/ciudadania\\\/\",\"name\":\"Conoce Ciudadan\u00edzate, el portal de apoyo para migrantes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\\\/ciudadania\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\\\/ciudadania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Ciudadanizate.jpeg\",\"datePublished\":\"2021-05-24T14:10:13+00:00\",\"dateModified\":\"2025-10-25T00:48:19+00:00\",\"description\":\"Ciudadan\u00edzate es un portal que apoya a migrantes en su proceso de obtenci\u00f3n de ciudadan\u00eda americana.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\\\/ciudadania\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\\\/ciudadania\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\\\/ciudadania\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Ciudadanizate.jpeg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Ciudadanizate.jpeg\",\"width\":1350,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\\\/ciudadania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciudadan\u00eda\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/ciudadania\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conoce Ciudadan\u00edzate, el portal de apoyo para migrantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Get to know Ciudadan\u00edzate, the support portal for migrants","description":"Ciudadan\u00edzate es un portal que apoya a migrantes en su proceso de obtenci\u00f3n de ciudadan\u00eda americana.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/","og_locale":"en_US","og_type":"article","og_title":"Acceso Latino | Conoce Ciudadan\u00edzate, el portal de apoyo para migrantes","og_description":"Ciudadan\u00edzate es un portal que apoya a migrantes en su proceso de obtenci\u00f3n de ciudadan\u00eda americana.","og_url":"https:\/\/accesolatino.org\/en\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2021-05-24T14:10:13+00:00","article_modified_time":"2025-10-25T00:48:19+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate.jpeg","type":"image\/jpeg"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_title":"Acceso Latino | Conoce Ciudadan\u00edzate, el portal de apoyo para migrantes","twitter_description":"Ciudadan\u00edzate es un portal que apoya a migrantes en su proceso de obtenci\u00f3n de ciudadan\u00eda americana.","twitter_image":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate.jpeg","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Conoce Ciudadan\u00edzate, el portal de apoyo para migrantes","datePublished":"2021-05-24T14:10:13+00:00","dateModified":"2025-10-25T00:48:19+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/"},"wordCount":200,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate.jpeg","keywords":["Acceso Latino","Ciudadan\u00edzate","Migrantes"],"articleSection":["Ciudadan\u00eda","Ciudadan\u00edzate"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/","url":"https:\/\/accesolatino.org\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/","name":"Get to know Ciudadan\u00edzate, the support portal for migrants","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate.jpeg","datePublished":"2021-05-24T14:10:13+00:00","dateModified":"2025-10-25T00:48:19+00:00","description":"Ciudadan\u00edzate es un portal que apoya a migrantes en su proceso de obtenci\u00f3n de ciudadan\u00eda americana.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate.jpeg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/05\/Ciudadanizate.jpeg","width":1350,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/conoce-ciudadanizate-el-portal-de-apoyo-para-migrantes\/ciudadania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Ciudadan\u00eda","item":"https:\/\/accesolatino.org\/category\/ciudadania\/"},{"@type":"ListItem","position":3,"name":"Conoce Ciudadan\u00edzate, el portal de apoyo para migrantes"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/36967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=36967"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/36967\/revisions"}],"predecessor-version":[{"id":65455,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/36967\/revisions\/65455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/36968"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=36967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=36967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=36967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}