{"id":3224,"date":"2016-02-27T11:55:43","date_gmt":"2016-02-27T17:55:43","guid":{"rendered":"https:\/\/accesolatino.org\/?p=3224"},"modified":"2025-10-29T14:24:49","modified_gmt":"2025-10-29T20:24:49","slug":"la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/","title":{"rendered":"&#8220;La situaci\u00f3n es complicada&#8221; se\u00f1alan abogados sobre las redadas y su legalidad"},"content":{"rendered":"<p>Las <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/accesolatino.org\/en\/2810-2\/\" target=\"_blank\" rel=\"noopener\">redadas implementadas a partir de los primeros d\u00edas de 2016<\/a><\/span> por agentes federales contra inmigrantes que cuentan con \u00f3rdenes de deportaci\u00f3n finales y que, en teor\u00eda, han agotados todos los recursos legales posibles por defender su estancia en Estados Unidos, ha sido uno de los principales temas de controversia en el pa\u00eds norteamericano; siendo activistas y abogados quienes m\u00e1s han hablado sobre el tema.<\/p>\n<p>A pesar de lo dicho por las autoridades federales sobre <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/accesolatino.org\/en\/dhs-comunica-quienes-son-los-indocumentados-prioritarios-buscados-en-redadas\/\" target=\"_blank\" rel=\"noopener\">los inmigrantes que son prioridad durante las redadas<\/a><\/span>, un reciente estudio elaborado por Transactional Records Access Clearinghouse (TRAC) de la Universidad de Syracuse, Nueva York, dio a conocer que <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/accesolatino.org\/en\/falta-de-asesoria-legal-facilita-deportacion-de-indocumentados\/\" target=\"_blank\" rel=\"noopener\">la mayor\u00eda de los inmigrantes detenidos y deportados durante las primeras redadas no tuvieron representaci\u00f3n legal<\/a><\/span> alguna; lo cual aviv\u00f3 la discusi\u00f3n sobre el tema.<\/p>\n<p>La abogada B\u00e1rbara Hines, ex directora de la Cl\u00ednica de Inmigraci\u00f3n de la Universidad de Texas, coment\u00f3 al respecto que, para efectos de imagen, \u201ces mejor arrestar y deportar a un adulto de 18 a\u00f1os que a una madre con su beb\u00e9, esto debido a la prensa negativa que genera\u201d. Hines a\u00f1adi\u00f3 que \u201cclaramente la falta de abogados, como se\u00f1al\u00f3 el TRAC, y honorarios accesibles\u201d, est\u00e1n causando esto: un elevado n\u00famero de casos perdidos en las cortes y la emisi\u00f3n de \u00f3rdenes de deportaci\u00f3n.<\/p>\n<p>La discusi\u00f3n que se escucha entre los activistas pro inmigrantes se centra en por qu\u00e9 el gobierno estadounidense insiste en deportar a inmigrantes que tienen orden de deportaci\u00f3n, estando enterados que un elevado porcentaje de ellos no tiene representaci\u00f3n legal en las cortes.<\/p>\n<p>\u201cLa situaci\u00f3n es complicada\u201d, dijo al respecto Lilia Vel\u00e1squez, profesora adjunta de la Universidad de California en San Diego. \u201cEn general, los menores no acompa\u00f1ados que solicitan el asilo seguir\u00e1n siendo menores de edad para prop\u00f3sitos de inmigraci\u00f3n. No me extra\u00f1ar\u00eda saber que ICE no conoce el tema de jurisdicci\u00f3n, y asumo que ahora, por cumplir los 18 a\u00f1os, ya dejan de ser menores. No obstante, si el menor de edad fue deportado en ausencia la orden de deportaci\u00f3n se puede ejecutar sin importar la edad\u201d, detall\u00f3.<\/p>\n<p>Por su parte, el abogado Jos\u00e9 Pertierra, de Washington DC, dice que \u201cno son redadas\u201d lo que practican los agentes federales, \u201cpor lo menos no en el sentido cl\u00e1sico de la palabra\u201d, comenta. \u201cICE no est\u00e1 haciendo redadas en los puntos de trabajo (en las f\u00e1bricas, los hoteles, los restaurantes, etc). Tampoco hay redadas en las escuelas. Lo que est\u00e1 ocurriendo son operaciones policiales para detener a ciertas personas que est\u00e1n clasificadas como prioridad para ser deportados\u201d.<\/p>\n<p>Pertierra expone que \u201cante esas prioridades, el inmigrante indocumentado tiene ciertas defensas. Entre ellas est\u00e1 la posibilidad de pedir asilo o la protecci\u00f3n que le concede la Convenci\u00f3n contra la Tortura. Pero <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/accesolatino.org\/en\/obtener-asilo-mision-casi-imposible-para-menores-inmigrantes\/\" target=\"_blank\" rel=\"noopener\">es dif\u00edcil calificar para el asilo<\/a><\/span>. Uno tiene que demostrar que el temor de persecuci\u00f3n que tiene est\u00e1 vinculado a su opini\u00f3n pol\u00edtica, su religi\u00f3n, su etnia o raza, su religi\u00f3n o su membres\u00eda en un grupo social perseguido\u201d.<\/p>\n<p>El abogado agreg\u00f3 que \u201cmuchos jueces piensan que el temor de persecuci\u00f3n, basado solamente en las condiciones generalizadas de violencia o de extorsi\u00f3n no ampara a la persona bajo las reglas de asilo. Por eso les niegan la solicitud a tantas personas que <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/accesolatino.org\/en\/de-que-huyen-los-inmigrantes-provenientes-del-triangulo-del-norte\/\" target=\"_blank\" rel=\"noopener\">vienen huyendo de la violencia en El Salvador, Guatemala y Honduras<\/a><\/span>\".<\/p>\n<p>Como posible soluci\u00f3n a este problema, Pertierra sugiri\u00f3 que, a los ni\u00f1os centroamericanos que piden asilo, \u201cla Casa Blanca les conceda <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/accesolatino.org\/en\/factible-entregar-tps-a-cerca-de-1-millon-de-centroamericanos-informe\/\" target=\"_blank\" rel=\"noopener\">un nuevo programa de TPS<\/a><\/span> (Temporary Protection Status). As\u00ed no tendr\u00edan que establecer su elegibilidad para el asilo para no ser deportados\u201d.<\/p>\n<p>\u201cHay mucho temor en la calle, pero si verdaderamente comprendemos lo que est\u00e1 ocurriendo podemos evitar el p\u00e1nico indebido\u201d, indic\u00f3 el abogado.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <em>La Opini\u00f3n, Univisi\u00f3n<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>Las redadas implementadas a partir de los primeros d\u00edas de 2016 por agentes federales contra inmigrantes que cuentan con \u00f3rdenes de deportaci\u00f3n finales y que, en teor\u00eda, han agotados todos los recursos legales posibles por defender su estancia en Estados Unidos, ha sido uno de los principales temas de controversia en el pa\u00eds norteamericano; siendo activistas y abogados quienes m\u00e1s han hablado sobre el tema. A pesar de lo dicho por las autoridades federales sobre los inmigrantes que son prioridad durante las redadas, un reciente estudio elaborado por Transactional Records Access Clearinghouse (TRAC) de la Universidad de Syracuse, Nueva York, dio a conocer que la mayor\u00eda de los inmigrantes detenidos y deportados durante las primeras redadas no tuvieron representaci\u00f3n legal alguna; lo cual aviv\u00f3 la discusi\u00f3n sobre el tema. La abogada B\u00e1rbara Hines, ex directora de la Cl\u00ednica de Inmigraci\u00f3n de la Universidad de Texas, coment\u00f3 al respecto que, para efectos de imagen, \u201ces mejor arrestar y deportar a un adulto de 18 a\u00f1os que a una madre con su beb\u00e9, esto debido a la prensa negativa que genera\u201d. Hines a\u00f1adi\u00f3 que \u201cclaramente la falta de abogados, como se\u00f1al\u00f3 el TRAC, y honorarios accesibles\u201d, est\u00e1n causando esto: un elevado n\u00famero de casos perdidos en las cortes y la emisi\u00f3n de \u00f3rdenes de deportaci\u00f3n. La discusi\u00f3n que se escucha entre los activistas pro inmigrantes se centra en por qu\u00e9 el gobierno estadounidense insiste en deportar a inmigrantes que tienen orden de deportaci\u00f3n, estando enterados que un elevado porcentaje de ellos no tiene representaci\u00f3n legal en las cortes. \u201cLa situaci\u00f3n es complicada\u201d, dijo al respecto Lilia Vel\u00e1squez, profesora adjunta de la Universidad de California en San Diego. \u201cEn general, los menores no acompa\u00f1ados que solicitan el asilo seguir\u00e1n siendo menores de edad para prop\u00f3sitos de inmigraci\u00f3n. No me extra\u00f1ar\u00eda saber que ICE no conoce el tema de jurisdicci\u00f3n, y asumo que ahora, por cumplir los 18 a\u00f1os, ya dejan de ser menores. No obstante, si el menor de edad fue deportado en ausencia la orden de deportaci\u00f3n se puede ejecutar sin importar la edad\u201d, detall\u00f3. Por su parte, el abogado Jos\u00e9 Pertierra, de Washington DC, dice que \u201cno son redadas\u201d lo que practican los agentes federales, \u201cpor lo menos no en el sentido cl\u00e1sico de la palabra\u201d, comenta. \u201cICE no est\u00e1 haciendo redadas en los puntos de trabajo (en las f\u00e1bricas, los hoteles, los restaurantes, etc). Tampoco hay redadas en las escuelas. Lo que est\u00e1 ocurriendo son operaciones policiales para detener a ciertas personas que est\u00e1n clasificadas como prioridad para ser deportados\u201d. Pertierra expone que \u201cante esas prioridades, el inmigrante indocumentado tiene ciertas defensas. Entre ellas est\u00e1 la posibilidad de pedir asilo o la protecci\u00f3n que le concede la Convenci\u00f3n contra la Tortura. Pero es dif\u00edcil calificar para el asilo. Uno tiene que demostrar que el temor de persecuci\u00f3n que tiene est\u00e1 vinculado a su opini\u00f3n pol\u00edtica, su religi\u00f3n, su etnia o raza, su religi\u00f3n o su membres\u00eda en un grupo social perseguido\u201d. El abogado agreg\u00f3 que \u201cmuchos jueces piensan que el temor de persecuci\u00f3n, basado solamente en las condiciones generalizadas de violencia o de extorsi\u00f3n no ampara a la persona bajo las reglas de asilo. Por eso les niegan la solicitud a tantas personas que vienen huyendo de la violencia en El Salvador, Guatemala y Honduras\u201d. Como posible soluci\u00f3n a este problema, Pertierra sugiri\u00f3 que, a los ni\u00f1os centroamericanos que piden asilo, \u201cla Casa Blanca les conceda un nuevo programa de TPS (Temporary Protection Status). As\u00ed no tendr\u00edan que establecer su elegibilidad para el asilo para no ser deportados\u201d. \u201cHay mucho temor en la calle, pero si verdaderamente comprendemos lo que est\u00e1 ocurriendo podemos evitar el p\u00e1nico indebido\u201d, indic\u00f3 el abogado. &nbsp; Fuente: La Opini\u00f3n, Univisi\u00f3n<\/p>","protected":false},"author":1,"featured_media":3225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-3224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;La situaci\u00f3n es complicada&quot; se\u00f1alan abogados sobre las redadas<\/title>\n<meta name=\"description\" content=\"&quot;La situaci\u00f3n es complicada&quot; se\u00f1alan abogados sobre las redadas y su legalidad\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;La situaci\u00f3n es complicada&quot; se\u00f1alan abogados sobre las redadas\" \/>\n<meta property=\"og:description\" content=\"&quot;La situaci\u00f3n es complicada&quot; se\u00f1alan abogados sobre las redadas y su legalidad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-27T17:55:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T20:24:49+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\\\/noticias\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/9fb7e1272a7201dd9a0e57b2c61d0d0d\"},\"headline\":\"&#8220;La situaci\u00f3n es complicada&#8221; se\u00f1alan abogados sobre las redadas y su legalidad\",\"datePublished\":\"2016-02-27T17:55:43+00:00\",\"dateModified\":\"2025-10-29T20:24:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\\\/noticias\\\/\"},\"wordCount\":678,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\\\/noticias\\\/\",\"name\":\"\\\"La situaci\u00f3n es complicada\\\" se\u00f1alan abogados sobre las redadas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-02-27T17:55:43+00:00\",\"dateModified\":\"2025-10-29T20:24:49+00:00\",\"description\":\"\\\"La situaci\u00f3n es complicada\\\" se\u00f1alan abogados sobre las redadas y su legalidad\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"&#8220;La situaci\u00f3n es complicada&#8221; se\u00f1alan abogados sobre las redadas y su legalidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/9fb7e1272a7201dd9a0e57b2c61d0d0d\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"La situaci\u00f3n es complicada\" se\u00f1alan abogados sobre las redadas","description":"\"La situaci\u00f3n es complicada\" se\u00f1alan abogados sobre las redadas y su legalidad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"\"La situaci\u00f3n es complicada\" se\u00f1alan abogados sobre las redadas","og_description":"\"La situaci\u00f3n es complicada\" se\u00f1alan abogados sobre las redadas y su legalidad","og_url":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2016-02-27T17:55:43+00:00","article_modified_time":"2025-10-29T20:24:49+00:00","author":"admin","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/"},"author":{"name":"admin","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/9fb7e1272a7201dd9a0e57b2c61d0d0d"},"headline":"&#8220;La situaci\u00f3n es complicada&#8221; se\u00f1alan abogados sobre las redadas y su legalidad","datePublished":"2016-02-27T17:55:43+00:00","dateModified":"2025-10-29T20:24:49+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/"},"wordCount":678,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/","url":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/","name":"\"La situaci\u00f3n es complicada\" se\u00f1alan abogados sobre las redadas","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-02-27T17:55:43+00:00","dateModified":"2025-10-29T20:24:49+00:00","description":"\"La situaci\u00f3n es complicada\" se\u00f1alan abogados sobre las redadas y su legalidad","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/la-situacion-es-complicada-senalan-abogados-sobre-las-redadas-y-su-legalidad\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"&#8220;La situaci\u00f3n es complicada&#8221; se\u00f1alan abogados sobre las redadas y su legalidad"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/9fb7e1272a7201dd9a0e57b2c61d0d0d","name":"admin"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/3224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=3224"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/3224\/revisions"}],"predecessor-version":[{"id":67839,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/3224\/revisions\/67839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=3224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=3224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=3224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}