{"id":3186,"date":"2016-02-22T11:55:41","date_gmt":"2016-02-22T17:55:41","guid":{"rendered":"https:\/\/accesolatino.org\/?p=3186"},"modified":"2025-10-29T14:20:26","modified_gmt":"2025-10-29T20:20:26","slug":"ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/","title":{"rendered":"EE UU cancela proyecto de albergue para menores centroamericanos"},"content":{"rendered":"<p>La semana pasada, el <strong>Departamento de Salud y Servicios Humanos de Estados Unidos<\/strong> (<strong>HHS<\/strong>, por sus siglas en ingl\u00e9s) dio a conocer que se cancel\u00f3 el proyecto de un albergue para menores indocumentados centroamericanos en el oeste de Denver, Colorado.<\/p>\n<p>De acuerdo con activistas locales, esta decisi\u00f3n podr\u00eda generar beneficios para los menores inmigrantes que han sido beneficiados con los servicios sociales en Colorado.<\/p>\n<p>El albergue empezar\u00eda a operar en el mes de abril, cuando recibir\u00eda a mil menores indocumentados centroamericanos. Iba a ser construido en Lakewood, pero los costos asociados al plan de renovaci\u00f3n, que pod\u00edan llegar hasta los 37 millones de d\u00f3lares, y el plazo de un a\u00f1o que implicaba la obra fueron razones suficientes para cancelar el proyecto.<\/p>\n<p>Rosa Vergil, miembro de la organizaci\u00f3n pro inmigrante FreshStart, dijo que \u201clas organizaciones que proveen ayuda a inmigrantes menores o a hijos de inmigrantes en el \u00e1rea metropolitana de Denver desde hace a\u00f1os operan casi al l\u00edmite de su capacidad\u201d, y agreg\u00f3 que &#8220;haber tra\u00eddo a mil ni\u00f1os m\u00e1s a Denver, aunque sea con la ayuda del gobierno federal, podr\u00eda haber complicado la situaci\u00f3n de los ni\u00f1os locales, porque las mismas organizaciones que ayudan a unos probablemente estar\u00edan ayudando a los otros&#8221;, situaci\u00f3n que ya no suceder\u00e1 con la cancelaci\u00f3n.<\/p>\n<p>Andrea Helling, portavoz de <strong>HHS<\/strong>, argument\u00f3 que el gobierno necesita un centro operativo a partir de la primavera, por lo que se encuentra buscando otros lugares por el pa\u00eds para gestionar la llegada de menores no acompa\u00f1ados provenientes de Centroam\u00e9rica.<\/p>\n<p>Seg\u00fan datos oficiales, al cierre del a\u00f1o fiscal 2014, entraron a Estados Unidos cerca de 68 mil menores indocumentados no acompa\u00f1ados, cifra que se redujo a 34 mil en 2015.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <em>Univisi\u00f3n<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>La semana pasada, el Departamento de Salud y Servicios Humanos de Estados Unidos (HHS, por sus siglas en ingl\u00e9s) dio a conocer que se cancel\u00f3 el proyecto de un albergue para menores indocumentados centroamericanos en el oeste de Denver, Colorado. De acuerdo con activistas locales, esta decisi\u00f3n podr\u00eda generar beneficios para los menores inmigrantes que han sido beneficiados con los servicios sociales en Colorado. El albergue empezar\u00eda a operar en el mes de abril, cuando recibir\u00eda a mil menores indocumentados centroamericanos. Iba a ser construido en Lakewood, pero los costos asociados al plan de renovaci\u00f3n, que pod\u00edan llegar hasta los 37 millones de d\u00f3lares, y el plazo de un a\u00f1o que implicaba la obra fueron razones suficientes para cancelar el proyecto. Rosa Vergil, miembro de la organizaci\u00f3n pro inmigrante FreshStart, dijo que \u201clas organizaciones que proveen ayuda a inmigrantes menores o a hijos de inmigrantes en el \u00e1rea metropolitana de Denver desde hace a\u00f1os operan casi al l\u00edmite de su capacidad\u201d, y agreg\u00f3 que &#8220;haber tra\u00eddo a mil ni\u00f1os m\u00e1s a Denver, aunque sea con la ayuda del gobierno federal, podr\u00eda haber complicado la situaci\u00f3n de los ni\u00f1os locales, porque las mismas organizaciones que ayudan a unos probablemente estar\u00edan ayudando a los otros&#8221;, situaci\u00f3n que ya no suceder\u00e1 con la cancelaci\u00f3n. Andrea Helling, portavoz de HHS, argument\u00f3 que el gobierno necesita un centro operativo a partir de la primavera, por lo que se encuentra buscando otros lugares por el pa\u00eds para gestionar la llegada de menores no acompa\u00f1ados provenientes de Centroam\u00e9rica. Seg\u00fan datos oficiales, al cierre del a\u00f1o fiscal 2014, entraron a Estados Unidos cerca de 68 mil menores indocumentados no acompa\u00f1ados, cifra que se redujo a 34 mil en 2015. &nbsp; Fuente: Univisi\u00f3n<\/p>","protected":false},"author":1,"featured_media":2951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-3186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EE UU cancela proyecto de albergue para menores centroamericanos<\/title>\n<meta name=\"description\" content=\"EE UU cancela proyecto de albergue para menores centroamericanos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE UU cancela proyecto de albergue para menores centroamericanos\" \/>\n<meta property=\"og:description\" content=\"EE UU cancela proyecto de albergue para menores centroamericanos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-22T17:55:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T20:20:26+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\\\/noticias\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/9fb7e1272a7201dd9a0e57b2c61d0d0d\"},\"headline\":\"EE UU cancela proyecto de albergue para menores centroamericanos\",\"datePublished\":\"2016-02-22T17:55:41+00:00\",\"dateModified\":\"2025-10-29T20:20:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\\\/noticias\\\/\"},\"wordCount\":316,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\\\/noticias\\\/\",\"name\":\"EE UU cancela proyecto de albergue para menores centroamericanos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-02-22T17:55:41+00:00\",\"dateModified\":\"2025-10-29T20:20:26+00:00\",\"description\":\"EE UU cancela proyecto de albergue para menores centroamericanos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EE UU cancela proyecto de albergue para menores centroamericanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/9fb7e1272a7201dd9a0e57b2c61d0d0d\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE UU cancela proyecto de albergue para menores centroamericanos","description":"EE UU cancela proyecto de albergue para menores centroamericanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"EE UU cancela proyecto de albergue para menores centroamericanos","og_description":"EE UU cancela proyecto de albergue para menores centroamericanos","og_url":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2016-02-22T17:55:41+00:00","article_modified_time":"2025-10-29T20:20:26+00:00","author":"admin","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/"},"author":{"name":"admin","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/9fb7e1272a7201dd9a0e57b2c61d0d0d"},"headline":"EE UU cancela proyecto de albergue para menores centroamericanos","datePublished":"2016-02-22T17:55:41+00:00","dateModified":"2025-10-29T20:20:26+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/"},"wordCount":316,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/","url":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/","name":"EE UU cancela proyecto de albergue para menores centroamericanos","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-02-22T17:55:41+00:00","dateModified":"2025-10-29T20:20:26+00:00","description":"EE UU cancela proyecto de albergue para menores centroamericanos","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/ee-uu-cancela-proyecto-de-albergue-para-menores-centroamericanos\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"EE UU cancela proyecto de albergue para menores centroamericanos"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/9fb7e1272a7201dd9a0e57b2c61d0d0d","name":"admin"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/3186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=3186"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/3186\/revisions"}],"predecessor-version":[{"id":67829,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/3186\/revisions\/67829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=3186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=3186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=3186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}