{"id":3057,"date":"2016-02-01T16:55:59","date_gmt":"2016-02-01T22:55:59","guid":{"rendered":"https:\/\/accesolatino.org\/?p=3057"},"modified":"2025-10-29T15:08:27","modified_gmt":"2025-10-29T21:08:27","slug":"recomendaciones-para-esperar-resolucion-de-dapa","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/","title":{"rendered":"Recomendaciones para esperar resoluci\u00f3n de DAPA"},"content":{"rendered":"<p>El pasado 19 de enero la Corte Suprema de Estados Unidos dio a conocer que <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/accesolatino.org\/en\/tribunal-supremo-acepta-estudiar-caso-de-alivios-migratorios\/\" target=\"_blank\" rel=\"noopener\">estudiar\u00eda el caso de los alivios migratorios<\/a><\/span> que se mantienen congelados por una demanda de 26 estados. Aunque es muy temprano para anticipar su decisi\u00f3n, existen posibilidades de que la Corte Suprema de un fallo favorable para los inmigrantes, por lo cual es importante hacer un repaso de qui\u00e9nes son los inmigrantes elegibles y qu\u00e9 hacer para estar listos si se llega a implementar <strong>DAPA<\/strong>.<\/p>\n<p>Para lo anterior, el doctor Nelson Castillo, abogado experto en inmigraci\u00f3n destaca los siguientes requisitos claves para ser elegibles a <strong>DAPA<\/strong>:<\/p>\n<p>1. Ser padre o madre de un ciudadano o residente permanente de los Estados Unidos que haya nacido en o antes del 20 de noviembre de 2014.<\/p>\n<p>2. Haber vivido en Estados Unidos de forma continua desde antes del 1 de enero de 2010.<\/p>\n<p>3. Haber estado f\u00edsicamente presente en Estados Unidos el 20 de noviembre de 2014, y al momento de presentar la petici\u00f3n de <strong>DAPA<\/strong> ante el Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos (USCIS, por sus siglas en ingl\u00e9s).<\/p>\n<p>4. No tener estatus legal el 20 de noviembre de 2014.<\/p>\n<p>5. No ser una prioridad para la deportaci\u00f3n (como por ejemplo, tener antecedentes criminales graves o ser considerado una amenaza a la seguridad nacional y seguridad p\u00fablica).<\/p>\n<p>Asimismo, el experto comparte c\u00f3mo prepararse en caso de que se apruebe <strong>DAPA<\/strong>:<\/p>\n<p>1. Asegurarse de tener documentaci\u00f3n que compruebe la relaci\u00f3n con el hijo ciudadano o residente.<\/p>\n<p>2. Juntar recibos y documentos que demuestren que ha estado viviendo en el pa\u00eds desde antes del 1 de enero de 2010; como por ejemplo, declaraciones de impuestos y recibos de alquiler, luz y tel\u00e9fono que est\u00e9n a su nombre.<\/p>\n<p>3. Si tiene alg\u00fan antecedente criminal o migratorio, consultar con un abogado de inmigraci\u00f3n para asegurarse que es elegible para iniciar el tr\u00e1mite.<\/p>\n<p>4. Ahorrar lo m\u00e1s que puedan para pagar los gastos del tr\u00e1mite en el futuro.<\/p>\n<p>Castillo conf\u00eda que para mediados de este a\u00f1o se de luz verde y se comience a implementar <strong>DAPA<\/strong>. El cual recuerda que es solo un alivio temporal. A su vez recomienda ir con un abogado, pues explica que una consulta con un abogado de inmigraci\u00f3n puede servir no solo para saber si es elegible para <strong>DAPA<\/strong>, sino tambi\u00e9n para analizar si existe una mejor opci\u00f3n legal para vivir en el pa\u00eds, como la residencia permanente.<\/p>\n<p>El punto principal, destaca, es asegurarse de ser elegible y que no existan complicaciones en su historial que puedan perjudicarlo ante el USCIS.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <em>La Opini\u00f3n<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>El pasado 19 de enero la Corte Suprema de Estados Unidos dio a conocer que estudiar\u00eda el caso de los alivios migratorios que se mantienen congelados por una demanda de 26 estados. Aunque es muy temprano para anticipar su decisi\u00f3n, existen posibilidades de que la Corte Suprema de un fallo favorable para los inmigrantes, por lo cual es importante hacer un repaso de qui\u00e9nes son los inmigrantes elegibles y qu\u00e9 hacer para estar listos si se llega a implementar DAPA. Para lo anterior, el doctor Nelson Castillo, abogado experto en inmigraci\u00f3n destaca los siguientes requisitos claves para ser elegibles a DAPA: 1. Ser padre o madre de un ciudadano o residente permanente de los Estados Unidos que haya nacido en o antes del 20 de noviembre de 2014. 2. Haber vivido en Estados Unidos de forma continua desde antes del 1 de enero de 2010. 3. Haber estado f\u00edsicamente presente en Estados Unidos el 20 de noviembre de 2014, y al momento de presentar la petici\u00f3n de DAPA ante el Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos (USCIS, por sus siglas en ingl\u00e9s). 4. No tener estatus legal el 20 de noviembre de 2014. 5. No ser una prioridad para la deportaci\u00f3n (como por ejemplo, tener antecedentes criminales graves o ser considerado una amenaza a la seguridad nacional y seguridad p\u00fablica). Asimismo, el experto comparte c\u00f3mo prepararse en caso de que se apruebe DAPA: 1. Asegurarse de tener documentaci\u00f3n que compruebe la relaci\u00f3n con el hijo ciudadano o residente. 2. Juntar recibos y documentos que demuestren que ha estado viviendo en el pa\u00eds desde antes del 1 de enero de 2010; como por ejemplo, declaraciones de impuestos y recibos de alquiler, luz y tel\u00e9fono que est\u00e9n a su nombre. 3. Si tiene alg\u00fan antecedente criminal o migratorio, consultar con un abogado de inmigraci\u00f3n para asegurarse que es elegible para iniciar el tr\u00e1mite. 4. Ahorrar lo m\u00e1s que puedan para pagar los gastos del tr\u00e1mite en el futuro. Castillo conf\u00eda que para mediados de este a\u00f1o se de luz verde y se comience a implementar DAPA. El cual recuerda que es solo un alivio temporal. A su vez recomienda ir con un abogado, pues explica que una consulta con un abogado de inmigraci\u00f3n puede servir no solo para saber si es elegible para DAPA, sino tambi\u00e9n para analizar si existe una mejor opci\u00f3n legal para vivir en el pa\u00eds, como la residencia permanente. El punto principal, destaca, es asegurarse de ser elegible y que no existan complicaciones en su historial que puedan perjudicarlo ante el USCIS. &nbsp; Fuente: La Opini\u00f3n<\/p>","protected":false},"author":1,"featured_media":3058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-3057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recomendaciones para esperar resoluci\u00f3n de DAPA<\/title>\n<meta name=\"description\" content=\"Recomendaciones para esperar resoluci\u00f3n de DAPA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recomendaciones para esperar resoluci\u00f3n de DAPA\" \/>\n<meta property=\"og:description\" content=\"Recomendaciones para esperar resoluci\u00f3n de DAPA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-01T22:55:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T21:08:27+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/recomendaciones-para-esperar-resolucion-de-dapa\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/recomendaciones-para-esperar-resolucion-de-dapa\\\/noticias\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/9fb7e1272a7201dd9a0e57b2c61d0d0d\"},\"headline\":\"Recomendaciones para esperar resoluci\u00f3n de DAPA\",\"datePublished\":\"2016-02-01T22:55:59+00:00\",\"dateModified\":\"2025-10-29T21:08:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/recomendaciones-para-esperar-resolucion-de-dapa\\\/noticias\\\/\"},\"wordCount\":445,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/recomendaciones-para-esperar-resolucion-de-dapa\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/recomendaciones-para-esperar-resolucion-de-dapa\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/recomendaciones-para-esperar-resolucion-de-dapa\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/recomendaciones-para-esperar-resolucion-de-dapa\\\/noticias\\\/\",\"name\":\"Recomendaciones para esperar resoluci\u00f3n de DAPA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/recomendaciones-para-esperar-resolucion-de-dapa\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/recomendaciones-para-esperar-resolucion-de-dapa\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-02-01T22:55:59+00:00\",\"dateModified\":\"2025-10-29T21:08:27+00:00\",\"description\":\"Recomendaciones para esperar resoluci\u00f3n de DAPA\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/recomendaciones-para-esperar-resolucion-de-dapa\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/en\\\/recomendaciones-para-esperar-resolucion-de-dapa\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/recomendaciones-para-esperar-resolucion-de-dapa\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/en\\\/recomendaciones-para-esperar-resolucion-de-dapa\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recomendaciones para esperar resoluci\u00f3n de DAPA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/9fb7e1272a7201dd9a0e57b2c61d0d0d\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recomendaciones para esperar resoluci\u00f3n de DAPA","description":"Recomendaciones para esperar resoluci\u00f3n de DAPA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Recomendaciones para esperar resoluci\u00f3n de DAPA","og_description":"Recomendaciones para esperar resoluci\u00f3n de DAPA","og_url":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2016-02-01T22:55:59+00:00","article_modified_time":"2025-10-29T21:08:27+00:00","author":"admin","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/"},"author":{"name":"admin","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/9fb7e1272a7201dd9a0e57b2c61d0d0d"},"headline":"Recomendaciones para esperar resoluci\u00f3n de DAPA","datePublished":"2016-02-01T22:55:59+00:00","dateModified":"2025-10-29T21:08:27+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/"},"wordCount":445,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/","url":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/","name":"Recomendaciones para esperar resoluci\u00f3n de DAPA","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-02-01T22:55:59+00:00","dateModified":"2025-10-29T21:08:27+00:00","description":"Recomendaciones para esperar resoluci\u00f3n de DAPA","breadcrumb":{"@id":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/en\/recomendaciones-para-esperar-resolucion-de-dapa\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Recomendaciones para esperar resoluci\u00f3n de DAPA"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/9fb7e1272a7201dd9a0e57b2c61d0d0d","name":"admin"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/3057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=3057"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/3057\/revisions"}],"predecessor-version":[{"id":67887,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/3057\/revisions\/67887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=3057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=3057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=3057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}