{"id":2244,"date":"2015-10-03T11:55:58","date_gmt":"2015-10-03T16:55:58","guid":{"rendered":"https:\/\/accesolatino.org\/?p=2244"},"modified":"2025-10-29T19:48:46","modified_gmt":"2025-10-30T01:48:46","slug":"madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/","title":{"rendered":"Madres inmigrantes presentan nuevas acusaciones ante ICE"},"content":{"rendered":"<p>The <strong>Servicio de Control de Inmigraci\u00f3n y Aduanas<\/strong> (<strong>ICE<\/strong>, por sus siglas en ingl\u00e9s), enfrenta nuevas acusaciones por parte de abogados que asisten a madres inmigrantes detenidas en los centros de detenci\u00f3n de Texas con hijos menores de edad.<\/p>\n<p>Las madres inmigrantes solicitaron una investigaci\u00f3n ante lo que los abogados describen como <strong>\u201ct\u00e1cticas de coerci\u00f3n\u201d<\/strong> para que las madres cedan su derecho a salir bajo fianza y acepten el uso de monitores electr\u00f3nicos de tobillo, adem\u00e1s de pr\u00e1cticas que les niegan el acceso para poder ver a sus abogados.<\/p>\n<p>Un comunicado de <strong>CARA<\/strong>, proyecto de asistencia gratuita a familias detenidas que asiste a las refugiadas en centros de detenci\u00f3n, exige \u201cque el <strong>Departamento de Seguridad Nacional<\/strong> investigue estos casos porque estamos presentando documentaci\u00f3n de pr\u00e1cticas intimidatorias, desinformaci\u00f3n y violaciones al derecho a asesor\u00eda legal en el Centro Residencial para Familias en Diley, Texas\u201d.<\/p>\n<p>De acuerdo con el documento acusatorio, \u201cluego que el juez de inmigraci\u00f3n ordena la liberaci\u00f3n de una madre inmigrante bajo fianza, <strong>ICE<\/strong> la llama a una reuni\u00f3n en la que le dice que debe aceptar los monitores electr\u00f3nicos en vez de poner fianza\u201d.<\/p>\n<p>Los abogados tambi\u00e9n alegan que en otras ocasiones, los agentes de <strong>ICE<\/strong> dicen a las madres inmigrantes que \u201ces mejor que usen el monitor\u201d porque conseguir fianza \u201cles saldr\u00e1 muy caro y tendr\u00e1n que estar detenidas m\u00e1s tiempo\u201d.<\/p>\n<p>\u201c<strong>ICE<\/strong> est\u00e1 usando t\u00e1cticas ilegales para intimidar a las madres inmigrantes y limitar sus derechos. Estas t\u00e1cticas incluyen bloquear el acceso a las detenidas por parte de sus abogados mientras ellas son interrogadas por agentes, las amenazan con no darles atenci\u00f3n m\u00e9dica a sus hijos si las madres solicitan fianza y las presionan para aceptar los monitores electr\u00f3nicos\u201d, se\u00f1ala el documento. \u201cTambi\u00e9n se han reportado amenazas de deportaci\u00f3n si las madres preguntan o tienen dudas o se preocupan por sus casos\u201d, sentencia.<\/p>\n<p>Fuente: <em>American Immigration Council<\/em>    \t<\/p>","protected":false},"excerpt":{"rendered":"<p>El Servicio de Control de Inmigraci\u00f3n y Aduanas (ICE, por sus siglas en ingl\u00e9s), enfrenta nuevas acusaciones por parte de abogados que asisten a madres inmigrantes detenidas en los centros de detenci\u00f3n de Texas con hijos menores de edad. Las madres inmigrantes solicitaron una investigaci\u00f3n ante lo que los abogados describen como \u201ct\u00e1cticas de coerci\u00f3n\u201d para que las madres cedan su derecho a salir bajo fianza y acepten el uso de monitores electr\u00f3nicos de tobillo, adem\u00e1s de pr\u00e1cticas que les niegan el acceso para poder ver a sus abogados. Un comunicado de CARA, proyecto de asistencia gratuita a familias detenidas que asiste a las refugiadas en centros de detenci\u00f3n, exige \u201cque el Departamento de Seguridad Nacional investigue estos casos porque estamos presentando documentaci\u00f3n de pr\u00e1cticas intimidatorias, desinformaci\u00f3n y violaciones al derecho a asesor\u00eda legal en el Centro Residencial para Familias en Diley, Texas\u201d. De acuerdo con el documento acusatorio, \u201cluego que el juez de inmigraci\u00f3n ordena la liberaci\u00f3n de una madre inmigrante bajo fianza, ICE la llama a una reuni\u00f3n en la que le dice que debe aceptar los monitores electr\u00f3nicos en vez de poner fianza\u201d. Los abogados tambi\u00e9n alegan que en otras ocasiones, los agentes de ICE dicen a las madres inmigrantes que \u201ces mejor que usen el monitor\u201d porque conseguir fianza \u201cles saldr\u00e1 muy caro y tendr\u00e1n que estar detenidas m\u00e1s tiempo\u201d. \u201cICE est\u00e1 usando t\u00e1cticas ilegales para intimidar a las madres inmigrantes y limitar sus derechos. Estas t\u00e1cticas incluyen bloquear el acceso a las detenidas por parte de sus abogados mientras ellas son interrogadas por agentes, las amenazan con no darles atenci\u00f3n m\u00e9dica a sus hijos si las madres solicitan fianza y las presionan para aceptar los monitores electr\u00f3nicos\u201d, se\u00f1ala el documento. \u201cTambi\u00e9n se han reportado amenazas de deportaci\u00f3n si las madres preguntan o tienen dudas o se preocupan por sus casos\u201d, sentencia. Fuente: American Immigration Council<\/p>","protected":false},"author":13,"featured_media":2245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-2244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Madres inmigrantes presentan nuevas acusaciones ante ICE<\/title>\n<meta name=\"description\" content=\"ICE enfrenta nuevas acusaciones por parte de abogados que asisten a madres inmigrantes detenidas en sus centros de detenci\u00f3n por \u201ct\u00e1cticas de coerci\u00f3n\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madres inmigrantes presentan nuevas acusaciones ante ICE\" \/>\n<meta property=\"og:description\" content=\"ICE enfrenta nuevas acusaciones por parte de abogados que asisten a madres inmigrantes detenidas en sus centros de detenci\u00f3n por \u201ct\u00e1cticas de coerci\u00f3n\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-03T16:55:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T01:48:46+00:00\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Madres inmigrantes presentan nuevas acusaciones ante ICE\",\"datePublished\":\"2015-10-03T16:55:58+00:00\",\"dateModified\":\"2025-10-30T01:48:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\\\/noticias\\\/\"},\"wordCount\":346,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\\\/noticias\\\/\",\"name\":\"Madres inmigrantes presentan nuevas acusaciones ante ICE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-10-03T16:55:58+00:00\",\"dateModified\":\"2025-10-30T01:48:46+00:00\",\"description\":\"ICE enfrenta nuevas acusaciones por parte de abogados que asisten a madres inmigrantes detenidas en sus centros de detenci\u00f3n por \u201ct\u00e1cticas de coerci\u00f3n\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\\\/noticias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Madres inmigrantes presentan nuevas acusaciones ante ICE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Madres inmigrantes presentan nuevas acusaciones ante ICE","description":"ICE enfrenta nuevas acusaciones por parte de abogados que asisten a madres inmigrantes detenidas en sus centros de detenci\u00f3n por \u201ct\u00e1cticas de coerci\u00f3n\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Madres inmigrantes presentan nuevas acusaciones ante ICE","og_description":"ICE enfrenta nuevas acusaciones por parte de abogados que asisten a madres inmigrantes detenidas en sus centros de detenci\u00f3n por \u201ct\u00e1cticas de coerci\u00f3n\u201d.","og_url":"https:\/\/accesolatino.org\/en\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2015-10-03T16:55:58+00:00","article_modified_time":"2025-10-30T01:48:46+00:00","author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Madres inmigrantes presentan nuevas acusaciones ante ICE","datePublished":"2015-10-03T16:55:58+00:00","dateModified":"2025-10-30T01:48:46+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/"},"wordCount":346,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/","url":"https:\/\/accesolatino.org\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/","name":"Madres inmigrantes presentan nuevas acusaciones ante ICE","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-10-03T16:55:58+00:00","dateModified":"2025-10-30T01:48:46+00:00","description":"ICE enfrenta nuevas acusaciones por parte de abogados que asisten a madres inmigrantes detenidas en sus centros de detenci\u00f3n por \u201ct\u00e1cticas de coerci\u00f3n\u201d.","breadcrumb":{"@id":"https:\/\/accesolatino.org\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/madres-inmigrantes-presentan-nuevas-acusaciones-ante-ice\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Madres inmigrantes presentan nuevas acusaciones ante ICE"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/2244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=2244"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/2244\/revisions"}],"predecessor-version":[{"id":68091,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/2244\/revisions\/68091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=2244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=2244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=2244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}