{"id":20019,"date":"2020-01-30T10:58:57","date_gmt":"2020-01-30T16:58:57","guid":{"rendered":"https:\/\/accesolatino.org\/?p=20019"},"modified":"2025-10-26T21:26:47","modified_gmt":"2025-10-27T03:26:47","slug":"inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/","title":{"rendered":"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20019\" class=\"elementor elementor-20019\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-369f77a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"369f77a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ef62e2\" data-id=\"8ef62e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9121ee elementor-widget elementor-widget-text-editor\" data-id=\"d9121ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Como todos los a\u00f1os, comienza la temporada de declaraci\u00f3n de impuestos que durar\u00e1 hasta el 15 de abril; inmigrantes e indocumentados y algunos extranjeros que no cuenten con green card o seguro social, deberan realizar este tr\u00e1mite, as\u00ed lo declar\u00f3 el Servicio de Renta Interna (IRS, por sus siglas en ingl\u00e9s).<\/p><p>Estos son los casos y las personas que deben presentar su declaraci\u00f3n de impuestos:<\/p><ul><li>Extranjeros residentes que manejaron alg\u00fan negocio o comercio en la Uni\u00f3n Americana durante el a\u00f1o anterior. Si los ingresos fueron m\u00ednimos, no se tiene que presentar ning\u00fan tr\u00e1mite tributario.<\/li><li>Estudiantes, maestros, o participantes en cursos, diplomados, o entrenamientos que tomaron en territorio norteamericano por un tiempo, con el tipo de visa F, J, M o Q, deben presentar su declaraci\u00f3n si tuvieron un sueldo o sus ingresos fueron mediante propinas, apoyos, becas y subvenciones.<\/li><li>Inmigrantes que adquirieron entradas de dinero procedentes de Estados Unidos y les fueron retenidos por su patr\u00f3n.<\/li><li>Extranjeros que sean herederos de una herencia o de un fideicomiso de un inmigrante.<\/li><li>Herederos residentes o ciudadanos encargados de cuidar a una persona inmigrante, o el inmueble de la misma y existe la posibilidad de que se le solicite presentar una declaraci\u00f3n de impuestos sobre la remuneraci\u00f3n econ\u00f3mica de dicha persona.<\/li><\/ul><p><strong>\u00bfC\u00f3mo se obtiene el N\u00famero de Identificaci\u00f3n de Contribuyente Individual o ITIN?<\/strong><\/p><p>Lo que se necesita es llenar el formulario de solicitud (W-7) donde viene informaci\u00f3n b\u00e1sica como nombre, fecha de nacimiento, domicilio \u2013 declaraci\u00f3n de impuestos federales y prueba de identidad que confirme la autenticidad de la persona. El formulario es gratuito.<\/p><p>No es necesario presentar la solicitud en persona, \u00a0el ITIN se env\u00eda por correo.<\/p><p>Recuerda: El ITIN no garantiza un estatus legal o laboral.<\/p><p>Aquellos que tienen n\u00famero de seguro social no necesitan el N\u00famero de Identificaci\u00f3n de Contribuyente Individual.<\/p><p>El ITIN se debe validar cada 5 a\u00f1os y expira aproximadamente cada tres en caso de que no se use.<\/p><p>Fuente: Telemundo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Como todos los a\u00f1os, comienza la temporada de declaraci\u00f3n de impuestos que durar\u00e1 hasta el 15 de abril; inmigrantes e indocumentados y algunos extranjeros que no cuenten con green card o seguro social, deberan realizar este tr\u00e1mite, as\u00ed lo declar\u00f3 el Servicio de Renta Interna (IRS, por sus siglas en ingl\u00e9s). Estos son los casos y las personas que deben presentar su declaraci\u00f3n de impuestos: Extranjeros residentes que manejaron alg\u00fan negocio o comercio en la Uni\u00f3n Americana durante el a\u00f1o anterior. Si los ingresos fueron m\u00ednimos, no se tiene que presentar ning\u00fan tr\u00e1mite tributario. Estudiantes, maestros, o participantes en cursos, diplomados, o entrenamientos que tomaron en territorio norteamericano por un tiempo, con el tipo de visa F, J, M o Q, deben presentar su declaraci\u00f3n si tuvieron un sueldo o sus ingresos fueron mediante propinas, apoyos, becas y subvenciones. Inmigrantes que adquirieron entradas de dinero procedentes de Estados Unidos y les fueron retenidos por su patr\u00f3n. Extranjeros que sean herederos de una herencia o de un fideicomiso de un inmigrante. Herederos residentes o ciudadanos encargados de cuidar a una persona inmigrante, o el inmueble de la misma y existe la posibilidad de que se le solicite presentar una declaraci\u00f3n de impuestos sobre la remuneraci\u00f3n econ\u00f3mica de dicha persona. \u00bfC\u00f3mo se obtiene el N\u00famero de Identificaci\u00f3n de Contribuyente Individual o ITIN? Lo que se necesita es llenar el formulario de solicitud (W-7) donde viene informaci\u00f3n b\u00e1sica como nombre, fecha de nacimiento, domicilio \u2013 declaraci\u00f3n de impuestos federales y prueba de identidad que confirme la autenticidad de la persona. El formulario es gratuito. No es necesario presentar la solicitud en persona, &nbsp;el ITIN se env\u00eda por correo. Recuerda: El ITIN no garantiza un estatus legal o laboral. Aquellos que tienen n\u00famero de seguro social no necesitan el N\u00famero de Identificaci\u00f3n de Contribuyente Individual. El ITIN se debe validar cada 5 a\u00f1os y expira aproximadamente cada tres en caso de que no se use. Fuente: Telemundo<\/p>","protected":false},"author":13,"featured_media":20020,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-20019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos<\/title>\n<meta name=\"description\" content=\"Como todos los a\u00f1os, comienza la temporada de declaraci\u00f3n de impuestos que durar\u00e1 hasta el 15 de abril; inmigrantes e indocumentados\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos\" \/>\n<meta property=\"og:description\" content=\"Como todos los a\u00f1os, comienza la temporada de declaraci\u00f3n de impuestos que durar\u00e1 hasta el 15 de abril; inmigrantes e indocumentados\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-30T16:58:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T03:26:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"601\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\"},\"headline\":\"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos\",\"datePublished\":\"2020-01-30T16:58:57+00:00\",\"dateModified\":\"2025-10-27T03:26:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\\\/noticias\\\/\"},\"wordCount\":358,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\\\/noticias\\\/\",\"name\":\"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg\",\"datePublished\":\"2020-01-30T16:58:57+00:00\",\"dateModified\":\"2025-10-27T03:26:47+00:00\",\"description\":\"Como todos los a\u00f1os, comienza la temporada de declaraci\u00f3n de impuestos que durar\u00e1 hasta el 15 de abril; inmigrantes e indocumentados\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg\",\"width\":601,\"height\":338,\"caption\":\"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/67cbd51f49f7aa98f6ad62bb965cf662\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos","description":"Como todos los a\u00f1os, comienza la temporada de declaraci\u00f3n de impuestos que durar\u00e1 hasta el 15 de abril; inmigrantes e indocumentados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos","og_description":"Como todos los a\u00f1os, comienza la temporada de declaraci\u00f3n de impuestos que durar\u00e1 hasta el 15 de abril; inmigrantes e indocumentados","og_url":"https:\/\/accesolatino.org\/en\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2020-01-30T16:58:57+00:00","article_modified_time":"2025-10-27T03:26:47+00:00","og_image":[{"width":601,"height":338,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg","type":"image\/jpeg"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662"},"headline":"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos","datePublished":"2020-01-30T16:58:57+00:00","dateModified":"2025-10-27T03:26:47+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/"},"wordCount":358,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/","url":"https:\/\/accesolatino.org\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/","name":"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg","datePublished":"2020-01-30T16:58:57+00:00","dateModified":"2025-10-27T03:26:47+00:00","description":"Como todos los a\u00f1os, comienza la temporada de declaraci\u00f3n de impuestos que durar\u00e1 hasta el 15 de abril; inmigrantes e indocumentados","breadcrumb":{"@id":"https:\/\/accesolatino.org\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Inmigrantes-e-indocumentados-deben-presentar-su-declaraci\u00f3n-de-impuestos.jpg","width":601,"height":338,"caption":"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos"},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/inmigrantes-e-indocumentados-deben-presentar-su-declaracion-de-impuestos\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Inmigrantes e indocumentados deben presentar su declaraci\u00f3n de impuestos"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/67cbd51f49f7aa98f6ad62bb965cf662","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/20019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=20019"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/20019\/revisions"}],"predecessor-version":[{"id":66014,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/20019\/revisions\/66014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/20020"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=20019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=20019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=20019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}