{"id":19940,"date":"2020-01-24T10:45:08","date_gmt":"2020-01-24T16:45:08","guid":{"rendered":"https:\/\/accesolatino.org\/?p=19940"},"modified":"2025-10-26T21:27:54","modified_gmt":"2025-10-27T03:27:54","slug":"andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados","status":"publish","type":"post","link":"https:\/\/accesolatino.org\/en\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/","title":{"rendered":"Andrew Cuomo da a conocer su presupuesto 2021 que beneficiar\u00eda a millones de indocumentados"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"19940\" class=\"elementor elementor-19940\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ae491ef elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2ae491ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29caa9c0\" data-id=\"29caa9c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2572709e elementor-widget elementor-widget-text-editor\" data-id=\"2572709e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El gobernador Andrew Cuomo, dio a conocer su presupuesto 2021 y las reformas de su administraci\u00f3n, en la que destaca la regulaci\u00f3n de bicicletas y motocicletas el\u00e9ctricas, para circular en la ciudad y que ayudar\u00eda a miles de indocumentados a transportarse y facilitar\u00eda el trabajo de millares de repartidores inmigrantes sin papeles en la Gran Manzana.<\/p><p>En un comunicado de prensa publicado el martes 21 de enero por la administraci\u00f3n de Cuomo, declararon que: \u201cpara disminuir el n\u00famero autom\u00f3viles circulando, el Gobernador propone una legislaci\u00f3n completa para legalizar y expandir la red de bicicletas y motocicletas el\u00e9ctricas sin que se vea en riesgo la seguridad ciudadana\u201d.<\/p><p>Esta decisi\u00f3n fue muy bien recibida por la ONG Make The Road, ya que en diciembre de 2019, fue anulada una reforma, por el alcalde de la ciudad de Nueva York, Bill de Blasio, que legalizaba este medio de transporte y que brindaba los mismos derechos de las bicis tradicionales a las el\u00e9ctricas.<\/p><p>Este veto fue muy criticado por Make The Road y otras organizaciones pro inmigrantes, por lo que destac\u00f3 que esta propuesta del gobernador Cuomo, ayudar\u00e1 a los repartidores que en su mayor\u00eda son indocumentados y que han tenido que pagar cuantiosas multas y sufrieron la incautaci\u00f3n de sus bicicletas solo por hacer su trabajo.<\/p><p>Adicional a esta medida, el gobernador de Nueva York, inform\u00f3 que har\u00eda una inversi\u00f3n de $33 mil millones de d\u00f3lares en cinco a\u00f1os para luchar contra el cambio clim\u00e1tico; tambi\u00e9n impulsar\u00eda una financiamiento de $275 mil millones para crear nuevas infraestructuras y desarrollar\u00eda un fondo de $25 millones para combatir los cr\u00edmenes de odio.<\/p><p>De igual forma, Cuomo dio su palaba de aumentar el presupuesto a la educaci\u00f3n de $28 mil 500 millones a $826 mil millones, con la clara idea de \u201cequilibrar las diferencias\u201d y ofrecer m\u00e1s ayuda a los colegios con menos recursos econ\u00f3micos.<\/p><p>Conjuntamente, destac\u00f3 un monto de $64 millones de d\u00f3lares, para los servicios que brindan apoyo a las personas sin hogar y buscar\u00e1 incrementar las inversiones para lidiar con la pobreza infantil.<\/p><p>Fuente: La Opini\u00f3n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El gobernador Andrew Cuomo, dio a conocer su presupuesto 2021 y las reformas de su administraci\u00f3n, en la que destaca la regulaci\u00f3n de bicicletas y motocicletas el\u00e9ctricas, para circular en la ciudad y que ayudar\u00eda a miles de indocumentados a transportarse y facilitar\u00eda el trabajo de millares de repartidores inmigrantes sin papeles en la Gran Manzana. En un comunicado de prensa publicado el martes 21 de enero por la administraci\u00f3n de Cuomo, declararon que: \u201cpara disminuir el n\u00famero autom\u00f3viles circulando, el Gobernador propone una legislaci\u00f3n completa para legalizar y expandir la red de bicicletas y motocicletas el\u00e9ctricas sin que se vea en riesgo la seguridad ciudadana\u201d. Esta decisi\u00f3n fue muy bien recibida por la ONG Make The Road, ya que en diciembre de 2019, fue anulada una reforma, por el alcalde de la ciudad de Nueva York, Bill de Blasio, que legalizaba este medio de transporte y que brindaba los mismos derechos de las bicis tradicionales a las el\u00e9ctricas. Este veto fue muy criticado por Make The Road y otras organizaciones pro inmigrantes, por lo que destac\u00f3 que esta propuesta del gobernador Cuomo, ayudar\u00e1 a los repartidores que en su mayor\u00eda son indocumentados y que han tenido que pagar cuantiosas multas y sufrieron la incautaci\u00f3n de sus bicicletas solo por hacer su trabajo. Adicional a esta medida, el gobernador de Nueva York, inform\u00f3 que har\u00eda una inversi\u00f3n de $33 mil millones de d\u00f3lares en cinco a\u00f1os para luchar contra el cambio clim\u00e1tico; tambi\u00e9n impulsar\u00eda una financiamiento de $275 mil millones para crear nuevas infraestructuras y desarrollar\u00eda un fondo de $25 millones para combatir los cr\u00edmenes de odio. De igual forma, Cuomo dio su palaba de aumentar el presupuesto a la educaci\u00f3n de $28 mil 500 millones a $826 mil millones, con la clara idea de \u201cequilibrar las diferencias\u201d y ofrecer m\u00e1s ayuda a los colegios con menos recursos econ\u00f3micos. Conjuntamente, destac\u00f3 un monto de $64 millones de d\u00f3lares, para los servicios que brindan apoyo a las personas sin hogar y buscar\u00e1 incrementar las inversiones para lidiar con la pobreza infantil. Fuente: La Opini\u00f3n<\/p>","protected":false},"author":13,"featured_media":19942,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-19940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-temas-de-interes"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Andrew Cuomo da a conocer su presupuesto 2021 que beneficiar\u00eda a millones de indocumentados<\/title>\n<meta name=\"description\" content=\"El gobernador Andrew Cuomo, dio a conocer su presupuesto 2021 y las reformas de su administraci\u00f3n, en la que destaca la regulaci\u00f3n de bicicletas y\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accesolatino.org\/en\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Andrew Cuomo da a conocer su presupuesto 2021 que beneficiar\u00eda a millones de indocumentados\" \/>\n<meta property=\"og:description\" content=\"El gobernador Andrew Cuomo, dio a conocer su presupuesto 2021 y las reformas de su administraci\u00f3n, en la que destaca la regulaci\u00f3n de bicicletas y\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accesolatino.org\/en\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Acceso Latino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AccesoLatinoOrg\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-24T16:45:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T03:27:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Andrew-Cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiar\u00eda-a-millones-de-indocumentados.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Noticias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:site\" content=\"@FAccLatino\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\\\/noticias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\\\/noticias\\\/\"},\"author\":{\"name\":\"Noticias\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\"},\"headline\":\"Andrew Cuomo da a conocer su presupuesto 2021 que beneficiar\u00eda a millones de indocumentados\",\"datePublished\":\"2020-01-24T16:45:08+00:00\",\"dateModified\":\"2025-10-27T03:27:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\\\/noticias\\\/\"},\"wordCount\":375,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Andrew-Cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiar\u00eda-a-millones-de-indocumentados.png\",\"articleSection\":[\"Noticias\",\"Temas de inter\u00e9s\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\\\/noticias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\\\/noticias\\\/\",\"name\":\"Andrew Cuomo da a conocer su presupuesto 2021 que beneficiar\u00eda a millones de indocumentados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\\\/noticias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\\\/noticias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Andrew-Cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiar\u00eda-a-millones-de-indocumentados.png\",\"datePublished\":\"2020-01-24T16:45:08+00:00\",\"dateModified\":\"2025-10-27T03:27:54+00:00\",\"description\":\"El gobernador Andrew Cuomo, dio a conocer su presupuesto 2021 y las reformas de su administraci\u00f3n, en la que destaca la regulaci\u00f3n de bicicletas y\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accesolatino.org\\\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\\\/noticias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\\\/noticias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Andrew-Cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiar\u00eda-a-millones-de-indocumentados.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Andrew-Cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiar\u00eda-a-millones-de-indocumentados.png\",\"width\":600,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/accesolatino.org\\\/category\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Andrew Cuomo da a conocer su presupuesto 2021 que beneficiar\u00eda a millones de indocumentados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#website\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"description\":\"Fundaci\u00f3n Carlos Slim\",\"publisher\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accesolatino.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#organization\",\"name\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"contentUrl\":\"https:\\\/\\\/accesolatino.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-footer-acceso-latino.png\",\"width\":240,\"height\":40,\"caption\":\"Acceso Latino | Fundaci\u00f3n Carlos Slim\"},\"image\":{\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AccesoLatinoOrg\",\"https:\\\/\\\/x.com\\\/FAccLatino\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/accesolatino.org\\\/#\\\/schema\\\/person\\\/02e18d7f2b61f1a94fe01638b3c2244b\",\"name\":\"Noticias\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Andrew Cuomo da a conocer su presupuesto 2021 que beneficiar\u00eda a millones de indocumentados","description":"El gobernador Andrew Cuomo, dio a conocer su presupuesto 2021 y las reformas de su administraci\u00f3n, en la que destaca la regulaci\u00f3n de bicicletas y","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accesolatino.org\/en\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/","og_locale":"en_US","og_type":"article","og_title":"Andrew Cuomo da a conocer su presupuesto 2021 que beneficiar\u00eda a millones de indocumentados","og_description":"El gobernador Andrew Cuomo, dio a conocer su presupuesto 2021 y las reformas de su administraci\u00f3n, en la que destaca la regulaci\u00f3n de bicicletas y","og_url":"https:\/\/accesolatino.org\/en\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/","og_site_name":"Acceso Latino","article_publisher":"https:\/\/www.facebook.com\/AccesoLatinoOrg","article_published_time":"2020-01-24T16:45:08+00:00","article_modified_time":"2025-10-27T03:27:54+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Andrew-Cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiar\u00eda-a-millones-de-indocumentados.png","type":"image\/png"}],"author":"Noticias","twitter_card":"summary_large_image","twitter_creator":"@FAccLatino","twitter_site":"@FAccLatino","twitter_misc":{"Written by":"Noticias","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/accesolatino.org\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/#article","isPartOf":{"@id":"https:\/\/accesolatino.org\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/"},"author":{"name":"Noticias","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b"},"headline":"Andrew Cuomo da a conocer su presupuesto 2021 que beneficiar\u00eda a millones de indocumentados","datePublished":"2020-01-24T16:45:08+00:00","dateModified":"2025-10-27T03:27:54+00:00","mainEntityOfPage":{"@id":"https:\/\/accesolatino.org\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/"},"wordCount":375,"commentCount":0,"publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"image":{"@id":"https:\/\/accesolatino.org\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Andrew-Cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiar\u00eda-a-millones-de-indocumentados.png","articleSection":["Noticias","Temas de inter\u00e9s"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/accesolatino.org\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/accesolatino.org\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/","url":"https:\/\/accesolatino.org\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/","name":"Andrew Cuomo da a conocer su presupuesto 2021 que beneficiar\u00eda a millones de indocumentados","isPartOf":{"@id":"https:\/\/accesolatino.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accesolatino.org\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/#primaryimage"},"image":{"@id":"https:\/\/accesolatino.org\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/#primaryimage"},"thumbnailUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Andrew-Cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiar\u00eda-a-millones-de-indocumentados.png","datePublished":"2020-01-24T16:45:08+00:00","dateModified":"2025-10-27T03:27:54+00:00","description":"El gobernador Andrew Cuomo, dio a conocer su presupuesto 2021 y las reformas de su administraci\u00f3n, en la que destaca la regulaci\u00f3n de bicicletas y","breadcrumb":{"@id":"https:\/\/accesolatino.org\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accesolatino.org\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/#primaryimage","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Andrew-Cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiar\u00eda-a-millones-de-indocumentados.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2020\/01\/Andrew-Cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiar\u00eda-a-millones-de-indocumentados.png","width":600,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/accesolatino.org\/andrew-cuomo-da-a-conocer-su-presupuesto-2021-que-beneficiaria-a-millones-de-indocumentados\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/accesolatino.org\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/accesolatino.org\/category\/noticias\/"},{"@type":"ListItem","position":3,"name":"Andrew Cuomo da a conocer su presupuesto 2021 que beneficiar\u00eda a millones de indocumentados"}]},{"@type":"WebSite","@id":"https:\/\/accesolatino.org\/#website","url":"https:\/\/accesolatino.org\/","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","description":"Fundaci\u00f3n Carlos Slim","publisher":{"@id":"https:\/\/accesolatino.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accesolatino.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/accesolatino.org\/#organization","name":"Acceso Latino | Fundaci\u00f3n Carlos Slim","url":"https:\/\/accesolatino.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/","url":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","contentUrl":"https:\/\/accesolatino.org\/wp-content\/uploads\/2021\/02\/logo-footer-acceso-latino.png","width":240,"height":40,"caption":"Acceso Latino | Fundaci\u00f3n Carlos Slim"},"image":{"@id":"https:\/\/accesolatino.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AccesoLatinoOrg","https:\/\/x.com\/FAccLatino"]},{"@type":"Person","@id":"https:\/\/accesolatino.org\/#\/schema\/person\/02e18d7f2b61f1a94fe01638b3c2244b","name":"News"}]}},"_links":{"self":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/19940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/comments?post=19940"}],"version-history":[{"count":1,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/19940\/revisions"}],"predecessor-version":[{"id":66020,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/posts\/19940\/revisions\/66020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media\/19942"}],"wp:attachment":[{"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/media?parent=19940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/categories?post=19940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/accesolatino.org\/en\/wp-json\/wp\/v2\/tags?post=19940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}